{"id":3593,"date":"2021-06-11T15:17:25","date_gmt":"2021-06-11T14:17:25","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=3593"},"modified":"2021-06-11T15:17:25","modified_gmt":"2021-06-11T14:17:25","slug":"efectivo-da-pir-mata-mulher-e-suicida-se","status":"publish","type":"post","link":"http:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/","title":{"rendered":"EFECTIVO DA PIR MATA MULHER e suicida-se"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Uma semana antes do anivers\u00e1rio da filha, Admiro Bala aproveitou-se do pretexto de uma festa para ter <\/strong><strong>Makiesse Nani Daniel , em sua casa e p\u00f4r fim \u00e0s suas vidas, numa esp\u00e9cie de &#8221; se n\u00e3o ficares comigo, n\u00e3o <\/strong><strong>ficas com mais ningu\u00e9m&#8221;.<\/strong><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"text-decoration: underline;\">Nzinga Manuel<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Onamoro entre o tamb\u00e9m agente da Pol\u00edcia de Interven\u00e7\u00e3o R\u00e1pida (PIR) Admiro Bala, e a estudante Makiesse Nani Daniel, era como que um mar de rosas, tendo resultado no nascimento de uma menina.<\/p>\n<blockquote><p>\u201cN\u00f3s sentamos, chamamos o jovem e, de uma forma amig\u00e1vel, como colega, porque eu perten\u00e7o ao Minist\u00e9rio da Defesa e ele do Interior, conversamos, de modo que este tipo de situa\u00e7\u00e3o n\u00e3o voltasse a acontecer, sob pena, de levarmos numa outra vertente\u201d<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Em Novembro de 2020, o amor falava mais alto e tinha dado mais um passo no relacionamento destes, com a firma\u00e7\u00e3o do noivado diante dos seus familiares e amigos.<br \/>\nEntretanto, algum tempo depois, a rela\u00e7\u00e3o, que parecia caminhar a mil maravilhas, come\u00e7ou a ganhar contornos alarmantes. Numa conversa entre Makiesse e os irm\u00e3os, aquela revelou os maus tratos de que vinha sendo v\u00edtima por parte do noivo, com amea\u00e7as de mortes, tendo, inclusive, certo dia, lhe apontado a arma em direc\u00e7\u00e3o \u00e0 cabe\u00e7a, conforme nos conta o irm\u00e3o mais velho da malograda, Estev\u00e3o Daniel.<br \/>\n\u201cN\u00f3s sentamos, chamamos o jovem e, de uma forma amig\u00e1vel, como colega, porque eu perten\u00e7o ao Minist\u00e9rio da Defesa e ele do Interior, conversamos, de modo que este tipo de situa\u00e7\u00e3o n\u00e3o voltasse a acontecer, sob pena de levarmos numa outra vertente&#8221;, disse Est\u00eav\u00e3o Daniel.<br \/>\nNos \u00faltimos tr\u00eas meses, continua, o cunhado havia-se tornado num homem muito ciumento, possessivo e controlador. \u201cA Makiesse n\u00e3o poderia ter aquelas sa\u00eddas com colegas da escola, ele a seguia, criava sempre situa\u00e7\u00f5es constrangedoras entre as amizades dela, em algumas vezes tirava-lhe, \u00e0 for\u00e7a, do conv\u00edvio das colegas e amigas\u201d.<br \/>\nDe acordo com o ele, diante de toda esta situa\u00e7\u00e3o, a malograda dizia-se farta do comportamento do ent\u00e3o companheiro e ponderava desistir do relacionamento.<br \/>\nAo aperceber-se da inten\u00e7\u00e3o, Adelmiro, o noivo, preferiu, acabar com a vida de ambos, a viver sem a companheira.<br \/>\nDaniel Est\u00eav\u00e3o disse O Crime que, nos \u00faltimos dois meses do ano em curso, eles sentaram novamente com aquele de modo, que transmitisse \u00e0 sua fam\u00edlia a pretens\u00e3o de uma reuni\u00e3o entre as partes (fam\u00edlia da noiva e do noivo). Nesta sentada, garante Daniel, a irm\u00e3 manifestou o desejo de n\u00e3o mais continuar na rela\u00e7\u00e3o, pois tinha medo. \u201cN\u00f3s conversamos com o jovem, dissemos-lhe que n\u00e3o estamos aqui para proibir ou obrigar, a nossa irm\u00e3 esta aqui e est\u00e1 dizer que n\u00e3o quer mais, por causa do teu comportamento, o teu ci\u00fame possessivo, n\u00f3s notamos que o jovem estava obcecado\u201d, garantiu.<br \/>\nEntretanto, ao que conta, aquele continuou a perseguir a malograda em todo s\u00edtio que ela fosse, arranjando sempre formas de a seguir. Ante ao cen\u00e1rio, os familares de Makiesse decidiram tir\u00e1-la do Cazenga, para o Talatona, em casa da irm\u00e3 mais velha, onde passou a residir.<br \/>\nTodavia, Admiro Bala pretendia realizar festa do anivers\u00e1rio da filha, no dia 15 do m\u00eas corrente, pelo que ele e Makiesse falavam sempre ao telefone por mensagens.<br \/>\nMakiesse deslocou-se ao Cazenga, para o anivers\u00e1rio de uma sobrinha que vive com a av\u00f3, no passado s\u00e1bado, dia 8. No dia seguinte, ap\u00f3s regressar da igreja, por volta das 13 horas, recebeu a mensagem do ent\u00e3o noivo, pedindo fosse buscar o dinheiro para fazer as compras da festa de anivers\u00e1rio da filha.<br \/>\nMakiesse foi ao encontro do noivo sem dar a conhecer a ningu\u00e9m, tendo deixado o telem\u00f3vel em casa. Por volta das 16 horas, o irm\u00e3o mais velho recebeu telefonema do irm\u00e3o mais novo, dizendo que ocorreu uma trag\u00e9dia: Makiesse Daniel foi assassinada com um tiro na cabe\u00e7a pelo seu noivo e este suicidou-se de seguida.<br \/>\nSegundo as testemunhas que estiveram no quintal onde o crime ocorreu, quando Makiesse chegou, encontrou o noivo sentado ao lado de fora, tendo a convidado a entrar, ao que aquela rejeitou, dizendo \u201cs\u00f3 vim buscar o dinheiro para organizar a festa da nossa filha\u201d. O noivo insistiu at\u00e9 convenc\u00ea-la.<br \/>\nEntretanto, os vizinhos relatam que, ap\u00f3s aquela entrar, houve um momento de sil\u00eancio seguido, depois, de gritarias, de onde se ouvia: \u201c voc\u00ea foi na piscina com as tuas amigas e levaram os vossos amigos, voc\u00ea estava com um jovem, \u00e9 melhor dizer-lhe que, se ele continuar a seguir vou lhe matar&#8221;, sendo que a noiva retorquia quem foi que disse isso? Sim, eu sai com as minhas amigas.<\/p>\n<blockquote><p>\u201cN\u00f3s at\u00e9 ao momento desconfiamos que seja por causa de uma suposta trai\u00e7\u00e3o que, alegadamente, ocorreu a dois ou tr\u00eas meses. Eles n\u00e3o viviam juntos, aguardava-se o casamento que, talvez, seria este ano ou pr\u00f3ximo\u201d, sublinhou.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Em meio a gritaria, ouviram o primeiro disparo, ao que correram a bater a porta, mas aquele gritou \u00ab ningu\u00e9m vem aqui, estamos a resolver nosso problema\u00bb. Em seguida, fez uma liga\u00e7\u00e3o telef\u00f3nica e, quando terminou, ouviram o segundo tiro, que se segui de um sil\u00eancio absoluto, que os levou a arrombar a porta, tendo se deparando com os dois ao ch\u00e3o e pistola de lado, Makiesse estava morta, mas Admiro apresentava, ainda, sinais vitais, foi transportado para o hospital dos Cajueiros. Por volta das 20 horas, n\u00e3o resistiu ao ferimento e acabou por falecer.<br \/>\nPor sua vez, o irm\u00e3o do malogrado, Samuel Baltazar, desconfia que tudo se deu em fun\u00e7\u00e3o de uma situa\u00e7\u00e3o anterior de suposta trai\u00e7\u00e3o da noiva.<br \/>\n\u201cN\u00f3s, at\u00e9 ao momento, desconfiamos que seja por causa de uma suposta trai\u00e7\u00e3o que ocorreu h\u00e1 dois ou tr\u00eas meses. Eles n\u00e3o viviam juntos, aguardava-se o casamento que seria este ou o pr\u00f3ximo ano\u201d, sublinhou.<br \/>\n&#8220;Mas o que conversavam est\u00e1 fora do nosso dom\u00ednio\u201d.<br \/>\nO irm\u00e3o do malogrado fez saber que a fam\u00edlia fez o seu papel, conversaram com os dois, no sentido de ultrapassarem a situa\u00e7\u00e3o. \u201cN\u00e3o tinha como eles cortarem essa rela\u00e7\u00e3o cem por cento, no meio disso tem uma filha. Tamb\u00e9m pegou-nos de surpresa. Ele era uma pessoa normal\u201d, terminou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma semana antes do anivers\u00e1rio da filha, Admiro Bala aproveitou-se do pretexto de uma festa para ter Makiesse Nani Daniel , em sua casa e p\u00f4r fim \u00e0s suas vidas, numa esp\u00e9cie de &#8221; se n\u00e3o ficares comigo, n\u00e3o ficas com mais ningu\u00e9m&#8221;. Nzinga Manuel Onamoro entre o tamb\u00e9m agente da Pol\u00edcia de Interven\u00e7\u00e3o R\u00e1pida (PIR) Admiro Bala, e a estudante Makiesse Nani Daniel, era como que um mar de rosas, tendo resultado no nascimento de uma menina. \u201cN\u00f3s sentamos, chamamos o jovem e, de uma forma amig\u00e1vel, como colega, porque eu perten\u00e7o ao Minist\u00e9rio da Defesa e ele do [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EFECTIVO DA PIR MATA MULHER e suicida-se - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EFECTIVO DA PIR MATA MULHER e suicida-se - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Uma semana antes do anivers\u00e1rio da filha, Admiro Bala aproveitou-se do pretexto de uma festa para ter Makiesse Nani Daniel , em sua casa e p\u00f4r fim \u00e0s suas vidas, numa esp\u00e9cie de &#8221; se n\u00e3o ficares comigo, n\u00e3o ficas com mais ningu\u00e9m&#8221;. Nzinga Manuel Onamoro entre o tamb\u00e9m agente da Pol\u00edcia de Interven\u00e7\u00e3o R\u00e1pida (PIR) Admiro Bala, e a estudante Makiesse Nani Daniel, era como que um mar de rosas, tendo resultado no nascimento de uma menina. \u201cN\u00f3s sentamos, chamamos o jovem e, de uma forma amig\u00e1vel, como colega, porque eu perten\u00e7o ao Minist\u00e9rio da Defesa e ele do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T14:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/06\/Noivos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"EFECTIVO DA PIR MATA MULHER e suicida-se\",\"datePublished\":\"2021-06-11T14:17:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/\"},\"wordCount\":1096,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Noivos.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/\",\"name\":\"EFECTIVO DA PIR MATA MULHER e suicida-se - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Noivos.jpg\",\"datePublished\":\"2021-06-11T14:17:25+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#primaryimage\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Noivos.jpg\",\"contentUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Noivos.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/efectivo-da-pir-mata-mulher-e-suicida-se\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EFECTIVO DA PIR MATA MULHER e suicida-se\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EFECTIVO DA PIR MATA MULHER e suicida-se - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/","og_locale":"pt_PT","og_type":"article","og_title":"EFECTIVO DA PIR MATA MULHER e suicida-se - Jornal O Crime","og_description":"Uma semana antes do anivers\u00e1rio da filha, Admiro Bala aproveitou-se do pretexto de uma festa para ter Makiesse Nani Daniel , em sua casa e p\u00f4r fim \u00e0s suas vidas, numa esp\u00e9cie de &#8221; se n\u00e3o ficares comigo, n\u00e3o ficas com mais ningu\u00e9m&#8221;. Nzinga Manuel Onamoro entre o tamb\u00e9m agente da Pol\u00edcia de Interven\u00e7\u00e3o R\u00e1pida (PIR) Admiro Bala, e a estudante Makiesse Nani Daniel, era como que um mar de rosas, tendo resultado no nascimento de uma menina. \u201cN\u00f3s sentamos, chamamos o jovem e, de uma forma amig\u00e1vel, como colega, porque eu perten\u00e7o ao Minist\u00e9rio da Defesa e ele do [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/","og_site_name":"Jornal O Crime","article_published_time":"2021-06-11T14:17:25+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/06\/Noivos.jpg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"EFECTIVO DA PIR MATA MULHER e suicida-se","datePublished":"2021-06-11T14:17:25+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/"},"wordCount":1096,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#primaryimage"},"thumbnailUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/06\/Noivos.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/","url":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/","name":"EFECTIVO DA PIR MATA MULHER e suicida-se - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#primaryimage"},"thumbnailUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/06\/Noivos.jpg","datePublished":"2021-06-11T14:17:25+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#primaryimage","url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/06\/Noivos.jpg","contentUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/06\/Noivos.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/efectivo-da-pir-mata-mulher-e-suicida-se\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"EFECTIVO DA PIR MATA MULHER e suicida-se"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"http:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=3593"}],"version-history":[{"count":0,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/3488"}],"wp:attachment":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=3593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=3593"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=3593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}