{"id":4092,"date":"2021-08-21T12:32:37","date_gmt":"2021-08-21T11:32:37","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=4092"},"modified":"2021-08-21T12:32:37","modified_gmt":"2021-08-21T11:32:37","slug":"jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez","status":"publish","type":"post","link":"http:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/","title":{"rendered":"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez"},"content":{"rendered":"<p style=\"text-align: justify;\">Na ter\u00e7a-feira, 17 de Agosto, o director do jornal O Crime foi notificado pela Direc\u00e7\u00e3o de Combate ao Crime Organizado do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC) para comparecer nas suas instala\u00e7\u00f5es, na pr\u00f3xima ter\u00e7a-feira, 24, \u00e0s 9 horas, a fim de ser ouvido no quadro do processo n.\u00ba 01\/020\/-05.<br \/>\nMariano Br\u00e1s j\u00e1 tinha sido ouvido, a 12 de Fevereiro de 2020, a prop\u00f3sito do mesmo processo, em que se sup\u00f5e ser queixoso o presidente do MPLA, Jo\u00e3o Manuel Gon\u00e7alves Louren\u00e7o, que tamb\u00e9m \u00e9 Presidente da Rep\u00fablica.<br \/>\nTer-se-\u00e1 sentido ofendido devido ao teor da \u00faltima capa de 2020 do jornal O Crime, que o elege como a pior figura do ano, com o t\u00edtulo \u201cDemagogo e Hip\u00f3crita\u201d.<br \/>\nDesta vez, o convite chegou via telefone, e com um aviso: &#8220;traga o seu advogado\u201d, aconselhou o instrutor do processo, que solicitou, portanto, a presen\u00e7a do jornalista nas instala\u00e7\u00f5es do SIC-Geral, no Bairro Popular.<br \/>\nNesta audi\u00e7\u00e3o, Mariano Br\u00e1s poder\u00e1 conhecer tr\u00eas cen\u00e1rios, sendo um o de ser informado de que foi constitu\u00eddo arguido e que o processo caminha para o tribunal.<br \/>\nNa pior das hip\u00f3teses que o processo segue, n\u00e3o se descarta a possibilidade de ser r\u00e9u-preso. O processo volta \u00e0 baila, curiosamente, depois de este jornal ter trazido, na sua \u00faltima edi\u00e7\u00e3o, como mat\u00e9ria de capa o caso do antigo ministro dos Transportes, com o ante-t\u00edtulo \u201cAugusto Tom\u00e1s de volta \u00e0 cadeia\u201d e o t\u00edtulo \u201cO preso especial do Presidente\u201d.<br \/>\nA ver vamos no que dar\u00e1. Na pr\u00f3xima edi\u00e7\u00e3o, informaremos sobre o referido interrogat\u00f3rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na ter\u00e7a-feira, 17 de Agosto, o director do jornal O Crime foi notificado pela Direc\u00e7\u00e3o de Combate ao Crime Organizado do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC) para comparecer nas suas instala\u00e7\u00f5es, na pr\u00f3xima ter\u00e7a-feira, 24, \u00e0s 9 horas, a fim de ser ouvido no quadro do processo n.\u00ba 01\/020\/-05. Mariano Br\u00e1s j\u00e1 tinha sido ouvido, a 12 de Fevereiro de 2020, a prop\u00f3sito do mesmo processo, em que se sup\u00f5e ser queixoso o presidente do MPLA, Jo\u00e3o Manuel Gon\u00e7alves Louren\u00e7o, que tamb\u00e9m \u00e9 Presidente da Rep\u00fablica. Ter-se-\u00e1 sentido ofendido devido ao teor da \u00faltima capa de 2020 do jornal O [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Na ter\u00e7a-feira, 17 de Agosto, o director do jornal O Crime foi notificado pela Direc\u00e7\u00e3o de Combate ao Crime Organizado do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC) para comparecer nas suas instala\u00e7\u00f5es, na pr\u00f3xima ter\u00e7a-feira, 24, \u00e0s 9 horas, a fim de ser ouvido no quadro do processo n.\u00ba 01\/020\/-05. Mariano Br\u00e1s j\u00e1 tinha sido ouvido, a 12 de Fevereiro de 2020, a prop\u00f3sito do mesmo processo, em que se sup\u00f5e ser queixoso o presidente do MPLA, Jo\u00e3o Manuel Gon\u00e7alves Louren\u00e7o, que tamb\u00e9m \u00e9 Presidente da Rep\u00fablica. Ter-se-\u00e1 sentido ofendido devido ao teor da \u00faltima capa de 2020 do jornal O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-21T11:32:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Capa-131.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1142\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez\",\"datePublished\":\"2021-08-21T11:32:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/\"},\"wordCount\":292,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capa-131.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/\",\"name\":\"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capa-131.jpg\",\"datePublished\":\"2021-08-21T11:32:37+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#primaryimage\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capa-131.jpg\",\"contentUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Capa-131.jpg\",\"width\":1142,\"height\":1575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/","og_locale":"pt_PT","og_type":"article","og_title":"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez - Jornal O Crime","og_description":"Na ter\u00e7a-feira, 17 de Agosto, o director do jornal O Crime foi notificado pela Direc\u00e7\u00e3o de Combate ao Crime Organizado do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC) para comparecer nas suas instala\u00e7\u00f5es, na pr\u00f3xima ter\u00e7a-feira, 24, \u00e0s 9 horas, a fim de ser ouvido no quadro do processo n.\u00ba 01\/020\/-05. Mariano Br\u00e1s j\u00e1 tinha sido ouvido, a 12 de Fevereiro de 2020, a prop\u00f3sito do mesmo processo, em que se sup\u00f5e ser queixoso o presidente do MPLA, Jo\u00e3o Manuel Gon\u00e7alves Louren\u00e7o, que tamb\u00e9m \u00e9 Presidente da Rep\u00fablica. Ter-se-\u00e1 sentido ofendido devido ao teor da \u00faltima capa de 2020 do jornal O [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/","og_site_name":"Jornal O Crime","article_published_time":"2021-08-21T11:32:37+00:00","og_image":[{"width":1142,"height":1575,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Capa-131.jpg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez","datePublished":"2021-08-21T11:32:37+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/"},"wordCount":292,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#primaryimage"},"thumbnailUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Capa-131.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/","url":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/","name":"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#primaryimage"},"thumbnailUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Capa-131.jpg","datePublished":"2021-08-21T11:32:37+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#primaryimage","url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Capa-131.jpg","contentUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Capa-131.jpg","width":1142,"height":1575},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/jlo-aperta-o-cerco-ao-jornal-o-crime-mariano-bras-notificado-pela-segunda-vez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"JLO aperta o cerco ao jornal O Crime: Mariano Br\u00e1s notificado pela segunda vez"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"http:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=4092"}],"version-history":[{"count":0,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/3997"}],"wp:attachment":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=4092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=4092"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=4092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}