{"id":5657,"date":"2023-01-04T19:54:01","date_gmt":"2023-01-04T18:54:01","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5657"},"modified":"2023-01-04T19:54:01","modified_gmt":"2023-01-04T18:54:01","slug":"pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes","status":"publish","type":"post","link":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/","title":{"rendered":"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A Pol\u00edcia Nacional Angolana (PNA), registou durante a quadra festiva 21 casos de homic\u00eddios, mais sete comparativamente a transi\u00e7\u00e3o de 2021 para o ano 2022 e 16 mortes v\u00edtimas de acidentes de via\u00e7\u00e3o a n\u00edvel nacional.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><em>Leal Mundunde<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">A pesar do Ministro do Interior Eug\u00e9nio Laborinho, na passada ter\u00e7a-feira, 3 de Janeiro, em Luanda, ter considerado tranquila a passagem de ano novo, os n\u00fameros de delitos no per\u00edodo de 31 de Dezembro de 2022 a 1 de Janeiro deste ano, aumentaram a n\u00edvel do pa\u00eds, equiparando com a transi\u00e7\u00e3o do ano anterior.<\/p>\n<p style=\"text-align: justify;\">Na apresenta\u00e7\u00e3o dos dados da \u201cOpera\u00e7\u00e3o Quadra Festiva Segura\u201d, na Unidade de Reac\u00e7\u00e3o e Patrulhamento (URP), em Luanda, na passada ter\u00e7a-feira, 3, o porta-voz da Opera\u00e7\u00e3o, Comiss\u00e1rio Orlando Bernardo, disse que a Pol\u00edcia Nacional registou no per\u00edodo em quest\u00e3o, 359 crimes.<\/p>\n<p style=\"text-align: justify;\">Com os n\u00fameros divulgados, o Comiss\u00e1rio Orlando Bernardo, referiu que houve aumento de mais 119 crimes em rela\u00e7\u00e3o a passagem de ano em 2021.<\/p>\n<p style=\"text-align: justify;\">Dos delitos registados pela corpora\u00e7\u00e3o, verificou-se 21 crimes de homic\u00eddios (mais sete em rela\u00e7\u00e3o a 2021), 145 ofensas \u00e0 integridade f\u00edsica (mais 81 que em 2021), 70 furtos e 57 roubos e 19 agress\u00f5es sexuais.<br \/>\nSobre os casos de homic\u00eddios, 61 por cento foram praticados por pessoas pr\u00f3ximas as vitimas, concretamente no seio familiar, como fez saber o Comiss\u00e1rio Orlando Bernardo.<\/p>\n<p style=\"text-align: justify;\">Na transi\u00e7\u00e3o para o ano 2023, foram tamb\u00e9m apreendidas sete armas de fogo do tipo AKM, 25 viaturas, 211 motociclos, mais de 4.920 litros de combust\u00edvel, bem como, a recupera\u00e7\u00e3o de uma arma de fogo e sete muni\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">O porta-voz da \u201cOpera\u00e7\u00e3o Quadra Festiva Segura\u201d, disse que a prov\u00edncia de Luanda foi a que registou mais casos de criminalidade, em rela\u00e7\u00e3o as demais, com um total de 114 casos, enquanto que Lunda Norte com 16, Bi\u00e9 e Bengo com 14 e Benguela com 10 surgem nas posi\u00e7\u00f5es subsequentes.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Pa\u00eds regista 16 mortes de acidentes de via\u00e7\u00e3o<\/span><\/h2>\n<p style=\"text-align: justify;\">Dezasseis cidad\u00e3os morreram \u00a0nos dias 31 de Dezembro de 2022 e 1 de Janeiro de 2023, a n\u00edvel nacional, num total de 88 casos de acidente de via\u00e7\u00e3o, tendo resultado em 69 feridos.<\/p>\n<p style=\"text-align: justify;\">O maior n\u00famero de acidentes de via\u00e7\u00e3o ocorreu nas prov\u00edncias de Luanda com 19, Benguela com nove, Huila com cinco e Huambo com 11, segundo o Porta-voz da \u201cOpera\u00e7\u00e3o Quadra Festiva Segura\u201d, Comiss\u00e1rio Orlando Bernardo.<\/p>\n<p style=\"text-align: justify;\">S\u00e3o no total 37 atropelamentos, 22 colis\u00f5es entre ve\u00edculos autom\u00f3veis, 12 despistes e nove colis\u00f5es, entre ve\u00edculos autom\u00f3veis e motociclos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Nacional Angolana (PNA), registou durante a quadra festiva 21 casos de homic\u00eddios, mais sete comparativamente a transi\u00e7\u00e3o de 2021 para o ano 2022 e 16 mortes v\u00edtimas de acidentes de via\u00e7\u00e3o a n\u00edvel nacional. Leal Mundunde A pesar do Ministro do Interior Eug\u00e9nio Laborinho, na passada ter\u00e7a-feira, 3 de Janeiro, em Luanda, ter considerado tranquila a passagem de ano novo, os n\u00fameros de delitos no per\u00edodo de 31 de Dezembro de 2022 a 1 de Janeiro deste ano, aumentaram a n\u00edvel do pa\u00eds, equiparando com a transi\u00e7\u00e3o do ano anterior. Na apresenta\u00e7\u00e3o dos dados da \u201cOpera\u00e7\u00e3o Quadra Festiva [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5657","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actual","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Nacional Angolana (PNA), registou durante a quadra festiva 21 casos de homic\u00eddios, mais sete comparativamente a transi\u00e7\u00e3o de 2021 para o ano 2022 e 16 mortes v\u00edtimas de acidentes de via\u00e7\u00e3o a n\u00edvel nacional. Leal Mundunde A pesar do Ministro do Interior Eug\u00e9nio Laborinho, na passada ter\u00e7a-feira, 3 de Janeiro, em Luanda, ter considerado tranquila a passagem de ano novo, os n\u00fameros de delitos no per\u00edodo de 31 de Dezembro de 2022 a 1 de Janeiro deste ano, aumentaram a n\u00edvel do pa\u00eds, equiparando com a transi\u00e7\u00e3o do ano anterior. Na apresenta\u00e7\u00e3o dos dados da \u201cOpera\u00e7\u00e3o Quadra Festiva [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-04T18:54:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/01\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1053\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes\",\"datePublished\":\"2023-01-04T18:54:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/\"},\"wordCount\":436,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/\",\"name\":\"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg\",\"datePublished\":\"2023-01-04T18:54:01+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#primaryimage\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg\",\"contentUrl\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg\",\"width\":1053,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/","og_locale":"pt_PT","og_type":"article","og_title":"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes - Jornal O Crime","og_description":"A Pol\u00edcia Nacional Angolana (PNA), registou durante a quadra festiva 21 casos de homic\u00eddios, mais sete comparativamente a transi\u00e7\u00e3o de 2021 para o ano 2022 e 16 mortes v\u00edtimas de acidentes de via\u00e7\u00e3o a n\u00edvel nacional. Leal Mundunde A pesar do Ministro do Interior Eug\u00e9nio Laborinho, na passada ter\u00e7a-feira, 3 de Janeiro, em Luanda, ter considerado tranquila a passagem de ano novo, os n\u00fameros de delitos no per\u00edodo de 31 de Dezembro de 2022 a 1 de Janeiro deste ano, aumentaram a n\u00edvel do pa\u00eds, equiparando com a transi\u00e7\u00e3o do ano anterior. Na apresenta\u00e7\u00e3o dos dados da \u201cOpera\u00e7\u00e3o Quadra Festiva [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/","og_site_name":"Jornal O Crime","article_published_time":"2023-01-04T18:54:01+00:00","og_image":[{"width":1053,"height":767,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/01\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes","datePublished":"2023-01-04T18:54:01+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/"},"wordCount":436,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#primaryimage"},"thumbnailUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/01\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/","url":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/","name":"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#primaryimage"},"thumbnailUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/01\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg","datePublished":"2023-01-04T18:54:01+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#primaryimage","url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/01\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg","contentUrl":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/01\/49EF066C-3C10-4C54-B0BB-2304C7F29226.jpeg","width":1053,"height":767},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/pna-apresenta-balanco-da-quadra-festiva-aumento-de-casos-de-homicidios-e-mortes-de-acidentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"PNA APRESENTA BALAN\u00c7O DA QUADRA FESTIVA: aumento de casos de homic\u00eddios e mortes de acidentes"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"http:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5657"}],"version-history":[{"count":0,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/5659"}],"wp:attachment":[{"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5657"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}