{"id":1858,"date":"2020-08-22T12:37:47","date_gmt":"2020-08-22T11:37:47","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=1858"},"modified":"2020-08-22T12:40:57","modified_gmt":"2020-08-22T11:40:57","slug":"antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/","title":{"rendered":"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL"},"content":{"rendered":"<p style=\"text-align: justify;\">O julgamento de Valdir Carlos, suposto bar\u00e3o da droga em Angola, cuja senten\u00e7a estava marcada para esta quarta-feira, 5, na 7.\u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal Provincial de Luanda, teve um ataque durante a sess\u00e3o, tendo sido transportado, urgentemente, para o Hospital Pris\u00e3o de S\u00e3o Paulo.<\/p>\n<p><strong>Por: Felicidade Kauanda<\/strong><\/p>\n<p style=\"text-align: justify;\">Waldir Egberto Jos\u00e9 Carlos, alegado bar\u00e3o da droga, sentiu-se mal durante a leitura do ac\u00f3rd\u00e3o, tendo ca\u00eddo inanimado. Depois de algumas manobras de reanima\u00e7\u00e3o, efectuadas por uma enfermeira que acompanhava o caso na plateia, e que se prontificou em ajudar o r\u00e9u que, posteriormente, foi transportado por uma ambul\u00e2ncia da Luanda Medical Center para o Hospital Pris\u00e3o de S\u00e3o Paulo.<\/p>\n<p style=\"text-align: justify;\">De acordo com o seu advogado, Jos\u00e9 Carlos, a sess\u00e3o deve retomar na pr\u00f3xima segunda-feira, 10 de Agosto.<\/p>\n<p style=\"text-align: justify;\">Ademais, segundo ainda o caus\u00eddico, Waldir Carlos, o r\u00e9u, ter\u00e1 tido uma baixa da glicemia, ou seja, baixo n\u00edvel de a\u00e7\u00facar no sangue. \u201cA crise ter\u00e1 ocorrido em fun\u00e7\u00e3o das condi\u00e7\u00f5es desumanas na pris\u00e3o em que se encontra preso\u201d, lamentou Jos\u00e9 Carlos, acrescentando que, se n\u00e3o fosse a pronta interven\u00e7\u00e3o daquela enfermeira, o pior teria acontecido.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, disse ainda o advogado, j\u00e1 na sess\u00e3o anterior, na \u00faltima semana, o r\u00e9u denunciou em tribunal que estava a ser tratado de forma desumana. \u201cO tribunal acolheu positivamente a den\u00fancia do r\u00e9u, notificou o estabelecimento prisional sobre o assunto, mas o cen\u00e1rio n\u00e3o mudou\u201d, refor\u00e7ou o advogado.<\/p>\n<p style=\"text-align: justify;\">\u201cInfelizmente ele continua na solit\u00e1ria, com dificuldade de alimentar -se porque n\u00e3o tem acesso a nada, como os demais reclusos\u201d, notou, para mais adiante dizer que Waldir Carlos n\u00e3o comia desde o dia anterior \u00e0 senten\u00e7a. \u201cE o resultado foi esse que vimos na sala\u201d.<\/p>\n<p style=\"text-align: justify;\">Entristecido com a situa\u00e7\u00e3o, Adilson Carlos, irm\u00e3o mais novo do r\u00e9u, denunciou tamb\u00e9m que, al\u00e9m das p\u00e9ssimas condi\u00e7\u00f5es em que vive na cadeia, j\u00e1 foi v\u00edtima de uma tentativa de envenenamento.<\/p>\n<p style=\"text-align: justify;\">De recordar que Waldir Egberto Jos\u00e9 Carlos est\u00e1 a ser julgado pelos crimes de tr\u00e1fico de actividades il\u00edcitas e associa\u00e7\u00e3o criminosa.<\/p>\n<p style=\"text-align: justify;\">O julgamento que teve in\u00edcio no dia 29 do m\u00eas passado, pode vir a conhecer o desfecho na pr\u00f3xima segunda-feira.<\/p>\n<p style=\"text-align: justify;\">Por\u00e9m, contactado por este jornal, Menezes\u00a0 Cassoma, porta voz dos Servi\u00e7os Prisionais, disse que a vers\u00e3o passada pelo advogado, sobre as poss\u00edveis condi\u00e7\u00f5es desumanas em que\u00a0 se encontrava o r\u00e9u, n\u00e3o condiz com a verdade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O julgamento de Valdir Carlos, suposto bar\u00e3o da droga em Angola, cuja senten\u00e7a estava marcada para esta quarta-feira, 5, na 7.\u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal Provincial de Luanda, teve um ataque durante a sess\u00e3o, tendo sido transportado, urgentemente, para o Hospital Pris\u00e3o de S\u00e3o Paulo. Por: Felicidade Kauanda Waldir Egberto Jos\u00e9 Carlos, alegado bar\u00e3o da droga, sentiu-se mal durante a leitura do ac\u00f3rd\u00e3o, tendo ca\u00eddo inanimado. Depois de algumas manobras de reanima\u00e7\u00e3o, efectuadas por uma enfermeira que acompanhava o caso na plateia, e que se prontificou em ajudar o r\u00e9u que, posteriormente, foi transportado por uma ambul\u00e2ncia da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O julgamento de Valdir Carlos, suposto bar\u00e3o da droga em Angola, cuja senten\u00e7a estava marcada para esta quarta-feira, 5, na 7.\u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal Provincial de Luanda, teve um ataque durante a sess\u00e3o, tendo sido transportado, urgentemente, para o Hospital Pris\u00e3o de S\u00e3o Paulo. Por: Felicidade Kauanda Waldir Egberto Jos\u00e9 Carlos, alegado bar\u00e3o da droga, sentiu-se mal durante a leitura do ac\u00f3rd\u00e3o, tendo ca\u00eddo inanimado. Depois de algumas manobras de reanima\u00e7\u00e3o, efectuadas por uma enfermeira que acompanhava o caso na plateia, e que se prontificou em ajudar o r\u00e9u que, posteriormente, foi transportado por uma ambul\u00e2ncia da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-22T11:37:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-22T11:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/08\/waldir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"261\" \/>\n\t<meta property=\"og:image:height\" content=\"193\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL\",\"datePublished\":\"2020-08-22T11:37:47+00:00\",\"dateModified\":\"2020-08-22T11:40:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/\"},\"wordCount\":451,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/waldir.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/\",\"name\":\"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/waldir.jpg\",\"datePublished\":\"2020-08-22T11:37:47+00:00\",\"dateModified\":\"2020-08-22T11:40:57+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/waldir.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/waldir.jpg\",\"width\":261,\"height\":193,\"caption\":\"Foto: DR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/","og_locale":"pt_PT","og_type":"article","og_title":"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL - Jornal O Crime","og_description":"O julgamento de Valdir Carlos, suposto bar\u00e3o da droga em Angola, cuja senten\u00e7a estava marcada para esta quarta-feira, 5, na 7.\u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal Provincial de Luanda, teve um ataque durante a sess\u00e3o, tendo sido transportado, urgentemente, para o Hospital Pris\u00e3o de S\u00e3o Paulo. Por: Felicidade Kauanda Waldir Egberto Jos\u00e9 Carlos, alegado bar\u00e3o da droga, sentiu-se mal durante a leitura do ac\u00f3rd\u00e3o, tendo ca\u00eddo inanimado. Depois de algumas manobras de reanima\u00e7\u00e3o, efectuadas por uma enfermeira que acompanhava o caso na plateia, e que se prontificou em ajudar o r\u00e9u que, posteriormente, foi transportado por uma ambul\u00e2ncia da [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/","og_site_name":"Jornal O Crime","article_published_time":"2020-08-22T11:37:47+00:00","article_modified_time":"2020-08-22T11:40:57+00:00","og_image":[{"width":261,"height":193,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/08\/waldir.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL","datePublished":"2020-08-22T11:37:47+00:00","dateModified":"2020-08-22T11:40:57+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/"},"wordCount":451,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/08\/waldir.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/","url":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/","name":"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/08\/waldir.jpg","datePublished":"2020-08-22T11:37:47+00:00","dateModified":"2020-08-22T11:40:57+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/08\/waldir.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/08\/waldir.jpg","width":261,"height":193,"caption":"Foto: DR"},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/antes-da-leitura-da-sentenca-waldir-apanha-atque-em-pleno-tribunal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Antes da leitura da senten\u00e7a: Waldir APANHA ATQUE EM PLENO TRIBUNAL"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/1858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=1858"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/1858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/1855"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=1858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=1858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=1858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}