{"id":2178,"date":"2020-09-19T16:07:06","date_gmt":"2020-09-19T15:07:06","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2178"},"modified":"2020-09-19T16:07:06","modified_gmt":"2020-09-19T15:07:06","slug":"em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/","title":{"rendered":"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Lu\u00eds Carlos, 31 anos de idade, morreu no local de servi\u00e7o, depois de ter sofrido v\u00e1rios golpes de faca na regi\u00e3o tor\u00e1cica, a 29 de Julho \u00faltimo. O crime aconteceu de madrugada, num momento em que o mesmo, tido por gerente da f\u00e1brica de gelo, em Viana, encontrava-se a descansar no quarto reservado para si. Entretanto, a sua morte est\u00e1 ainda por se esclarecer, apesar de j\u00e1 haver dois suspeitos sob cust\u00f3dia, estando a maioria \u00e0 monte.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Costa Kilunda <\/strong><\/p>\n<p style=\"text-align: justify;\">Sabe-se apenas que o crime aconteceu num momento em que Lu\u00eds Tutala Batispta Carlos, de 31 anos de idade, gerente da referida f\u00e1brica, localizada na zona do KM 14 A, na Estalagem, em Viana, demitiu, na v\u00e9spera, dois funcion\u00e1rios. Entretanto, algumas pessoas levantam a hip\u00f3tese deste assassinato ter por motiva\u00e7\u00e3o as demiss\u00f5es, mais a mais porque acreditam que o seu autor seja algu\u00e9m que conhece bem a institui\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">\u00c0 data, segundo foi contado ao \u2018O Crime\u2019 por algumas testemunhas; por volta das duas horas da madrugada, cerca de sete indiv\u00edduos entraram na f\u00e1brica de gelo e seguiram at\u00e9 ao quarto onde a v\u00edtima dormia. Seguidamente, os mesmos indiv\u00edduos, at\u00e9 ao momento n\u00e3o identificados, agrediram o gerente, tendo-o desferido v\u00e1rios golpes de faca em v\u00e1rias zonas do corpo, maioritariamente na regi\u00e3o tor\u00e1cica, pelo que a v\u00edtima teve morte imediata.<\/p>\n<p style=\"text-align: justify;\">Contaram testemunhas: \u201cA miss\u00e3o dos suspeitos era de matar Lu\u00eds Carlos\u201d, j\u00e1 que estes n\u00e3o levaram absolutamente nada da empresa, inclusive, alegam, havia uma sala bem ao lado do quarto do malogrado cheia de televisor plasma, mas nada foi tocado, o que sustenta a sua teoria. Para al\u00e9m do gerente, os suspeitos agrediram, tamb\u00e9m, o agente de seguran\u00e7a, que ficou com ligeiro ferimento de faca numa das pernas, o auxiliar de limpeza, que foi amarrado com o pr\u00f3prio cinto.<\/p>\n<p style=\"text-align: justify;\">\u201cO nosso espanto \u00e9: Se a inten\u00e7\u00e3o era levar o rolo de fios de cobre, a carrinha e os televisores, deveriam actuar, em primeiro lugar, o seguran\u00e7a da empresa, porque ele \u00e9 quem guarnece o local\u201d, afirmou Deolinda Francisco Baptista, a m\u00e3e da v\u00edtima, para quem, o que se deu naquela noite foi uma demonstra\u00e7\u00e3o clara de que alegados assaltantes foram destinados a assassinar filho.<\/p>\n<p style=\"text-align: justify;\">Sem mais nada para esperar, aquela m\u00e3e pede apenas que a justi\u00e7a seja feita e que os assassinos do filho sejam capturados e levados \u00e0s barras do tribunal.<\/p>\n<p style=\"text-align: justify;\">Apesar de todos os esfor\u00e7os dos familiares do malogrado, no sentido de receberem uma explica\u00e7\u00e3o da parte das testemunhas oculares do incidente, no caso o seguran\u00e7a e o trabalhador de limpeza, estes tamb\u00e9m sumiram, sem que se lhes conhe\u00e7a agora o rasto, pelo que, para eles, nada \u00e9 mais adequado do que apontar o dedo \u00e0queles tamb\u00e9m.<\/p>\n<p style=\"text-align: justify;\">\u201cN\u00e3o nos querem dar acesso ao seguran\u00e7a e ao rapaz de limpeza, que, no nosso entender, s\u00e3o as pessoas que deveriam sofrer primeiro as consequ\u00eancias desta ac\u00e7\u00e3o, porque eles dormem no quintal e o meu filho na resid\u00eancia da empresa\u201d, reclamou, para depois suplicar \u00e0 Pol\u00edcia Nacional uma profunda investiga\u00e7\u00e3o para se descobrir o que, na verdade, aconteceu naquela noite.<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cDespedimento de dois funcion\u00e1rios pode ser o mote do crime\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Soube a nossa equipa de reportagem que \u201co falecido teria despedido dois trabalhadores, depois de receber ordens espec\u00edficas do dono da empresa\u201d. Na ocasi\u00e3o, desconformados com o acto, \u201cos visados teriam reagido com amea\u00e7as\u201d: \u201cVais ver o que te vai acontecer\u201d. Soube, tamb\u00e9m, o \u2018O Crime\u2019, que um dos visados era, afinal, irm\u00e3o do dono da empresa.<\/p>\n<p style=\"text-align: justify;\">\u201cTudo que sabemos at\u00e9 agora sobre este assassinato \u00e9 que quem pode explicar o que aconteceu \u00e9 o dono da empresa\u201d, a m\u00e3e de Lu\u00eds Carlos, acrescentando que, quando chegaram ao local, por volta das 5 horas, j\u00e1 o corpo do filho havia sido levado \u00e0 morgue.<\/p>\n<p style=\"text-align: justify;\">Os familiares acreditam, piamente, que um dos elementos demitidos pode ser o presum\u00edvel autor do crime. \u201cEle era um rapaz muito tranquilo, simp\u00e1tico e n\u00e3o tinha problemas com quem quer que seja. Nunca se envolveu em coisas estranhas\u201d, atestou Diolinda Baptista, denunciando que o irm\u00e3o do dono da empresa sumiu para n\u00e3o ser interrogado.<\/p>\n<p style=\"text-align: justify;\">Outra inquieta\u00e7\u00e3o da fam\u00edlia enlutada \u00e9 o facto de terem realizado uma aut\u00f3psia no cad\u00e1ver sem a autoriza\u00e7\u00e3o dos familiares, e como se n\u00e3o bastasse, um alegado m\u00e9dico n\u00e3o certificado deixou de assinar a certid\u00e3o de \u00f3bito.<\/p>\n<p style=\"text-align: justify;\">\u201cN\u00e3o \u00e9 aut\u00f3psia, o cad\u00e1ver estava em estado de putrefac\u00e7\u00e3o e nauseabundo. Por isso, mandei abrir a barriga para fazerem limpeza\u201d, justificou Adjane dos Santos, o antigo patr\u00e3o do malogrado.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 para os familiares, esta explica\u00e7\u00e3o n\u00e3o colhe, por entenderem que, em momento algum, em menos de 24 horas, o cad\u00e1ver poderia estar nas referidas condi\u00e7\u00f5es. Outrossim, alega a fam\u00edlia, Adjane dos Santos est\u00e1 a mentir para se furtar das suas responsabilidades, na qualidade de dono do estabelecimento. Ele, afirmam, para escapar do seu dever patronal, diz que a empresa n\u00e3o \u00e9 sua e o malogrado n\u00e3o era o gerente da mesma.<\/p>\n<p style=\"text-align: justify;\">\u201cEu desminto isso. Ele est\u00e1 com muitos subterf\u00fagios, por isso exijo que o apertem, porque ele sabe como o meu filho foi morto\u201d, apelou a m\u00e3e.<\/p>\n<p style=\"text-align: justify;\">De referir que j\u00e1 est\u00e3o a contas com a Pol\u00edcia dois elementos que, supostamente, participaram da ac\u00e7\u00e3o, sendo que entre os detidos est\u00e1 um dos indiv\u00edduos demitidos pelo malogrado, estando j\u00e1 o processo n. \u00ba 14644\/20 em instru\u00e7\u00e3o, junto do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC) adstrito \u00e0 Divis\u00e3o Municipal de Viana.<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cEle j\u00e1 n\u00e3o trabalhava aqui e nunca foi gerente\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Contactado por via telefone, num discurso controverso, Adjane dos Santos, o ent\u00e3o patr\u00e3o do falecido, come\u00e7ou por dizer que \u201caquele era seu irm\u00e3o, mas no momento em que se deu a ac\u00e7\u00e3o, ele j\u00e1 n\u00e3o trabalhava para si\u201d. Explicou, ainda, que a v\u00edtima s\u00f3 continuou a\u00ed porque havia aparecido algu\u00e9m interessado no neg\u00f3cio e Lu\u00eds Carlos estava l\u00e1 para prestar aux\u00edlio, por ser a pessoa que dominava as m\u00e1quinas da empresa.<\/p>\n<p style=\"text-align: justify;\">Disse que, em momento algum, ele trabalhou como gerente daquela f\u00e1brica. \u201cN\u00e3o podemos estar a falar de coisas que n\u00e3o sabemos. Ele era um simples trabalhador e n\u00e3o tinha compet\u00eancias para despedir quem quer que fosse. E, para falarmos sobre este despedimento, devemos recuar at\u00e9 finais de Dezembro passado e n\u00e3o agora\u201d.<\/p>\n<p style=\"text-align: justify;\">Quanto \u00e0 suposta autopsia realizada, disse n\u00e3o corresponder \u00e0 verdade. \u201cO que se fez foi um procedimento aconselhado pelos m\u00e9dicos, no sentido de preservar o corpo at\u00e9 ao dia do funeral. N\u00e3o se fez aut\u00f3psia, apenas tratamos do corpo\u201d, esclareceu.<\/p>\n<p style=\"text-align: justify;\">Concluiu dizendo que \u201ca fam\u00edlia materna do malogrado deveria contwactar as pessoas certas para saberem da verdade, pois, por ser um golpe de faca, criou-se uma hemorragia interna e, por isso, os m\u00e9dicos aconselharam dar um tratamento no corpo para n\u00e3o exalar mau odor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lu\u00eds Carlos, 31 anos de idade, morreu no local de servi\u00e7o, depois de ter sofrido v\u00e1rios golpes de faca na regi\u00e3o tor\u00e1cica, a 29 de Julho \u00faltimo. O crime aconteceu de madrugada, num momento em que o mesmo, tido por gerente da f\u00e1brica de gelo, em Viana, encontrava-se a descansar no quarto reservado para si. Entretanto, a sua morte est\u00e1 ainda por se esclarecer, apesar de j\u00e1 haver dois suspeitos sob cust\u00f3dia, estando a maioria \u00e0 monte. Por: Costa Kilunda Sabe-se apenas que o crime aconteceu num momento em que Lu\u00eds Tutala Batispta Carlos, de 31 anos de idade, gerente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Lu\u00eds Carlos, 31 anos de idade, morreu no local de servi\u00e7o, depois de ter sofrido v\u00e1rios golpes de faca na regi\u00e3o tor\u00e1cica, a 29 de Julho \u00faltimo. O crime aconteceu de madrugada, num momento em que o mesmo, tido por gerente da f\u00e1brica de gelo, em Viana, encontrava-se a descansar no quarto reservado para si. Entretanto, a sua morte est\u00e1 ainda por se esclarecer, apesar de j\u00e1 haver dois suspeitos sob cust\u00f3dia, estando a maioria \u00e0 monte. Por: Costa Kilunda Sabe-se apenas que o crime aconteceu num momento em que Lu\u00eds Tutala Batispta Carlos, de 31 anos de idade, gerente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-19T15:07:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/09\/12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"303\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS\",\"datePublished\":\"2020-09-19T15:07:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/\"},\"wordCount\":1225,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/12.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/\",\"name\":\"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/12.jpg\",\"datePublished\":\"2020-09-19T15:07:06+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/12.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/12.jpg\",\"width\":303,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/","og_locale":"pt_PT","og_type":"article","og_title":"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS - Jornal O Crime","og_description":"Lu\u00eds Carlos, 31 anos de idade, morreu no local de servi\u00e7o, depois de ter sofrido v\u00e1rios golpes de faca na regi\u00e3o tor\u00e1cica, a 29 de Julho \u00faltimo. O crime aconteceu de madrugada, num momento em que o mesmo, tido por gerente da f\u00e1brica de gelo, em Viana, encontrava-se a descansar no quarto reservado para si. Entretanto, a sua morte est\u00e1 ainda por se esclarecer, apesar de j\u00e1 haver dois suspeitos sob cust\u00f3dia, estando a maioria \u00e0 monte. Por: Costa Kilunda Sabe-se apenas que o crime aconteceu num momento em que Lu\u00eds Tutala Batispta Carlos, de 31 anos de idade, gerente [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/","og_site_name":"Jornal O Crime","article_published_time":"2020-09-19T15:07:06+00:00","og_image":[{"width":303,"height":277,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/09\/12.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS","datePublished":"2020-09-19T15:07:06+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/"},"wordCount":1225,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/09\/12.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/","url":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/","name":"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/09\/12.jpg","datePublished":"2020-09-19T15:07:06+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/09\/12.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/09\/12.jpg","width":303,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/em-viana-gerente-de-fabrica-de-gelo-morto-a-facadas-depois-de-despedir-dois-funcionarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Em Viana: GERENTE DE F\u00c1BRICA DE GELO MORTO A FACADAS DEPOIS DE DESPEDIR DOIS FUNCION\u00c1RIOS"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2178"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2179"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}