{"id":2290,"date":"2020-10-03T12:55:36","date_gmt":"2020-10-03T11:55:36","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2290"},"modified":"2020-10-14T16:02:02","modified_gmt":"2020-10-14T15:02:02","slug":"mulher-e-condenada-por-abandonar-o-lar","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/","title":{"rendered":"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Devido \u00e0s constantes diverg\u00eancias com o parceiro, Mbimbixa Singue Ndomaxi fugiu do lar, deixando os tr\u00eas filhos menores, de 5, 6 e 8 anos, sob responsabilidade do pai. Depois de alguns meses, voltou e levou os pequenos, tendo falsificado os seus documentos, sem, no entanto, fazer constar o nome do progenitor.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Felicidade Kauanda<\/strong><\/p>\n<p style=\"text-align: justify;\">Djoline de Almeida, ju\u00edza da causa, leu a senten\u00e7a da r\u00e9, Mbimbixa Singue Ndomaxi, acusada pela pr\u00e1tica de quatro crimes, nomeadamente, abandono familiar, viol\u00eancia dom\u00e9stica na vertente psicol\u00f3gica, falsifica\u00e7\u00e3o de documentos e mudan\u00e7a ilegal de nome.<\/p>\n<p style=\"text-align: justify;\">Atentando que os factos foram praticados no ano de 2012, e tratando-se de crimes cuja moldura penal n\u00e3o \u00e9 superior a 12 anos de pris\u00e3o maior, por for\u00e7a do artigo 3.\u00ba da Lei da Amnistia, Lei n.\u00ba 11 \/16 de 12 de Agosto, tr\u00eas deles foram amnistiados.<\/p>\n<p style=\"text-align: justify;\">Assim, pelo crime \u00fanico de viol\u00eancia dom\u00e9stica foi sentenciada \u00e0 pena de 1 ano de pris\u00e3o suspensa, por um per\u00edodo de 5 anos, o que significa que, durante este tempo, n\u00e3o poder\u00e1 cometer nenhum crime. Uma decis\u00e3o, segundo a ju\u00edza, baseada no interesse superior da crian\u00e7a.<\/p>\n<p style=\"text-align: justify;\">Foi, ainda, condenada ao pagamento de AKZ 50.000,00 (cinquenta mil kwanzas) de taxa de justi\u00e7a, AKZ 5.000,000 (cinco mil kwanzas) \u00e0 defensora oficiosa e AKZ 500.000,00 (quinhentos mil kwanzas) de indemniza\u00e7\u00e3o ao ofendido, Adriano Dombaxi, pelos danos n\u00e3o patrimoniais causados, tendo em aten\u00e7\u00e3o ao artigo 30.\u00ba da Lei Contra Viol\u00eancia Dom\u00e9stica.<\/p>\n<p style=\"text-align: justify;\">Quanto \u00e0 guarda dos filhos, n\u00e3o foi decidida, pelo facto de n\u00e3o caber ao \u00e2mbito criminal. Entretanto, o tribunal oficiou a sala de julgado de menores, com a respectiva certid\u00e3o do presente ac\u00f3rd\u00e3o, no sentido de os progenitores serem chamados, para repor a legalidade do registo dos menores, bem como ao acompanhamento psicol\u00f3gico dos mesmos.<\/p>\n<p style=\"text-align: justify;\">Recuando 9 anos no tempo, consta que, devido \u00e0s constantes diverg\u00eancias que existia entre o casal, Mbimbixa Ndomaxi e Adriano Dombaxi, a mulher decidiu abandonar a resid\u00eancia, no dia 14 de Fevereiro de 2011, deixando os tr\u00eas filhos menores de 5, 6 e 8 anos de idade com o pai.<\/p>\n<p style=\"text-align: justify;\">Alguns meses depois, por interm\u00e9dio do pastor Benvindo Matondo, da Igreja Internacional da Paz, a r\u00e9 pediu ao ex-marido que lhe deixasse ficar com os filhos durante a quadra festiva, tendo este permitido, advertindo que deveriam ser entregues no dia 29 de Janeiro de 2012, devido ao regresso \u00e0s aulas.<\/p>\n<p style=\"text-align: justify;\">Na data acordada, a r\u00e9 compareceu com os menores, juntamente com o pastor, que disse ao ofendido que os filhos n\u00e3o voltariam a viver com o mesmo, mas sim com a m\u00e3e. Situa\u00e7\u00e3o que gerou uma confus\u00e3o, que s\u00f3 terminou com interven\u00e7\u00e3o da Pol\u00edcia, tendo Adriano ficado com os dois filhos mais novos e a r\u00e9 com a primog\u00e9nita.<\/p>\n<p style=\"text-align: justify;\">Perante este facto, Adriano apresentou queixa junto ao INAC, tendo o lit\u00edgio sido encaminhado ao Julgado de Menores e Fam\u00edlia e ao SIC-Geral, todos com processo devidamente constitu\u00eddos.<\/p>\n<p style=\"text-align: justify;\">Mais \u00e0 frente, refere os autos, no dia 18 de Dezembro de 2017, sem conhecimento de Adriano, os dois menores que estavam sob sua cust\u00f3dia, ligaram \u00e0 m\u00e3e, manifestando vontade de viverem com a mesma, facto que a levou a ir busc\u00e1-los. Apesar das crian\u00e7as j\u00e1 serem registadas, a r\u00e9 registou-as novamente, sem fazer constar o nome do ex-companheiro.<\/p>\n<p style=\"text-align: justify;\">De frisar que, em 2013, a r\u00e9 e o ofendido j\u00e1 estiveram na sala de fam\u00edlia, discutindo a guarda dos filhos, n\u00e3o constando, no entanto, nenhuma decis\u00e3o nos autos.<\/p>\n<p style=\"text-align: justify;\">Quanto \u00e0 gravidade e repara\u00e7\u00e3o dos danos emocionais, causados pelo comportamento da r\u00e9 ao ofendido e aos menores, o tribunal entende que \u00e9 imput\u00e1vel \u00e0 ofendida, porquanto o nexo de casualidade verifica-se no desgaste emocional que o ofendido teve, ao percorrer, por cerca de nove anos, a cidade de Luanda, \u00e0 procura de uma institui\u00e7\u00e3o do Estado, a fim de obter resposta da causa, sendo que, em momento algum, demonstrou abdicar de seu dever paternal.<\/p>\n<p style=\"text-align: justify;\">A t\u00edtulo de nota explicativa, o crime de abandono traduz-se em qualquer conduta que diz respeito \u00e0 forma grave e reiterada de presta\u00e7\u00e3o de assist\u00eancia, devendo-se considerar abandono familiar, quando a v\u00edtima sai de casa por raz\u00f5es ponderosas, como a sua seguran\u00e7a.<\/p>\n<p style=\"text-align: justify;\">Entretanto, dos factos alegados, apenas se conseguiu provar que a r\u00e9 saiu de casa por causa das diverg\u00eancias entre ambos, n\u00e3o se provando se saiu por raz\u00f5es de seguran\u00e7a ou n\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Os crimes de falsifica\u00e7\u00e3o de documentos aut\u00eanticos, o de uso de documento falso e mudan\u00e7a ilegal de nome foram provados quanto ao registo dos dois filhos, pois existem dois registos, um feito a posterior, onde o nome do progenitor foi ocultado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devido \u00e0s constantes diverg\u00eancias com o parceiro, Mbimbixa Singue Ndomaxi fugiu do lar, deixando os tr\u00eas filhos menores, de 5, 6 e 8 anos, sob responsabilidade do pai. Depois de alguns meses, voltou e levou os pequenos, tendo falsificado os seus documentos, sem, no entanto, fazer constar o nome do progenitor. Por: Felicidade Kauanda Djoline de Almeida, ju\u00edza da causa, leu a senten\u00e7a da r\u00e9, Mbimbixa Singue Ndomaxi, acusada pela pr\u00e1tica de quatro crimes, nomeadamente, abandono familiar, viol\u00eancia dom\u00e9stica na vertente psicol\u00f3gica, falsifica\u00e7\u00e3o de documentos e mudan\u00e7a ilegal de nome. Atentando que os factos foram praticados no ano de 2012, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MULHER \u00c9 CONDENADA POR ABANDONAR O LAR - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Devido \u00e0s constantes diverg\u00eancias com o parceiro, Mbimbixa Singue Ndomaxi fugiu do lar, deixando os tr\u00eas filhos menores, de 5, 6 e 8 anos, sob responsabilidade do pai. Depois de alguns meses, voltou e levou os pequenos, tendo falsificado os seus documentos, sem, no entanto, fazer constar o nome do progenitor. Por: Felicidade Kauanda Djoline de Almeida, ju\u00edza da causa, leu a senten\u00e7a da r\u00e9, Mbimbixa Singue Ndomaxi, acusada pela pr\u00e1tica de quatro crimes, nomeadamente, abandono familiar, viol\u00eancia dom\u00e9stica na vertente psicol\u00f3gica, falsifica\u00e7\u00e3o de documentos e mudan\u00e7a ilegal de nome. Atentando que os factos foram praticados no ano de 2012, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-03T11:55:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T15:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"684\" \/>\n\t<meta property=\"og:image:height\" content=\"456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR\",\"datePublished\":\"2020-10-03T11:55:36+00:00\",\"dateModified\":\"2020-10-14T15:02:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/\"},\"wordCount\":794,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/4.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/\",\"name\":\"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/4.jpg\",\"datePublished\":\"2020-10-03T11:55:36+00:00\",\"dateModified\":\"2020-10-14T15:02:02+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/4.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/4.jpg\",\"width\":684,\"height\":456},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-e-condenada-por-abandonar-o-lar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/","og_locale":"pt_PT","og_type":"article","og_title":"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR - Jornal O Crime","og_description":"Devido \u00e0s constantes diverg\u00eancias com o parceiro, Mbimbixa Singue Ndomaxi fugiu do lar, deixando os tr\u00eas filhos menores, de 5, 6 e 8 anos, sob responsabilidade do pai. Depois de alguns meses, voltou e levou os pequenos, tendo falsificado os seus documentos, sem, no entanto, fazer constar o nome do progenitor. Por: Felicidade Kauanda Djoline de Almeida, ju\u00edza da causa, leu a senten\u00e7a da r\u00e9, Mbimbixa Singue Ndomaxi, acusada pela pr\u00e1tica de quatro crimes, nomeadamente, abandono familiar, viol\u00eancia dom\u00e9stica na vertente psicol\u00f3gica, falsifica\u00e7\u00e3o de documentos e mudan\u00e7a ilegal de nome. Atentando que os factos foram praticados no ano de 2012, [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/","og_site_name":"Jornal O Crime","article_published_time":"2020-10-03T11:55:36+00:00","article_modified_time":"2020-10-14T15:02:02+00:00","og_image":[{"width":684,"height":456,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/4.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR","datePublished":"2020-10-03T11:55:36+00:00","dateModified":"2020-10-14T15:02:02+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/"},"wordCount":794,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/4.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/","url":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/","name":"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/4.jpg","datePublished":"2020-10-03T11:55:36+00:00","dateModified":"2020-10-14T15:02:02+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/4.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/4.jpg","width":684,"height":456},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/mulher-e-condenada-por-abandonar-o-lar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"MULHER \u00c9 CONDENADA POR ABANDONAR O LAR"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2290"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2291"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}