{"id":2471,"date":"2020-10-28T18:55:10","date_gmt":"2020-10-28T17:55:10","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2471"},"modified":"2020-10-28T20:11:13","modified_gmt":"2020-10-28T19:11:13","slug":"por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/","title":{"rendered":"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O tiro efectuado por Ant\u00f3nio Augusto Rafael, agente de 1.\u00aa classe da Pol\u00edcia Nacional, afecto \u00e0 44.\u00aa Esquadra, no distrito da Estalagem, perfurou as bochechas da v\u00edtima, tendo-lhe causado graves ferimentos na l\u00edngua e nos maxilares.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Costa Kilunda <\/strong><\/p>\n<p style=\"text-align: justify;\">Jo\u00e3o Fernando, o mototaxista de 28 anos, encontra-se, agora, a recuperar em casa, depois de ficar internado por mais de duas semanas no Hospital Am\u00e9rico Boavida, em fun\u00e7\u00e3o dos estragos causados na sua boca, pelo proj\u00e9ctil que o atingiu.<\/p>\n<p style=\"text-align: justify;\">A raz\u00e3o do incidente, segundo fez saber a v\u00edtima, deveu-se ao facto de ter recusado a dar 100 kwanzas, exigidos pelo referido agente, como uma esp\u00e9cie de \u201cpropina\u201d, por quem ali trabalha.<\/p>\n<p style=\"text-align: justify;\">\u201cPediu-me 100 kwanzas e respondi que n\u00e3o tinha. Ent\u00e3o, decidi ir-me embora, pois ele insistia que o entregasse. T\u00e3o logo liguei a motorizada, ele disparou contra mim e deixou-me ferido no local, sem oferecer-me qualquer tipo de ajuda\u201d, explicou a v\u00edtima, acrescentando que foram os colegas que o levaram para o hospital.<\/p>\n<p style=\"text-align: justify;\">Hoje, obrigado a conviver com a l\u00edngua remendada em v\u00e1rios peda\u00e7os, bem como os maxilares e os dentes partidos, Jo\u00e3o Fernando est\u00e1 impedido de seguir com a sua actividade e com a agravante de nada ter para enviar \u00e0 fam\u00edlia que deixou na prov\u00edncia do Huambo.<\/p>\n<p style=\"text-align: justify;\">Para esse jovem mototaxista, agora a abra\u00e7os com a pen\u00faria, se s\u00e3o, as dificuldades eram \u201cmil\u201d, o seu estado actual veio agudizar as coisas. Tem dificuldades em falar, sobretudo, em mastigar os alimentos, ao que est\u00e1, agora, condenado a ingerir apenas l\u00edquidos.<\/p>\n<p style=\"text-align: justify;\">\u00c9 tanto o sofrimento, que Jo\u00e3o chega a considerar a possibilidade de colocar termo a sua vida. \u201cTodos os dias penso em p\u00f4r fim \u00e0 minha vida\u201d, afirma, enquanto mostra ao rep\u00f3rter os estragos causados a si, pelo agente da Pol\u00edcia.<\/p>\n<p style=\"text-align: justify;\">O jovem confidenciou \u00e0 nossa equipa de reportagem que todos os fins-de-semana enviava dinheiro para a mulher e os seus quatro filhos, no Planalto Central, todavia, desde que esta trag\u00e9dia aconteceu, deixou de o fazer. Por\u00e9m, sublinhou que, at\u00e9 ao dia desta entrevista, 6 de Outubro, o agente em causa j\u00e1 fez chegar aos familiares um total de AKZ 67.000.00 (sessenta e sete mil kwanzas), dados em duas presta\u00e7\u00f5es, com o prop\u00f3sito de cobrir o tratamento, tendo, ainda, se comprometido a entregar mais 25.000,00 (vinte e cinco mil kwanzas), mensalmente, para cobrir o tratamento.<\/p>\n<p style=\"text-align: justify;\">\u201cEsse dinheiro n\u00e3o serve para todas as despesas e, t\u00e3o pouco, consigo enviar alguma coisa para a minha fam\u00edlia no Huambo\u201d, contou, alegando que, de minuto a minuto, se tem questionado sobre a forma como a mulher e os filhos t\u00eam conseguido sobreviver sem dinheiro. \u201cEst\u00e1 duro, meu irm\u00e3o. N\u00e3o sei como eles v\u00e3o virar-se\u201d, desabafou para o jornalista.<\/p>\n<p style=\"text-align: justify;\"><strong>Familiares exigem indeminiza\u00e7\u00e3o junto da PGR<\/strong><\/p>\n<p style=\"text-align: justify;\">Adelino Oseias Chinendele, o pai do lesado, em entrevista \u00e0 nossa reportagem, fez saber que o caso est\u00e1 a ser resolvido na PGR junto \u00e0 44.\u00aa Esquadra, na Estalagem, onde o aludido agente funciona. \u201cDesde o primeiro dia, depois que nos reunimos com o camarada Celso, segundo comandante da Esquadra, o agente tem prestado o necess\u00e1rio apoio ao lesado\u201d, assegurou.<\/p>\n<p style=\"text-align: justify;\">Por esta altura, revelou o senhor, falta-lhe ainda realizar alguns exames m\u00e9dicos, como s\u00e3o os casos de tomografia computadorizada de maxilar, que tem como enfoque o osso maxilar e as arcadas dent\u00e1rias do paciente \u2014 e a de resson\u00e2ncia magn\u00e9tica, para o estudo da articula\u00e7\u00e3o da mand\u00edbula, que possibilita a visualiza\u00e7\u00e3o do disco articular e tecidos moles circunjacentes.<\/p>\n<p style=\"text-align: justify;\">\u201cTalvez seja necess\u00e1rio levar placa\u201d, opinou, acrescentando que os dentes t\u00eam ca\u00eddo por si s\u00f3, e que tal situa\u00e7\u00e3o o tem incomodado bastante. Por isso, prosseguiu, o filho tem aventado, em algumas ocasi\u00f5es, p\u00f4r fim \u00e0 vida.<\/p>\n<p style=\"text-align: justify;\">Asseverou, igualmente, que a fam\u00edlia j\u00e1 se reuniu com a PGR, mas no primeiro encontro entre as partes, nada ficou decidido. Entretanto, disse, est\u00e3o a aguardar pela recupera\u00e7\u00e3o do jovem, para voltarem a contactar aquela institui\u00e7\u00e3o. \u201cVoltaremos a contactar a PGR para finalizarmos este processo, porque, como sabemos, o agente em causa deve, a t\u00edtulo de indeminiza\u00e7\u00e3o, entregar uma quantia em dinheiro \u00e0 v\u00edtima\u201d, referiu, dizendo de seguida que n\u00e3o podem ainda adiantar o valor, mas que tudo ser\u00e1 definido junto da PGR.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, revelou que h\u00e1 algumas vozes cr\u00edticas, em rela\u00e7\u00e3o ao facto de terem contactado a imprensa, por\u00e9m, garantiu que, \u201cse n\u00e3o fosse o grito de socorro feito \u00e0 imprensa, seria dif\u00edcil suprir as despesas e as necessidades do jovem\u201d, notou.<\/p>\n<p style=\"text-align: justify;\">Por fim, explicou que, a n\u00edvel interno da unidade policial, nenhum processo foi instaurado contra o referido agente, sendo que foram aconselhados a resolver o assunto \u201camigavelmente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O tiro efectuado por Ant\u00f3nio Augusto Rafael, agente de 1.\u00aa classe da Pol\u00edcia Nacional, afecto \u00e0 44.\u00aa Esquadra, no distrito da Estalagem, perfurou as bochechas da v\u00edtima, tendo-lhe causado graves ferimentos na l\u00edngua e nos maxilares. Por: Costa Kilunda Jo\u00e3o Fernando, o mototaxista de 28 anos, encontra-se, agora, a recuperar em casa, depois de ficar internado por mais de duas semanas no Hospital Am\u00e9rico Boavida, em fun\u00e7\u00e3o dos estragos causados na sua boca, pelo proj\u00e9ctil que o atingiu. A raz\u00e3o do incidente, segundo fez saber a v\u00edtima, deveu-se ao facto de ter recusado a dar 100 kwanzas, exigidos pelo referido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O tiro efectuado por Ant\u00f3nio Augusto Rafael, agente de 1.\u00aa classe da Pol\u00edcia Nacional, afecto \u00e0 44.\u00aa Esquadra, no distrito da Estalagem, perfurou as bochechas da v\u00edtima, tendo-lhe causado graves ferimentos na l\u00edngua e nos maxilares. Por: Costa Kilunda Jo\u00e3o Fernando, o mototaxista de 28 anos, encontra-se, agora, a recuperar em casa, depois de ficar internado por mais de duas semanas no Hospital Am\u00e9rico Boavida, em fun\u00e7\u00e3o dos estragos causados na sua boca, pelo proj\u00e9ctil que o atingiu. A raz\u00e3o do incidente, segundo fez saber a v\u00edtima, deveu-se ao facto de ter recusado a dar 100 kwanzas, exigidos pelo referido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-28T17:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-28T19:11:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/DSC_0461-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA\",\"datePublished\":\"2020-10-28T17:55:10+00:00\",\"dateModified\":\"2020-10-28T19:11:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/\"},\"wordCount\":821,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/DSC_0461-scaled.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/\",\"name\":\"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/DSC_0461-scaled.jpg\",\"datePublished\":\"2020-10-28T17:55:10+00:00\",\"dateModified\":\"2020-10-28T19:11:13+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/DSC_0461-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/DSC_0461-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/","og_locale":"pt_PT","og_type":"article","og_title":"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA - Jornal O Crime","og_description":"O tiro efectuado por Ant\u00f3nio Augusto Rafael, agente de 1.\u00aa classe da Pol\u00edcia Nacional, afecto \u00e0 44.\u00aa Esquadra, no distrito da Estalagem, perfurou as bochechas da v\u00edtima, tendo-lhe causado graves ferimentos na l\u00edngua e nos maxilares. Por: Costa Kilunda Jo\u00e3o Fernando, o mototaxista de 28 anos, encontra-se, agora, a recuperar em casa, depois de ficar internado por mais de duas semanas no Hospital Am\u00e9rico Boavida, em fun\u00e7\u00e3o dos estragos causados na sua boca, pelo proj\u00e9ctil que o atingiu. A raz\u00e3o do incidente, segundo fez saber a v\u00edtima, deveu-se ao facto de ter recusado a dar 100 kwanzas, exigidos pelo referido [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/","og_site_name":"Jornal O Crime","article_published_time":"2020-10-28T17:55:10+00:00","article_modified_time":"2020-10-28T19:11:13+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/DSC_0461-scaled.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA","datePublished":"2020-10-28T17:55:10+00:00","dateModified":"2020-10-28T19:11:13+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/"},"wordCount":821,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/DSC_0461-scaled.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/","url":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/","name":"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/DSC_0461-scaled.jpg","datePublished":"2020-10-28T17:55:10+00:00","dateModified":"2020-10-28T19:11:13+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/DSC_0461-scaled.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/10\/DSC_0461-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/por-miseros-100-kwanzas-agente-da-pna-dispara-contra-o-rosto-de-um-mototaxista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Por m\u00edseros 100 kwanzas: AGENTE DA PNA DISPARA CONTRA O ROSTO DE UM MOTOTAXISTA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2471"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2481"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}