{"id":2518,"date":"2020-11-07T00:43:19","date_gmt":"2020-11-06T23:43:19","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2518"},"modified":"2020-11-07T00:44:50","modified_gmt":"2020-11-06T23:44:50","slug":"detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/","title":{"rendered":"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA"},"content":{"rendered":"<p style=\"text-align: justify;\">O SIC deteve, nos dias 3 e 5 deste m\u00eas, tr\u00eas dos quatro cidad\u00e3os que aparecem em v\u00eddeos virais nas redes sociais proferindo ofensas morais ao Chefe de Estado, Jo\u00e3o Louren\u00e7o, e amea\u00e7as de incendiar a TPA e RNA.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2522\" src=\"https:\/\/jornalocrime.com\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0002-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0002-225x300.jpg 225w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0002-768x1024.jpg 768w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0002-400x533.jpg 400w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0002.jpg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>Tal foi poss\u00edvel mediante um trabalho de seguimento e intelig\u00eancia criminal e um dos mentores apresentou-se voluntariamente \u00e0s autoridades.<\/p>\n<p>Por\u00e9m, &#8220;outro envolvidos continua foragido, pelo que dilig\u00eancias prosseguem para a sua captura&#8221;, informou o SIC.<!--Clip_XXXX_201107_003608_317--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O SIC deteve, nos dias 3 e 5 deste m\u00eas, tr\u00eas dos quatro cidad\u00e3os que aparecem em v\u00eddeos virais nas redes sociais proferindo ofensas morais ao Chefe de Estado, Jo\u00e3o Louren\u00e7o, e amea\u00e7as de incendiar a TPA e RNA. Tal foi poss\u00edvel mediante um trabalho de seguimento e intelig\u00eancia criminal e um dos mentores apresentou-se voluntariamente \u00e0s autoridades. Por\u00e9m, &#8220;outro envolvidos continua foragido, pelo que dilig\u00eancias prosseguem para a sua captura&#8221;, informou o SIC.<\/p>\n","protected":false},"author":2,"featured_media":2519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[208,197],"class_list":["post-2518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedade","tag-chefe-de-estado","tag-manifestacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O SIC deteve, nos dias 3 e 5 deste m\u00eas, tr\u00eas dos quatro cidad\u00e3os que aparecem em v\u00eddeos virais nas redes sociais proferindo ofensas morais ao Chefe de Estado, Jo\u00e3o Louren\u00e7o, e amea\u00e7as de incendiar a TPA e RNA. Tal foi poss\u00edvel mediante um trabalho de seguimento e intelig\u00eancia criminal e um dos mentores apresentou-se voluntariamente \u00e0s autoridades. Por\u00e9m, &#8220;outro envolvidos continua foragido, pelo que dilig\u00eancias prosseguem para a sua captura&#8221;, informou o SIC.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-06T23:43:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T23:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA\",\"datePublished\":\"2020-11-06T23:43:19+00:00\",\"dateModified\":\"2020-11-06T23:44:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/\"},\"wordCount\":98,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/IMG-20201107-WA0001.jpg\",\"keywords\":[\"Chefe de Estado\",\"Manifesta\u00e7\u00e3o\"],\"articleSection\":[\"SOCIEDADE\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/\",\"name\":\"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/IMG-20201107-WA0001.jpg\",\"datePublished\":\"2020-11-06T23:43:19+00:00\",\"dateModified\":\"2020-11-06T23:44:50+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/IMG-20201107-WA0001.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/IMG-20201107-WA0001.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/","og_locale":"pt_PT","og_type":"article","og_title":"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA - Jornal O Crime","og_description":"O SIC deteve, nos dias 3 e 5 deste m\u00eas, tr\u00eas dos quatro cidad\u00e3os que aparecem em v\u00eddeos virais nas redes sociais proferindo ofensas morais ao Chefe de Estado, Jo\u00e3o Louren\u00e7o, e amea\u00e7as de incendiar a TPA e RNA. Tal foi poss\u00edvel mediante um trabalho de seguimento e intelig\u00eancia criminal e um dos mentores apresentou-se voluntariamente \u00e0s autoridades. Por\u00e9m, &#8220;outro envolvidos continua foragido, pelo que dilig\u00eancias prosseguem para a sua captura&#8221;, informou o SIC.","og_url":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/","og_site_name":"Jornal O Crime","article_published_time":"2020-11-06T23:43:19+00:00","article_modified_time":"2020-11-06T23:44:50+00:00","og_image":[{"width":768,"height":1024,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0001.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA","datePublished":"2020-11-06T23:43:19+00:00","dateModified":"2020-11-06T23:44:50+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/"},"wordCount":98,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0001.jpg","keywords":["Chefe de Estado","Manifesta\u00e7\u00e3o"],"articleSection":["SOCIEDADE"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/","url":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/","name":"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0001.jpg","datePublished":"2020-11-06T23:43:19+00:00","dateModified":"2020-11-06T23:44:50+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0001.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/IMG-20201107-WA0001.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/detidos-cidadaos-que-proferiram-ofensas-contra-chefe-de-estado-e-ameacaram-queimar-tpa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"DETIDOS CIDAD\u00c3OS QUE PROFERIRAM OFENSAS CONTRA CHEFE DE ESTADO E AMEA\u00c7ARAM QUEIMAR TPA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2518"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2519"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}