{"id":2547,"date":"2020-11-14T13:53:48","date_gmt":"2020-11-14T12:53:48","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2547"},"modified":"2020-11-14T13:53:48","modified_gmt":"2020-11-14T12:53:48","slug":"ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/","title":{"rendered":"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Tr\u00eas indiv\u00edduos, fortemente armados com AKM, assaltaram e executaram, na via p\u00fablica, um mototaxista de, apenas, 17 anos. Testemunhas oculares contaram ao \u2018O CRIME\u2019 que a v\u00edtima ofereceu resist\u00eancia e foi alvejada com dois tiros no abd\u00f3mem. O crime aconteceu na passada sexta-feira, 9\/10, no Calemba 2, e o adolescente veio a falecer no dia seguinte.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0Por: Costa Kilunda <\/strong><\/p>\n<p style=\"text-align: justify;\">Segundo fez saber os familiares da v\u00edtima, o assalto ocorreu por volta das 18 horas de sexta-feira, 9, uma altura em que Kololo Andr\u00e9, de 17 anos de idade, regressava para casa, depois de mais um dia de trabalho. Numa das ruas daquele intrigado bairro, o adolescente deu de caras com um grupo de tr\u00eas indiv\u00edduos, fortemente armados, transportados por duas motorizadas, que o abordaram e de seguida anunciaram o crime.<\/p>\n<p style=\"text-align: justify;\">Temendo pela sua vida, contou Augusto Pembele, irm\u00e3o mais velho da v\u00edtima, o adolescente decidiu escapar dos marginais que, sem hesitar, efectuaram dois disparos \u00e0 queima-roupa, atingindo-o na regi\u00e3o do abd\u00f3mem. Na sequ\u00eancia, disse, os suspeitos retiraram a v\u00edtima da motorizada e colocaram-se em fuga com a mesma. \u201cUma das balas perfurou a barriga e saiu, mas a outra ficou no interior\u201d, afirmou Augusto, acrescentando que, de imediato, foi socorrido por colegas, que o levaram at\u00e9 ao Hospital Geral de Luanda, onde foi assistido pelo corpo cl\u00ednico daquela unidade.<\/p>\n<p style=\"text-align: justify;\">Augusto contou, ainda, que apesar de o irm\u00e3o ter sido submetido a uma interven\u00e7\u00e3o cir\u00fargica, para remo\u00e7\u00e3o do proj\u00e9ctil, aparentemente com sucesso, do qual foram precisos seis bal\u00f5es de sangue, Kololo veio a sucumbir no dia seguinte, s\u00e1bado, 10\/10, por volta das duas da tarde, n\u00e3o resistindo aos ferimentos.<\/p>\n<p style=\"text-align: justify;\">Bastante condo\u00edda com a trag\u00e9dia, estava tamb\u00e9m a m\u00e3e do adolescente, Ngunga Maria, que se mostrava incapaz de compreender tamanha barb\u00e1rie, por causa de uma motorizada. \u201cPor que matar um mi\u00fado por causa de uma motorizada?\u201d, questiona agora a senhora, de quem o finado filho era, tamb\u00e9m, apoio. \u201cTudo que ele queria era, apenas, trabalhar e custear os seus estudos\u201d, reitera.<\/p>\n<p style=\"text-align: justify;\">Visivelmente magoada e quase sem reac\u00e7\u00e3o, suplica para que seja feita a justi\u00e7a pelo filho.<\/p>\n<p style=\"text-align: justify;\">Segundo apurou a reportagem do \u2018O CRIME\u2019, o bairro Calemba 2, no munic\u00edpio do Kilamba Kiaxi, \u00e9 bastante f\u00e9rtil em epis\u00f3dios como o que aconteceu com este cidad\u00e3o, acrescentando mais um nome \u00e0, j\u00e1 extensa, lista de execu\u00e7\u00f5es, por marginais, em plena via p\u00fablica. Em uma das edi\u00e7\u00f5es anteriores deste jornal, trouxemos o relato de um caso em que um mototaxista tamb\u00e9m teve o mesmo fim.<\/p>\n<p style=\"text-align: justify;\">Na maioria das vezes, segundo deram a conhecer alguns moradores, os crimes acontecem bem \u00e0s barbas das autoridades, que se apresentam impotentes de reagir ou, at\u00e9 mesmo, de reverter o quadro. De acordo com uma testemunha, que preferiu anonimato, explicou que, pela frequ\u00eancia com que tais epis\u00f3dios acontecem, n\u00e3o \u00e9 de se estranhar que tal venha a contar com a participa\u00e7\u00e3o dos agentes da Pol\u00edcia, mais preocupados em extorquir os mototaxista e automobilistas, do que, propriamente, em combater o crime.<\/p>\n<p style=\"text-align: justify;\">\u201c\u00c9 lament\u00e1vel\u201d, deplora, para depois dizer que um pouco por toda extens\u00e3o do bairro, ouve-se, dia-ap\u00f3s-dia, relatos de pessoas que perderam a vida em consequ\u00eancia das ac\u00e7\u00f5es dos marginais, que tomaram de assalto a zona.<\/p>\n<p style=\"text-align: justify;\">Para este morador, n\u00e3o \u00e9 por acaso que, tamb\u00e9m, de quando em vez, preferem fazer justi\u00e7a por m\u00e3os pr\u00f3prias, a esperarem que a Pol\u00edcia os venha defender. \u201cPreferimos queim\u00e1-los\u201d, disse, enquanto conta, aos dedos, os casos em que se viram for\u00e7ados a defenderem a sua honra.<\/p>\n<p style=\"text-align: justify;\">O bairro Calemba 2, segundo os nossos interlocutores, est\u00e1 dominado pelo crime, mais a mais, aventam, por ser uma zona com bastante movimenta\u00e7\u00e3o, devido aos mercados, que o tornaram em alvo e terra f\u00e9rtil para o cometimento de crimes. Ali\u00e1s, ao inv\u00e9s de combat\u00ea-los, afirmam, os homens da farda azul transformaram-se em aliados dos bandidos.<\/p>\n<p style=\"text-align: justify;\">De real\u00e7ar que o caso do adolescente Kololo Andr\u00e9, assassinado no passado dia 9 de Outubro, sexta-feira, j\u00e1 \u00e9 do dom\u00ednio do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC), tendo, j\u00e1, sido instaurado um processo-crime, com o n\u00famero 7202\/20, para investiga\u00e7\u00e3o, localiza\u00e7\u00e3o e poss\u00edvel deten\u00e7\u00e3o dos marginais, ainda a monte.<\/p>\n<p style=\"text-align: justify;\">De real\u00e7ar, tamb\u00e9m, que os restos mortais de Kololo Andr\u00e9, de 17 anos, foram a enterrar no passado s\u00e1bado, 17, no Cemit\u00e9rio da Camama.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas indiv\u00edduos, fortemente armados com AKM, assaltaram e executaram, na via p\u00fablica, um mototaxista de, apenas, 17 anos. Testemunhas oculares contaram ao \u2018O CRIME\u2019 que a v\u00edtima ofereceu resist\u00eancia e foi alvejada com dois tiros no abd\u00f3mem. O crime aconteceu na passada sexta-feira, 9\/10, no Calemba 2, e o adolescente veio a falecer no dia seguinte. \u00a0Por: Costa Kilunda Segundo fez saber os familiares da v\u00edtima, o assalto ocorreu por volta das 18 horas de sexta-feira, 9, uma altura em que Kololo Andr\u00e9, de 17 anos de idade, regressava para casa, depois de mais um dia de trabalho. Numa das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Tr\u00eas indiv\u00edduos, fortemente armados com AKM, assaltaram e executaram, na via p\u00fablica, um mototaxista de, apenas, 17 anos. Testemunhas oculares contaram ao \u2018O CRIME\u2019 que a v\u00edtima ofereceu resist\u00eancia e foi alvejada com dois tiros no abd\u00f3mem. O crime aconteceu na passada sexta-feira, 9\/10, no Calemba 2, e o adolescente veio a falecer no dia seguinte. \u00a0Por: Costa Kilunda Segundo fez saber os familiares da v\u00edtima, o assalto ocorreu por volta das 18 horas de sexta-feira, 9, uma altura em que Kololo Andr\u00e9, de 17 anos de idade, regressava para casa, depois de mais um dia de trabalho. Numa das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-14T12:53:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA\",\"datePublished\":\"2020-11-14T12:53:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/\"},\"wordCount\":765,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1-1.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/\",\"name\":\"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1-1.jpg\",\"datePublished\":\"2020-11-14T12:53:48+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/1-1.jpg\",\"width\":400,\"height\":526},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/","og_locale":"pt_PT","og_type":"article","og_title":"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA - Jornal O Crime","og_description":"Tr\u00eas indiv\u00edduos, fortemente armados com AKM, assaltaram e executaram, na via p\u00fablica, um mototaxista de, apenas, 17 anos. Testemunhas oculares contaram ao \u2018O CRIME\u2019 que a v\u00edtima ofereceu resist\u00eancia e foi alvejada com dois tiros no abd\u00f3mem. O crime aconteceu na passada sexta-feira, 9\/10, no Calemba 2, e o adolescente veio a falecer no dia seguinte. \u00a0Por: Costa Kilunda Segundo fez saber os familiares da v\u00edtima, o assalto ocorreu por volta das 18 horas de sexta-feira, 9, uma altura em que Kololo Andr\u00e9, de 17 anos de idade, regressava para casa, depois de mais um dia de trabalho. Numa das [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/","og_site_name":"Jornal O Crime","article_published_time":"2020-11-14T12:53:48+00:00","og_image":[{"width":400,"height":526,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/1-1.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA","datePublished":"2020-11-14T12:53:48+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/"},"wordCount":765,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/1-1.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/","url":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/","name":"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/1-1.jpg","datePublished":"2020-11-14T12:53:48+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/1-1.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/1-1.jpg","width":400,"height":526},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/ao-resistir-ao-assalto-mototaxista-e-executado-na-via-publica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Ao resistir ao assalto: MOTOTAXISTA \u00c9 EXECUTADO NA VIA P\u00daBLICA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2547"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2596"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}