{"id":2549,"date":"2020-11-14T13:36:57","date_gmt":"2020-11-14T12:36:57","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2549"},"modified":"2020-11-14T13:36:57","modified_gmt":"2020-11-14T12:36:57","slug":"agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/","title":{"rendered":"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Numa negocia\u00e7\u00e3o que durou pouco mais de 15 minutos, uma cidad\u00e3, suposta mulher de um comiss\u00e1rio da PNA, ter\u00e1 \u201ccalado a boca de agentes do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC)\u201d, ao pagar 1 milh\u00e3o de kwanzas para retirar o seu nome de um processo em que figura como a mandante e compradora de diversos produtos roubados de um armaz\u00e9m.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0Por: Costa Kilunda <\/strong><\/p>\n<p style=\"text-align: justify;\">Fernando Lucas, Fidelino M\u00e1rio Gast\u00e3o e outro comparsa, apenas identificado por Osvaldo, s\u00e3o um trio de marginais que, segundo consta, engendraram e assaltaram um armaz\u00e9m de venda de produtos alimentares diversos no passado dia 9 de Setembro, no bairro Vidrul, munic\u00edpio de Cacuaco.<\/p>\n<p style=\"text-align: justify;\">Todavia, depois de uma investiga\u00e7\u00e3o minuciosa dos Servi\u00e7os de Investiga\u00e7\u00e3o Criminal (SIC), que culminou com a identifica\u00e7\u00e3o e deten\u00e7\u00e3o dos mesmos, os supostos assaltantes foram submetidos a tortura e, por fim, confessaram a autoria do crime, assim como denunciaram, \u00e0s autoridades, a suposta mandante e compradora dos bens roubados.<\/p>\n<p style=\"text-align: justify;\">Mas a quadrilha n\u00e3o ficou pela den\u00fancia da alegada autora moral do crime, bem como conduziram os investigadores at\u00e9 \u00e0 moradia desta, localizada nos arredores da casa militar, no Kikolo. De acordo com um \u00e1udio a que \u2018O CRIME\u2019 teve acesso, as provas do crime foram encontradas na resid\u00eancia da aludida senhora, num total de 102 (cento e duas) caixas de \u00d3leo de Palma, 8 (oito) sacos de Arroz, 2 (duas) caixas de Whisky e 1 (uma) caixa de sumo Compal.<\/p>\n<p style=\"text-align: justify;\">No entanto, ouve-se, os bens apreendidos n\u00e3o retornaram ao armaz\u00e9m, de onde sa\u00edram ilicitamente, t\u00e3o pouco deram entrada na unidade policial a fim de serem catalogadas e fazer-se constar dos autos de apreens\u00e3o.<\/p>\n<p style=\"text-align: justify;\">De acordo com um dos marginais, como \u00e9 poss\u00edvel ouvir-se no referido \u00e1udio, para al\u00e9m dos bens acima mencionados, os investigadores do SIC encontraram ainda avultadas somas em dinheiro. \u201cLogo empurraram-nos para fora e nos mandaram para o carro com objectivo de melhor negociarem com a senhora\u201d, denunciou um dos suspeitos, para depois dizer que o montante pago aos agentes ter\u00e1 rondado os um milh\u00e3o de kwanzas (AKZ 1 000.000.000.00), numa negociata que durou cerca de 15 minutos.<\/p>\n<p style=\"text-align: justify;\">Ainda no mesmo \u00e1udio, \u00e9 poss\u00edvel ouvir a voz de um alegado efectivo do SIC a orientar os colegas a dizer que a mesma cidad\u00e3 \u00e9 esposa de um comiss\u00e1rio da PN. \u201cDigam que o marido dela \u00e9 um comiss\u00e1rio da Pol\u00edcia Nacional\u201d, ouve-se. Ademais, denunciam, os supostos assaltantes, quando regressaram \u00e0 esquadra foram, minutos depois, coagidos a assinar um documento cujo conte\u00fado era por eles desconhecido.<\/p>\n<p style=\"text-align: justify;\">Seguidamente, depois da assinatura do referido documento, foram colocados em celas separadas. \u201cO Osvaldo e eu (Fernando Lucas), fomos colocados na mesma cela, porquanto o Fidelino M\u00e1rio Gast\u00e3o, por n\u00e3o colaborar, foi transferido para a Divis\u00e3o Municipal de Cacuaco, onde permanece at\u00e9 a presente data\u201d, prossegue a grava\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cAli houve neg\u00f3cio rijo\u201d, afirma suposto meliante<\/strong><\/p>\n<p style=\"text-align: justify;\">De acordo ainda com a mesma grava\u00e7\u00e3o, para o sucesso da opera\u00e7\u00e3o, os alegados marginais usaram armas de fogo, do tipo AKM, em quantidade n\u00e3o mencionada, alugadas no valor de AKz 300.000.00 (trezentos mil kwanzas), bem como uma carrinha de marca Toyota, modelo Hilux, para o transporte da mercadoria roubada.<\/p>\n<p style=\"text-align: justify;\">\u201cAli ouve neg\u00f3cio rijo\u201d, diz um dos suspeitos, fazendo alus\u00e3o ao acordo entre a suposta mandante e os agentes do SIC. Por outro lado, denunciaram que os mesmos agentes tinham apreendido, inclusive, o telefone da senhora, mas que o alegado esposo desta, \u201cpor gozar de influ\u00eancia\u201d, deslocou-se at\u00e9 \u00e0 esquadra onde, inicialmente, estavam detidos, no bairro da Vidrul, e levou de volta o telefone consigo.<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cO meu irm\u00e3o n\u00e3o \u00e9 visto h\u00e1 quase dois meses\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Entretanto, Ant\u00f3nio Muxito, irm\u00e3o mais velho de Fidelino M\u00e1rio Gast\u00e3o, o \u00fanico elemento do bando que continua detido desde o pret\u00e9rito dia nove de Setembro at\u00e9 a presente data, disse que h\u00e1 quase dois meses que n\u00e3o se sabe o paradeiro do irm\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Em entrevista \u00e0 nossa reportagem, contou que os demais membros da quadrilha est\u00e3o agora em liberdade, estranhamente num momento em que o processo-crime, acoberto do n\u00famero 7884\/20, j\u00e1 estava sob dom\u00ednio da PGR junto do SIC-Cacuaco.<\/p>\n<p style=\"text-align: justify;\">\u201cDepois da negocia\u00e7\u00e3o entre o SIC e a senhora, um dos agentes sugeria aos seus companheiros que colocassem todos os assaltantes em liberdade, alegando que por terem chegado a um acordo com a compradora, diriam aos seus superiores que nada foi encontrado em posse da mesma\u201d, contou o jovem, sublinhando que um dos agentes retorquiu, \u201cn\u00e3o, vamos mant\u00ea-los presos\u201d.<\/p>\n<p style=\"text-align: justify;\">A fonte disse estar preocupado com o sumi\u00e7o do irm\u00e3o, o \u00fanico sacrificado para justificar o trabalho realizado pelas for\u00e7as castrenses. Por outro lado, afirmou ter contactado o instrutor processual, que o informou que o propriet\u00e1rio do armaz\u00e9m nunca teve de volta os bens roubados, j\u00e1 que o acordo feito permitiria a liberta\u00e7\u00e3o dos suspeitos caso os bens roubados fossem restitu\u00eddos.<\/p>\n<p style=\"text-align: justify;\">\u201cN\u00e3o nos permitem visit\u00e1-lo. A \u00fanica coisa que fa\u00e7o \u00e9 saber junto do piquete se o nome consta da lista dos detidos, para todos os dias levar-lhe comida\u201d, notou.<\/p>\n<p style=\"text-align: justify;\">De referir que a nossa equipa de reportagens tentou contactar o investigador Jo\u00e3o Saldanha, director do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal junto da Divis\u00e3o Municipal de Cacuaco para poss\u00edveis esclarecimentos sobre o assunto, mas n\u00e3o teve sucesso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa negocia\u00e7\u00e3o que durou pouco mais de 15 minutos, uma cidad\u00e3, suposta mulher de um comiss\u00e1rio da PNA, ter\u00e1 \u201ccalado a boca de agentes do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC)\u201d, ao pagar 1 milh\u00e3o de kwanzas para retirar o seu nome de um processo em que figura como a mandante e compradora de diversos produtos roubados de um armaz\u00e9m. \u00a0Por: Costa Kilunda Fernando Lucas, Fidelino M\u00e1rio Gast\u00e3o e outro comparsa, apenas identificado por Osvaldo, s\u00e3o um trio de marginais que, segundo consta, engendraram e assaltaram um armaz\u00e9m de venda de produtos alimentares diversos no passado dia 9 de Setembro, no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Numa negocia\u00e7\u00e3o que durou pouco mais de 15 minutos, uma cidad\u00e3, suposta mulher de um comiss\u00e1rio da PNA, ter\u00e1 \u201ccalado a boca de agentes do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC)\u201d, ao pagar 1 milh\u00e3o de kwanzas para retirar o seu nome de um processo em que figura como a mandante e compradora de diversos produtos roubados de um armaz\u00e9m. \u00a0Por: Costa Kilunda Fernando Lucas, Fidelino M\u00e1rio Gast\u00e3o e outro comparsa, apenas identificado por Osvaldo, s\u00e3o um trio de marginais que, segundo consta, engendraram e assaltaram um armaz\u00e9m de venda de produtos alimentares diversos no passado dia 9 de Setembro, no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-14T12:36:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Caso-Cacuacon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O\",\"datePublished\":\"2020-11-14T12:36:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/\"},\"wordCount\":923,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Caso-Cacuacon.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/\",\"name\":\"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Caso-Cacuacon.jpg\",\"datePublished\":\"2020-11-14T12:36:57+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Caso-Cacuacon.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Caso-Cacuacon.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/","og_locale":"pt_PT","og_type":"article","og_title":"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O - Jornal O Crime","og_description":"Numa negocia\u00e7\u00e3o que durou pouco mais de 15 minutos, uma cidad\u00e3, suposta mulher de um comiss\u00e1rio da PNA, ter\u00e1 \u201ccalado a boca de agentes do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC)\u201d, ao pagar 1 milh\u00e3o de kwanzas para retirar o seu nome de um processo em que figura como a mandante e compradora de diversos produtos roubados de um armaz\u00e9m. \u00a0Por: Costa Kilunda Fernando Lucas, Fidelino M\u00e1rio Gast\u00e3o e outro comparsa, apenas identificado por Osvaldo, s\u00e3o um trio de marginais que, segundo consta, engendraram e assaltaram um armaz\u00e9m de venda de produtos alimentares diversos no passado dia 9 de Setembro, no [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/","og_site_name":"Jornal O Crime","article_published_time":"2020-11-14T12:36:57+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Caso-Cacuacon.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O","datePublished":"2020-11-14T12:36:57+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/"},"wordCount":923,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Caso-Cacuacon.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/","url":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/","name":"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Caso-Cacuacon.jpg","datePublished":"2020-11-14T12:36:57+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Caso-Cacuacon.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Caso-Cacuacon.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/agentes-do-sic-cacuaco-acusados-de-libertar-criminosos-em-troca-de-akz-1-milhao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Agentes do SIC-Cacuaco: ACUSADOS DE LIBERTAR CRIMINOSOS EM TROCA DE AKZ 1 MILH\u00c3O"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2549"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2592"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}