{"id":2606,"date":"2020-11-14T15:07:42","date_gmt":"2020-11-14T14:07:42","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2606"},"modified":"2020-11-16T12:09:19","modified_gmt":"2020-11-16T11:09:19","slug":"ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/","title":{"rendered":"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Rodrigues Cambala \u00e9 jornalista h\u00e1 21 anos, tendo ao longo da sua carreira, passado pelos extintos jornais \u2018Actual\u2019, onde deu os primeiros passos, e o \u2018O Independente\u2019, bem como colaborou em v\u00e1rios outros e revistas no pa\u00eds. \u00c9 licenciado em Comunica\u00e7\u00e3o Social pela Faculdade de Ci\u00eancias Sociais da Universidade Agostinho Neto e especialista em Comunica\u00e7\u00e3o Corporativa, frequentando o curso de p\u00f3s-gradua\u00e7\u00e3o em Direc\u00e7\u00e3o Estrat\u00e9gica e Marketing. Com forma\u00e7\u00e3o em \u2018Reportagem e Escrita de Texto n\u00e3o Fic\u00e7\u00e3o\u2019, realizado no Cenjor-Lisboa, \u00e9 tamb\u00e9m formador em mat\u00e9ria de Comunica\u00e7\u00e3o Corporativa e Jornalismo e prev\u00ea, para breve, o lan\u00e7amento do seu livro, \u2018Reportagem\u2019. \u00c9 com este actual quadro do Jornal de Angola que chegamos \u00e0 fala para abordar o cen\u00e1rio actual do Jornalismo angolano e conjecturar o futuro.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Jo\u00e3o Feliciano<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Que leitura se pode fazer sobre o estado actual da nossa Comunica\u00e7\u00e3o Social?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Ora, fazendo um recuo ao tempo em que n\u00f3s faz\u00edamos o Jornalismo, at\u00e9 \u00e0 altura antes do multipartidarismo, 1992, quando come\u00e7aram a surgir \u00f3rg\u00e3os de comunica\u00e7\u00e3o ou jornais privados, t\u00ednhamos um Jornalismo muito centralizado, um Jornalismo assente no comunismo. Mas j\u00e1 com o processo de paz e com ele o multipartidarismo, abriu-se um pouco esse processo e come\u00e7amos a viver novas formas de fazer comunica\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Surgem, da\u00ed, algumas r\u00e1dios e jornais privados nesse per\u00edodo. Mas, de l\u00e1 para c\u00e1, come\u00e7amos a registar novos modelos e novas formas de se fazer Jornalismo. Mas, claro, os colegas daquele per\u00edodo, nessa transi\u00e7\u00e3o, naturalmente, como qualquer transi\u00e7\u00e3o, acredito que tiveram alguma dificuldade. Nessa altura, e depois de qualquer processo, achamos que tivemos um per\u00edodo muito bom, isto \u00e9, em finais da d\u00e9cada de 1990 e princ\u00edpio da d\u00e9cada de 2000.<\/p>\n<p style=\"text-align: justify;\">Nessa altura, em princ\u00edpios do novo mil\u00e9nio, o Jornalismo angolano j\u00e1 se fazia com algum grau de responsabilidade, maturidade, enfim. Mas depois come\u00e7ou a registar-se, novamente, algumas situa\u00e7\u00f5es menos boas, em que o jornalismo angolano voltou a entrar em decad\u00eancia, fruto de grupos comerciais que come\u00e7aram a adquirir alguns jornais e foram dizimando- este \u00e9 o termo correcto-, os \u00f3rg\u00e3os de comunica\u00e7\u00e3o social, alguns deles muito bons.<\/p>\n<p style=\"text-align: justify;\">Portanto, da d\u00e9cada passada para c\u00e1, come\u00e7amos a ter algumas dificuldades no campo jornal\u00edstico, desapareceram muitos \u00f3rg\u00e3os de comunica\u00e7\u00e3o privados e, fruto das dificuldades financeiras, do facto de alguns terem sido adquiridos por grupos comerciais, que tinham liga\u00e7\u00f5es muito fortes com o poder.<\/p>\n<p style=\"text-align: justify;\">Mas, ainda assim, surgiram outros \u00f3rg\u00e3os, maioritariamente, feitos por jovens muito din\u00e2micos, \u00e9 claro, alguns deles sem muita experi\u00eancia, mas era o poss\u00edvel que se poderia fazer. Portanto, at\u00e9 hoje temos tr\u00eas ou quatro jornais f\u00edsicos, sendo que os demais s\u00e3o digitais, fruto das dificuldades que se vai vivendo no pa\u00eds- n\u00e3o h\u00e1 pap\u00e9is, n\u00e3o h\u00e1 publicidades, n\u00e3o h\u00e1 cr\u00e9ditos, portanto, n\u00e3o h\u00e1 como sobreviver nestas condi\u00e7\u00f5es. Mais a mais, pelo facto de os jornais privados n\u00e3o serem subsidiados pelo Estado angolano. Da\u00ed essa dificuldade.<\/p>\n<blockquote><p>\u201cOs jornais f\u00edsicos n\u00e3o v\u00e3o desaparecer\u201d<\/p><\/blockquote>\n<p style=\"text-align: justify;\"><strong>O Crime: Essa transforma\u00e7\u00e3o dos jornais em formato de papel para o digital n\u00e3o ter\u00e1 muito a ver com o advento das novas tecnologias, caindo, assim, num processo autom\u00e1tico da pr\u00f3pria evolu\u00e7\u00e3o?\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Esse processo seria natural, concordo consigo! Chegaria uma altura em que os jornais deveriam, automaticamente, transferir-se, tamb\u00e9m, para o mundo digital. Isto \u00e9 daquelas coisas indiz\u00edveis.<\/p>\n<p style=\"text-align: justify;\">Naturalmente, hoje, com este desenvolvimento muito grande das novas tecnologias de comunica\u00e7\u00e3o e informa\u00e7\u00e3o, as pessoas, estando em qualquer ponto, precisam informar-se, precisam comunicar-se. Era normal que os jornais, falando da nossa realidade, tamb\u00e9m penetrassem na Internet. Ali\u00e1s, grandes jornais mundiais, como \u00e9 o caso, por exemplo, do The Independent, uma publica\u00e7\u00e3o brit\u00e2nica com uma hist\u00f3ria muito grande, portanto, deixou de ser impresso para ser \u00fanica e exclusivamente digital. E h\u00e1 outras grandes publica\u00e7\u00f5es internacionais que n\u00e3o deixaram de imprimir, mas que hoje t\u00eam um pendor digital muito forte. Portanto, \u00e9 um processo normal.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Desta feita, acredita que os jornais f\u00edsicos ir\u00e3o desaparecer?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Mas, tamb\u00e9m, como eu costumo dizer, os jornais f\u00edsicos n\u00e3o v\u00e3o desaparecer, porque t\u00eam uma tradi\u00e7\u00e3o. Ali\u00e1s, eu mesmo j\u00e1 encontrei muitos leitores que se sentem mais confort\u00e1veis a ler o jornal f\u00edsico do que o digital. Muitos deles t\u00eam ainda, digamos, uma resist\u00eancia aos meios digitais, mas h\u00e1 maior apet\u00eancia e at\u00e9 mesmo gozo em ler o jornal em papel do que o digital.<\/p>\n<p style=\"text-align: justify;\">Infelizmente, o que aconteceu aqui, em Angola, n\u00e3o foi este processo normal, natural das coisas; os jornais viram-se for\u00e7ados a imigrar para a Internet, pois este formato tem menos custos, os donos dos jornais t\u00eam menos despesas com o pessoal, em termos de pagamento de sal\u00e1rios, contas correntes, enfim. At\u00e9 porque d\u00e1 maior jeito para praticar o Jornalismo, porque n\u00e3o precisa ser feito com um n\u00famero elevado de profissionais e tem o benepl\u00e1cito de a informa\u00e7\u00e3o ser difundida com maior rapidez e atingir um n\u00famero de leitores maior que o formato f\u00edsico.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, vivemos um tempo em que as pessoas querem o imediatismo, e a informa\u00e7\u00e3o n\u00e3o fica atr\u00e1s. A necessidade de as pessoas estarem informadas de imediato obriga que os \u00f3rg\u00e3os virem as baterias para essa nova forma de fazer jornalismo, tamb\u00e9m. Porque, sen\u00e3o, \u00e9s ultrapassado, cais no desuso.<\/p>\n<p style=\"text-align: justify;\">A informa\u00e7\u00e3o tem de ser actualizada minuto a minuto, a cada instante h\u00e1 um dado novo a ser acrescentado na informa\u00e7\u00e3o, e \u00e9 por a\u00ed que todos os \u00f3rg\u00e3os devem partir.<\/p>\n<p style=\"text-align: justify;\">Mas eu noto que alguns jornais, sobretudo os mais tradicionais, vivam ainda alguma dificuldade em rela\u00e7\u00e3o a isto, a pr\u00f3pria Angop, a \u00fanica ag\u00eancia de not\u00edcias que o pa\u00eds tem, o Jornal de Angola, e essa \u00e9 uma opini\u00e3o muito particular, precisam fazer maior investimento nisto. H\u00e1 quem possa dizer que, nesses \u00f3rg\u00e3os, as not\u00edcias tamb\u00e9m s\u00e3o colocadas minuto a minuto, mas o que eu defendo, o jornal O Crime tamb\u00e9m entra nessas contas, \u00e9 que o jornalista, a partir do terreno, tem de ter a capacidade de colocar a not\u00edcia ao ar, ele n\u00e3o precisa de ir \u00e0 redac\u00e7\u00e3o para que a not\u00edcia seja divulgada. \u00c9 uma quest\u00e3o do imediato, por isso \u00e9 que as r\u00e1dios t\u00eam essa vantagem. H\u00e1 maior facilidade disto acontecer na r\u00e1dio.<\/p>\n<p style=\"text-align: justify;\">Eu acho que, se as r\u00e1dios podem, minuto a minuto, colocar a not\u00edcia ao ar, as ag\u00eancias de not\u00edcias e os jornais, tamb\u00e9m, t\u00eam de ter essa capacidade. A partir do terreno e, hoje os telefones d\u00e3o-nos essa possibilidade, os rep\u00f3rteres podem e devem colocar as not\u00edcias no ar. Em dois ou tr\u00eas par\u00e1grafos, mas a not\u00edcia tem de fluir.<\/p>\n<p style=\"text-align: justify;\">\u00c9 necess\u00e1rio evoluirmos por a\u00ed, os \u00f3rg\u00e3os t\u00eam de fazer um investimento mais do ponto de vista da forma\u00e7\u00e3o dos seus colaboradores e dos meios, para que isto aconte\u00e7a. Mas o que notamos \u00e9 que, para as pessoas terem acesso \u00e0s not\u00edcias, os rep\u00f3rteres t\u00eam que ir \u00e0s redac\u00e7\u00f5es, produzir os textos, serem corrigidos e revisados e s\u00f3 depois coloc\u00e1-los ao ar.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Mas esse processo n\u00e3o pode ser perigoso, j\u00e1 que abrir\u00e1 espa\u00e7o para que o rep\u00f3rter cometa muitos erros?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Eu costumo dizer que os donos das empresas de comunica\u00e7\u00e3o contratam os jornalistas a quem incumbem a responsabilidade de dirigir o jornal, e estes, por sua vez, tamb\u00e9m t\u00eam a responsabilidade de recrutar outros profissionais. Mas eu defendo que devem ser recrutados os melhores profissionais, at\u00e9 porque existem no mercado.<\/p>\n<p style=\"text-align: justify;\">Temos muitos bons quadros que est\u00e3o a sair agora das universidades, jovens com capacidade de exercer um bom trabalho. O que acontece \u00e9 que ningu\u00e9m quer correr este risco, sob justificativa de vir a fazer um investimento v\u00e3o. Mas \u00e9 preciso dar um treinamento a esses jovens para os dotar de ferramentas necess\u00e1rias, para que eles possam, rapidamente, entrar no esp\u00edrito da miss\u00e3o, para as quais foram recrutados.<\/p>\n<p style=\"text-align: justify;\">\u00c9 poss\u00edvel evitarmos determinados erros, porque temos profissionais capazes de contorn\u00e1-los. Claro que vamos ter, tamb\u00e9m, aqueles menos experientes, que est\u00e3o no in\u00edcio da carreira, mas que podem produzir os textos a partir do terreno, enviar para o profissional s\u00e9nior que esteja na redac\u00e7\u00e3o ou em qualquer outro ponto, que vai olhar para a not\u00edcia, dar o tratamento e colocar ao ar.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Fazendo um paralelismo entre o tipo de Jornalismo que se praticava antigamente, entre os anos 1990, antes de muitos \u00f3rg\u00e3os serem comprados por grupos comerciais, e o modo como o Jornalismo \u00e9 exercido hoje, acha que houve alguma quebra do ponto de vista do rigor?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala:<\/strong> Acredito que houve sim. Embora estejamos, ainda hoje, com dificuldades de regular a pr\u00f3pria actividade, hoje por hoje, acredito que o debate seria outro, mas, ainda, estamos nesse processo de regularizar o exerc\u00edcio da actividade c\u00e1. Infelizmente, parece existir vontade de algumas pessoas em atrasar este processo, e est\u00e1 claro!<\/p>\n<p style=\"text-align: justify;\">\u00c9 s\u00f3 olharmos para o n\u00e3o funcionamento dos conselhos de redac\u00e7\u00e3o, que \u00e9 um \u00f3rg\u00e3o dentro das redac\u00e7\u00f5es muito importante, j\u00e1 que t\u00eam uma palavra at\u00e9 na indica\u00e7\u00e3o de directores do \u00f3rg\u00e3o, dos editores, enfim. Est\u00e3o na discuss\u00e3o daquilo que \u00e9 a produ\u00e7\u00e3o do \u00f3rg\u00e3o, do ponto de vista da not\u00edcia que se vai produzir e outros conte\u00fados noticiosos. Ent\u00e3o, tudo isto nos leva a crer que h\u00e1 vontade de algumas pessoas para que este processo continue atrasado, porque, com uma Lei de Imprensa a vigorar intensamente, muitos dos nossos l\u00edderes ter\u00e3o alguma dificuldade.<\/p>\n<p style=\"text-align: justify;\">Realmente perdermos algum rigor, alguma qualidade, e temos de ser honestos e admitirmos isto. Eu leio muitos jornais digitais, e, \u00e0s vezes, fico chocado com determinadas not\u00edcias, porque acho que deveriam ser melhor escritas, deveriam ter cumprido as regras deontol\u00f3gicas, o cruzamento da pr\u00f3pria informa\u00e7\u00e3o, que s\u00e3o regras b\u00e1sicas no Jornalismo.<\/p>\n<p style=\"text-align: justify;\">\u201cO problema do jornalismo em Angola pode estar na forma\u00e7\u00e3o dos jornalistas\u201d<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Onde acha que reside o problema?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Eu acho que o problema est\u00e1, um pouco, se n\u00e3o muito, na forma\u00e7\u00e3o. Porque algu\u00e9m facilita isto, essas mesmas pessoas que criam bloqueios no funcionamento integral da Lei de Imprensa, interessa-lhes que tenhamos uma imprensa com estas insufici\u00eancias, dado que, no final, eles v\u00e3o dizer que h\u00e1 mediocridade no Jornalismo angolano, sentem gozo nisso.<\/p>\n<p style=\"text-align: justify;\">Recentemente tive uma discuss\u00e3o com um l\u00edder sindical que escreveu que os jornalistas dos \u00f3rg\u00e3os p\u00fablicos eram med\u00edocres. Eu disse-lhe que eu tenho forma\u00e7\u00e3o igual a de um m\u00e9dico, igual a de um engenheiro.<\/p>\n<p style=\"text-align: justify;\">Fazem isso para que a sociedade afirme que o jornalista angolano \u00e9 um med\u00edocre.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: A t\u00edtulo de exemplo, o PR angolano, n\u00e3o raras vezes, fala mais \u00e0 imprensa privada acreditada em Angola, do que aos jornais, r\u00e1dios ou TVs nacionais! Ser\u00e1 este um certificado de incompet\u00eancia \u00e0 media angolana?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Mesmo o anterior presidente, e se a mem\u00f3ria n\u00e3o me atrai\u00e7oa, s\u00f3 falou uma vez \u00e0 imprensa nacional, isso no final da d\u00e9cada de 1980. N\u00e3o \u00e9 normal.<\/p>\n<p style=\"text-align: justify;\">Embora fa\u00e7a parte do programa do presidente, Jo\u00e3o Louren\u00e7o, conceder entrevista colectiva no princ\u00edpio de cada ano, achamos que n\u00e3o \u00e9 suficiente. Mas acredito, piamente, que h\u00e1 pessoas, no c\u00edrculo do PR, que lhe dizem que os jornalistas angolanos s\u00e3o med\u00edocres, n\u00e3o duvido! Sabe por que isso acontece? Porque n\u00f3s, os jornalistas, temos culpas nisso! Hoje por hoje, n\u00f3s, jornalistas, passamos a imagem de escorias. Olha, houve um per\u00edodo, nos EUA, de 1950 e 60, em que os jornalistas eram chamados de b\u00eabados, menos inteligentes, enfim. N\u00f3s tivemos essa situa\u00e7\u00e3o c\u00e1, em Angola, nos anos de 1980 e 90, em que \u00e9ramos rotulados de b\u00eabados. Mas h\u00e1 uma gera\u00e7\u00e3o que conseguiu combater esta situa\u00e7\u00e3o. Hoje, j\u00e1 n\u00e3o permitimos que nos atribuem tais nomes, porque n\u00e3o \u00e9 salutar.<\/p>\n<p style=\"text-align: justify;\">Temos culpa, dizia eu, porque temos jornalistas que, ainda, se deixam cair ao descr\u00e9dito, jornalistas que se transformaram em pedintes, e estas pessoas t\u00eam essa no\u00e7\u00e3o, que n\u00e3o valemos nada.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 vi jornalistas a andarem atr\u00e1s de fontes a pedirem dinheiro ou alguma outra coisa em troca. Eu j\u00e1 vi jornalistas a fazerem chantagem, estou a falar em jornalista com largos anos de experi\u00eancia. Isso \u00e9 muito grave, temos de combater!\u00a0 E claro, estas pessoas v\u00e3o aproveitar-se desta situa\u00e7\u00e3o, deste comportamento de alguns colegas nossos para nos chamarem, a todos, de med\u00edocres, porque depois ficamos ref\u00e9ns de quem nos deu alguma esmola. Isso tem de ser combatido. Temos de olhar para a nossa profiss\u00e3o como nobre.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Olhando para o perfil do jornalista angolano, \u00e9 poss\u00edvel concluir que esta \u00e9 uma profiss\u00e3o nobre ou h\u00e1 um jugo desigual?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Essa situa\u00e7\u00e3o que acabei de falar, claro, cria este desn\u00edvel na forma de olhar para o jornalista, temos de ser honestos. Mas a profiss\u00e3o \u00e9 nobre, ali\u00e1s, eu tenho dito que o Jornalismo \u00e9 uma grande profiss\u00e3o, porque, para al\u00e9m de ci\u00eancia, arte de informar, \u00e9 das melhores profiss\u00f5es do mundo.<\/p>\n<p style=\"text-align: justify;\">Quando produzimos not\u00edcias, quando levamos os factos ao conhecimento do p\u00fablico, informamos com verdade, isen\u00e7\u00e3o e imparcialidade, nos sentimos satisfeitos, sentimos, dentro de n\u00f3s, o dever de ter cumprido uma miss\u00e3o nobre e isso nos d\u00e1 uma satisfa\u00e7\u00e3o muito grande. Ademais, a forma como n\u00f3s, jornalistas, interagimos uns com os outros, a forma como o meu texto, o meu trabalho deve ser visto entre os colegas, isso n\u00e3o acontece em muitas profiss\u00f5es. O que n\u00f3s fazemos ou produzimos \u00e9, antes de mais nada, colocado ao crivo dos colegas de redac\u00e7\u00e3o e, ao primeiro minuto, os poss\u00edveis erros s\u00e3o vistos e corrigidos, antes mesmo de a mat\u00e9ria ser publicada. Isto n\u00e3o acontece em qualquer profiss\u00e3o, n\u00f3s temos este privil\u00e9gio. Mas n\u00e3o \u00e9 uma nobreza do ponto de vista material, porque, hoje por hoje, as pessoas est\u00e3o muito materialistas, \u00e9 do ponto de vista funcional.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Com a dissolu\u00e7\u00e3o de grande parte dos jornais que existiam outrora, por exemplo, a classe tamb\u00e9m perdeu muitos bons filhos para outras profiss\u00f5es. Acha que o Jornalismo angolano ressentiu-se destas perdas?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Evidentemente. Ali\u00e1s, esta \u00e9 uma das nobrezas do Jornalismo, ele d\u00e1 quadros para quase todas as \u00e1reas de todos os sectores. D\u00e1 bons pol\u00edticos, bons economistas, bons m\u00e9dicos, bons advogados, enfim. Eu tenho d\u00favidas que um indiv\u00edduo que tenha passado pelo Jornalismo, n\u00e3o seja um bom t\u00e9cnico na \u00e1rea em que ele est\u00e1, actualmente, enquadrado, porque o Jornalismo te d\u00e1 esta carga, do ponto de vista do conhecimento. S\u00f3 a t\u00edtulo de exemplo, o primeiro ministro ingl\u00eas, Boris Johnson, foi jornalista; o antigo vice-primeiro ministro portugu\u00eas, Paulo Portas, foi jornalista. \u00c9 normal que o Jornalismo d\u00ea para as outras \u00e1reas bons profissionais.<\/p>\n<p style=\"text-align: justify;\">Agora, tamb\u00e9m \u00e9 preciso colhermos que muitos abandonaram o exerc\u00edcio da actividade jornal\u00edstica e optaram por outras actividades mais e melhores rent\u00e1veis e, nos \u00faltimos tempos, temos vindo a assistir colegas que manifestam essa vontade de abra\u00e7ar outra actividade. Se conversarmos com, pelo menos, cinco jornalistas, tr\u00eas ou dois h\u00e3o de manifestar essa vontade de abandonar o Jornalismo.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime: Para al\u00e9m de todo o brio e nobreza associada a ele, o Jornalismo d\u00e1 alguma garantia de bem-estar social, pelo menos em Angola?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Rodrigues Cambala: <\/strong>Alguns abandonam o Jornalismo por causa do desencanto, pois tinham outra vis\u00e3o, quando sa\u00edram das universidades, isso \u00e9 comum. Ali\u00e1s, as pessoas, quando est\u00e3o na academia, t\u00eam uma outra vis\u00e3o da coisa, entendem que tudo que elas pensam e escrevem tem de ser publicado.<\/p>\n<p style=\"text-align: justify;\">Essa \u00e9 uma vis\u00e3o errada que se tem, porque todos os \u00f3rg\u00e3os de Comunica\u00e7\u00e3o Social do mundo t\u00eam linha editorial. Ali\u00e1s, se pegares o The New York Times, de Nova Iorque, o P\u00fablico, de Portugal ou o jornal O Pa\u00eds e O Crime, de Angola, ver\u00e1s que t\u00eam a mesma linha editorial. Por que que digo que s\u00e3o iguais? Porque t\u00eam os tr\u00eas ou quatro elementos semelhantes que s\u00e3o: o rigor, imparcialidade, isen\u00e7\u00e3o, respeito \u00e0s normas de \u00e9tica e deontologia profissional, tudo. Nenhum tem o contr\u00e1rio destas leis.<\/p>\n<p style=\"text-align: justify;\">E se nos perguntarem se, na Coreia do Norte, existe o direito \u00e0 informa\u00e7\u00e3o, sim, existe. N\u00e3o acredito que exista uma Constitui\u00e7\u00e3o no mundo em que n\u00e3o exista este direito. Portanto, s\u00e3o estas linhas que norteiam a actividade jornal\u00edstica, e o aspirante a jornalista come\u00e7a a trabalhar com todas estas linhas orientadoras na cabe\u00e7a: rigor, imparcialidade, isen\u00e7\u00e3o. Ora, vejamos onde est\u00e1 o problema: os jornais, a r\u00e1dio e as televis\u00f5es pertencem a grupos econ\u00f3micos, os \u00f3rg\u00e3os de comunica\u00e7\u00e3o n\u00e3o pertencem aos jornalistas, pertencem a estes grupos econ\u00f3micos que, como qualquer grupo, t\u00eam interesses em v\u00e1rios outros investimentos. Portanto, basta notarem que h\u00e1 uma informa\u00e7\u00e3o contra o outro sector que eles investem, a mat\u00e9ria n\u00e3o sai. Por isso, muitas vezes tem havido esse choque entre o patr\u00e3o e o jornalista.<\/p>\n<p style=\"text-align: justify;\">Ali\u00e1s, eu tenho estado a dizer que \u00e9 imprescind\u00edvel, do ponto de vista da Filosofia da Comunica\u00e7\u00e3o, que se estude bem a quest\u00e3o da imparcialidade. Dentro da Sociologia da Comunica\u00e7\u00e3o, eu olho para estes elementos como subjectivos. H\u00e1 uma subjectividade muito grande na imparcialidade e na isen\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rodrigues Cambala \u00e9 jornalista h\u00e1 21 anos, tendo ao longo da sua carreira, passado pelos extintos jornais \u2018Actual\u2019, onde deu os primeiros passos, e o \u2018O Independente\u2019, bem como colaborou em v\u00e1rios outros e revistas no pa\u00eds. \u00c9 licenciado em Comunica\u00e7\u00e3o Social pela Faculdade de Ci\u00eancias Sociais da Universidade Agostinho Neto e especialista em Comunica\u00e7\u00e3o Corporativa, frequentando o curso de p\u00f3s-gradua\u00e7\u00e3o em Direc\u00e7\u00e3o Estrat\u00e9gica e Marketing. Com forma\u00e7\u00e3o em \u2018Reportagem e Escrita de Texto n\u00e3o Fic\u00e7\u00e3o\u2019, realizado no Cenjor-Lisboa, \u00e9 tamb\u00e9m formador em mat\u00e9ria de Comunica\u00e7\u00e3o Corporativa e Jornalismo e prev\u00ea, para breve, o lan\u00e7amento do seu livro, \u2018Reportagem\u2019. \u00c9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[],"class_list":["post-2606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Rodrigues Cambala \u00e9 jornalista h\u00e1 21 anos, tendo ao longo da sua carreira, passado pelos extintos jornais \u2018Actual\u2019, onde deu os primeiros passos, e o \u2018O Independente\u2019, bem como colaborou em v\u00e1rios outros e revistas no pa\u00eds. \u00c9 licenciado em Comunica\u00e7\u00e3o Social pela Faculdade de Ci\u00eancias Sociais da Universidade Agostinho Neto e especialista em Comunica\u00e7\u00e3o Corporativa, frequentando o curso de p\u00f3s-gradua\u00e7\u00e3o em Direc\u00e7\u00e3o Estrat\u00e9gica e Marketing. Com forma\u00e7\u00e3o em \u2018Reportagem e Escrita de Texto n\u00e3o Fic\u00e7\u00e3o\u2019, realizado no Cenjor-Lisboa, \u00e9 tamb\u00e9m formador em mat\u00e9ria de Comunica\u00e7\u00e3o Corporativa e Jornalismo e prev\u00ea, para breve, o lan\u00e7amento do seu livro, \u2018Reportagem\u2019. \u00c9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-14T14:07:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-16T11:09:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Cambala.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"939\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dumilde Fuxi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dumilde Fuxi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/\"},\"author\":{\"name\":\"Dumilde Fuxi\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"headline\":\"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d\",\"datePublished\":\"2020-11-14T14:07:42+00:00\",\"dateModified\":\"2020-11-16T11:09:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/\"},\"wordCount\":3074,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Cambala.jpg\",\"articleSection\":[\"ENTREVISTA\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/\",\"name\":\"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Cambala.jpg\",\"datePublished\":\"2020-11-14T14:07:42+00:00\",\"dateModified\":\"2020-11-16T11:09:19+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Cambala.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Cambala.jpg\",\"width\":1024,\"height\":939},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/e2c6b14b5efec23ece95210339ab8c1f\",\"name\":\"Dumilde Fuxi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g\",\"caption\":\"Dumilde Fuxi\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/dumilde-fuxi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/","og_locale":"pt_PT","og_type":"article","og_title":"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d - Jornal O Crime","og_description":"Rodrigues Cambala \u00e9 jornalista h\u00e1 21 anos, tendo ao longo da sua carreira, passado pelos extintos jornais \u2018Actual\u2019, onde deu os primeiros passos, e o \u2018O Independente\u2019, bem como colaborou em v\u00e1rios outros e revistas no pa\u00eds. \u00c9 licenciado em Comunica\u00e7\u00e3o Social pela Faculdade de Ci\u00eancias Sociais da Universidade Agostinho Neto e especialista em Comunica\u00e7\u00e3o Corporativa, frequentando o curso de p\u00f3s-gradua\u00e7\u00e3o em Direc\u00e7\u00e3o Estrat\u00e9gica e Marketing. Com forma\u00e7\u00e3o em \u2018Reportagem e Escrita de Texto n\u00e3o Fic\u00e7\u00e3o\u2019, realizado no Cenjor-Lisboa, \u00e9 tamb\u00e9m formador em mat\u00e9ria de Comunica\u00e7\u00e3o Corporativa e Jornalismo e prev\u00ea, para breve, o lan\u00e7amento do seu livro, \u2018Reportagem\u2019. \u00c9 [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/","og_site_name":"Jornal O Crime","article_published_time":"2020-11-14T14:07:42+00:00","article_modified_time":"2020-11-16T11:09:19+00:00","og_image":[{"width":1024,"height":939,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Cambala.jpg","type":"image\/jpeg"}],"author":"Dumilde Fuxi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dumilde Fuxi","Est. reading time":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/"},"author":{"name":"Dumilde Fuxi","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"headline":"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d","datePublished":"2020-11-14T14:07:42+00:00","dateModified":"2020-11-16T11:09:19+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/"},"wordCount":3074,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Cambala.jpg","articleSection":["ENTREVISTA"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/","url":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/","name":"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Cambala.jpg","datePublished":"2020-11-14T14:07:42+00:00","dateModified":"2020-11-16T11:09:19+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Cambala.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/Cambala.jpg","width":1024,"height":939},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/ainda-temos-jornalistas-pedintes-que-passam-a-imagem-de-mediocridade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"\u201cAINDA TEMOS JORNALISTAS PEDINTES QUE PASSAM A IMAGEM DE MEDIOCRIDADE\u201d"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/e2c6b14b5efec23ece95210339ab8c1f","name":"Dumilde Fuxi","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6baf16415046accb506abd812d50a00b9a118fbc2f2efb6ca302fcbb86af9e60?s=96&d=mm&r=g","caption":"Dumilde Fuxi"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/dumilde-fuxi\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2606"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2615"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}