{"id":2655,"date":"2020-12-02T15:41:39","date_gmt":"2020-12-02T14:41:39","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2655"},"modified":"2024-07-17T16:07:32","modified_gmt":"2024-07-17T15:07:32","slug":"assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/","title":{"rendered":"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS"},"content":{"rendered":"<p><strong>Numa entrevista exclusiva ao jornal O Crime, o juiz de Direito e assessor para Comunica\u00e7\u00e3o Institucional e Imprensa do Conselho Superior da Magistratura Judicial e do Tribunal Supremo, Pedro Chilicuessue, revelou in\u00fameras vicissitudes vividas pelos administradores da justi\u00e7a por excel\u00eancia, os ju\u00edzes, de deixar boquiabertos, com destaque ao facto de alguns, sobretudo os que labutam nas demais prov\u00edncias do pa\u00eds, terem de se locomover em cami\u00f5es e triciclos, vulgos \u201cKupapatas\u201d, para cumprirem a miss\u00e3o.<\/strong><\/p>\n<p><strong>Por: Felicidade Kauanda<\/strong><\/p>\n<p><strong>O Crime \u2014Tom\u00e1mos conhecimento que muitos ju\u00edzes e oficiais de dilig\u00eancias usam de meios pr\u00f3prios para a realiza\u00e7\u00e3o da tarefa. O que nos pode dizer? <\/strong><\/p>\n<p><strong>Pedro Chilicuessue\u00a0 <\/strong>\u2014 Primeiro, queremos agradecer, em nome do Conselho da Magistratura Judicial e do Tribunal Supremo, os quais representamos nesta assessoria de comunica\u00e7\u00e3o institucional e imprensa, por esta oportunidade, por ser a nossa primeira interac\u00e7\u00e3o com um \u00f3rg\u00e3o de comunica\u00e7\u00e3o social.<\/p>\n<p>Sim, \u00e9 uma realidade que os oficias de justi\u00e7a e os pr\u00f3prios magistrados usam meios pr\u00f3prios para trabalhar. \u00c9 resultado de toda uma conjuntura que o pa\u00eds vive, julgo ser, tamb\u00e9m, do conhecimento da senhora jornalista. Mas devo dizer que do diagn\u00f3stico feito da situa\u00e7\u00e3o dos tribunais, depois que entrou em fun\u00e7\u00f5es o actual presidente do Conselho Superior da Magistratura Judicial, Dr. Joel Leonardo, elucidou-nos que o quadro, de facto, n\u00e3o \u00e9 bom, pois os tribunais, enquanto infra-estruturas, o quadro dos recursos humanos, as condi\u00e7\u00f5es materiais e o equipamento t\u00e9cnico ou inform\u00e1tico \u00e0 disposi\u00e7\u00e3o dos tribunais n\u00e3o est\u00e3o conforme os desafios que hoje os tribunais t\u00eam, pelo que urge a altera\u00e7\u00e3o deste quadro.<\/p>\n<p>Da\u00ed que se elaborou um plano estrat\u00e9gico de desenvolvimento dos tribunais de jurisdi\u00e7\u00e3o comum, isto \u00e9, os que t\u00eam, no topo, o Tribunal Supremo, na posi\u00e7\u00e3o interm\u00e9dia, os Tribunais da Rela\u00e7\u00e3o e, na base, os Tribunais de Comarca.<\/p>\n<p><strong>O Crime \u2014 Corresponde \u00e0 verdade a informa\u00e7\u00e3o, segundo a qual alguns magistrados andam de cami\u00f5es e \u201ckupapatas\u201d, com maior incid\u00eancia no interior do pa\u00eds, para trabalhar?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> Todos n\u00f3s sabemos que \u00e9 uma realidade de v\u00e1rios ju\u00edzes de primeira inst\u00e2ncia hoje. Gostaria de desafiar a senhora jornalista a fazer um bom trabalho no interior do pa\u00eds, para ver a realidade dos ju\u00edzes. Entretanto, posso dizer- lhe que n\u00e3o precisa ir ao interior, mesmo em Luanda h\u00e1 isso, s\u00f3 que em Luanda tudo se confunde\u2026 mas h\u00e1 muitos problemas sociais que os magistrados enfrentam.<\/p>\n<p><strong>O Crime \u2014 As dificuldades que os ju\u00edzes de primeira inst\u00e2ncia passam s\u00e3o as mesmas que as dos ju\u00edzes conselheiros do Tribunal Supremo? <\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> Vamos buscar o exemplo do corpo humano\u2026 o corpo humano sem os p\u00e9s fica de p\u00e9? Sem a cabe\u00e7a, v\u00ea ou pensa? Pois \u00e9, um complemento, ent\u00e3o, os tribunais da Comarca s\u00e3o os p\u00e9s, a estrutura, a base ou o alicerce do sistema judici\u00e1rio. Qual \u00e9 o lado da casa que deve estar muito bem apetrechada para n\u00e3o desabar? \u00c9 o alicerce! Aqui a nossa base s\u00e3o os tribunais de Comarca. Se os Tribunais de Comarca estiverem mal, n\u00e3o h\u00e1 Tribunal da Rela\u00e7\u00e3o nenhum que vai brilhar, muito menos o Supremo.<\/p>\n<p>Portanto, deve-se olhar para os Tribunais de Comarca, para os magistrados que est\u00e3o adstritos a estes tribunais, os chamados ju\u00edzes de primeira inst\u00e2ncia, que s\u00e3o aqueles que, na linguagem militar, podemos chamar de \u201cchoques\u201d, assim como os demais funcion\u00e1rios, porque um juiz, sozinho, n\u00e3o faz nada, precisa de um bom oficial de justi\u00e7a, motivado, porque, o facto de ele ser oficial de dilig\u00eancias, n\u00e3o o afasta de ser pai, marido, namorado e de ser filho. Ele, na sua dignidade, tem que estar confort\u00e1vel, para atender as suas necessidades, enquanto pessoa humana, enquanto chefe de fam\u00edlia ou candidato a outros patamares sociais, o que, tamb\u00e9m, vai permitir a reten\u00e7\u00e3o dos quadros.<\/p>\n<p>Se a tend\u00eancia for reconfortar sempre o topo, isso estimula a corrida para aquela posi\u00e7\u00e3o, pois \u00e9 ali onde as pessoas v\u00e3o buscar a resolu\u00e7\u00e3o dos seus problemas sociais. S\u00e3o v\u00e1rios problemas na base que, provavelmente, as pessoas n\u00e3o est\u00e3o interessadas a dar resposta em tempo \u00fatil, e isso faz com que ningu\u00e9m mais queira ficar na base e, quando isso acontece, o resultado que esperamos \u00e9 colapsar o sistema.<\/p>\n<p><strong>O Crime \u2014 Quais s\u00e3o as regalias dos ju\u00edzes do Tribunal Supremo?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> N\u00e3o me posso pronunciar sobre isso, dado que n\u00e3o as conhe\u00e7o e n\u00e3o gostava de me meter em seara alheia. O que posso dizer \u00e9 que, grosso modo, isso consta do plano estrat\u00e9gico do venerando juiz conselheiro presidente, pois, provou que a situa\u00e7\u00e3o social dos magistrados, no pa\u00eds, n\u00e3o est\u00e1 boa. Por isso \u00e9 que, volta e meia, ouve-se v\u00e1rios coment\u00e1rios por ali, que os ju\u00edzes fizeram e deixaram de fazer, que os procuradores fizeram deixaram de fazer.<\/p>\n<p>Portanto, o social desta classe n\u00e3o est\u00e1 boa e inspira algum cuidado e \u00e9 este o trabalho que se est\u00e1 a fazer, para que se inverta o quadro, tanto no dom\u00ednio das infra-estruturas, j\u00e1 que grande parte delas anda degradada, dos recursos humanos, que escasseiam cada vez mais, do equipamento t\u00e9cnico e inform\u00e1tico, que \u00e9 necess\u00e1rio para moderniza\u00e7\u00e3o que temos em m\u00e3os que, a cada dia, nos desafia e quanto \u00e0quilo que tem a ver com a pessoa, a remunera\u00e7\u00e3o, para al\u00e9m das outras condi\u00e7\u00f5es sociais ali congregadas, porque queremos ultrapassar outras conversas que ouvimos por ali&#8230;<\/p>\n<p><strong>O Crime \u2014 Os coment\u00e1rios de que os magistrados est\u00e3o a fazer negociatas correspondem \u00e0 verdade?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> \u00c9 uma conversa quase comum, que ningu\u00e9m assume, mas, provavelmente, acontece, se partirmos do pensamento filos\u00f3fico que \u201cdo nada, nada vem\u201d. Ent\u00e3o, h\u00e1 esta preocupa\u00e7\u00e3o, por parte do Conselho Superior da Magistratura, para que, junto de quem tem a responsabilidade de prover os recursos necess\u00e1rios para os tribunais, possam desempenhar bem a sua tarefa, sintam-se tocados, sensibilizados, atendam e deem aquilo que \u00e9 de direito para a classe judici\u00e1ria, que precisa e clama por um novo alento.<\/p>\n<p><strong>O Crime \u2014 Ajude-nos a entender o que a lei diz sobre a independ\u00eancia financeira dos tribunais.<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> \u00c9 uma mat\u00e9ria de dignidade constitucional, a autonomia administrativa financeira e patrimonial, resulta do disposto no artigo 178.\u00ba da Constitui\u00e7\u00e3o da Rep\u00fablica de Angola, \u201cos tribunais gozam de autonomia administrativa e financeira, devendo a lei definir os mecanismos de comparticipa\u00e7\u00e3o do poder judicial, no processo de elabora\u00e7\u00e3o do seu or\u00e7amento\u201d. Por\u00e9m, na pr\u00e1tica, dependem, grandemente, do Executivo, designadamente do Minist\u00e9rio das Finan\u00e7as.<\/p>\n<p><strong>O Crime \u2014 Que apelo deixa, aos de direito, para acautelar o quadro prec\u00e1rio que acabamos de reportar? <\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> O nosso primeiro apelo \u00e9 encorajar a nossa super estrutura da gest\u00e3o e disciplina dos magistrados, estamos a falar da Direc\u00e7\u00e3o dos Vogais do Conselho Superior da Magistratura Judicial, no sentido de que todos n\u00f3s devemos ajud\u00e1-los a concretizar aquilo que est\u00e1 contemplado no Plano Estrat\u00e9gico de Desenvolvimento dos Tribunais de Jurisdi\u00e7\u00e3o Comum, que \u00e9 um plano abrangente, que olha para as infra-estruturas, para os homens, para os utentes dos servi\u00e7os dos tribunais.<\/p>\n<p>Segundo, que a classe pol\u00edtica d\u00ea o seu apoio no limite das suas atribui\u00e7\u00f5es, para que, na verdade, aquilo que \u00e9 ac\u00e7\u00e3o pol\u00edtica n\u00e3o caia em banca rota, porque n\u00e3o haver\u00e1 pragm\u00e1tica entre o que se fala e o que se faz, ou o que se vive na pr\u00e1tica. Ent\u00e3o, hoje o exerc\u00edcio da actividade pol\u00edtica j\u00e1 recomenda a \u00e9tica, e a \u00e9tica nos interpela para que todos fa\u00e7amos bem aquilo que temos em m\u00e3os como responsabilidade\u2026 pois \u00e9 assim que deve funcionar aquele tribunal que falta t\u00e9cnicos de justi\u00e7a e infra-estruturas para albergar os servi\u00e7os, que falta magistrados comprometidos e animados para a miss\u00e3o\u2026 aqueles que t\u00eam a responsabilidade pol\u00edtica devem fazer bem o seu trabalho, para que esse quadro altere o quanto antes.<\/p>\n<p>\u00c9 este o desejo de todos n\u00f3s que estamos nisso imbu\u00eddos, para que possamos dar o nosso contributo da melhor maneira poss\u00edvel, sem focar no que se vai comer, quando chegar \u00e0 casa ou na renda que est\u00e1 no fim\u2026<\/p>\n<p>Ju\u00edzes devem, apenas, pautar-se pela legalidade, ao impedir cobertura jornal\u00edstica<\/p>\n<p><strong>O Crime \u2014 Pode apresentar-nos o Gabinete de Comunica\u00e7\u00e3o Institucional e Imprensa, que nos parece novo?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> Estamos \u00e0 frente deste gabinete desde 4 de Agosto de 2020. O gabinete, como tal, sempre existiu, provavelmente o que h\u00e1 de novo \u00e9 a din\u00e2mica que queremos conferir na rela\u00e7\u00e3o com os \u00f3rg\u00e3os de comunica\u00e7\u00e3o social. Hoje, o mundo \u00e9 veloz e o Conselho Superior da Magistratura Judicial e o Tribunal Supremo, atentos, exactamente, a este pormenor, de que \u00e9 preciso nos comunicarmos mais, para evitar especula\u00e7\u00f5es, est\u00e3o a potenciar este lado. Ainda n\u00e3o estamos satisfeitos, mas j\u00e1 come\u00e7amos.<\/p>\n<p>Este exerc\u00edcio concorre para que os mal-intencionados tenham cada vez menos espa\u00e7o para mentir os jornalistas, porque o jornalista deve saber onde buscar uma informa\u00e7\u00e3o cred\u00edvel, para melhor cumprir o seu dever, da\u00ed que se pretende harmonizar os dois mundos. N\u00f3s n\u00e3o olhamos para a exist\u00eancia de jornalistas privados ou p\u00fablicos, todos eles s\u00e3o, para n\u00f3s, filhos da mesma idade e devem ter os mesmos direitos e deveres. Estamos abertos para continuarmos a interagir e, de novo, agradecer por esta primeira entrevista com o jornal O Crime, ao qual encorajamos e incentivamos, para que siga na linha da especializa\u00e7\u00e3o de um jornal, iminentemente, jur\u00eddico, a julgar pelo seu tema e as mat\u00e9rias que, tendencialmente, traz para o seu p\u00fablico leitor.<\/p>\n<p><strong>O Crime \u2014 O que a lei quer dizer, ao referir que o julgamento \u00e9 publico?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014 <\/strong>\u00c9 a lei que imp\u00f5e, a come\u00e7ar pela disposi\u00e7\u00e3o contida no artigo 174.\u00ba da Constitui\u00e7\u00e3o, que diz que os tribunais s\u00e3o \u00f3rg\u00e3os de soberania, com compet\u00eancia de administrar a justi\u00e7a em nome do povo. Portanto, \u00e9 justamente por administrar a justi\u00e7a em nome do povo, da salvaguarda do interesse p\u00fablico ou privado, que ela deve estar aberta a este mesmo povo, p\u00fablico, n\u00e3o estando restringida a participa\u00e7\u00e3o nas audi\u00eancias de julgamento.<\/p>\n<p>Obviamente, cada julgamento \u00e9 um julgamento, pelo que, o juiz que preside a audi\u00eancia deve anunciar aos participantes, n\u00e3o s\u00f3 \u00e0s partes processuais, as medidas que devem ser observadas durante o julgamento, no sentido de manter a ordem, a disciplina que essa solenidade imp\u00f5e.<\/p>\n<p>Portanto, a audi\u00eancia \u00e9 uma sess\u00e3o p\u00fablica por conta disso, porque nela participa n\u00e3o s\u00f3 as partes directamente ligadas ao processo em julgamento, como tamb\u00e9m o p\u00fablico interessado, se calhar, em aprender, pois \u00e9, tamb\u00e9m, um momento pedag\u00f3gico para os futuros operadores da justi\u00e7a e do Direito, futuros ju\u00edzes, escriv\u00e3es e procuradores.<\/p>\n<p><strong>O Crime \u2014 Quais s\u00e3o os limites da publicidade do julgamento?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> A norma contida no artigo 407.\u00ba do C\u00f3digo do Processo Penal diz que a audi\u00eancia de julgamento \u00e9 p\u00fablica, salvo se o tribunal entender que a publicidade pode ofender a moral, o interesse ou a ordem p\u00fablica. S\u00f3 nestes casos \u00e9 que a audi\u00eancia deve ser declarada secreta. Mas, ainda assim, essa declara\u00e7\u00e3o deve ser feita previamente, ou seja, antes do in\u00edcio do julgamento propriamente dito, o juiz que tem a seu cargo a direc\u00e7\u00e3o da audi\u00eancia deve anunciar que determinadas pessoas presentes devem abandonar a sala, porque a mat\u00e9ria a ser abordada n\u00e3o deve ser tornada p\u00fablica, para deixar que, da audi\u00eancia de julgamento, participe apenas as pessoas directamente ligadas.<\/p>\n<p><strong>O Crime \u2014 Pode um juiz, enquanto presidente da sess\u00e3o de julgamento, proibir, deliberadamente, que se fa\u00e7a anota\u00e7\u00f5es e fotografias, para efeito de cobertura jornal\u00edstica?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> \u00c9 uma pergunta que eu gostava de responder com sim e n\u00e3o. Sim, porque \u00e9 ao juiz que incumbe a presid\u00eancia da audi\u00eancia de julgamento, nos termos do artigo 409.\u00ba do CPP. N\u00e3o, porque ele est\u00e1 ali para dirigir, marcando todos os seus actos, com base no princ\u00edpio da legalidade e n\u00e3o com base na arbitrariedade. Portanto, se o juiz entende, nos termos que a lei prev\u00ea, que a presen\u00e7a de determinadas pessoas, que determinados movimentos, durante a audi\u00eancia, v\u00e3o perturbar a ordem ou o interesse que se pretende alcan\u00e7ar, pondo em crise a moral p\u00fablica, ent\u00e3o deve advertir as pessoas ou os profissionais da informa\u00e7\u00e3o, designadamente aos jornalistas, que devem abandonar a sala, porque n\u00e3o \u00e9 conveniente que aquela audi\u00eancia seja por eles reportada ou tornada p\u00fablica, mas n\u00e3o com base na arbitrariedade, e sim com cortesia, porque \u00e9 isso que a lei recomenda, ali\u00e1s, presume-se que um juiz \u00e9 uma pessoa moralmente equilibrada, portanto, n\u00e3o pode guiar-se por arbitrariedade.<\/p>\n<p><strong>O Crime \u2014 Tendo o jornal O Crime uma autoriza\u00e7\u00e3o do Tribunal Provincial de Luanda, para cobertura jornal\u00edstica de julgamentos que ocorrem nesta circunscri\u00e7\u00e3o, como se explica as atitudes de alguns ju\u00edzes em negarem que se fa\u00e7a?<\/strong><\/p>\n<p><strong>Pedro Chilicuessue \u2014<\/strong> Sendo atitudes isoladas, posso dizer que \u00e9 a primeira vez que ou\u00e7o da voz de uma jornalista, mas devo dizer que, n\u00e3o obstante existir, no plano administrativo, a figura de juiz presidente do tribunal que, nestes termos, cuida do expediente de natureza administrativa, o presidente dos autos \u00e9 o juiz concreto para aquele processo e, provavelmente, um juiz presidente n\u00e3o tem o dom\u00ednio sobre aquele processo, s\u00f3 nestes casos \u00e9 que se passa esse laivo de encontro, entre o pensamento do juiz presidente de uma determinada prov\u00edncia e o juiz presidente daquele julgamento.<\/p>\n<p>Como disse, s\u00e3o casos isolados, n\u00e3o \u00e9 isso que a lei recomenda, mas o Conselho Superior da Magistratura, que \u00e9 o \u00f3rg\u00e3o de gest\u00e3o e disciplina dos magistrados, est\u00e1 atento a tudo isto e, certamente, nos encontros que vai organizando, vai acautelar, para que essas situa\u00e7\u00f5es pouco abonat\u00f3rias, que n\u00e3o agregam valor \u00e0 actividade judicat\u00f3ria, n\u00e3o fa\u00e7am morada nos actos praticados por determinados ju\u00edzes no exerc\u00edcio das suas fun\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa entrevista exclusiva ao jornal O Crime, o juiz de Direito e assessor para Comunica\u00e7\u00e3o Institucional e Imprensa do Conselho Superior da Magistratura Judicial e do Tribunal Supremo, Pedro Chilicuessue, revelou in\u00fameras vicissitudes vividas pelos administradores da justi\u00e7a por excel\u00eancia, os ju\u00edzes, de deixar boquiabertos, com destaque ao facto de alguns, sobretudo os que labutam nas demais prov\u00edncias do pa\u00eds, terem de se locomover em cami\u00f5es e triciclos, vulgos \u201cKupapatas\u201d, para cumprirem a miss\u00e3o. Por: Felicidade Kauanda O Crime \u2014Tom\u00e1mos conhecimento que muitos ju\u00edzes e oficiais de dilig\u00eancias usam de meios pr\u00f3prios para a realiza\u00e7\u00e3o da tarefa. O que nos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Numa entrevista exclusiva ao jornal O Crime, o juiz de Direito e assessor para Comunica\u00e7\u00e3o Institucional e Imprensa do Conselho Superior da Magistratura Judicial e do Tribunal Supremo, Pedro Chilicuessue, revelou in\u00fameras vicissitudes vividas pelos administradores da justi\u00e7a por excel\u00eancia, os ju\u00edzes, de deixar boquiabertos, com destaque ao facto de alguns, sobretudo os que labutam nas demais prov\u00edncias do pa\u00eds, terem de se locomover em cami\u00f5es e triciclos, vulgos \u201cKupapatas\u201d, para cumprirem a miss\u00e3o. Por: Felicidade Kauanda O Crime \u2014Tom\u00e1mos conhecimento que muitos ju\u00edzes e oficiais de dilig\u00eancias usam de meios pr\u00f3prios para a realiza\u00e7\u00e3o da tarefa. O que nos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T14:41:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T15:07:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0376.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2304\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS\",\"datePublished\":\"2020-12-02T14:41:39+00:00\",\"dateModified\":\"2024-07-17T15:07:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/\"},\"wordCount\":2455,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0376.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/\",\"name\":\"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0376.jpg\",\"datePublished\":\"2020-12-02T14:41:39+00:00\",\"dateModified\":\"2024-07-17T15:07:32+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0376.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0376.jpg\",\"width\":2304,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/","og_locale":"pt_PT","og_type":"article","og_title":"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS - Jornal O Crime","og_description":"Numa entrevista exclusiva ao jornal O Crime, o juiz de Direito e assessor para Comunica\u00e7\u00e3o Institucional e Imprensa do Conselho Superior da Magistratura Judicial e do Tribunal Supremo, Pedro Chilicuessue, revelou in\u00fameras vicissitudes vividas pelos administradores da justi\u00e7a por excel\u00eancia, os ju\u00edzes, de deixar boquiabertos, com destaque ao facto de alguns, sobretudo os que labutam nas demais prov\u00edncias do pa\u00eds, terem de se locomover em cami\u00f5es e triciclos, vulgos \u201cKupapatas\u201d, para cumprirem a miss\u00e3o. Por: Felicidade Kauanda O Crime \u2014Tom\u00e1mos conhecimento que muitos ju\u00edzes e oficiais de dilig\u00eancias usam de meios pr\u00f3prios para a realiza\u00e7\u00e3o da tarefa. O que nos [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/","og_site_name":"Jornal O Crime","article_published_time":"2020-12-02T14:41:39+00:00","article_modified_time":"2024-07-17T15:07:32+00:00","og_image":[{"width":2304,"height":1536,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0376.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS","datePublished":"2020-12-02T14:41:39+00:00","dateModified":"2024-07-17T15:07:32+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/"},"wordCount":2455,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0376.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/","url":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/","name":"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0376.jpg","datePublished":"2020-12-02T14:41:39+00:00","dateModified":"2024-07-17T15:07:32+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0376.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0376.jpg","width":2304,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/assim-vai-a-nossa-justica-magistrados-andam-de-kupapatas-para-concluirem-processos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Assim vai a nossa justi\u00e7a:\u00a0MAGISTRADOS ANDAM DE \u2018KUPAPATAS\u2019\u00a0PARA CONCLU\u00cdREM PROCESSOS"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2655"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2698"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}