{"id":2660,"date":"2020-12-02T16:00:42","date_gmt":"2020-12-02T15:00:42","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2660"},"modified":"2024-07-17T16:07:32","modified_gmt":"2024-07-17T15:07:32","slug":"jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/","title":{"rendered":"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Tr\u00eas dias foi quanto durou o noivado de Herculano Costa, 24 anos, que perdeu a vida na sequ\u00eancia de uma briga, com um amigo de inf\u00e2ncia, por n\u00e3o o ter convidado para a sua festa. O caso aconteceu na passada quinta-feira, 22 de Outubro, no Zango 3, bairro Capapinha.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Costa Kilunda <\/strong><\/p>\n<p style=\"text-align: justify;\">O infausto acontecimento ocorreu tr\u00eas dias depois de Herculano Fidel Jo\u00e3o da Costa, ter formalizado a sua rela\u00e7\u00e3o com a, agora, noiva, com quem pretendia viver longos e felizes anos. O sonho foi interrompido por um amigo, que, motivado pela f\u00faria de n\u00e3o ter sido convidado, partiu para a briga, at\u00e9 deixar o rec\u00e9m noivo sem vida.<\/p>\n<p style=\"text-align: justify;\">O acusado, apenas identificado por Nunzi, teria cruzado com a v\u00edtima numa esquina, algures do bairro, tendo-o abordado sobre as raz\u00f5es que o levaram a n\u00e3o convid\u00e1-lo. Em resposta, contam testemunhas, Herculano ter\u00e1 dito que \u201ctudo aconteceu muito r\u00e1pido, por isso n\u00e3o foi poss\u00edvel convidar todo mundo\u201d. Entretanto, a resposta n\u00e3o colheu, tendo o acusado iniciado uma sequ\u00eancia de ofensas contra o amigo, que, respondendo no mesmo tom, ter\u00e1 dado raz\u00f5es mais do que suficientes para que o seu algoz partisse para a viol\u00eancia.<\/p>\n<p style=\"text-align: justify;\">Segundo a m\u00e3e do malogrado, Maria Jo\u00e3o, a briga ocorreu junto da casa do acusado, sendo que a m\u00e3e desse, sua comadre, ter\u00e1 sa\u00eddo em defesa do filho e os dois agrediram o malogrado. \u201cN\u00e3o sei como, mesmo sendo minha comadre, interveio contra o meu filho, e ambos bateram nele no rosto\u201d, disse, acrescentando que tanto a comadre quanto o filho daquela s\u00e3o pessoas pr\u00f3ximas a si, por isso n\u00e3o entende as raz\u00f5es de tal acto.<\/p>\n<p style=\"text-align: justify;\">Segundo a mesma, os golpes que o filho levou, lhe ter\u00e3o causado uma contus\u00e3o cerebral traum\u00e1tica, o que, alegadamente, provocou a morte ao jovem noivo.<\/p>\n<p style=\"text-align: justify;\">Maria Jo\u00e3o informou que o caso j\u00e1 \u00e9 de dom\u00ednio da Pol\u00edcia Nacional, que j\u00e1 instaurou o processo-crime n\u00famero 19647\/20, estando sob al\u00e7ada do SIC-Luanda. Por outro lado, disse que o agressor se p\u00f4s em fuga no dia da briga.<\/p>\n<p style=\"text-align: justify;\">Amigos do malogrados destroem casa de suposto assassino<\/p>\n<p style=\"text-align: justify;\">\u201cN\u00e3o foram os familiares do malogrado que vandalizaram aquela resid\u00eancia. Eu, apesar da dor, ainda tentei impedir que aquilo acontecesse, mas dentro daquela afli\u00e7\u00e3o, enquanto n\u00f3s chor\u00e1vamos, os amigos do falecido invadiam a moradia\u201d, explicou, ao alegar que se fosse pretens\u00e3o da fam\u00edlia, teria sido feito no dia da trag\u00e9dia.<\/p>\n<p style=\"text-align: justify;\">Maria Jo\u00e3o conta que o filho era uma pessoa de bem e que, com a morte prematura, sente-se desprotegida e insegura, no bairro onde o filho foi assassinado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas dias foi quanto durou o noivado de Herculano Costa, 24 anos, que perdeu a vida na sequ\u00eancia de uma briga, com um amigo de inf\u00e2ncia, por n\u00e3o o ter convidado para a sua festa. O caso aconteceu na passada quinta-feira, 22 de Outubro, no Zango 3, bairro Capapinha. Por: Costa Kilunda O infausto acontecimento ocorreu tr\u00eas dias depois de Herculano Fidel Jo\u00e3o da Costa, ter formalizado a sua rela\u00e7\u00e3o com a, agora, noiva, com quem pretendia viver longos e felizes anos. O sonho foi interrompido por um amigo, que, motivado pela f\u00faria de n\u00e3o ter sido convidado, partiu para [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Tr\u00eas dias foi quanto durou o noivado de Herculano Costa, 24 anos, que perdeu a vida na sequ\u00eancia de uma briga, com um amigo de inf\u00e2ncia, por n\u00e3o o ter convidado para a sua festa. O caso aconteceu na passada quinta-feira, 22 de Outubro, no Zango 3, bairro Capapinha. Por: Costa Kilunda O infausto acontecimento ocorreu tr\u00eas dias depois de Herculano Fidel Jo\u00e3o da Costa, ter formalizado a sua rela\u00e7\u00e3o com a, agora, noiva, com quem pretendia viver longos e felizes anos. O sonho foi interrompido por um amigo, que, motivado pela f\u00faria de n\u00e3o ter sido convidado, partiu para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T15:00:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T15:07:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0527.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"1384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO\",\"datePublished\":\"2020-12-02T15:00:42+00:00\",\"dateModified\":\"2024-07-17T15:07:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/\"},\"wordCount\":474,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0527.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/\",\"name\":\"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0527.jpg\",\"datePublished\":\"2020-12-02T15:00:42+00:00\",\"dateModified\":\"2024-07-17T15:07:32+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0527.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DSC_0527.jpg\",\"width\":840,\"height\":1384},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/","og_locale":"pt_PT","og_type":"article","og_title":"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO - Jornal O Crime","og_description":"Tr\u00eas dias foi quanto durou o noivado de Herculano Costa, 24 anos, que perdeu a vida na sequ\u00eancia de uma briga, com um amigo de inf\u00e2ncia, por n\u00e3o o ter convidado para a sua festa. O caso aconteceu na passada quinta-feira, 22 de Outubro, no Zango 3, bairro Capapinha. Por: Costa Kilunda O infausto acontecimento ocorreu tr\u00eas dias depois de Herculano Fidel Jo\u00e3o da Costa, ter formalizado a sua rela\u00e7\u00e3o com a, agora, noiva, com quem pretendia viver longos e felizes anos. O sonho foi interrompido por um amigo, que, motivado pela f\u00faria de n\u00e3o ter sido convidado, partiu para [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/","og_site_name":"Jornal O Crime","article_published_time":"2020-12-02T15:00:42+00:00","article_modified_time":"2024-07-17T15:07:32+00:00","og_image":[{"width":840,"height":1384,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0527.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO","datePublished":"2020-12-02T15:00:42+00:00","dateModified":"2024-07-17T15:07:32+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/"},"wordCount":474,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0527.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/","url":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/","name":"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0527.jpg","datePublished":"2020-12-02T15:00:42+00:00","dateModified":"2024-07-17T15:07:32+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0527.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/11\/DSC_0527.jpg","width":840,"height":1384},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/jovem-mata-amigo-por-nao-ser-convidado-a-festa-de-pedido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"JOVEM MATA AMIGO POR N\u00c3O SER CONVIDADO \u00c0 FESTA DE PEDIDO"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2660"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2705"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}