{"id":2774,"date":"2020-12-09T17:50:46","date_gmt":"2020-12-09T16:50:46","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2774"},"modified":"2024-07-17T16:07:30","modified_gmt":"2024-07-17T15:07:30","slug":"mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/","title":{"rendered":"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Um ano depois do falecimento de Deolinda Salvador, esquartejada e enterrada em terreno baldio pelo pr\u00f3prio marido, preso desde o ano passado, o julgamento continua sem data prevista para in\u00edcio, porque o tribunal de Luanda diz n\u00e3o ter compet\u00eancia para julgar o caso, pois desconhece o crime pelo qual o arguido \u00e9 indiciado.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Costa Kilunda<\/strong><\/p>\n<p style=\"text-align: justify;\">Foi, ainda, not\u00edcia neste jornal que Edmilson da Silva Mukwanda, ent\u00e3o esposo da v\u00edtima, na altura com 22 anos, acabou detido alguns dias depois, acusado de ser o autor do b\u00e1rbaro assassinato.\u00a0 \u00a0crime de que foi v\u00edtima a cidad\u00e3 Deolinda da Silva Francisco Salvador, \u00e0 data com 21 anos, ocorreu a 31 de Outubro de 2019, no bairro Chimbicato, munic\u00edpio do Talatona, e mereceu destaque no jornal O Crime.<\/p>\n<p style=\"text-align: justify;\">Entretanto, decorridos cerca de treze meses, e terminada a fase de instru\u00e7\u00e3o preparat\u00f3ria, faltando apenas ser pronunciado e marcado a data do julgamento, eis que a fam\u00edlia da malograda \u00e9 confrontada com a informa\u00e7\u00e3o de que o tribunal n\u00e3o tem compet\u00eancia para julgar o caso por desconhecer o crime pelo qual o suspeito \u00e9 indiciado.<\/p>\n<p style=\"text-align: justify;\">O pai da malograda, Franklin In\u00e1cio Salvador, que apela \u00e0 solidariedade por parte da Ordem dos Advogados Angola (OAA), disse em entrevista a este jornal que tem recebido \u201cvoltas e mais voltas\u201d, todas as vezes que se desloca at\u00e9 ao pal\u00e1cio Dona Ana Joaquina para ter informa\u00e7\u00f5es sobre o andamento do processo. \u201cQuando vamos ao Dona Ana Joaquina, mandam-nos ir ao Tribunal da Comarca do Benfica e vice-versa\u201d, lamentou o pai, acrescentando que \u00e9 neste \u00faltimo, em que o processo se encontra desde Julho \u00faltimo\u2026 engavetado.<\/p>\n<p style=\"text-align: justify;\">E foi na mais recente desloca\u00e7\u00e3o que fez ao tribunal do Benfica, no dia 3 do m\u00eas em curso, que foi informado que este tribunal havia decretado incompet\u00eancia para julgar o caso. Por isso mesmo, solicitou que o processo (n.\u00ba 75\/20-B) fosse encaminhado para a 9.\u00aa Sec\u00e7\u00e3o do Pal\u00e1cio Dona Ana Joaquina, de onde j\u00e1 havia sa\u00eddo.<\/p>\n<p style=\"text-align: justify;\">\u201cEstamos tristes porque muitos processos que deram entrada na mesma altura j\u00e1 foram julgados\u201d, disse senhor Franklin, para depois esclarecer que nada do que for feito a seguir trar\u00e1 de volta a sua filha, mas \u00e9 honrar a morte da filha, com a feitura da justi\u00e7a, que a fam\u00edlia quer agora.<\/p>\n<p style=\"text-align: justify;\">Tendo em conta a preocupa\u00e7\u00e3o deste cidad\u00e3o, a nossa equipa de reportagem deslocou-se, na passada segunda-feira, 23, para o Pal\u00e1cio Dona Ana Joaquina, no sentido de apurar o que se passa, de facto. Postos l\u00e1, no cart\u00f3rio da 9.\u00aa Sec\u00e7\u00e3o, fomos atendidos por uma funcion\u00e1ria que, sem gravar entrevista, alegou que essa \u201cconfus\u00e3o\u201d se deveu ao facto de, inicialmente, os processos terem sido distribu\u00eddos pela compet\u00eancia territorial. A mesma funcion\u00e1ria, que preferiu omitir o seu nome, reconheceu que o \u201cerro\u201d se deu na Distribui\u00e7\u00e3o Geral do Tribunal Provincial de Luanda, um departamento do Tribunal Provincial de Luanda, por\u00e9m, alegou que o processo foi novamente transferido para a 9.\u00aa Sec\u00e7\u00e3o, porque a 14.\u00aa Sec\u00e7\u00e3o \u201cn\u00e3o julga processos de viol\u00eancia dom\u00e9stica\u201d.<\/p>\n<p style=\"text-align: justify;\">No entanto, segundo aquela funcion\u00e1ria, tudo ser\u00e1 feito para corrigir \u201ctais falhas\u201d e, em tempo oportuno, ser\u00e1 conhecido a data de in\u00edcio do julgamento do referido caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um ano depois do falecimento de Deolinda Salvador, esquartejada e enterrada em terreno baldio pelo pr\u00f3prio marido, preso desde o ano passado, o julgamento continua sem data prevista para in\u00edcio, porque o tribunal de Luanda diz n\u00e3o ter compet\u00eancia para julgar o caso, pois desconhece o crime pelo qual o arguido \u00e9 indiciado. Por: Costa Kilunda Foi, ainda, not\u00edcia neste jornal que Edmilson da Silva Mukwanda, ent\u00e3o esposo da v\u00edtima, na altura com 22 anos, acabou detido alguns dias depois, acusado de ser o autor do b\u00e1rbaro assassinato.\u00a0 \u00a0crime de que foi v\u00edtima a cidad\u00e3 Deolinda da Silva Francisco Salvador, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Um ano depois do falecimento de Deolinda Salvador, esquartejada e enterrada em terreno baldio pelo pr\u00f3prio marido, preso desde o ano passado, o julgamento continua sem data prevista para in\u00edcio, porque o tribunal de Luanda diz n\u00e3o ter compet\u00eancia para julgar o caso, pois desconhece o crime pelo qual o arguido \u00e9 indiciado. Por: Costa Kilunda Foi, ainda, not\u00edcia neste jornal que Edmilson da Silva Mukwanda, ent\u00e3o esposo da v\u00edtima, na altura com 22 anos, acabou detido alguns dias depois, acusado de ser o autor do b\u00e1rbaro assassinato.\u00a0 \u00a0crime de que foi v\u00edtima a cidad\u00e3 Deolinda da Silva Francisco Salvador, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-09T16:50:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T15:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_05851.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1264\" \/>\n\t<meta property=\"og:image:height\" content=\"1752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA\",\"datePublished\":\"2020-12-09T16:50:46+00:00\",\"dateModified\":\"2024-07-17T15:07:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/\"},\"wordCount\":560,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_05851.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/\",\"name\":\"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_05851.jpg\",\"datePublished\":\"2020-12-09T16:50:46+00:00\",\"dateModified\":\"2024-07-17T15:07:30+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_05851.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_05851.jpg\",\"width\":1264,\"height\":1752},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/","og_locale":"pt_PT","og_type":"article","og_title":"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA - Jornal O Crime","og_description":"Um ano depois do falecimento de Deolinda Salvador, esquartejada e enterrada em terreno baldio pelo pr\u00f3prio marido, preso desde o ano passado, o julgamento continua sem data prevista para in\u00edcio, porque o tribunal de Luanda diz n\u00e3o ter compet\u00eancia para julgar o caso, pois desconhece o crime pelo qual o arguido \u00e9 indiciado. Por: Costa Kilunda Foi, ainda, not\u00edcia neste jornal que Edmilson da Silva Mukwanda, ent\u00e3o esposo da v\u00edtima, na altura com 22 anos, acabou detido alguns dias depois, acusado de ser o autor do b\u00e1rbaro assassinato.\u00a0 \u00a0crime de que foi v\u00edtima a cidad\u00e3 Deolinda da Silva Francisco Salvador, [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/","og_site_name":"Jornal O Crime","article_published_time":"2020-12-09T16:50:46+00:00","article_modified_time":"2024-07-17T15:07:30+00:00","og_image":[{"width":1264,"height":1752,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_05851.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA","datePublished":"2020-12-09T16:50:46+00:00","dateModified":"2024-07-17T15:07:30+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/"},"wordCount":560,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_05851.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/","url":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/","name":"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_05851.jpg","datePublished":"2020-12-09T16:50:46+00:00","dateModified":"2024-07-17T15:07:30+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_05851.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_05851.jpg","width":1264,"height":1752},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/mulher-esquartejada-pelo-marido-um-ano-depois-julgamento-ainda-sem-data\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"MULHER ESQUARTEJADA PELO MARIDO UM ANO DEPOIS JULGAMENTO AINDA SEM DATA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2774"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2777"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}