{"id":2874,"date":"2020-12-26T16:06:43","date_gmt":"2020-12-26T15:06:43","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2874"},"modified":"2020-12-26T16:06:43","modified_gmt":"2020-12-26T15:06:43","slug":"justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/","title":{"rendered":"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A v\u00edtima mais fresca da brutalidade popular, que se vai tornando h\u00e1bito um pouco por toda extens\u00e3o do munic\u00edpio do Kilamba Kiaxi, at\u00e9 \u00e9 descrito como um \u201cindiv\u00edduo de boa-\u00edndole\u201d. Entretanto, dizem testemunhas, estava no lugar errado e na hora errada.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Costa Kilunda<\/strong><\/p>\n<p><span style=\"text-align: justify;\">Jos\u00e9 Joaquim Kidiu, ou simplesmente \u201cBig Sexy\u201d, contava, at\u00e9 \u00e0 data da sua morte, 28 de Novembro, s\u00e1bado, com 31 anos de idade, bem na flor da sua mocidade. \u201cMas uma escolha errada na amizade ditou a sua senten\u00e7a\u201d, assim dizem alguns dos seus conhecidos.<\/span><\/p>\n<p style=\"text-align: justify;\">O caso aconteceu no bairro 28 de Agosto, nas imedia\u00e7\u00f5es do Golf 2. E, segundo contaram ao jornal O Crime os seus familiares, \u201cBig Sexy\u201d ter\u00e1 sido espancado, por populares, com catanas, pedras, bast\u00f5es e outros elementos contundentes. A raz\u00e3o por detr\u00e1s deste horrendo crime, disseram, tem que ver com o facto de a v\u00edtima ter sido visto a deambular pelas ruas daquele intrigado bairro em companhia de um amigo, supostamente militar, cuja reputa\u00e7\u00e3o, nas cercanias, n\u00e3o \u00e9 das mais simp\u00e1ticas.<\/p>\n<p style=\"text-align: justify;\">\u00c0 data dos factos, como fez saber Catarina Kidiu, irm\u00e3 do malogrado, por volta das 20 horas daquele fat\u00eddico dia, num momento em que o irm\u00e3o at\u00e9 j\u00e1 se encontrava a dormir, apareceu em sua resid\u00eancia o referido amigo, o suposto militar, que atende, segundo ela, pelo nome de Eduardo Gonga, e que \u00e9 vulgarmente tratado por \u201cEdu\u201d \u2013 a convid\u00e1-lo para irem a uma festa. Jos\u00e9 Kidiu\u00a0 atendeu ao chamamento do amigo e ambos partiram para o local do evento.<\/p>\n<p style=\"text-align: justify;\">\u201cMas, segundo ficamos a saber, n\u00e3o permaneceram l\u00e1 por muito tempo, uma vez que, depois, o Edu levou-o para outra zona a fim de comprarem mais cervejas\u201d, explicou a mo\u00e7a, para depois estranhar a necessidade de eles se deslocarem para comprar mais cervejas, quando, no entender dela, o que demais havia na festa era cerveja.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m disso, explicou, na zona em que ambos se deslocaram para comprar as cervejas, e onde a v\u00edtima veio a sofrer retalia\u00e7\u00e3o mais tarde, dias antes, Edu, o amigo, havia criado uma confus\u00e3o e, ao retirar-se, teria, alegadamente, feito disparos de arma de fogo, tendo um dos proj\u00e9cteis atingido os olhos de uma menor e a ter deixado com graves les\u00f5es.<\/p>\n<p style=\"text-align: justify;\">\u201c\u00c9 isto que ele faz aqui no bairro. Ouvem-se tiros atr\u00e1s de tiros, sobretudo quando est\u00e1 embriagado\u201d, denunciou Catarina Kidiu, para mais adiante dizer que assim que foram identificados, num piscar de olhos estavam cercados por uma multid\u00e3o de revoltados, que aguardavam, expectantes, por uma oportunidade para se vingar.<\/p>\n<p style=\"text-align: justify;\">\u201cEle, o Edu, conseguiu escapar, e abandonou o meu irm\u00e3o no local\u201d, lembrou, revoltada, acrescentando que os populares o bateram com tanta viol\u00eancia, e, moribundo, estatelado ao ch\u00e3o, s\u00f3 n\u00e3o o atearam fogo gra\u00e7as a pronta interven\u00e7\u00e3o de um cidad\u00e3o, que o reconheceu, e apelou que o deixassem ir. Pois, segundo os mesmos, tratava-se de um \u201cinocente\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cFoi arrepiante o que fizeram com o meu irm\u00e3o\u201d, lamentou Catarina. Prosseguindo, disse que alguns motociclistas passavam por cima do seu corpo, o que o deixou com v\u00e1rios membros fracturados. \u201cComo \u00e9 que o Edu, que at\u00e9 estava armado, colocou-se em fuga sem prestar socorro ao amigo?\u201d, questiona agora a jovem.<\/p>\n<p style=\"text-align: justify;\">Depois da clem\u00eancia, Jos\u00e9 Kidiu foi levado pelos seus familiares at\u00e9 ao Hospital Geral de Luanda, no Camama, mas n\u00e3o lhe foi dada a aten\u00e7\u00e3o necess\u00e1ria \u2013 porque \u2013, de acordo com a irm\u00e3, \u201cos m\u00e9dicos o abandonaram\u201d quando foi reconhecido pelos familiares da mesma menina que havia sido ferida pelo seu amigo, que tamb\u00e9m se encontrava na mesma unidade hospitalar a tratamento. \u201cOs familiares da menina informaram aos enfermeiros que se tratava de um dos marginais que havia ferido a sua filha\u201d, disse Catarina.<\/p>\n<p style=\"text-align: justify;\"><strong>Suposto militar ouvido pelas autoridades<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cPouco depois que recebemos a not\u00edcia do seu falecimento, por neglig\u00eancia dos enfermeiros, alguns dos meus familiares procuraram o Edu, e, quando o encontraram, levaram-lhe \u00e0 Divis\u00e3o de Pol\u00edcia do Kilamba Kiaxi, No Nova Vida, para prestar declara\u00e7\u00f5es\u201d, explicou a jovem, acrescentando que depois de ouvidos pelo Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC), este mandaram de volta o alegado militar para casa, alegando que as informa\u00e7\u00f5es prestadas pelas partes eram bastante contradit\u00f3rias, e que n\u00e3o haviam elementos de provas suficientes para manter o acusado sob cust\u00f3dia.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, os familiares do malogrado acusaram os investigadores da referida unidade policial de estarem a encobrir Eduardo Gonga, por ser, alegadamente, familiar de um dos seus colegas. \u201cSabemos que ele goza de alguma influ\u00eancia naquela esquadra, por ser familiar de algu\u00e9m que exerce ali fun\u00e7\u00f5es de relev\u00e2ncia\u201d, denunciou.<\/p>\n<p style=\"text-align: justify;\">Apesar de n\u00e3o haver, ainda, detidos, as autoridades j\u00e1 abriram um procedimento criminal, sob o n\u00famero de processo 8243\/20, j\u00e1 encaminhado para o SIC-geral, agora sob al\u00e7ada do investigador Yuri Mendon\u00e7a.<\/p>\n<p style=\"text-align: justify;\">De referir que os restos mortais de Jos\u00e9 Joaquim Kidiu foram a enterrar na passada quinta-feira, 27 de Novembro, no Cemit\u00e9rio municipal da Camama.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A v\u00edtima mais fresca da brutalidade popular, que se vai tornando h\u00e1bito um pouco por toda extens\u00e3o do munic\u00edpio do Kilamba Kiaxi, at\u00e9 \u00e9 descrito como um \u201cindiv\u00edduo de boa-\u00edndole\u201d. Entretanto, dizem testemunhas, estava no lugar errado e na hora errada. Costa Kilunda Jos\u00e9 Joaquim Kidiu, ou simplesmente \u201cBig Sexy\u201d, contava, at\u00e9 \u00e0 data da sua morte, 28 de Novembro, s\u00e1bado, com 31 anos de idade, bem na flor da sua mocidade. \u201cMas uma escolha errada na amizade ditou a sua senten\u00e7a\u201d, assim dizem alguns dos seus conhecidos. O caso aconteceu no bairro 28 de Agosto, nas imedia\u00e7\u00f5es do Golf [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"A v\u00edtima mais fresca da brutalidade popular, que se vai tornando h\u00e1bito um pouco por toda extens\u00e3o do munic\u00edpio do Kilamba Kiaxi, at\u00e9 \u00e9 descrito como um \u201cindiv\u00edduo de boa-\u00edndole\u201d. Entretanto, dizem testemunhas, estava no lugar errado e na hora errada. Costa Kilunda Jos\u00e9 Joaquim Kidiu, ou simplesmente \u201cBig Sexy\u201d, contava, at\u00e9 \u00e0 data da sua morte, 28 de Novembro, s\u00e1bado, com 31 anos de idade, bem na flor da sua mocidade. \u201cMas uma escolha errada na amizade ditou a sua senten\u00e7a\u201d, assim dizem alguns dos seus conhecidos. O caso aconteceu no bairro 28 de Agosto, nas imedia\u00e7\u00f5es do Golf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-26T15:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_0450.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1229\" \/>\n\t<meta property=\"og:image:height\" content=\"1843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE\",\"datePublished\":\"2020-12-26T15:06:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/\"},\"wordCount\":869,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_0450.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/\",\"name\":\"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_0450.jpg\",\"datePublished\":\"2020-12-26T15:06:43+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_0450.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DSC_0450.jpg\",\"width\":1229,\"height\":1843},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/","og_locale":"pt_PT","og_type":"article","og_title":"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE - Jornal O Crime","og_description":"A v\u00edtima mais fresca da brutalidade popular, que se vai tornando h\u00e1bito um pouco por toda extens\u00e3o do munic\u00edpio do Kilamba Kiaxi, at\u00e9 \u00e9 descrito como um \u201cindiv\u00edduo de boa-\u00edndole\u201d. Entretanto, dizem testemunhas, estava no lugar errado e na hora errada. Costa Kilunda Jos\u00e9 Joaquim Kidiu, ou simplesmente \u201cBig Sexy\u201d, contava, at\u00e9 \u00e0 data da sua morte, 28 de Novembro, s\u00e1bado, com 31 anos de idade, bem na flor da sua mocidade. \u201cMas uma escolha errada na amizade ditou a sua senten\u00e7a\u201d, assim dizem alguns dos seus conhecidos. O caso aconteceu no bairro 28 de Agosto, nas imedia\u00e7\u00f5es do Golf [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/","og_site_name":"Jornal O Crime","article_published_time":"2020-12-26T15:06:43+00:00","og_image":[{"width":1229,"height":1843,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_0450.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE","datePublished":"2020-12-26T15:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/"},"wordCount":869,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_0450.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/","url":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/","name":"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_0450.jpg","datePublished":"2020-12-26T15:06:43+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_0450.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/DSC_0450.jpg","width":1229,"height":1843},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/justica-por-maos-proprias-ganha-terreno-no-kilamba-kiaxi-mais-um-suposto-marginal-e-espancado-ate-a-morte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Justi\u00e7a por m\u00e3os pr\u00f3prias ganha terreno no Kilamba Kiaxi:\u00a0MAIS UM SUPOSTO MARGINAL \u00c9 ESPANCADO AT\u00c9 \u00c0 MORTE"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2874"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2875"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}