{"id":2885,"date":"2020-12-26T16:27:09","date_gmt":"2020-12-26T15:27:09","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2885"},"modified":"2020-12-26T16:38:32","modified_gmt":"2020-12-26T15:38:32","slug":"garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/","title":{"rendered":"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O n\u00famero de cidad\u00e3os que recorre a liga\u00e7\u00f5es ilegais de \u00e1gua, para fazer face \u00e0s necessidades do l\u00edquido precioso, que o Estado n\u00e3o consegue, est\u00e1, cada vez mais, se tornando numa verdadeira fonte de renda n\u00e3o s\u00f3 para o sustento das fam\u00edlias, como para propiciar outros neg\u00f3cios.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Honorina Kiampava<\/strong><\/p>\n<p style=\"text-align: justify;\">O garimpo de \u00e1gua n\u00e3o \u00e9 nada mais do que o desvio do curso normal da \u00e1gua com o \u00fanico fim de vender a mais ou menos pre\u00e7o para as popula\u00e7\u00f5es que carecem desse l\u00edquido precioso, usando os electrobombas.<\/p>\n<p style=\"text-align: justify;\">V\u00e1rios jovens dizem-se, hoje, \u201cempres\u00e1rios\u201d, porque, al\u00e9m da venda da \u00e1gua em cami\u00f5es cisternas, s\u00e3o respons\u00e1veis por liga\u00e7\u00f5es domiciliares e \u201cd\u00e3o resposta a quase todas as preocupa\u00e7\u00f5es de moradores\u201d, quando o assunto \u00e9 \u00e1gua.<\/p>\n<p style=\"text-align: justify;\">Um dos muitos que v\u00ea no garimpo de \u00e1gua uma fonte de rendimento \u00e9 o jovem Fortunato de Sousa Filipe, que h\u00e1 tr\u00eas anos tem sustentado a fam\u00edlia, composta por esposa e sete filhos, atrav\u00e9s de liga\u00e7\u00f5es il\u00edcitas. Apesar de saber que tal pr\u00e1tica \u00e9 errada, n\u00e3o pretende abandonar a actividade t\u00e3o cedo.<\/p>\n<p style=\"text-align: justify;\">\u201c\u00c9 um neg\u00f3cio que traz dinheiro, por isso muitos se tornaram garimpeiros, assim como eu. N\u00e3o tenho uma previs\u00e3o para deixar de trabalhar nisso, acabei comprando mais casas e carros por meio deste neg\u00f3cio\u201d, faz saber.<\/p>\n<p style=\"text-align: justify;\">Ao Fortunato junta-se Alfredo Gomes, de 34 anos, que nos conta que entrou neste mundo por falta de emprego. \u201cPassava por v\u00e1rias necessidades, quase ningu\u00e9m me ajudava, n\u00e3o vi outra solu\u00e7\u00e3o a n\u00e3o ser de pedir aos meus amigos que me enquadrassem neste neg\u00f3cio. N\u00e3o \u00e9 dif\u00edcil aprender a ser garimpeiro, aqui, o que nos move \u00e9 o dinheiro\u201d.<\/p>\n<p style=\"text-align: justify;\">Com o dinheiro que ganha, salienta, consegue sustentar os filhos, a m\u00e3e e os outros irm\u00e3os. Quando lhe foi perguntado sobre a possibilidade de um dia vir a abandonar esta pr\u00e1tica, sorriu e disse \u201cquando o Estado cumprir com as suas promessas, dar uma vida digna \u00e0 popula\u00e7\u00e3o, muitos que fazem isso v\u00e3o desistir, inclusive eu\u201d.<\/p>\n<p style=\"text-align: justify;\">Por seu turno, Bernardo Ndombele Sim\u00f5es passou a ser garimpeiro por curiosidade, quando via seus ex-colegas da EPAL a fazerem neg\u00f3cios do g\u00e9nero, ou seja, a desviarem os tubos de \u00e1gua e venderem a outras pessoas por pre\u00e7os mais baixos, recebendo um valor extra, a par do sal\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">Da\u00ed, a sua gan\u00e2ncia falou mais alto e decidiu. Entretanto, foi apanhado e, consequentemente, preso. \u201cFiquei enjaulado por um ano. Quando sa\u00ed, perdi meu emprego, mas continuei com o garimpo. Hoje tem pessoas que solicitam meus servi\u00e7os, tenho os meus contactos dentro da EPAL, nem com aquilo que aconteceu denunciei os meus amigos, porque ningu\u00e9m me obrigou a ser como eles, a minha curiosidade levou-me distante e paguei por isso\u201d, revela.<\/p>\n<p style=\"text-align: justify;\"><strong>O povo \u00e9 sempre o mais prejudicado<\/strong><\/p>\n<p style=\"text-align: justify;\">Nelma Gon\u00e7alves, moradora do bairro Rocha Pinto, h\u00e1 mais de dez anos, considera que a pr\u00e1tica constitui um acto criminoso e cria problemas acrescidos aos moradores que n\u00e3o o praticam. \u201cUm morador n\u00e3o pode e nem deve fazer liga\u00e7\u00e3o de \u00e1gua sem a licen\u00e7a da EPAL, porque isso consiste numa ac\u00e7\u00e3o criminosa e p\u00f5e a comunidade em desvantagem\u201d referiu.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, In\u00eas Ant\u00f3nio, tamb\u00e9m residente daquele bairro, salientou que se o mun\u00edcipe tem executado estas actividades de maneira il\u00edcita, a falha \u00e9 do Governo que n\u00e3o cumpre com o projecto \u201c\u00c1gua para Todos\u201d. \u201cA culpa \u00e9 do Governo, que n\u00e3o p\u00f5e \u00e1gua em todas as casas, porque, em pa\u00edses mais organizados, o problema da \u00e1gua e energia j\u00e1 deixou de ser um bicho-de-sete-cabe\u00e7as, mas n\u00f3s, em Angola, com tantos recursos h\u00eddricos, ainda passamos por essas dificuldades\u201d afirmou.<\/p>\n<p style=\"text-align: justify;\">O que intriga os moradores do Rocha \u00e9 que todos t\u00eam torneiras em casa, mas quase ningu\u00e9m tem \u00e1gua, o que os leva a questionar se \u201co projecto \u00e9 \u00e1gua para todos ou torneiras para todos, porque, se for torneiras para todos, o Estado realizou, com \u00eaxito, a sua miss\u00e3o\u201d, diz um dos moradores, que n\u00e3o quis ser identificado.<\/p>\n<p style=\"text-align: justify;\">Actualmente, o bairro Rocha Pinto observa um n\u00famero elevado de rupturas de condutas de \u00e1gua e os moradores s\u00e3o obrigados a percorrerem grandes dist\u00e2ncias, em busca do l\u00edquido precioso, para satisfa\u00e7\u00e3o das suas necessidades di\u00e1rias.<\/p>\n<p style=\"text-align: justify;\">Ainda no mesmo bairro, a equipa de reportagem encontrou Ana Domingos Manuel, que deslocou o p\u00e9, quando tentava atravessar a barreira que existe no meio da estrada, tudo porque precisava de \u00e1gua. \u201cHoje sofro com o p\u00e9 inflamado, as dores que sentia s\u00f3 pioraram desde o momento que isso aconteceu\u201d.<\/p>\n<p style=\"text-align: justify;\">Numa ronda feita pela EPAL em 2019, para detectar os pontos de garimpo de \u00e1gua, os t\u00e9cnicos comprovaram a exist\u00eancia de v\u00e1rios locais onde se desenvolve o garimpo, com maior incid\u00eancia para o bairro An\u00edbal Rocha, no distrito da Sapu.<\/p>\n<p style=\"text-align: justify;\">Naquelas zonas, as liga\u00e7\u00f5es e a venda ilegal de \u00e1gua s\u00e3o feitas tanto a luz do sol, como de noite. Para facilitar o trabalho, os garimpeiros, muitas vezes, usam maquinaria pesada para escava\u00e7\u00f5es e perfura\u00e7\u00e3o de condutas indutoras.<\/p>\n<p style=\"text-align: justify;\">No bairro Cassequel do Buraco, h\u00e1 moradores que afirmaram que nunca mais viram a famosa \u201c\u00e1gua da Covid\u201d, desde Junho deste ano, e que h\u00e1 bairros que nunca beneficiaram de nenhuma gota, como no distrito da Sapu.<\/p>\n<p style=\"text-align: justify;\">Neste tempo de pandemia, em que \u00e9 necess\u00e1rio o uso constante da \u00e1gua para a lavagem das m\u00e3os e n\u00e3o s\u00f3, os cidad\u00e3os sentem-se de m\u00e3os atadas, perguntando se v\u00e3o gastar a \u00e1gua na lavagem das m\u00e3os ou priorizam outras necessidades, como beber, cozinhar e lavar.<\/p>\n<p style=\"text-align: justify;\">Em Maio do ano em curso, o Minist\u00e9rio da Energia e \u00c1guas, com ajuda de parceiros, distribu\u00edram cerca de 115 milh\u00f5es de litros de \u00e1gua, n\u00famero que n\u00e3o foi suficiente para suprir a necessidade do povo.<\/p>\n<p style=\"text-align: justify;\">De real\u00e7ar que o projecto \u201c\u00c1gua para Todos\u201d \u00e9 um plano do Governo angolano, criado em julho de 2007, que visa assegurar o abastecimento de \u00e1gua a 80% da popula\u00e7\u00e3o, e teve a sua fase inicial nas prov\u00edncias do Bengo, Benguela, Cabinda e U\u00edge, posteriormente em Luanda (2012), e em 2014 o processo alargou-se a todo pa\u00eds. Entretanto, os choros pela car\u00eancia desse l\u00edquido ainda \u00e9 bastante alargado.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o obstante, enquanto uns est\u00e3o privados do l\u00edquido precioso e s\u00e3o obrigados a percorrer longas dist\u00e2ncias para adquiri-lo, outros o desperdi\u00e7am. No bairro Nova Vida, por exemplo, muitos moradores deixam as torneiras abertas e, al\u00e9m dos preju\u00edzos para a EPAL, causam danos ao tapete asf\u00e1ltico.<\/p>\n<p style=\"text-align: justify;\">Nesta urbaniza\u00e7\u00e3o, v\u00e1rios s\u00e3o os charcos de \u00e1gua por mau consumo, sem falar das roturas que, no princ\u00edpio, s\u00e3o pouco vis\u00edveis, mas, por insufici\u00eancia de equipamentos pela EPAL, transformam-se em grandes crateras.<\/p>\n<p style=\"text-align: justify;\"><strong>A solu\u00e7\u00e3o passa por deixar o ego\u00edsmo<\/strong><\/p>\n<p style=\"text-align: justify;\">Para Edgar dos Santos, soci\u00f3logo, o garimpo de \u00e1gua \u00e9 visto como um acto de desumaniza\u00e7\u00e3o, pois, muitos sofrem com esta pr\u00e1tica. \u201cEnquanto n\u00e3o existir amor ao pr\u00f3ximo, coisas do g\u00e9nero v\u00e3o sempre existir\u2026 um dos motivos que faz com que muitos pa\u00edses regridam \u00e9 a falta de humanismo, todos querem alcan\u00e7ar riquezas por interm\u00e9dio de sacrif\u00edcios alheios\u201d, considerou.<\/p>\n<p style=\"text-align: justify;\">\u201c\u00d3bvio que alguns membros da EPAL coadunam com essa pr\u00e1tica, \u00e0s vezes, s\u00e3o eles pr\u00f3prios que fornecem os principais materiais, em troca de remunera\u00e7\u00e3o\u201d, frisou, apelando, a seguir, que \u201ca necessidade n\u00e3o pode nos levar a cometer actos indecorosos, a fome n\u00e3o pode ser maior que a educa\u00e7\u00e3o que recebemos em casa\u2026 uma sociedade faz-se de exemplos, tanto bons, quanto maus\u201d.<\/p>\n<p style=\"text-align: justify;\">Sobre o principal motivo que faz com que muitos adiram a tal pr\u00e1tica, o soci\u00f3logo sublinhou que n\u00e3o \u00e9 a necessidade, mas sim gan\u00e2ncia, arrog\u00e2ncia e imediatismo, tendo acrescido, mais tarde, que existem v\u00e1rias solu\u00e7\u00f5es para resolver tal problema, mas a principal delas \u201c\u00e9 cada um deixar de pensar no seu pr\u00f3prio umbigo, h\u00e1 necessidade de existir empatia pelos outros, n\u00e3o precisa conhecer, para fazer o bem\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O n\u00famero de cidad\u00e3os que recorre a liga\u00e7\u00f5es ilegais de \u00e1gua, para fazer face \u00e0s necessidades do l\u00edquido precioso, que o Estado n\u00e3o consegue, est\u00e1, cada vez mais, se tornando numa verdadeira fonte de renda n\u00e3o s\u00f3 para o sustento das fam\u00edlias, como para propiciar outros neg\u00f3cios. Por: Honorina Kiampava O garimpo de \u00e1gua n\u00e3o \u00e9 nada mais do que o desvio do curso normal da \u00e1gua com o \u00fanico fim de vender a mais ou menos pre\u00e7o para as popula\u00e7\u00f5es que carecem desse l\u00edquido precioso, usando os electrobombas. V\u00e1rios jovens dizem-se, hoje, \u201cempres\u00e1rios\u201d, porque, al\u00e9m da venda da \u00e1gua [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O n\u00famero de cidad\u00e3os que recorre a liga\u00e7\u00f5es ilegais de \u00e1gua, para fazer face \u00e0s necessidades do l\u00edquido precioso, que o Estado n\u00e3o consegue, est\u00e1, cada vez mais, se tornando numa verdadeira fonte de renda n\u00e3o s\u00f3 para o sustento das fam\u00edlias, como para propiciar outros neg\u00f3cios. Por: Honorina Kiampava O garimpo de \u00e1gua n\u00e3o \u00e9 nada mais do que o desvio do curso normal da \u00e1gua com o \u00fanico fim de vender a mais ou menos pre\u00e7o para as popula\u00e7\u00f5es que carecem desse l\u00edquido precioso, usando os electrobombas. V\u00e1rios jovens dizem-se, hoje, \u201cempres\u00e1rios\u201d, porque, al\u00e9m da venda da \u00e1gua [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-26T15:27:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-26T15:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"296\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL\",\"datePublished\":\"2020-12-26T15:27:09+00:00\",\"dateModified\":\"2020-12-26T15:38:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/\"},\"wordCount\":1415,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/21.jpg\",\"articleSection\":[\"SOCIEDADE\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/\",\"name\":\"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/21.jpg\",\"datePublished\":\"2020-12-26T15:27:09+00:00\",\"dateModified\":\"2020-12-26T15:38:32+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/21.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/21.jpg\",\"width\":296,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/","og_locale":"pt_PT","og_type":"article","og_title":"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL - Jornal O Crime","og_description":"O n\u00famero de cidad\u00e3os que recorre a liga\u00e7\u00f5es ilegais de \u00e1gua, para fazer face \u00e0s necessidades do l\u00edquido precioso, que o Estado n\u00e3o consegue, est\u00e1, cada vez mais, se tornando numa verdadeira fonte de renda n\u00e3o s\u00f3 para o sustento das fam\u00edlias, como para propiciar outros neg\u00f3cios. Por: Honorina Kiampava O garimpo de \u00e1gua n\u00e3o \u00e9 nada mais do que o desvio do curso normal da \u00e1gua com o \u00fanico fim de vender a mais ou menos pre\u00e7o para as popula\u00e7\u00f5es que carecem desse l\u00edquido precioso, usando os electrobombas. V\u00e1rios jovens dizem-se, hoje, \u201cempres\u00e1rios\u201d, porque, al\u00e9m da venda da \u00e1gua [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/","og_site_name":"Jornal O Crime","article_published_time":"2020-12-26T15:27:09+00:00","article_modified_time":"2020-12-26T15:38:32+00:00","og_image":[{"width":296,"height":180,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/21.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL","datePublished":"2020-12-26T15:27:09+00:00","dateModified":"2020-12-26T15:38:32+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/"},"wordCount":1415,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/21.jpg","articleSection":["SOCIEDADE"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/","url":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/","name":"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/21.jpg","datePublished":"2020-12-26T15:27:09+00:00","dateModified":"2020-12-26T15:38:32+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/21.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/21.jpg","width":296,"height":180},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/garimpo-de-agua-cria-empresarios-que-nao-pretendem-largar-a-actividade-ilegal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Garimpo de \u00e1gua:\u00a0CRIA \u201cEMPRES\u00c1RIOS\u201d QUE N\u00c3O PRETENDEM LARGAR A ACTIVIDADE ILEGAL"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2885"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2886"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}