{"id":2888,"date":"2020-12-26T17:02:05","date_gmt":"2020-12-26T16:02:05","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=2888"},"modified":"2020-12-26T17:02:41","modified_gmt":"2020-12-26T16:02:41","slug":"burladores-digitais-aprimoram-metodos-de-extorsao","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/","title":{"rendered":"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Desde emprego a terrenos, os burladores v\u00eam utilizando, cada vez mais, n\u00e3o s\u00f3 a tecnologia, como tamb\u00e9m \u201cpaix\u00f5es\u201d pelas v\u00edtimas, de forma a alici\u00e1-las mais facilmente. Domingas Gabriela, psic\u00f3loga cl\u00ednica e orientadora vocacional, foi-lhe declarada \u201camor\u201d, por meio de ofertas aliciantes.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Por: Jaime Tabo<\/strong><\/p>\n<p><span style=\"text-align: justify;\">Presumivelmente, em cena estava uma dupla estrangeira, um americano e outro nigeriano. Domingas recebeu, na sua conta empresarial, um contacto identificado por James Peter\u00b4s, supostamente americano, que se passava de cliente, solicitando, em portugu\u00eas, o seu whatsapp pessoal.<\/span><\/p>\n<p style=\"text-align: justify;\">Dias depois, al\u00e9m de cliente, mostrava interesses conjugais, tentando fazer crer que estava totalmente apaixonado pela psic\u00f3loga. Desta forma, enviou-lhe a fotografia de uma factura actual, 24 de Novembro, onde listava um Iphone 7X PRO, Perfume Louis VuittonX2, sapatos femininos, roupas, rel\u00f3gio de pulso, um laptop da Apple e mais USD 50.000 (cinquenta mil d\u00f3lares), como oferta para a sua \u201capaixonada\u201d.<\/p>\n<p style=\"text-align: justify;\">Mais tarde, caiu em sua caixa, uma mensagem de uma suposta alf\u00e2ndega sul-africana, representada por um nigeriano n\u00e3o identificado, a instar que a psic\u00f3loga fizesse o pagamento, por transfer\u00eancia banc\u00e1ria, de 4.200,00 rands, para desalfandegar a sua mercadoria, vinda dos EUA.<\/p>\n<p style=\"text-align: justify;\">\u201cQuando a oferta \u00e9 demais, o santo desconfia\u201d, este dito popular cumpriu-se na vida de Domingas, que percebeu estar diante de uma burla. \u201cDescobri que era burla, porque ele disse que dentro da caixa tinha 50 mil USD e, tamb\u00e9m, pela press\u00e3o que me fazia\u201d, revelou, acrescentando que reencaminhou o texto para o ofertante e, supostamente, ficou muito irado, porque o tempo todo insistia em saber se j\u00e1 havia recebido a oferta.<\/p>\n<p style=\"text-align: justify;\">Domingas Gabriela recusou-se a fazer o pagamento. \u201cPela forma insistente, facilmente percebi que a sua preocupa\u00e7\u00e3o n\u00e3o era o presente, mas sim o meu dinheiro\u201d.<\/p>\n<p style=\"text-align: justify;\">Como artimanha, depois de perceber que foi descoberta a sua real inten\u00e7\u00e3o, amea\u00e7ou colocar as fotografias da profissional nas redes sociais e estragar a sua vida. \u201cHoje, com o avan\u00e7o da tecnologia, eu receio que ele use as minhas fotos em exerc\u00edcio profissional para fazer maldade\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">Cristina Maria tamb\u00e9m travou uma burla, quando, procurando artigos para um sal\u00e3o de beleza que est\u00e1 a montar, obteve o contacto de whatsapp de algu\u00e9m que faz um pre\u00e7o muito abaixo do mercado. \u201cEle mostrava as fotos e os respectivos pre\u00e7os, alguns eram a metade do que se faz nas pra\u00e7as e outros mais baixos ainda\u201d.<\/p>\n<p style=\"text-align: justify;\">Entretanto, o primeiro ponto que chamou a sua aten\u00e7\u00e3o foi quando perguntou a localiza\u00e7\u00e3o da loja ou armaz\u00e9m de vendas, para l\u00e1 ir e escolher tudo a dedo. \u201cEle come\u00e7ou a enrolar\u2026 Perguntou-me onde vivo, eu respondi, s\u00f3 assim me disse que a sua loja est\u00e1 em Viana. Perguntei-lhe se trabalham todos os dias, respondeu positivamente, ent\u00e3o lhe falei que iria para l\u00e1 na segunda-feira. A\u00ed disse que na segunda n\u00e3o trabalhariam, porque o chefe estava ausente, tentei dar alternativa para outro dia, ele dava desculpas e insistia que era s\u00f3 fazer o pagamento que eu receberia o material em casa\u201d, conta.<\/p>\n<p style=\"text-align: justify;\">Muito atenta, disse, apercebeu-se logo que era burla e p\u00f4s um ponto final ao contacto. \u201c\u00c9 preciso que estejamos atentos a tudo, os burladores n\u00e3o v\u00e3o desistir, \u00e0 medida que tudo vai ficar mais dif\u00edcil\u201d, apelou.<\/p>\n<p style=\"text-align: justify;\">Outro esquema usado pelos burladores tem sido com o novo aplicativo multicaixa-express. Devido \u00e0 sua facilidade de uso e m\u00faltiplas val\u00eancias, vem se tornando o favorito de pessoas que detestam fileiras para fazer pagamentos ou transfer\u00eancias.<\/p>\n<p style=\"text-align: justify;\">Raul Ad\u00e3o, que queria p\u00f4r \u00e0 venda o seu cami\u00e3o, cairia num esquema de extors\u00e3o, se n\u00e3o chamasse o seu filho, Miguel Ad\u00e3o, para intervir e averiguar se estava a lidar com pessoa s\u00e9ria.<\/p>\n<p style=\"text-align: justify;\">O suposto comprador orientou-o a adicionar o seu cart\u00e3o de cr\u00e9dito no referido aplicativo, por\u00e9m, associando um n\u00famero que ele, o burlador, forneceu. Desse jeito, o burlador teria total comando deste cart\u00e3o e gastaria o que l\u00e1 estivesse ao seu bel-prazer.<\/p>\n<p style=\"text-align: justify;\">\u201cPrimeira coisa a notar, deve ser a insist\u00eancia. Os burladores n\u00e3o querem esperar, eles insistem que fa\u00e7as a opera\u00e7\u00e3o, sob pena de procurarem outro vendedor, explica Miguel, que livrou o pai daquela farsa. \u201cEu tive de ligar ao senhor e amea\u00e7ar que era militar, que o conhecia e que o encontraria para lhe dar porrada. Depois disso, ele nunca mais ligou\u201d, finalizou.<\/p>\n<p style=\"text-align: justify;\"><strong>Todo o cuidado \u00e9 pouco<\/strong><\/p>\n<p style=\"text-align: justify;\">No entanto, sobre burlas n\u00e3o \u00e9 tudo, a Unitel confirmou que, nos \u00faltimos meses, tem se divulgado mensagens, associando a operadora e outras entidades a pr\u00e9mios e ganhos que n\u00e3o correspondem \u00e0 verdade, denunciando, assim, caos de burla.<\/p>\n<p style=\"text-align: justify;\">Por meio de mensagens de texto, os burladores, n\u00e3o identificados, indicam contactos telef\u00f3nicos para os quais se deve ligar, a fim de se levantar os supostos pr\u00e9mios. Entretanto, o objectivo desses \u00e9 que as pessoas visadas retomem as chamadas, para que percam para si muito saldo, por causa dos altos custos das chamadas internacionais.<\/p>\n<p style=\"text-align: justify;\">Nas redes sociais, \u00e9 muito comum ver p\u00e1ginas de empresas falsas ou pessoas singulares a publicitarem venda de mercadorias a pre\u00e7os irris\u00f3rios. Uma motorizada, que actualmente custa, mais ou menos, AKZ 300.000,00 (trezentos mil kwanzas), pode custar a metade do pre\u00e7o.<\/p>\n<p style=\"text-align: justify;\">Geralmente, nunca disp\u00f5em de um endere\u00e7o fixo, apenas o terminal, telef\u00f3nico a partir do qual orientam que se fa\u00e7a uma transfer\u00eancia banc\u00e1ria. Feita a opera\u00e7\u00e3o, maior parte deles torna-se incomunic\u00e1vel. Esta rede busca por qualquer meio, para extorquir o dinheiro de quem procura por um servi\u00e7o ou produto ao menor custo poss\u00edvel.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, h\u00e1 quem oferece oportunidades de emprego em v\u00e1rias \u00e1reas departamentais. Usam, muitas vezes, nome de institui\u00e7\u00f5es para ati\u00e7ar o desejo dos potenciais visados.<\/p>\n<p style=\"text-align: justify;\">Neste sentido, o Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC), numa nota de imprensa, real\u00e7a que \u201cmuitos cidad\u00e3os t\u00eam sido v\u00edtimas de crimes de burla por neg\u00f3cios via Internet, atra\u00eddos por baixos pre\u00e7os de determinados produtos, sem verificarem a idoneidade das empresas ou comerciantes que promovem a venda de tais produtos\u201d, reza a nota.<\/p>\n<p style=\"text-align: justify;\">Segundo o documento, o SIC, atrav\u00e9s do seu contacto associado \u00e0 p\u00e1gina do Facebook e dos seus piquetes, tem estado a receber v\u00e1rias queixas de pessoas burladas, mediante transfer\u00eancia, via multicaixa-express, de valores das suas contas banc\u00e1rias, depois de terem recebido instru\u00e7\u00f5es telef\u00f3nicas para se dirigir a um ATM.<\/p>\n<p style=\"text-align: justify;\">O SIC assevera que, no \u00e2mbito das suas compet\u00eancias, tudo tem feito no sentido de responsabilizar criminalmente os autores destes actos, pelo que espera continuar a receber a colabora\u00e7\u00e3o de todos para, de forma implac\u00e1vel, n\u00e3o dar tr\u00e9guas a esses malfeitores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde emprego a terrenos, os burladores v\u00eam utilizando, cada vez mais, n\u00e3o s\u00f3 a tecnologia, como tamb\u00e9m \u201cpaix\u00f5es\u201d pelas v\u00edtimas, de forma a alici\u00e1-las mais facilmente. Domingas Gabriela, psic\u00f3loga cl\u00ednica e orientadora vocacional, foi-lhe declarada \u201camor\u201d, por meio de ofertas aliciantes. Por: Jaime Tabo Presumivelmente, em cena estava uma dupla estrangeira, um americano e outro nigeriano. Domingas recebeu, na sua conta empresarial, um contacto identificado por James Peter\u00b4s, supostamente americano, que se passava de cliente, solicitando, em portugu\u00eas, o seu whatsapp pessoal. Dias depois, al\u00e9m de cliente, mostrava interesses conjugais, tentando fazer crer que estava totalmente apaixonado pela psic\u00f3loga. Desta [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Desde emprego a terrenos, os burladores v\u00eam utilizando, cada vez mais, n\u00e3o s\u00f3 a tecnologia, como tamb\u00e9m \u201cpaix\u00f5es\u201d pelas v\u00edtimas, de forma a alici\u00e1-las mais facilmente. Domingas Gabriela, psic\u00f3loga cl\u00ednica e orientadora vocacional, foi-lhe declarada \u201camor\u201d, por meio de ofertas aliciantes. Por: Jaime Tabo Presumivelmente, em cena estava uma dupla estrangeira, um americano e outro nigeriano. Domingas recebeu, na sua conta empresarial, um contacto identificado por James Peter\u00b4s, supostamente americano, que se passava de cliente, solicitando, em portugu\u00eas, o seu whatsapp pessoal. Dias depois, al\u00e9m de cliente, mostrava interesses conjugais, tentando fazer crer que estava totalmente apaixonado pela psic\u00f3loga. Desta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-26T16:02:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-26T16:02:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/20-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"453\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O\",\"datePublished\":\"2020-12-26T16:02:05+00:00\",\"dateModified\":\"2020-12-26T16:02:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/\"},\"wordCount\":1152,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20-1.jpg\",\"articleSection\":[\"SOCIEDADE\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/\",\"name\":\"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20-1.jpg\",\"datePublished\":\"2020-12-26T16:02:05+00:00\",\"dateModified\":\"2020-12-26T16:02:41+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20-1.jpg\",\"width\":453,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/burladores-digitais-aprimoram-metodos-de-extorsao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/","og_locale":"pt_PT","og_type":"article","og_title":"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O - Jornal O Crime","og_description":"Desde emprego a terrenos, os burladores v\u00eam utilizando, cada vez mais, n\u00e3o s\u00f3 a tecnologia, como tamb\u00e9m \u201cpaix\u00f5es\u201d pelas v\u00edtimas, de forma a alici\u00e1-las mais facilmente. Domingas Gabriela, psic\u00f3loga cl\u00ednica e orientadora vocacional, foi-lhe declarada \u201camor\u201d, por meio de ofertas aliciantes. Por: Jaime Tabo Presumivelmente, em cena estava uma dupla estrangeira, um americano e outro nigeriano. Domingas recebeu, na sua conta empresarial, um contacto identificado por James Peter\u00b4s, supostamente americano, que se passava de cliente, solicitando, em portugu\u00eas, o seu whatsapp pessoal. Dias depois, al\u00e9m de cliente, mostrava interesses conjugais, tentando fazer crer que estava totalmente apaixonado pela psic\u00f3loga. Desta [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/","og_site_name":"Jornal O Crime","article_published_time":"2020-12-26T16:02:05+00:00","article_modified_time":"2020-12-26T16:02:41+00:00","og_image":[{"width":453,"height":312,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/20-1.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O","datePublished":"2020-12-26T16:02:05+00:00","dateModified":"2020-12-26T16:02:41+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/"},"wordCount":1152,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/20-1.jpg","articleSection":["SOCIEDADE"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/","url":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/","name":"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/20-1.jpg","datePublished":"2020-12-26T16:02:05+00:00","dateModified":"2020-12-26T16:02:41+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/20-1.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2020\/12\/20-1.jpg","width":453,"height":312},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/burladores-digitais-aprimoram-metodos-de-extorsao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"BURLADORES \u201cDIGITAIS\u201d APRIMORAM M\u00c9TODOS DE EXTORS\u00c3O"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=2888"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/2888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/2889"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=2888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=2888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=2888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}