{"id":3070,"date":"2021-04-20T19:46:33","date_gmt":"2021-04-20T18:46:33","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=3070"},"modified":"2021-04-20T21:28:44","modified_gmt":"2021-04-20T20:28:44","slug":"depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/","title":{"rendered":"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><a href=\"https:\/\/jornalocrime.com\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3025\" src=\"https:\/\/jornalocrime.com\/wp-content\/uploads\/2021\/01\/DSC_0546-300x183.jpg\" alt=\"\" width=\"300\" height=\"183\" srcset=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546-300x183.jpg 300w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546-1024x625.jpg 1024w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546-768x469.jpg 768w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546-1536x938.jpg 1536w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546-400x244.jpg 400w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg 1843w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Depois de dois meses de julgamento, a primeira inst\u00e2ncia deu por assente que Vivaldo Lu\u00eds Domingos assassinou a estudante \u00c9rica Bas\u00edlio e o condenou a 17 anos de pris\u00e3o maior, pena com efeito suspensivo, por conta do recurso interposto pela defesa do r\u00e9u.<\/h3>\n<p style=\"text-align: justify;\">Felicidade Kauanda<\/p>\n<p style=\"text-align: justify;\">Nos termos do ac\u00f3rd\u00e3o, lido pela ju\u00edza Isabel Tona, na 14\u00aa Sec\u00e7\u00e3o do Tribunal de Comarca, situado no Benfica, ficou efectivamente provado que Vivaldo Lu\u00eds Domingos, ao desferir a facada contra \u00c9rica Bas\u00edlio, f\u00ea-lo com clara inten\u00e7\u00e3o de exclu\u00ed-la do mundo dos vivos, cabendo-lhe, ent\u00e3o, o crime de homic\u00eddio volunt\u00e1rio simples.<br \/>\nO r\u00e9u, que at\u00e9 \u00e0 pen\u00faltima audi\u00eancia arrogava-se inocente, foi igualmente condenado a pagar, no prazo de 6 meses, o montante AKZ 2.000.000,00 (dois milh\u00f5es de kwanzas) \u00e0 fam\u00edlia da malograda, assim como ao pagamento de AKZ 70.000,00 (setenta mil kwanzas) de taxa de justi\u00e7a. Descontente, Ant\u00f3nio Soma, defensor de Vivaldo, interp\u00f4s recurso, com efeito suspensivo.<br \/>\nEntretanto, depois da publica\u00e7\u00e3o do ac\u00f3rd\u00e3o, a express\u00e3o de dor e amargura permanecia nos rostos dos familiares de \u00c9rica, que ainda convivem com o trauma da perda irrepar\u00e1vel e prematura da sua ente. Solicitados, por este jornal, a se pronunciarem sobre a senten\u00e7a, falaram que apenas o fariam depois da decis\u00e3o do tribunal da segunda inst\u00e2ncia. Argumento tamb\u00e9m dito por Ant\u00f3nio Soma, advogado de Vivaldo.<br \/>\nRelembramos que as circunst\u00e2ncias do crime se deram na virada de ano 2019-2020, quando, pelas 19 horas do dia 31 de Dezembro, Vivaldo Domingos, junto dos amigos, Francisco Jos\u00e9 Henriques, Jos\u00e9 Alfredo Jorge, Marcos Jos\u00e9 Fernando Pedro Augusto Domingos e mais quatro raparigas, conhecidas apenas por Teresa, Mad\u00f3, Mami e No\u00e9mia, chegaram \u00e0 Ilha do Mussulo, para comemorarem ano que chegaria.<br \/>\nEntretanto, \u00e0 meia-noite do dia 1 de Janeiro, os amigos de Vivaldo decidiram tirar fotografias entre eles, enquanto ele separou-se e p\u00f4s-se a caminhar pela praia com uma garrafa de u\u00edsque.<br \/>\nQuando eram 4 horas, \u00c9rica Bas\u00edlio, que achava-se tamb\u00e9m na Ilha numa festa de reveillion, realizada no espa\u00e7o Bruno Ouro, na rua \u2018Boia Amarela\u2019, pediu a sua amiga, Daniela Loiro, que a acompanhasse a procurar algum s\u00edtio onde ela poderia urinar, uma vez que as casas de banho do local estavam sujas.<br \/>\nPostas numa via estreita, foram surpreendidas por dois jovens que as queriam violar sexualmente, entre eles Vivaldo, que trajava um cal\u00e7\u00e3o branco, e o comparsa n\u00e3o identificado, que vestia um cal\u00e7\u00e3o de cor laranja, e usava turbante da mesma cor na cabe\u00e7a.<br \/>\nNa sequ\u00eancia, Vivaldo agarrou \u00c9rica pelos cabelos, enquanto o outro agarrou a m\u00e3o de Daniela. Num esfor\u00e7o para escaparem dos algozes, Vivaldo, que empunhava uma faca, golpeou \u00c9rica na regi\u00e3o do t\u00f3rax, causando-lhe um ferimento grave. N\u00e3o obstante, conseguiram fugir, por\u00e9m, pouco tempo depois, Daniela se apercebeu do ferimento da amiga, j\u00e1 que, enquanto corriam, aquela dava passos lentos, notando, depois, que estava manchada de sangue.<br \/>\nActo cont\u00ednuo, Daniela pediu ajuda aos participantes da festa que, imediatamente, levaram \u00c9rica ao Centro M\u00e9dico dos Bombeiros da Ilha do Mussulo, transportando-a numa viatura de marca Toyota prado, de cor branca. Tendo em conta a gravidade do ferimento, foi transferida para Cl\u00ednica Girassol. Pelo caminho, \u00c9rica foi perdendo os sinais vitais, tendo conhecido a morte quando chegou.<br \/>\nDe frisar que, embora Daniela tenha passado por trauma e ter precisado, inclusive, de ajuda profissional para recupera\u00e7\u00e3o, passado um ano desde o infort\u00fanio, conseguiu reconhecer Vivaldo, em audi\u00eancia de julgamento, como sendo o assassino de \u00c9rica.<br \/>\nOs factos trazidos ao tribunal n\u00e3o esclareceram a localiza\u00e7\u00e3o da arma do crime, quem foi o comparsa de Vivaldo, nem onde ele conseguiu a faca que usou, uma vez que o tribunal deu como n\u00e3o provada a confiss\u00e3o de Vivaldo na fase de instru\u00e7\u00e3o, segundo a qual, retirou de uma senhora que vendia frango grelhado no local.<br \/>\nAdemais, o \u00faltimo declarante, Mois\u00e9s Quissoca, 2\u00ba Comandante dos Servi\u00e7os de Protec\u00e7\u00e3o Civil e Bombeiros, na altura colocado no Mussulo, que apenas compareceu ao tribunal depois de v\u00e1rias notifica\u00e7\u00f5es, tendo, inclusive, se emitido mandado de captura, n\u00e3o soube esclarecer as circunst\u00e2ncias que Vivaldo foi detido, nem qual dos seus efectivos procedeu \u00e0 deten\u00e7\u00e3o. Entretanto, disse que n\u00e3o reconhecia o acusado e que n\u00e3o se lembrava que crime cometeu. \u201c\u00c9 poss\u00edvel que os outros saibam a raz\u00e3o do r\u00e9u ter sido capturado, n\u00e3o me lembro dele, nem t\u00e3o pouco do que fez\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Quem era Erica Patr\u00edcio Bas\u00edlio<\/strong><br \/>\nNascida em Luanda, aos 19 de Julho, \u00c9rica Patr\u00edcio Chambula Bas\u00edlio foi uma jovem estudiosa que, depois de concluir o ensino m\u00e9dio na Escola Portuguesa, em Luanda, foi para Inglaterra, onde frequentava o 2\u00ba ano do curso de Engenharia Biom\u00e9dica, tendo vindo a Angola, apenas para passar a \u00e9poca festiva e visitar a fam\u00edlia.<br \/>\nAmante de todo tipo de arte, os livros eram a sua grande paix\u00e3o e a m\u00fasica o seu ref\u00fagio. Segundo a nossa fonte que preferiu anonimato, \u00c9rica era alegre, amiga dos amigos, dona de um futuro promissor e uma verdadeira caixa de surpresa, pois, apesar do curso superior que fazia, tinha m\u00e3os de fada na culin\u00e1ria, sendo que era considerada uma boa chefe de cozinha.<br \/>\nDentre as suas qualidades, destacavam-se o facto de ser muito sonhadora e persistente, pois, nunca desistia dos seus desafios. Por ser muito alegre, era vista como fonte de energia para os outros, especialmente para as amigas, de quem era muito companheira e leal.<\/p>\n<p style=\"text-align: justify;\"><strong>Conhe\u00e7a o suposto assassino<\/strong><br \/>\nVivaldo Lu\u00eds Domingos, 23 anos de idade, tamb\u00e9m conhecido por Vivi, nasceu na prov\u00edncia de Kwanza Norte. Antes de preso, residia em Luanda, no bairro S\u00e3o Pedro da Barra, Distrito do Sambizanga, rua da Jamaica.<br \/>\n\u00c9 pai de um filho e, para ganhar a vida, trabalhava como ajudante de pedreiro. Considerado pelos amigos como pessoa de trato f\u00e1cil, alegre e bom companheiro, n\u00e3o fumava, apenas consumia bebidas alco\u00f3licas. O homic\u00eddio de \u00c9rica \u00e9 o primeiro a constar do seu registo criminal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de dois meses de julgamento, a primeira inst\u00e2ncia deu por assente que Vivaldo Lu\u00eds Domingos assassinou a estudante \u00c9rica Bas\u00edlio e o condenou a 17 anos de pris\u00e3o maior, pena com efeito suspensivo, por conta do recurso interposto pela defesa do r\u00e9u. Felicidade Kauanda Nos termos do ac\u00f3rd\u00e3o, lido pela ju\u00edza Isabel Tona, na 14\u00aa Sec\u00e7\u00e3o do Tribunal de Comarca, situado no Benfica, ficou efectivamente provado que Vivaldo Lu\u00eds Domingos, ao desferir a facada contra \u00c9rica Bas\u00edlio, f\u00ea-lo com clara inten\u00e7\u00e3o de exclu\u00ed-la do mundo dos vivos, cabendo-lhe, ent\u00e3o, o crime de homic\u00eddio volunt\u00e1rio simples. O r\u00e9u, que at\u00e9 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Depois de dois meses de julgamento, a primeira inst\u00e2ncia deu por assente que Vivaldo Lu\u00eds Domingos assassinou a estudante \u00c9rica Bas\u00edlio e o condenou a 17 anos de pris\u00e3o maior, pena com efeito suspensivo, por conta do recurso interposto pela defesa do r\u00e9u. Felicidade Kauanda Nos termos do ac\u00f3rd\u00e3o, lido pela ju\u00edza Isabel Tona, na 14\u00aa Sec\u00e7\u00e3o do Tribunal de Comarca, situado no Benfica, ficou efectivamente provado que Vivaldo Lu\u00eds Domingos, ao desferir a facada contra \u00c9rica Bas\u00edlio, f\u00ea-lo com clara inten\u00e7\u00e3o de exclu\u00ed-la do mundo dos vivos, cabendo-lhe, ent\u00e3o, o crime de homic\u00eddio volunt\u00e1rio simples. O r\u00e9u, que at\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T18:46:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T20:28:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1843\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O\",\"datePublished\":\"2021-04-20T18:46:33+00:00\",\"dateModified\":\"2021-04-20T20:28:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/\"},\"wordCount\":1064,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/DSC_0546.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/\",\"name\":\"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/DSC_0546.jpg\",\"datePublished\":\"2021-04-20T18:46:33+00:00\",\"dateModified\":\"2021-04-20T20:28:44+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/DSC_0546.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/DSC_0546.jpg\",\"width\":1843,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/","og_locale":"pt_PT","og_type":"article","og_title":"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O - Jornal O Crime","og_description":"Depois de dois meses de julgamento, a primeira inst\u00e2ncia deu por assente que Vivaldo Lu\u00eds Domingos assassinou a estudante \u00c9rica Bas\u00edlio e o condenou a 17 anos de pris\u00e3o maior, pena com efeito suspensivo, por conta do recurso interposto pela defesa do r\u00e9u. Felicidade Kauanda Nos termos do ac\u00f3rd\u00e3o, lido pela ju\u00edza Isabel Tona, na 14\u00aa Sec\u00e7\u00e3o do Tribunal de Comarca, situado no Benfica, ficou efectivamente provado que Vivaldo Lu\u00eds Domingos, ao desferir a facada contra \u00c9rica Bas\u00edlio, f\u00ea-lo com clara inten\u00e7\u00e3o de exclu\u00ed-la do mundo dos vivos, cabendo-lhe, ent\u00e3o, o crime de homic\u00eddio volunt\u00e1rio simples. O r\u00e9u, que at\u00e9 [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/","og_site_name":"Jornal O Crime","article_published_time":"2021-04-20T18:46:33+00:00","article_modified_time":"2021-04-20T20:28:44+00:00","og_image":[{"width":1843,"height":1125,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O","datePublished":"2021-04-20T18:46:33+00:00","dateModified":"2021-04-20T20:28:44+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/"},"wordCount":1064,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/","url":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/","name":"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg","datePublished":"2021-04-20T18:46:33+00:00","dateModified":"2021-04-20T20:28:44+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/01\/DSC_0546.jpg","width":1843,"height":1125},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-condenado-a-17-anos-de-prisao-maior-advogado-de-assassino-de-erica-basilio-recorre-da-decisao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Depois de condenado a 17 anos de pris\u00e3o maior ADVOGADO DE ASSASSINO DE \u00c9RICA BAS\u00cdLIO RECORRE DA DECIS\u00c3O"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=3070"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/3025"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=3070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=3070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=3070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}