{"id":3719,"date":"2021-07-05T23:28:44","date_gmt":"2021-07-05T22:28:44","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=3719"},"modified":"2021-07-05T23:28:44","modified_gmt":"2021-07-05T22:28:44","slug":"depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/","title":{"rendered":"Depois de estuprar uma menor:  CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>O Tribunal de Comarca de Luanda, Sala dos Crimes Comuns, condenou Ant\u00f3nio Roque Domingos, tamb\u00e9m conhecido por Didi, de 65<span class=\"Apple-converted-space\">\u00a0 <\/span>anos de idade, pelo estupro de uma menor de 14 anos, no Rangel.<\/b><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"text-decoration: underline;\"><b><span class=\"Apple-converted-space\">\u00a0<\/span>Felicidade Kauanda<\/b><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">A\u00a0hist\u00f3ria remonta o ano 2019, em dia n\u00e3o preciso, no bairro Madeira, Distrito Urbano do Rangel, rua da Brigada, quando, Ant\u00f3nio Roque Domingos \u2018Didi\u2019, que, antes de preso, vivia sozinho, na qualidade de vizinho de Edmazia Domingos, irm\u00e3 mais velha da lesada, Joana Pascoal (nome fict\u00edcio), com quem esta vivia, frequentava a casa destas, pois era tido como membro da fam\u00edlia, por se mostrar pessoa de confian\u00e7a e solid\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">Aproveitando-se da inoc\u00eancia de Joana, por duas vezes aliciou-a com 500 e 1000 kwanzas e passou a convid\u00e1-la para a sua resid\u00eancia. Quando a\u00ed chegavam, levava-la seu quarto, mandava que se deitasse de barriga para cima na sua cama, despia-a e mantinha rela\u00e7\u00f5es sexuais com a menor, sob amea\u00e7as de morte.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<blockquote><p><b>Contudo, agravam o comportamento criminal do r\u00e9u, as circunst\u00e2ncias: 11.\u00aa crime cometido com surpresa, 25.\u00aa cometido por algu\u00e9m que tem a obriga\u00e7\u00e3o de o n\u00e3o cometer, sendo que a diferen\u00e7a de idade entre ambos diz tudo, todas do artigo 34.\u00ba do C\u00f3digo Penal.<span class=\"Apple-converted-space\">\u00a0 <\/span>A seu favor, atenuam as circunst\u00e2ncias: 1\u00aa aus\u00eancia de antecedentes criminais, 23.\u00ba baixa condi\u00e7\u00e3o social, do artigo 39.\u00ba do C\u00f3digo Penal.<\/b><\/p><\/blockquote>\n<p style=\"text-align: justify;\">Em audi\u00eancia de julgamento, o idoso negou os factos, alegando que a menor era apenas sua amiga, por serem vizinhos, enquanto que esta refutou tal argumento, ao afirmar, \u00e0 inst\u00e2ncia do Minist\u00e9rio P\u00fablico, que o acusado a amea\u00e7ava de morte, dizendo \u201cse voc\u00ea se queixar, vou matar a sua irm\u00e3\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Foi pelo medo, conta, que aceitou, nas duas vezes,<span class=\"Apple-converted-space\">\u00a0 <\/span>manter rela\u00e7\u00f5es sexuais com aquele sem o uso de preservativo, acrescentando que, numa das ocasi\u00f5es, o r\u00e9u ejaculou na sua cavidade vaginal e noutra, fora.<\/p>\n<p style=\"text-align: justify;\"><span class=\"Apple-converted-space\">\u00a0<\/span>Ademais, confessou, diante do Minist\u00e9rio P\u00fablico e do consult\u00f3rio onde foi examinada que, at\u00e9 ao momento que o r\u00e9u a violou, era virgem, pois, nunca teve rela\u00e7\u00f5es sexuais, sendo o acusado o autor do seu desfloramento, facto, igualmente, confirmado pelos exames a que foi submetida, constantes dos autos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Segundo o tribunal, dos autos, ilustra-se, claramente, que o acusado agiu livre e voluntariamente, na pr\u00e1tica do crime do estupro, pois, para al\u00e9m das declara\u00e7\u00f5es prestadas pela ofendida, o tribunal formou a sua convic\u00e7\u00e3o nos depoimentos do r\u00e9u. Portanto, fazendo uso das regras de conviv\u00eancias comum, aquela inst\u00e2ncia concluiu que est\u00e3o reunidos os pressupostos do crime de que vem acusado, pronunciado e julgado.<\/p>\n<p style=\"text-align: justify;\">Assim, sua conduta \u00e9 subsum\u00edvel ao crime de estupro, que \u00e9 punido com a pena de 2 a 8 anos de pris\u00e3o maior. Contudo, agravam o comportamento criminal do r\u00e9u, as circunst\u00e2ncias: 11.\u00aa crime cometido com surpresa, 25.\u00aa cometido por algu\u00e9m que tem a obriga\u00e7\u00e3o de o n\u00e3o cometer, sendo que a diferen\u00e7a de idade entre ambos diz tudo, todas do artigo 34.\u00ba do C\u00f3digo Penal.<span class=\"Apple-converted-space\">\u00a0 <\/span>A seu favor, atenuam as circunst\u00e2ncias: 1\u00aa aus\u00eancia de antecedentes criminais, 23.\u00ba baixa condi\u00e7\u00e3o social, do artigo 39.\u00ba do C\u00f3digo Penal.<\/p>\n<p style=\"text-align: justify;\">Importa<span class=\"Apple-converted-space\">\u00a0 <\/span>frisar que, tamb\u00e9m, na fase de instru\u00e7\u00e3o prim\u00e1ria, Ant\u00f3nio Roque Domingos \u2018Didi\u2019 n\u00e3o confessou o crime nem demonstrou arrependimento. Al\u00e9m dos 4 anos de pris\u00e3o, foi condenado ao pagamento de AKZ 200.000,00 (duzentos mil kwanzas) de indemniza\u00e7\u00e3o \u00e0 menor lesada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Comarca de Luanda, Sala dos Crimes Comuns, condenou Ant\u00f3nio Roque Domingos, tamb\u00e9m conhecido por Didi, de 65\u00a0 anos de idade, pelo estupro de uma menor de 14 anos, no Rangel. \u00a0Felicidade Kauanda A\u00a0hist\u00f3ria remonta o ano 2019, em dia n\u00e3o preciso, no bairro Madeira, Distrito Urbano do Rangel, rua da Brigada, quando, Ant\u00f3nio Roque Domingos \u2018Didi\u2019, que, antes de preso, vivia sozinho, na qualidade de vizinho de Edmazia Domingos, irm\u00e3 mais velha da lesada, Joana Pascoal (nome fict\u00edcio), com quem esta vivia, frequentava a casa destas, pois era tido como membro da fam\u00edlia, por se mostrar pessoa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O Tribunal de Comarca de Luanda, Sala dos Crimes Comuns, condenou Ant\u00f3nio Roque Domingos, tamb\u00e9m conhecido por Didi, de 65\u00a0 anos de idade, pelo estupro de uma menor de 14 anos, no Rangel. \u00a0Felicidade Kauanda A\u00a0hist\u00f3ria remonta o ano 2019, em dia n\u00e3o preciso, no bairro Madeira, Distrito Urbano do Rangel, rua da Brigada, quando, Ant\u00f3nio Roque Domingos \u2018Didi\u2019, que, antes de preso, vivia sozinho, na qualidade de vizinho de Edmazia Domingos, irm\u00e3 mais velha da lesada, Joana Pascoal (nome fict\u00edcio), com quem esta vivia, frequentava a casa destas, pois era tido como membro da fam\u00edlia, por se mostrar pessoa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T22:28:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0547-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA\",\"datePublished\":\"2021-07-05T22:28:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/\"},\"wordCount\":600,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0547-scaled.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/\",\"name\":\"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0547-scaled.jpg\",\"datePublished\":\"2021-07-05T22:28:44+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0547-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0547-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/","og_locale":"pt_PT","og_type":"article","og_title":"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA - Jornal O Crime","og_description":"O Tribunal de Comarca de Luanda, Sala dos Crimes Comuns, condenou Ant\u00f3nio Roque Domingos, tamb\u00e9m conhecido por Didi, de 65\u00a0 anos de idade, pelo estupro de uma menor de 14 anos, no Rangel. \u00a0Felicidade Kauanda A\u00a0hist\u00f3ria remonta o ano 2019, em dia n\u00e3o preciso, no bairro Madeira, Distrito Urbano do Rangel, rua da Brigada, quando, Ant\u00f3nio Roque Domingos \u2018Didi\u2019, que, antes de preso, vivia sozinho, na qualidade de vizinho de Edmazia Domingos, irm\u00e3 mais velha da lesada, Joana Pascoal (nome fict\u00edcio), com quem esta vivia, frequentava a casa destas, pois era tido como membro da fam\u00edlia, por se mostrar pessoa [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/","og_site_name":"Jornal O Crime","article_published_time":"2021-07-05T22:28:44+00:00","og_image":[{"width":1707,"height":2560,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0547-scaled.jpg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA","datePublished":"2021-07-05T22:28:44+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/"},"wordCount":600,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0547-scaled.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/","url":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/","name":"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0547-scaled.jpg","datePublished":"2021-07-05T22:28:44+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0547-scaled.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0547-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/depois-de-estuprar-uma-menor-cidadao-de-65-sentenciado-a-4-anos-de-prisao-efectiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Depois de estuprar uma menor: CIDAD\u00c3O DE 65 SENTENCIADO A 4 ANOS DE PRIS\u00c3O EFECTIVA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=3719"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3719\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/3720"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=3719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=3719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=3719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}