{"id":3744,"date":"2021-07-06T00:06:42","date_gmt":"2021-07-05T23:06:42","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=3744"},"modified":"2021-07-06T00:06:42","modified_gmt":"2021-07-05T23:06:42","slug":"em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/","title":{"rendered":"Em Cacuaco:  AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>Um 2.\u00ba subchefe da Pol\u00edcia Nacional de Angola (PNA) e um comerciante do oeste-africano foram assassinados por um grupo de seis marginais, durante uma tentativa de assalto no bairro da Cer\u00e2mica, arredores do munic\u00edpio de Cacuaco, em Luanda. O crime ocorreu na madrugada de domingo, 6.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"text-decoration: underline;\"><b>Engr\u00e1cia Francisco<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Para al\u00e9m do agente da corpora\u00e7\u00e3o Mois\u00e9s Augusto Grosso, de 35 anos, e do comerciante oeste-africano Mamadou Yaya Diallo, 47 anos, os marginais alvejaram, tamb\u00e9m, a esposa do efectivo, Rosalina Perp\u00e9tua, de 32 anos, no bra\u00e7o esquerdo, e encontra-se a recuperar no hospital.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">As duas fam\u00edlias que partilhavam o mesmo quintal, no bairro da Cer\u00e2mica, em Cacuaco, viveram uma madrugada aterrorizante, depois que seis marginais, fortemente armados, invadiram os seus domic\u00edlios.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Segundo contou uma testemunha, os meliantes chegaram por volta das duas da madrugada enquanto todos dormiam. A adolescente que descreveu o evento \u00e0 nossa reportagem, disse que estava a ver televis\u00e3o, quando ouviu um barulho vindo da rua. Na sequ\u00eancia, explicou, correu at\u00e9 ao quintal, espreitou por um orif\u00edcio do muro da sua casa, e viu quatro homens armados a dirigirem-se \u00e0 casa do senhor Mois\u00e9s.<\/p>\n<p style=\"text-align: justify;\">\u201cFizeram uma passagem entre as grades da marquise, e, dois deles, introduziram-se na resid\u00eancia, enquanto os outros dois aguardavam no port\u00e3o principal\u201d, elucidou, para depois dizer que, minutos depois, ouviu um disparo de arma de fogo vindo do interior da resid\u00eancia do agente da Pol\u00edcia Nacional. \u201cDepois do primeiro disparo, ouvi mais dois. Corri para acordar os meus pais, no mesmo instante, um dos jovens sa\u00eda pela mesma abertura por onde entrou\u201d, descreveu.<\/p>\n<p style=\"text-align: justify;\">Por seu turno, Domingos Sarrama, cunhado do agente da Pol\u00edcia Nacional Mois\u00e9s Grosso, disse que estava na cama quando os marginais escalaram o muro do quintal e introduziram-se nela. \u201cCorri para a sala onde estava o meu cunhado e a minha irm\u00e3, contei o que acabava de ouvir, mas eles ignoraram dizendo que se tratava de um gato a brincar no tecto\u201d, afirmou, para, seguidamente, dizer que instantes depois o seu cunhado ouviu passos no quintal e, t\u00e3o logo abriu a porta, os marginais<span class=\"Apple-converted-space\">\u00a0 <\/span>receberam-no com um tiro das costelas que perfurou o cora\u00e7\u00e3o.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Por outro lado, explicou, ao tentar aproximar-se junto ao esposo, foi tamb\u00e9m baleada no bra\u00e7o esquerdo e imediatamente fechou a porta. \u201cApesar do tiro, a minha irm\u00e3 foi \u00e1gil e fechou a porta porque os meus sobrinhos menores tamb\u00e9m estavam na sala a presenciar tudo\u201d, disse Domingos Sarrama.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Naquele triste acontecimento, juntou-se, tamb\u00e9m, o comerciante Mamadou Yaya Diallo, vizinho de Mois\u00e9s, que, ao procurar saber o que se estava a passar, foi igualmente baleado pelos marginais. De acordo com Domingos, o primeiro disparo atingiu o abd\u00f3men e o segundo as costelas, causando a sua morte imediata.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s concluir o acto macabro, disse a fonte que vimos citando, os meliantes, que se faziam transportar por uma carrinha de marca Toyota, modelo Hilux, retiraram-se do local sem, no entanto, levar algum pertence das v\u00edtimas.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">O acto, segundo Domingos Sarrama, foi presenciado pelos filhos menores dos dois homens mortos. \u201cO meu sobrinho ficou completamente traumatizado e tentava, em l\u00e1grimas, acordar o pai que estava estatelado ao ch\u00e3o j\u00e1 sem vida\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 Mamadou Alpha Diallo, primo de Mamadou Yaya Diallo, lamentou o ocorrido e clamou para que as autoridades encontrem os respons\u00e1veis por este b\u00e1rbaro crime. Mamadou Yaya Diallo foi a enterrar no dia 8 deste m\u00eas no cemit\u00e9rio do Benfica, enquanto Mois\u00e9s foi a enterrar no dia 9 no cemit\u00e9rio do 14, no Cazenga.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">O infort\u00fanio j\u00e1 \u00e9 de conhecimento das autoridades, que j\u00e1 instauraram o competente processo-crime (processo n.\u00ba 725-021 PGR), a fim de se apurar as motiva\u00e7\u00f5es deste duplo homic\u00eddio, bem como identificar os seus actores e responsabiliz\u00e1-los.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">No entanto, uma fonte da Pol\u00edcia Nacional confidenciou ao jornal O Crime que o assassinato do 2.\u00ba subchefe afecto ao Comando de Pol\u00edcia do Cazenga pode ser um acto de revanche, em fun\u00e7\u00e3o de algumas ac\u00e7\u00f5es praticadas por aquele cidad\u00e3o enquanto agente da Ordem. \u201cSabemos que ele gostava muito de prender motos, e isso pressup\u00f5es arranjar problemas, porque grande parte dos donos das motos s\u00e3o meliantes\u201d, elucidou.<\/p>\n<p style=\"text-align: justify;\">Ademais, segundo relato de alguns vizinhos, revelaram que nos \u00faltimos dias,<span class=\"Apple-converted-space\">\u00a0 <\/span>o antigo agente da PN mantinha-se muito isolado e pensativo, como se estivesse a passar por algum problema grave. \u201cInclusive, come\u00e7ou a beber muito, tornou-se uma pessoa irreconhec\u00edvel\u201d, contam. J\u00e1 outro vizinho afirmou ter visto, por volta das zero horas do mesmo dia, dois jovens estranhos a rondarem a rua como se estivessem \u00e0 procura de algu\u00e9m.<\/p>\n<h3 style=\"text-align: justify;\"><b>Esposa do agente da PN luta pela vida no hospital<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p style=\"text-align: justify;\">Rosalina Perpetua, de 32 anos de idade, esposa do 2.\u00ba subchefe da PN afecto ao Comando Municipal do Cazenga, foi tamb\u00e9m alvejada durante a ac\u00e7\u00e3o, e encontra-se nos cuidados intensivos do hospital Am\u00e9rico Boavida, uma vez que a bala que a atingiu ainda se encontra encravada no bra\u00e7o. \u201cOs m\u00e9dicos disseram que n\u00e3o podem fazer a cirurgia agora, pois ela ainda se contra bastante debilitada e perdeu muito sangue\u201d, disse Domingos Sarrama.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um 2.\u00ba subchefe da Pol\u00edcia Nacional de Angola (PNA) e um comerciante do oeste-africano foram assassinados por um grupo de seis marginais, durante uma tentativa de assalto no bairro da Cer\u00e2mica, arredores do munic\u00edpio de Cacuaco, em Luanda. O crime ocorreu na madrugada de domingo, 6.\u00a0 Engr\u00e1cia Francisco\u00a0 Para al\u00e9m do agente da corpora\u00e7\u00e3o Mois\u00e9s Augusto Grosso, de 35 anos, e do comerciante oeste-africano Mamadou Yaya Diallo, 47 anos, os marginais alvejaram, tamb\u00e9m, a esposa do efectivo, Rosalina Perp\u00e9tua, de 32 anos, no bra\u00e7o esquerdo, e encontra-se a recuperar no hospital.\u00a0 As duas fam\u00edlias que partilhavam o mesmo quintal, no [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Um 2.\u00ba subchefe da Pol\u00edcia Nacional de Angola (PNA) e um comerciante do oeste-africano foram assassinados por um grupo de seis marginais, durante uma tentativa de assalto no bairro da Cer\u00e2mica, arredores do munic\u00edpio de Cacuaco, em Luanda. O crime ocorreu na madrugada de domingo, 6.\u00a0 Engr\u00e1cia Francisco\u00a0 Para al\u00e9m do agente da corpora\u00e7\u00e3o Mois\u00e9s Augusto Grosso, de 35 anos, e do comerciante oeste-africano Mamadou Yaya Diallo, 47 anos, os marginais alvejaram, tamb\u00e9m, a esposa do efectivo, Rosalina Perp\u00e9tua, de 32 anos, no bra\u00e7o esquerdo, e encontra-se a recuperar no hospital.\u00a0 As duas fam\u00edlias que partilhavam o mesmo quintal, no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T23:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0203-1-910x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"910\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO\",\"datePublished\":\"2021-07-05T23:06:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/\"},\"wordCount\":885,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0203-1.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/\",\"name\":\"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0203-1.jpg\",\"datePublished\":\"2021-07-05T23:06:42+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0203-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/DSC_0203-1.jpg\",\"width\":2136,\"height\":2404},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/","og_locale":"pt_PT","og_type":"article","og_title":"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO - Jornal O Crime","og_description":"Um 2.\u00ba subchefe da Pol\u00edcia Nacional de Angola (PNA) e um comerciante do oeste-africano foram assassinados por um grupo de seis marginais, durante uma tentativa de assalto no bairro da Cer\u00e2mica, arredores do munic\u00edpio de Cacuaco, em Luanda. O crime ocorreu na madrugada de domingo, 6.\u00a0 Engr\u00e1cia Francisco\u00a0 Para al\u00e9m do agente da corpora\u00e7\u00e3o Mois\u00e9s Augusto Grosso, de 35 anos, e do comerciante oeste-africano Mamadou Yaya Diallo, 47 anos, os marginais alvejaram, tamb\u00e9m, a esposa do efectivo, Rosalina Perp\u00e9tua, de 32 anos, no bra\u00e7o esquerdo, e encontra-se a recuperar no hospital.\u00a0 As duas fam\u00edlias que partilhavam o mesmo quintal, no [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/","og_site_name":"Jornal O Crime","article_published_time":"2021-07-05T23:06:42+00:00","og_image":[{"width":910,"height":1024,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0203-1-910x1024.jpg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO","datePublished":"2021-07-05T23:06:42+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/"},"wordCount":885,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0203-1.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/","url":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/","name":"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0203-1.jpg","datePublished":"2021-07-05T23:06:42+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0203-1.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/07\/DSC_0203-1.jpg","width":2136,"height":2404},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/em-cacuaco-agente-da-pna-e-comerciante-estrangeiro-mortos-a-tiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Em Cacuaco: AGENTE DA PNA E COMERCIANTE ESTRANGEIRO MORTOS A TIRO"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=3744"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/3747"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=3744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=3744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=3744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}