{"id":3872,"date":"2021-08-02T02:25:54","date_gmt":"2021-08-02T01:25:54","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=3872"},"modified":"2021-08-02T02:25:54","modified_gmt":"2021-08-02T01:25:54","slug":"luanda-agora-e-residence-da-mboa-ana","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/","title":{"rendered":"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>Est\u00e1 na berra as exonera\u00e7\u00f5es no pa\u00eds, mormente a de governador de Luanda, e o que se fala e escreve perde-se como horas mortas; pior, soa a alertas em ouvidos moucos que despertar\u00e3o em pleno voo irrevers\u00edvel a consumar o suic\u00eddio.<\/b><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"text-decoration: underline;\"><span class=\"Apple-converted-space\">\u00a0<\/span><b>Liberato Furtado<\/b><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">No<span class=\"Apple-converted-space\">\u00a0 <\/span>consulado mais recente da governa\u00e7\u00e3o do pa\u00eds, a poucos meses de completar quatro anos, Luanda j\u00e1 experimentou tr\u00eas regentes e se apresta a mais uma, depois do \u00faltimo ensaio se ter mostrado um descalabro total que n\u00e3o deixar\u00e1 saudades, mas far\u00e1 levantar velhas mem\u00f3rias e perguntas entaladas.<\/p>\n<p style=\"text-align: justify;\">Se fez coro e dir\u00edamos sim, Luanda, efectivamente, tornou-se a casa da m\u00e3e Joana com a entrada de Joana Lina ao Pal\u00e1cio do Alto do Carmo da Mutamba, quando, atabalhoadamente, mexeu na colmeia de abelhas que \u00e9 o \u201cdossier lixo\u201d, que revirou e veio ao de cima o cheiro, as moscas e, consequentemente, doen\u00e7as, mortes e a desesperan\u00e7a por maior o andor\u2026<\/p>\n<p style=\"text-align: justify;\">Joana (Lixo), a olho de ver, demonstrou total despreparo para o cargo, insensibilidade de arrogante incompet\u00eancia e, tamb\u00e9m, nos parece que lhe ter\u00e1 animado a ambi\u00e7\u00e3o de procurar tirar o seu quinh\u00e3o dessa mina generosa, mas n\u00e3o foi, at\u00e9 nisso, competente.<\/p>\n<p style=\"text-align: justify;\">O seu defeito \u00e9 trabalhar, diria, despudoradamente, a ex-governadora de Luanda Joana Lina. O trabalho que deixa, entretanto, \u00e9 de remo\u00e7\u00e3o de toda a trapalhada que fez e do lixo que tornou as moscas obreiras com horas extras, emulando 24\/24 horas.<\/p>\n<p style=\"text-align: justify;\">Procuramos e convidamos \u00e0 obra, mas n\u00e3o encontramos realiza\u00e7\u00e3o que seja de Joana Lina. Que nos perdoe a incapacidade, nesse exerc\u00edcio c\u00edvico, mas, sinceramente, o<span class=\"Apple-converted-space\">\u00a0 <\/span>esfor\u00e7o foi feito no sentido, por\u00e9m,<span class=\"Apple-converted-space\">\u00a0 <\/span>para nosso desalento, por mais que matemos a cachola, n\u00e3o sobressai nenhuma virtude em seu legado.<\/p>\n<p style=\"text-align: justify;\">Tal como, a t\u00edtulo de exemplo, vem \u00e0 tona, e sem esfor\u00e7o algum, os feitos do jovem Luther Rescova, de in\u00edcio contestado por tudo e por nada, mas em poucos meses deixou marcas indel\u00e9veis no Prenda, no Ensino, aos mais velhos do Beiral e, antes que nos esque\u00e7amos, tamb\u00e9m ao caluanda marcou a div\u00edcia da sua empatia de quem quer governar, tudo em sentido contr\u00e1rio ao de Joana Lina.<\/p>\n<p style=\"text-align: justify;\">Em democracia, Joana Lina n\u00e3o seria exonerada com essa dignidade, mas sim pass\u00edvel de destitui\u00e7\u00e3o<span class=\"Apple-converted-space\">\u00a0 <\/span>por improbidade sanit\u00e1ria e, subsequentemente, julgada por alegada culpa por tantas mortes que derivam, cremos, da sua ominosa governa\u00e7\u00e3o, nos termos do n.\u00ba 2 do artigo 91.\u00ba da Constitui\u00e7\u00e3o da Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Improbidade sanit\u00e1ria se chama \u00e0 cola\u00e7\u00e3o, quando os actos do governante atentam contra a seguran\u00e7a sanit\u00e1ria dos governados. J\u00e1 quando os recursos p\u00fablicos n\u00e3o s\u00e3o geridos com probidade, da melhor forma ou de modo a acautelar a sa\u00fade do colectivo, como \u00e9 obriga\u00e7\u00e3o do gestor p\u00fablico, em outras paragens , poder-se-ia ainda associar o crime de responsabilidade, algo que em nossos dom\u00ednios \u00e9 coisa doutro mundo.<\/p>\n<p style=\"text-align: justify;\">Uma fonte em defesa de Joana Lina contou-nos que aquela cometeu as sandices no \u201cneg\u00f3cio do lixo\u201d, n\u00e3o por mote pr\u00f3prio, mas por voz de mando superior e, posteriormente, foi abandonada em mato sem cachorro.<\/p>\n<p style=\"text-align: justify;\">A ser verdade, ainda assim, n\u00e3o removemos uma v\u00edrgula nesse texto, porque acreditamos que s\u00f3 vem agregar outros itens ao pacote de incompet\u00eancias. Se servem do pa\u00eds, quando se espera que sejam servidores p\u00fablicos e,<span class=\"Apple-converted-space\">\u00a0 <\/span>\u201cpra bobear\u201d, a garantia do tacho sobrep\u00f5e-se a mais \u00ednfima dignidade\u2026 <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Em despedida \u00e0 Joana Lina, n\u00e3o ser\u00edamos mais fi\u00e9is que o poeta brasileiro, Greg\u00f3rio de Matos.<\/p>\n<h3 style=\"text-align: justify;\"><b>\u201c\u00c0 despedida do mau governo que fez o governador da Bahia\u201d (de Luanda\/nossa adapta\u00e7\u00e3o)<\/b><\/h3>\n<p style=\"text-align: justify;\"><i>Senhora Governadora Joana Lina (nossa adapta\u00e7\u00e3o)<span class=\"Apple-converted-space\">\u00a0<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i>\u201c Quem sobe ao alto lugar, que n\u00e3o merece,<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Homem sobe, asno vai, burro parece,<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Que o subir \u00e9 desgra\u00e7a muitas vezes.<\/i><\/p>\n<p style=\"text-align: justify;\"><i>A fortunilha, autora de entremezes<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Transp\u00f5e em burro o her\u00f3i que indigno cresce:<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Desanda a roda, e logo homem parece,<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Que \u00e9 discreta a fortuna em seus reveses.<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Homem sei eu que foi Vossenhoria,<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Quando o pisava da fortuna a roda,<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Burro foi ao subir t\u00e3o alto clima.<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Pois, alto! V\u00e1 descendo onde jazia,<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Ver\u00e1 quanto melhor se lhe acomoda<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Ser homem em baixo do que burro em cima\u201d.<\/i><\/p>\n<h3 style=\"text-align: justify;\">Governar Luanda<\/h3>\n<p style=\"text-align: justify;\">Para governar Luanda e mal justificar o desaire, muito se recorre ao \u00f3bice das interfer\u00eancias do poder concentrado, chamado \u00e0 li\u00e7a pela primeira vez pelo carism\u00e1tico escritor e pol\u00edtico Uanhenga Xitu, enquanto, tamb\u00e9m, governador de Luanda.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Naquela altura e at\u00e9 bem pouco tempo, ainda se podia engolir e atribuir alguma verdade nessa justificativa em determinados assuntos. Mas n\u00e3o pode servir de bode expiat\u00f3rio para todos os que descarrilam. J\u00e1 n\u00e3o \u00e9 uma verdade absoluta, se alguma vez foi, salvo melhor entendimento.<\/p>\n<p style=\"text-align: justify;\">Negamo-nos, por outro lado, a aceitar tamb\u00e9m que se mude governadores ao ritmo de fraldas descart\u00e1veis, fazendo v\u00e9nia \u00e0 falta de respeito \u00e0 eticidade dos processos na nossa j\u00e1 adulta independ\u00eancia e governa\u00e7\u00e3o feita por angolanos, que depois de mais de 40 anos ainda n\u00e3o se desenvencilhou do terreno lodoso.<\/p>\n<p style=\"text-align: justify;\">Sem que nos esque\u00e7amos de continuar a falar sobre a descontinuidade nos processos, que o faremos mais adiante, dir\u00edamos que o fandango que se observa na constante troca de governadores n\u00e3o respeita qualquer raz\u00e3o l\u00f3gica de governa\u00e7\u00e3o, tampouco demonstra intelig\u00eancia e estabilidade emotiva governativa.<\/p>\n<p style=\"text-align: justify;\">O jeito enviesado ou pouco ortodoxo com que se escolhe \u201co peru da vez\u201d (perdoe a analogia ou cola\u00e7\u00e3o) faz, cada vez mais, convencer-nos que o MPLA n\u00e3o conhece os seus quadros. \u00c9 lugar comum dizer-se que a meritocracia n\u00e3o faz aqui morada, que o seja e confirmamos, todavia, a esfera p\u00fablica, o Estado Democr\u00e1tico de Direito e o projecto na\u00e7\u00e3o n\u00e3o se compadece com tais derrapagens, as necessidades sociais n\u00e3o se rev\u00eaem nesse conceito que configura uma perspectiva individualista, isolada e partid\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">Hoje, Luanda, diante da conjuntura social, est\u00e1 \u00e0 beira de um ataque de nervos,<span class=\"Apple-converted-space\">\u00a0 <\/span>ou melhor, de um AVC isqu\u00e9mico (porque o hemorr\u00e1gico j\u00e1 ocorreu), que se manifestaria contra o MPLA. Assim, se esperava, na atitude retardada de se nomear novo maestro da prov\u00edncia, uma escolha sem margens para erro e com um presente que revolucionaria a governa\u00e7\u00e3o na capital do pa\u00eds.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Sem que sejamos paranormais, vamos dizer que n\u00e3o nos parece que tenha sido assim. Todavia, tamb\u00e9m \u00e9 justo que nos lembremos do caso Luther Rescova ou at\u00e9 mesmo An\u00edbal Rocha que, quando baixou voo no Pal\u00e1cio do Alto do Carmo da Mutamba, poucos lhe davam cr\u00e9dito.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Inobstante o benef\u00edcio da d\u00favida que assiste a novel governadora de Luanda, a despeito de como ser\u00e1 o seu desempenho ou que val\u00eancias traz, n\u00e3o \u00e9 demais lembrar que piar baixinho ter\u00e1 que ser a sua forma de estar e agir diante do famoso poder institu\u00eddo em Luanda e ser\u00e1 mais uma para o cadafalso.<\/p>\n<p style=\"text-align: justify;\">\u201cSumbal\u00e1\u201d Bento Bento e Adriano Mendes, a exemplo, reclamaram das interfer\u00eancias dos generais e companhia limitada\u2026 \u00e9 a Ana Paula de Carvalho sem gal\u00f5es ao ombro, na biografia ou no nome?! Preferimos engolir em seco essa esp\u00e9cie de premoni\u00e7\u00e3o daqui a alguns tempos, mas n\u00e3o vemos, \u00e0 partida, predicados que nos conven\u00e7am do contr\u00e1rio, n\u00e3o por falta de capacidade intelectual da governante, por\u00e9m, de outros adjectivos que imperativamente devem fazer parte do seu perfil e l\u00e1 nunca estiveram.<\/p>\n<p style=\"text-align: justify;\">Repetimos, as interfer\u00eancias n\u00e3o podem servir de resguardo das incompet\u00eancias que por l\u00e1 passaram, entretanto, de algum modo existem e n\u00e3o ser\u00e1 por belos olhos que elas se evaporam.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Luanda em seu comando precisa de algu\u00e9m que tenha lugar no Bureau Pol\u00edtico, Comit\u00e9 Central, no Conselho de Ministros, tenha \u2018Carte Blanche\u2019 e saiba usar os seus trunfos sem receios do que<span class=\"Apple-converted-space\">\u00a0 <\/span>pode vir a posteriori.<\/p>\n<p style=\"text-align: justify;\">Ocorre-nos que se quer uma mulher no cargo para capitalizar votos femininos, tendo em aten\u00e7\u00e3o a popula\u00e7\u00e3o votante de Luanda.<span class=\"Apple-converted-space\">\u00a0 <\/span>Sendo, que se fa\u00e7a muito bem o escrut\u00ednio, o momento n\u00e3o admite \u201cabu\u00e7aite\u201d.<\/p>\n<p style=\"text-align: justify;\">Ana Paula Chantre Luna de Carvalho, n\u00e3o sabemos se \u00e9 ilustre mas certos estamos que \u00e9 desconhecida, ter\u00e1 \u201cpeito\u201d? Estar\u00e1 temperada para governar Luanda\/pa\u00eds com a actual apelante situa\u00e7\u00e3o social<span class=\"Apple-converted-space\">\u00a0 <\/span>e as elei\u00e7\u00f5es \u00e0 perna?<span class=\"Apple-converted-space\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">A capital ter\u00e1 \u00e0 volta de dez milh\u00f5es de habitantes, ou seja, \u00e9 um pa\u00eds dentro d\u2019outro, por\u00e9m, o centro das aten\u00e7\u00f5es. Para a governar, tem de ser um presidenci\u00e1vel\u2026 Quem, dentro do \u201cKremlin\u201d, tiver estofo para governar o pa\u00eds, o seu primeiro teste de fogo seria governar Luanda. Enfim, n\u00e3o nos parece que \u201c La Luna\u201d esteja tarimbada para o cargo!<\/p>\n<h3 style=\"text-align: justify;\">Paradigmas inexistem<\/h3>\n<p style=\"text-align: justify;\">Ora, desconstruindo a nossa passagem que versava sobre o desprezo aos processos, se verificar, notar\u00e1 que em cada director, administrador, governador, secret\u00e1rio de Estado, ministro ou qualquer outra prole de respons\u00e1vel c\u00e1 entre n\u00f3s, ou seja, em Angola, salvo parcos exemplos diferentes e em extin\u00e7\u00e3o, quando assumem um cargo, mudam tudo: do pano de ch\u00e3o passando pelo pessoal do gabinete ao plano estrat\u00e9gico da institui\u00e7\u00e3o. \u00c9 uma aut\u00eantica varredura!<\/p>\n<p style=\"text-align: justify;\">N\u00e3o se respeita processos que inspiram a continuidade para um trabalho que se torna adulto com a observ\u00e2ncia das diferentes etapas. Se o bicho-careta sai do cargo, o lobisomem vem e n\u00e3o quer saber dos bons of\u00edcios do seu predecessor. Come\u00e7a tudo ao ritmo dos seus caprichos e \u00e0s favas v\u00e3o quaisquer possibilidades de ganhos com experi\u00eancias que se acumulam com a governa\u00e7\u00e3o, respeitando processos. \u00c9 como se estiv\u00e9ssemos num c\u00edrculo vicioso dum eterno reiniciar, envolvidos continuamente num tubo de ensaio.<\/p>\n<p style=\"text-align: justify;\">Quer um simples exemplo? N\u00f3s demos-lhe: An\u00edbal Rocha teve uma governa\u00e7\u00e3o em Luanda que, passados quase vinte anos, ainda serve de exemplo. No entanto, o seu sucessor, assim que assumiu, mudou o slogan, \u201cLuanda nossa casa comum\u201d. Agora, perguntamos: o que tinha de mal no slogan que at\u00e9 se tornou viral de t\u00e3o acolhedor? Mudaria para melhor a nova governa\u00e7\u00e3o? Est\u00e1 a ver, at\u00e9 isso se mudam! Ooooohhhh c\u00e9us\u2026.!!!<span class=\"Apple-converted-space\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Algu\u00e9m nessa carruagem \u00e9 capaz de dar primazia \u00e0 harmonia colectiva, respeitando o pleno interesse desse povo, desse pa\u00eds que se quer na\u00e7\u00e3o?! O ego\u00edsmo humano est\u00e1 a retardar esse pa\u00eds, precisamos de um tratado de compromisso com Angola!<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 na berra as exonera\u00e7\u00f5es no pa\u00eds, mormente a de governador de Luanda, e o que se fala e escreve perde-se como horas mortas; pior, soa a alertas em ouvidos moucos que despertar\u00e3o em pleno voo irrevers\u00edvel a consumar o suic\u00eddio. \u00a0Liberato Furtado No\u00a0 consulado mais recente da governa\u00e7\u00e3o do pa\u00eds, a poucos meses de completar quatro anos, Luanda j\u00e1 experimentou tr\u00eas regentes e se apresta a mais uma, depois do \u00faltimo ensaio se ter mostrado um descalabro total que n\u00e3o deixar\u00e1 saudades, mas far\u00e1 levantar velhas mem\u00f3rias e perguntas entaladas. Se fez coro e dir\u00edamos sim, Luanda, efectivamente, tornou-se [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportagem"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 na berra as exonera\u00e7\u00f5es no pa\u00eds, mormente a de governador de Luanda, e o que se fala e escreve perde-se como horas mortas; pior, soa a alertas em ouvidos moucos que despertar\u00e3o em pleno voo irrevers\u00edvel a consumar o suic\u00eddio. \u00a0Liberato Furtado No\u00a0 consulado mais recente da governa\u00e7\u00e3o do pa\u00eds, a poucos meses de completar quatro anos, Luanda j\u00e1 experimentou tr\u00eas regentes e se apresta a mais uma, depois do \u00faltimo ensaio se ter mostrado um descalabro total que n\u00e3o deixar\u00e1 saudades, mas far\u00e1 levantar velhas mem\u00f3rias e perguntas entaladas. Se fez coro e dir\u00edamos sim, Luanda, efectivamente, tornou-se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-02T01:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Governadora-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA\",\"datePublished\":\"2021-08-02T01:25:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/\"},\"wordCount\":1779,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Governadora-2021.jpg\",\"articleSection\":[\"REPORTAGEM\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/\",\"name\":\"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Governadora-2021.jpg\",\"datePublished\":\"2021-08-02T01:25:54+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Governadora-2021.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Governadora-2021.jpg\",\"width\":1080,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/luanda-agora-e-residence-da-mboa-ana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/","og_locale":"pt_PT","og_type":"article","og_title":"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA - Jornal O Crime","og_description":"Est\u00e1 na berra as exonera\u00e7\u00f5es no pa\u00eds, mormente a de governador de Luanda, e o que se fala e escreve perde-se como horas mortas; pior, soa a alertas em ouvidos moucos que despertar\u00e3o em pleno voo irrevers\u00edvel a consumar o suic\u00eddio. \u00a0Liberato Furtado No\u00a0 consulado mais recente da governa\u00e7\u00e3o do pa\u00eds, a poucos meses de completar quatro anos, Luanda j\u00e1 experimentou tr\u00eas regentes e se apresta a mais uma, depois do \u00faltimo ensaio se ter mostrado um descalabro total que n\u00e3o deixar\u00e1 saudades, mas far\u00e1 levantar velhas mem\u00f3rias e perguntas entaladas. Se fez coro e dir\u00edamos sim, Luanda, efectivamente, tornou-se [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/","og_site_name":"Jornal O Crime","article_published_time":"2021-08-02T01:25:54+00:00","og_image":[{"width":1080,"height":933,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Governadora-2021.jpg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA","datePublished":"2021-08-02T01:25:54+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/"},"wordCount":1779,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Governadora-2021.jpg","articleSection":["REPORTAGEM"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/","url":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/","name":"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Governadora-2021.jpg","datePublished":"2021-08-02T01:25:54+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Governadora-2021.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Governadora-2021.jpg","width":1080,"height":933},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/luanda-agora-e-residence-da-mboa-ana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"LUANDA \u201cAGORA \u00c9 RESIDENCE\u201d DA MBOA ANA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=3872"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/3876"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=3872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=3872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=3872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}