{"id":3878,"date":"2021-08-02T02:29:28","date_gmt":"2021-08-02T01:29:28","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=3878"},"modified":"2021-08-02T02:29:28","modified_gmt":"2021-08-02T01:29:28","slug":"caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/","title":{"rendered":"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>Apurou o Jornal O Crime, de fonte pr\u00f3xima \u00e0 fam\u00edlia, que o assassinato de Anderson Kamukotele, 51 anos de idade, s\u00f3 n\u00e3o aconteceu h\u00e1 mais tempo devido \u00e0s suas constantes sa\u00eddas.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"text-decoration: underline;\"><b>Maiomona Paxe<\/b><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">De acordo com a nossa fonte, est\u00e1 claro que o mote do crime \u00e9 o dinheiro da indemniza\u00e7\u00e3o que Anderson recebera, cerca de $US 500.000,00 (quinhentos mil d\u00f3lares americanos), da British Petroleum (BP), como, de resto, Edil\u00e1sio Wander Fortes, o enteado da v\u00edtima e principal suspeito, havia confessado em interrogat\u00f3rio no Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC).<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Ali\u00e1s, revela ainda a fonte, a ambi\u00e7\u00e3o e o desejo de ser o \u00fanico herdeiro de todos bens fizeram com que Wander arquitectasse o plano macabro de acabar com a vida do homem que o criara, do irm\u00e3o mais novo e, inclusive, da pr\u00f3pria m\u00e3e, Elizabeth Manuel, que tamb\u00e9m figurava na sua lista.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<blockquote><p><b>Caso viesse a consumar-se a morte da m\u00e3e, Wander seria o herdeiro leg\u00edtimo da heran\u00e7a adquirida pela m\u00e3e, devido \u00e0 morte do c\u00f4njuge, algo que n\u00e3o veio a acontecer, pois, o plano foi frustrado pelo SIC, pese embora n\u00e3o puderam evitar o assassinato dos tr\u00eas membros da mesma fam\u00edlia, que foram a enterrar a 29 de Maio, no cemit\u00e9rio do Benfica, num funeral marcado por momentos de turbul\u00eancia e desordem, onde agentes da Pol\u00edcia Nacional, afectos ao Comando Municipal de Belas, foram obrigados a intervir.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p><\/blockquote>\n<p style=\"text-align: justify;\">Durante a reconstitui\u00e7\u00e3o do crime, nas instala\u00e7\u00f5es do SIC- Luanda, Ludy Justino, comparsa de Edil\u00e1sio Wander, confessou que o plano j\u00e1 havia sido arquitectado desde 2020 e s\u00f3 n\u00e3o se concretizou antes por conta da presen\u00e7a de uma prima de Wander que estava a passar uma temporada na casa da fam\u00edlia Kamukotele na altura.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">No entanto, como a ambi\u00e7\u00e3o n\u00e3o podia esperar mais, decidiram aproveitar a aus\u00eancia da esposa para prosseguir com o plano. Ap\u00f3s o assassinato do padrasto, o meio-irm\u00e3o o sobrinho de 9 anos, que se encontrava na hora errada e no lugar errado, o plano era p\u00f4r fim \u00e0 vida da m\u00e3e, para que ele herdasse tudo e dividisse com o comparsa.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Entretanto, a grande quest\u00e3o tem precisamente a ver com o facto de como Wander ficou a saber dos valores da indemniza\u00e7\u00e3o que o padrasto recebera, j\u00e1 que fazia tempo que fora<span class=\"Apple-converted-space\">\u00a0 <\/span>expulso de casa por m\u00e1 conduta e desaven\u00e7as com o padrasto.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Contactada para mais esclarecimentos sobre o assunto, Elizabeth Manuel, esposa de Kamukotele e m\u00e3e do principal suspeito, referiu n\u00e3o estar em condi\u00e7\u00f5es de se pronunciar sobre o caso e que deixa tudo nas m\u00e3os do SIC. Al\u00e9m das desconfian\u00e7as que agora paira entre as duas fam\u00edlias, uma vez que do lado do malogrado acusam a vi\u00fava de estar envolvida na morte do marido, cogita-se, tamb\u00e9m, que al\u00e9m de Edil\u00e1sio Wander Fortes e Ludy Justino, presos na Comarca de Viana, haja um terceiro elemento, este, no entanto, pertencente \u00e0 fam\u00edlia do malogrado que ter\u00e1, tamb\u00e9m, participado da ac\u00e7\u00e3o criminosa, embora at\u00e9 ao momento n\u00e3o tenha sido identificado.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">De acordo com alguns familiares do malogrado, as contas banc\u00e1rias de Anderson permanecem intactas desde a sua morte.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h3 style=\"text-align: justify;\"><b>Disputa pelos bens do malogrado<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p style=\"text-align: justify;\">Se para Edil\u00e1sio Wander Fortes a ideia era ser o \u00fanico herdeiro, j\u00e1 a sua m\u00e3e tem encontrado s\u00e9rias dificuldades, junto da fam\u00edlia do<span class=\"Apple-converted-space\">\u00a0 <\/span>esposo, para ter a sua parte da heran\u00e7a.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Segundo a fonte que vimos citando, a fam\u00edlia do malogrado tenciona expulsar a quela de casa, no condom\u00ednio Vereda das Flores, e, inclusive, receber todas viaturas deixadas pelo malogrado.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h3 style=\"text-align: justify;\"><b>\u201cEsposa \u00e9 a herdeira legitima\u201d<\/b><\/h3>\n<p style=\"text-align: justify;\">De acordo com o jurista Gildo Isa\u00edas, uma vez que o malogrado j\u00e1 n\u00e3o tem nenhum descendente vivo, a esposa, \u00e0 luz da lei, casada em comunh\u00e3o de bens, \u00e9 a principal herdeira.<\/p>\n<p style=\"text-align: justify;\">No entanto, acrescenta o jurista, a se confirmar as suspeitas que aludem contra ela, ser\u00e1 considerada, \u00e0 luz do art. 2034\u00ba, al\u00ednea a) do C\u00f3digo Civil, incapaz, por indignidade, de receber a heran\u00e7a. Do referido artigo, explica Gildo Isa\u00edas, extrai-se que carece de capacidade sucess\u00f3ria, por motivo de indignidade: o condenado como autor ou c\u00famplice de homic\u00eddio doloso, ainda que n\u00e3o consumado, contra o autor da sucess\u00e3o ou contra o seu c\u00f4njuge, descendente, ascendente, adoptante ou adoptado.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Caso viesse a consumar-se a morte da m\u00e3e, Wander seria o herdeiro leg\u00edtimo da heran\u00e7a adquirida pela m\u00e3e, devido \u00e0 morte do c\u00f4njuge, algo que n\u00e3o veio a acontecer, pois o plano foi frustrado pelo SIC, pese embora n\u00e3o puderam evitar o assassinato dos tr\u00eas membros da mesma fam\u00edlia, que foram a enterrar a 29 de Maio, no cemit\u00e9rio do Benfica, num funeral marcado por momentos de turbul\u00eancia e desordem, onde agentes da Pol\u00edcia Nacional, afectos ao Comando Municipal de Belas, foram obrigados a intervir.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">A esposa do malogrado, acusada de ser a principal mandante do crime, foi expulsa de primeira inst\u00e2ncia pelos familiares da v\u00edtima e o facto de os mesmos n\u00e3o quererem a perman\u00eancia de nenhuma fam\u00edlia daquela no local f\u00fanebre gerou confus\u00e3o, tendo sido efectuados disparos pelo corpo de seguran\u00e7a interna do condom\u00ednio, a fim de tomar o controle da situa\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apurou o Jornal O Crime, de fonte pr\u00f3xima \u00e0 fam\u00edlia, que o assassinato de Anderson Kamukotele, 51 anos de idade, s\u00f3 n\u00e3o aconteceu h\u00e1 mais tempo devido \u00e0s suas constantes sa\u00eddas.\u00a0 Maiomona Paxe De acordo com a nossa fonte, est\u00e1 claro que o mote do crime \u00e9 o dinheiro da indemniza\u00e7\u00e3o que Anderson recebera, cerca de $US 500.000,00 (quinhentos mil d\u00f3lares americanos), da British Petroleum (BP), como, de resto, Edil\u00e1sio Wander Fortes, o enteado da v\u00edtima e principal suspeito, havia confessado em interrogat\u00f3rio no Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC).\u00a0 Ali\u00e1s, revela ainda a fonte, a ambi\u00e7\u00e3o e o desejo de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Apurou o Jornal O Crime, de fonte pr\u00f3xima \u00e0 fam\u00edlia, que o assassinato de Anderson Kamukotele, 51 anos de idade, s\u00f3 n\u00e3o aconteceu h\u00e1 mais tempo devido \u00e0s suas constantes sa\u00eddas.\u00a0 Maiomona Paxe De acordo com a nossa fonte, est\u00e1 claro que o mote do crime \u00e9 o dinheiro da indemniza\u00e7\u00e3o que Anderson recebera, cerca de $US 500.000,00 (quinhentos mil d\u00f3lares americanos), da British Petroleum (BP), como, de resto, Edil\u00e1sio Wander Fortes, o enteado da v\u00edtima e principal suspeito, havia confessado em interrogat\u00f3rio no Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC).\u00a0 Ali\u00e1s, revela ainda a fonte, a ambi\u00e7\u00e3o e o desejo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-02T01:29:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Fam\u00edlia-morta-pelo-enteado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"918\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO\",\"datePublished\":\"2021-08-02T01:29:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/\"},\"wordCount\":935,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Fam\u00edlia-morta-pelo-enteado.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/\",\"name\":\"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Fam\u00edlia-morta-pelo-enteado.jpg\",\"datePublished\":\"2021-08-02T01:29:28+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Fam\u00edlia-morta-pelo-enteado.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Fam\u00edlia-morta-pelo-enteado.jpg\",\"width\":918,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/","og_locale":"pt_PT","og_type":"article","og_title":"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO - Jornal O Crime","og_description":"Apurou o Jornal O Crime, de fonte pr\u00f3xima \u00e0 fam\u00edlia, que o assassinato de Anderson Kamukotele, 51 anos de idade, s\u00f3 n\u00e3o aconteceu h\u00e1 mais tempo devido \u00e0s suas constantes sa\u00eddas.\u00a0 Maiomona Paxe De acordo com a nossa fonte, est\u00e1 claro que o mote do crime \u00e9 o dinheiro da indemniza\u00e7\u00e3o que Anderson recebera, cerca de $US 500.000,00 (quinhentos mil d\u00f3lares americanos), da British Petroleum (BP), como, de resto, Edil\u00e1sio Wander Fortes, o enteado da v\u00edtima e principal suspeito, havia confessado em interrogat\u00f3rio no Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC).\u00a0 Ali\u00e1s, revela ainda a fonte, a ambi\u00e7\u00e3o e o desejo de [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/","og_site_name":"Jornal O Crime","article_published_time":"2021-08-02T01:29:28+00:00","og_image":[{"width":918,"height":612,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Fam\u00edlia-morta-pelo-enteado.jpg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO","datePublished":"2021-08-02T01:29:28+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/"},"wordCount":935,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Fam\u00edlia-morta-pelo-enteado.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/","url":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/","name":"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Fam\u00edlia-morta-pelo-enteado.jpg","datePublished":"2021-08-02T01:29:28+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Fam\u00edlia-morta-pelo-enteado.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/08\/Fam\u00edlia-morta-pelo-enteado.jpg","width":918,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/caso-kamukotele-enteado-confessa-que-motivacao-do-crime-foi-a-indemnizacao-recebida-pelo-padrasto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Caso Kamukotele: ENTEADO CONFESSA QUE MOTIVA\u00c7\u00c3O DO CRIME FOI A INDEMNIZA\u00c7\u00c3O RECEBIDA PELO PADRASTO"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=3878"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/3878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/3879"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=3878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=3878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=3878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}