{"id":4316,"date":"2021-11-30T18:02:01","date_gmt":"2021-11-30T17:02:01","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=4316"},"modified":"2021-11-30T18:18:40","modified_gmt":"2021-11-30T17:18:40","slug":"finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/","title":{"rendered":"Finalmente em tribunal:  Jornalista David Diogo acusado de estupro"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O julgamento do jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, acusado de ter estuprado a adolescente Domingas Kamia Francisco, 17 anos, no 24 de Junho de 2020, no Cabo-Ledo, munic\u00edpio da Qui\u00e7ama, em Luanda. Ter\u00e1 in\u00edcio no dia 16 de Dezembro do corrente, na 8\u00aa sec\u00e7\u00e3o do Tribunal do Benfica. <\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Engr\u00e1cia Francisco <\/em><\/p>\n<p style=\"text-align: justify;\">Relembra a entrevista da v\u00edtima \u201cEle abusou-me das 18 \u00e0s 00 horas\u201d O jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, \u00e9 acusado de ter estuprado a adolescente Domingas Kamia Francisco, de 17 anos, no passado dia 24 de Junho, no Cabo-Ledo, munic\u00edpio da Qui\u00e7ama, em Luanda. O acusado que, segundo soube o \u2018O Crime\u2019, j\u00e1 constituiu mandat\u00e1rios, ter\u00e1 sido ouvido, em instru\u00e7\u00e3o, por um Procurador da Rep\u00fablica junto \u00e0 unidade policial da comuna de Cabo-Ledo, e sa\u00eddo em liberdade depois de lhe ter sido arbitrada uma cau\u00e7\u00e3o no valor de 200 mil kwanzas.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 Como te chamas? KF \u2014 Sou a Domingas Kamia Francisco e tenho 17 anos. O Crime \u2013 Com quem vives? KF<\/strong> \u2013 Vivo com os meus pais e irm\u00e3os. O Crime \u2014 Que fazes? KF \u2014 Sou estudante de Enfermagem, 10.\u00aa classe. O Crime \u2014 Quando \u00e9 que saiu de casa e para onde ias? KF &#8211; Sa\u00ed de casa na ter\u00e7a-feira, dia 23, \u00e0s 10 horas. Estava a caminho do Kwanza Sul, para visitar a minha irm\u00e3 g\u00e9mea.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0O Crime \u2014 Deste a conhecer aos teus pais onde, quando e por que ias? KF<\/strong> \u2014 N\u00e3o! Preferi n\u00e3o dizer nada porque o pai n\u00e3o havia de permitir, tamb\u00e9m por conta da cerca sanit\u00e1ria imposta a Luanda.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 Como foi que chegaste at\u00e9 ao Cabo-Ledo, uma vez que, segundo apuramos, estavas sem dinheiro para o transporte? KF<\/strong> \u2014 Fui at\u00e9 \u00e0 paragem de t\u00e1xis da Vila do Gamek e ali fiquei um tempo, sem saber o que fazer. Pouco tempo depois, apareceu um camionista que se prontificou em levar-me. Assim que se apercebeu que eu parecia completamente angustiada e confusa, aproximou-se e perguntou-me para onde eu queria ir \u2014 eu disse-lhe que precisava passar a cerca sanit\u00e1ria e chegar at\u00e9 \u00e0 prov\u00edncia do Kwanza Sul para ver a minha irm\u00e3. Da\u00ed, ele levou-me at\u00e9 ao Cabo-Ledo, junto do controlo da cerca.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 Quanto tempo levou at\u00e9 aparecer o camionista? KF<\/strong> \u2014 Aproximadamente uma hora.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 J\u00e1 conhecias o camionista? KF<\/strong> \u2014 N\u00e3o. N\u00e3o conhecia de lugar nenhum.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 N\u00e3o tiveste receio de ir com o senhor, uma vez que n\u00e3o o conhecias? KF<\/strong> \u2014 N\u00e3o. Porque estava bastante confusa e ele foi a \u00fanica pessoa que me ajudou.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 Quanto tempo durou a viajem at\u00e9 ao Cabo-Ledo? KF<\/strong> \u2014 N\u00e3o consigo precisar. Lembro-me, apenas, de que chegamos l\u00e1 por volta das 21 horas.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 O camionista fez alguma paragem antes de chegarem ao cabo-Ledo? KF<\/strong> \u2014 Sim. Paramos num posto de abastecimento.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 Postos no Cabo-Ledo, o que aconteceu depois? KF<\/strong> \u2014 Fomos impedidos de atravessar a cerca. E assim que os agentes da Pol\u00edcia se aperceberam da nossa presen\u00e7a ali, mandaram-me voltar para casa. Mas, como j\u00e1 era tarde, tive que pernoitar a\u00ed mesmo \u2014 ao relento.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 Por que ao relento, se podia passar a noite no cami\u00e3o que te lavara at\u00e9 aquele lugar? KF<\/strong> \u2014 N\u00e3o sei por que, mas o camionista recusou-se em colocar-me dentro do cami\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2014 O que aconteceu no dia seguinte? KF<\/strong> \u2013 J\u00e1 no dia seguinte, veio ter comigo um agente da Pol\u00edcia, que me pediu o terminal dos meus pais, mas eu n\u00e3o o tinha. A seguir, dei o meu Facebook ao mesmo agente para ajudar a localizar a minha fam\u00edlia \u2013 e ele ficou de comunicar \u00e0 minha fam\u00edlia.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 O que fizeste a seguir, enquanto aguardavas pela resposta do agente da Pol\u00edcia? KF<\/strong> \u2013 Continuei na rua, sentada, at\u00e9 que apareceu um jovem, apenas identificado por Toy, a dizer que o seu tio, o David Diogo, jornalista da TV Zimbo, estava a chamar-me. Perguntou se eu conhecia o jornalista e eu disse que n\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 O que fizeste a seguir? KF<\/strong> \u2013 Fui com o jovem, mas n\u00e3o aonde o mesmo (David Diogo) estava, sentado junto a uma cantina. Pelo contr\u00e1rio, fui com o mesmo jovem at\u00e9 a uma outra cantina, a\u00ed ao lado, onde me mandou aguardar. Mas como ele demorava muito, sa\u00ed e voltei at\u00e9 onde estivera anteriormente, junto de umas zungueiras. Minutos depois, apareceu um outro jovem a dizer que o senhor David estava a chamar-me \u2013 disse para eu ir \u00e0 vontade, e fui com ele.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 J\u00e1 conhecias o senhor David Diogo de algum lugar? KF<\/strong> \u2013 N\u00e3o, foi a primeira vez a v\u00ea-lo pessoalmente. Via-o apenas pela televis\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 O jornalista que dizes conhecer pela televis\u00e3o \u00e9 o mesmo que solicitava a tua presen\u00e7a? KF<\/strong> \u2013 Sim! Fui at\u00e9 \u00e0 cantina onde ele estava, acompanhado do sobrinho (Toy) e mais um agente da pol\u00edcia, \u00e0 paisana, apenas identificado por Hugo \u2013 e sim, era ele mesmo (David Diogo), e estava com uma garrafa de Nocal \u00e0s m\u00e3os. Perguntou-me o que se passava e eu disse que precisava chegar \u00e0 Gabela, para visitar uma irm\u00e3, e ele, David Diogo, se prontificou em ajudar-me a atravessar a cerca sanit\u00e1ria. Ali\u00e1s, perguntou-me se me fazia acompanhar de um documento de identifica\u00e7\u00e3o, e eu disse que n\u00e3o \u2013 apesar de que estava a andar com o acento de nascimento \u2013, preferi ocultar-lhe esta informa\u00e7\u00e3o porque n\u00e3o sabia quais eram as suas reais inten\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 E o senhor David Diogo, como dizes, conseguiu fazer-te atravessar a cerca? KF<\/strong> \u2013 N\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Por qu\u00ea? KF<\/strong> \u2013 Porque depois que ele me fez todas aquelas perguntas, regressei aonde estava, e minutos depois veio ter comigo um agente do SME, dizendo que n\u00e3o havia possibilidade de eu passar a cerca e que tinha de regressar \u00e0 casa. No mesmo instante, veio novamente o senhor David Diogo a dizer que iria levar-me \u00e0 casa \u2013 da\u00ed o agente do SME disse a ele (David Diogo): \u201cestou a confiar a menina nas tuas m\u00e3os\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Como te apercebeste que o jovem ao seu lado era, de facto, sobrinho do senhor David Diogo? KF<\/strong> \u2013 Ele mesmo (o suposto jovem) afirmou que era o seu tio que chamava por mim.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Pode descrev\u00ea-lo? KF<\/strong> \u2013 Era um jovem de baixa estatura, escuro e usava cal\u00e7\u00f5es, t-shirt e chinelos.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Foste coagida a subir na viatura do senhor David Diogo? KF<\/strong> \u2013 N\u00e3o. Depois que o agente do SME disse que me confiava nas m\u00e3os do senhor David Diogo e disse ainda que a \u00fanica solu\u00e7\u00e3o era eu voltar para casa, porque o comandante n\u00e3o tinha permitido a minha passagem, subi no carro e fomos.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Quantas pessoas estavam na viatura? KF<\/strong> \u2013 No carro estavam quatro pessoas: o seu suposto sobrinho, Toy, o suposto agente, Hugo, o senhor David, que ia ao volante, e eu. J\u00e1 a caminho de Luanda, ao inv\u00e9s de seguir \u00e0 estrada, desviou o carro e fomos em direc\u00e7\u00e3o a uma terra batida. Eu perguntei onde \u00edamos, ele disse que vamos \u00e0 praia, e assim seguimos.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; E tu concordaste em ir com eles \u00e0 praia? KF<\/strong> &#8211; Eu simplesmente fiquei calada e n\u00e3o falei absolutamente nada.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 O que aconteceu depois? KF<\/strong> \u2013 Postos na praia de Cabo-Ledo, estacionou o carro junto a uma lanchonete onde sentamos todos. Da\u00ed pediram bebidas (alco\u00f3licas) para eles, o senhor David perguntou-me se aceitaria beber uma gasosa, mas eu recusei \u2013 mas ele insistia que eu bebesse, e acabei por aceitar. J\u00e1 agastada com a situa\u00e7\u00e3o, levantei-me e fui sentar no interior da viatura. Entretanto, enquanto chorava, sozinha no interior do carro, o senhor David pediu ao propriet\u00e1rio do estabelecimento que aumentasse o volume da m\u00fasica que ali tocava, e depois foi ao meu encontro no carro, ligou tamb\u00e9m a m\u00fasica do seu carro e depois subiu os vidros.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Que horas eram? KF \u2013 Eram aproximadamente dezoito horas. O Crime \u2013 Chegaste a sofrer alguma amea\u00e7a? KF<\/strong> \u2013 Sim. Depois o seu sobrinho entrou, tamb\u00e9m, no carro, mostrou uma arma e disse que eu tinha de fazer um sacrif\u00edcio para que nada me acontecesse. De seguida, o jovem retirou-se e ficamos apenas eu e o senhor David, que, a seguir, tirou-me a roupa e for\u00e7ou-me a ter rela\u00e7\u00f5es sexuais comigo.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Durante quanto tempo ter\u00e1 ele abusado de ti? KF<\/strong> \u2013 Sei que ficamos na viatura das 18 at\u00e9 \u00e0s 00h.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Em algum momento tentou pedir socorro? KF<\/strong> &#8211; Eu gritava e, inclusive, bati v\u00e1rias vezes no carro, mas ningu\u00e9m veio socorrer-me. Talvez porque a m\u00fasica estava muito alta.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Em algum momento voc\u00ea seduziu o senhor? KF<\/strong> \u2013 N\u00e3o. Fiquei calada durante todo percurso.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 O senhor David Diogo parecia ou estava b\u00eabado? KF<\/strong> \u2013 N\u00e3o. N\u00e3o estava b\u00eabado, pese embora estivesse a beber.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Quanto a tua virgindade, ainda a mantinhas at\u00e9 aquele dia? KF<\/strong> \u2013 Sim, at\u00e9 ser estuprada pelo senhor David Diogo.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime \u2013 Ap\u00f3s o acto, o que aconteceu? KF<\/strong> \u2013 J\u00e1 por volta da madrugada, depois dele ter abusado de mim, subimos todos na viatura e volt\u00e1vamos para o bairro onde estamos anteriormente. De longe, o seu sobrinho apercebeu-se que os meus familiares estavam \u00e0 minha procura e deu um sinal ao tio. Da\u00ed, o tio pediu ao sobrinho e ao suposto agente, o Hugo, num ponto estrat\u00e9gico para que fossem a p\u00e9. J\u00e1 s\u00f3 eu e ele, o senhor Diogo tentou trancar-me num contentor para que o meu irm\u00e3o e os meus pais, que j\u00e1 ali se encontravam n\u00e3o apercebessem que estava com eles.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Contaste \u00e0 Pol\u00edcia o que havia acontecido contigo? KF<\/strong> &#8211; A princ\u00edpio fiquei com medo porque ele havia me amea\u00e7ado, mas depois o meu irm\u00e3o chamou-me de lado e disse que eu podia confiar nele e lhe contasse a verdade. E acabei por contar a ele.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; O seu irm\u00e3o deu a conhecer \u00e0 Pol\u00edcia? KF<\/strong> &#8211; Sim. E neste momento ele, o senhor Diogo ainda estava no local, e a pol\u00edcia ordenou-o a n\u00e3o se ausentar porque tinha de o confrontar.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; O aconteceu depois? KF<\/strong> &#8211; A Pol\u00edcia local ordenou que f\u00f4ssemos todos \u00e0 Esquadra da Qui\u00e7ama. A princ\u00edpio, o senhor estava a recusar-se em subir na viatura da Pol\u00edcia, mas depois o comandante daquele posto acabou por sensibiliz\u00e1-lo e assim fomos. E neste momento ele estava sozinho, o sobrinho e o amigo, suposto agente da pol\u00edcia, j\u00e1 n\u00e3o estavam com ele.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Como \u00e9 que ele (David Diogo) estava vestido? KF<\/strong> &#8211; Estava de um cal\u00e7\u00e3o vermelho, camisola interior e chinelos.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Qual \u00e9 a marca e cor da viatura do senhor Diogo? KF<\/strong> &#8211; Era um Land Cruiser, V8, de cor preta.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Foi a primeira vez que tentaste viajar sozinha? KF<\/strong> &#8211; Sim. Estava a tentar ir para o Kwanza Sul, Gabela, ver a minha irm\u00e3 g\u00e9mea.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Como \u00e9 que estavas vestida? KF &#8211;<\/strong> Estava de uma cal\u00e7a jeans azul e uma blusa.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Qual foi a rea\u00e7\u00e3o do senhor David Diogo quanto \u00e0s acusa\u00e7\u00f5es que o fazias? KF<\/strong> &#8211; Ele dizia que sou maluca, que apenas queria prejudic\u00e1-lo. Disse ainda que me encontrou na rua, com fome, e ele apenas se predispos a ajudar-me.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Como \u00e9 que te sentes agora? KF <\/strong>&#8211; Sinto-me mal, inclusive sinto dores nos membros e \u00e0s vezes ficam paralisados. D\u00f3i-me tamb\u00e9m a coluna e os \u00f3rg\u00e3os genitais.<\/p>\n<p style=\"text-align: justify;\"><strong>O Crime &#8211; Qual \u00e9 o teu sonho? KF &#8211;<\/strong> Eu queria ser uma oftalmologista e empres\u00e1ria, mas com essa situa\u00e7\u00e3o a minha mente apagou tudo isso. O que mais desejo nesse momento \u00e9 me recuperar para voltar a brincar com os meus irm\u00e3os, conforme faz\u00edamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O julgamento do jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, acusado de ter estuprado a adolescente Domingas Kamia Francisco, 17 anos, no 24 de Junho de 2020, no Cabo-Ledo, munic\u00edpio da Qui\u00e7ama, em Luanda. Ter\u00e1 in\u00edcio no dia 16 de Dezembro do corrente, na 8\u00aa sec\u00e7\u00e3o do Tribunal do Benfica. Engr\u00e1cia Francisco Relembra a entrevista da v\u00edtima \u201cEle abusou-me das 18 \u00e0s 00 horas\u201d O jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, \u00e9 acusado de ter estuprado a adolescente Domingas Kamia Francisco, de 17 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92],"tags":[],"class_list":["post-4316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finalmente em tribunal: Jornalista David Diogo acusado de estupro - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finalmente em tribunal: Jornalista David Diogo acusado de estupro - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O julgamento do jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, acusado de ter estuprado a adolescente Domingas Kamia Francisco, 17 anos, no 24 de Junho de 2020, no Cabo-Ledo, munic\u00edpio da Qui\u00e7ama, em Luanda. Ter\u00e1 in\u00edcio no dia 16 de Dezembro do corrente, na 8\u00aa sec\u00e7\u00e3o do Tribunal do Benfica. Engr\u00e1cia Francisco Relembra a entrevista da v\u00edtima \u201cEle abusou-me das 18 \u00e0s 00 horas\u201d O jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, \u00e9 acusado de ter estuprado a adolescente Domingas Kamia Francisco, de 17 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-30T17:02:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-30T17:18:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/11\/maxresdefault-e1638291361313.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"Finalmente em tribunal: Jornalista David Diogo acusado de estupro\",\"datePublished\":\"2021-11-30T17:02:01+00:00\",\"dateModified\":\"2021-11-30T17:18:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/\"},\"wordCount\":2039,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maxresdefault-e1638291361313.jpg\",\"articleSection\":[\"ENTREVISTA\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/\",\"name\":\"Finalmente em tribunal: Jornalista David Diogo acusado de estupro - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maxresdefault-e1638291361313.jpg\",\"datePublished\":\"2021-11-30T17:02:01+00:00\",\"dateModified\":\"2021-11-30T17:18:40+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maxresdefault-e1638291361313.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/maxresdefault-e1638291361313.jpg\",\"width\":1280,\"height\":566},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finalmente em tribunal: Jornalista David Diogo acusado de estupro\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finalmente em tribunal: Jornalista David Diogo acusado de estupro - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/","og_locale":"pt_PT","og_type":"article","og_title":"Finalmente em tribunal: Jornalista David Diogo acusado de estupro - Jornal O Crime","og_description":"O julgamento do jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, acusado de ter estuprado a adolescente Domingas Kamia Francisco, 17 anos, no 24 de Junho de 2020, no Cabo-Ledo, munic\u00edpio da Qui\u00e7ama, em Luanda. Ter\u00e1 in\u00edcio no dia 16 de Dezembro do corrente, na 8\u00aa sec\u00e7\u00e3o do Tribunal do Benfica. Engr\u00e1cia Francisco Relembra a entrevista da v\u00edtima \u201cEle abusou-me das 18 \u00e0s 00 horas\u201d O jornalista David Jos\u00e9 Diogo, de 53 anos, \u201cpivot\u201d do jornal da noite da TV Zimbo, \u00e9 acusado de ter estuprado a adolescente Domingas Kamia Francisco, de 17 [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/","og_site_name":"Jornal O Crime","article_published_time":"2021-11-30T17:02:01+00:00","article_modified_time":"2021-11-30T17:18:40+00:00","og_image":[{"width":1280,"height":566,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/11\/maxresdefault-e1638291361313.jpg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"Finalmente em tribunal: Jornalista David Diogo acusado de estupro","datePublished":"2021-11-30T17:02:01+00:00","dateModified":"2021-11-30T17:18:40+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/"},"wordCount":2039,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/11\/maxresdefault-e1638291361313.jpg","articleSection":["ENTREVISTA"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/","url":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/","name":"Finalmente em tribunal: Jornalista David Diogo acusado de estupro - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/11\/maxresdefault-e1638291361313.jpg","datePublished":"2021-11-30T17:02:01+00:00","dateModified":"2021-11-30T17:18:40+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/11\/maxresdefault-e1638291361313.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2021\/11\/maxresdefault-e1638291361313.jpg","width":1280,"height":566},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/finalmente-em-tribunal-jornalista-david-diogo-acusado-de-estupro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Finalmente em tribunal: Jornalista David Diogo acusado de estupro"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=4316"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/4317"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=4316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=4316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=4316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}