{"id":4393,"date":"2022-01-13T16:09:36","date_gmt":"2022-01-13T15:09:36","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=4393"},"modified":"2022-01-13T16:09:36","modified_gmt":"2022-01-13T15:09:36","slug":"4393-2","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/","title":{"rendered":""},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00c3E E FILHO ESPANCADOS AT\u00c9 A MORTE<\/p>\n<p style=\"text-align: justify;\">Uma crian\u00e7a de seis anos de idade, na comuna da Lucira, prov\u00edncia do Namibe, presenciou o assassinato da m\u00e3e e de seguida foi morta pelo av\u00f4, alegadamente pela progenitora estar em falta dos 100 kwanzas que a solicitou.<\/p>\n<p style=\"text-align: justify;\">O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal explica que, enquanto as v\u00edtimas tomavam o pequeno-almo\u00e7o, o acusado solicitou que fosse servida a mesma refei\u00e7\u00e3o para si, por\u00e9m n\u00e3o havia sobrado.<\/p>\n<p style=\"text-align: justify;\">Assim, prossegue o SIC, solicitou 100 kwanzas \u00e0 sobrinha, Vivi Trindade Janeiro, e, por n\u00e3o ter sido atendida a solicita\u00e7\u00e3o, come\u00e7ou a agredi-la com catana, tendo afectado a regi\u00e3o craniana, costas e bra\u00e7o direito, pelo que teve morte imediata.<\/p>\n<p style=\"text-align: justify;\">O pequeno Elias Quintas, que presenciou a morte da m\u00e3e, tentou escapar da f\u00faria do av\u00f4, mas foi perseguido e submetido \u00e0 mesma tortura, at\u00e9 \u00e0 morte.<\/p>\n<p style=\"text-align: justify;\">O ora pr\u00f3fugo, de 53 anos, j\u00e1 est\u00e1 \u00e0 contas com a justi\u00e7a e foi apreendido, tamb\u00e9m, o objecto usado para cometer o crime.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00c3E E FILHO ESPANCADOS AT\u00c9 A MORTE Uma crian\u00e7a de seis anos de idade, na comuna da Lucira, prov\u00edncia do Namibe, presenciou o assassinato da m\u00e3e e de seguida foi morta pelo av\u00f4, alegadamente pela progenitora estar em falta dos 100 kwanzas que a solicitou. O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal explica que, enquanto as v\u00edtimas tomavam o pequeno-almo\u00e7o, o acusado solicitou que fosse servida a mesma refei\u00e7\u00e3o para si, por\u00e9m n\u00e3o havia sobrado. Assim, prossegue o SIC, solicitou 100 kwanzas \u00e0 sobrinha, Vivi Trindade Janeiro, e, por n\u00e3o ter sido atendida a solicita\u00e7\u00e3o, come\u00e7ou a agredi-la com catana, tendo afectado [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4393","post","type-post","status-publish","format-standard","hentry","category-outros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/4393-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"M\u00c3E E FILHO ESPANCADOS AT\u00c9 A MORTE Uma crian\u00e7a de seis anos de idade, na comuna da Lucira, prov\u00edncia do Namibe, presenciou o assassinato da m\u00e3e e de seguida foi morta pelo av\u00f4, alegadamente pela progenitora estar em falta dos 100 kwanzas que a solicitou. O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal explica que, enquanto as v\u00edtimas tomavam o pequeno-almo\u00e7o, o acusado solicitou que fosse servida a mesma refei\u00e7\u00e3o para si, por\u00e9m n\u00e3o havia sobrado. Assim, prossegue o SIC, solicitou 100 kwanzas \u00e0 sobrinha, Vivi Trindade Janeiro, e, por n\u00e3o ter sido atendida a solicita\u00e7\u00e3o, come\u00e7ou a agredi-la com catana, tendo afectado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/4393-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-13T15:09:36+00:00\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/4393-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/4393-2\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"No title\",\"datePublished\":\"2022-01-13T15:09:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/4393-2\\\/\"},\"wordCount\":177,\"commentCount\":0,\"articleSection\":[\"OUTROS\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/4393-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/4393-2\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/4393-2\\\/\",\"name\":\"- Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"datePublished\":\"2022-01-13T15:09:36+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/4393-2\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/","og_locale":"pt_PT","og_type":"article","og_title":"- Jornal O Crime","og_description":"M\u00c3E E FILHO ESPANCADOS AT\u00c9 A MORTE Uma crian\u00e7a de seis anos de idade, na comuna da Lucira, prov\u00edncia do Namibe, presenciou o assassinato da m\u00e3e e de seguida foi morta pelo av\u00f4, alegadamente pela progenitora estar em falta dos 100 kwanzas que a solicitou. O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal explica que, enquanto as v\u00edtimas tomavam o pequeno-almo\u00e7o, o acusado solicitou que fosse servida a mesma refei\u00e7\u00e3o para si, por\u00e9m n\u00e3o havia sobrado. Assim, prossegue o SIC, solicitou 100 kwanzas \u00e0 sobrinha, Vivi Trindade Janeiro, e, por n\u00e3o ter sido atendida a solicita\u00e7\u00e3o, come\u00e7ou a agredi-la com catana, tendo afectado [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/","og_site_name":"Jornal O Crime","article_published_time":"2022-01-13T15:09:36+00:00","author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"No title","datePublished":"2022-01-13T15:09:36+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/"},"wordCount":177,"commentCount":0,"articleSection":["OUTROS"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/4393-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/","url":"https:\/\/jornalocrime.com\/ilnes\/4393-2\/","name":"- Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"datePublished":"2022-01-13T15:09:36+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/4393-2\/"]}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=4393"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4393\/revisions"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=4393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=4393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=4393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}