{"id":4826,"date":"2022-05-27T23:30:24","date_gmt":"2022-05-27T22:30:24","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=4826"},"modified":"2022-05-27T23:30:24","modified_gmt":"2022-05-27T22:30:24","slug":"covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/","title":{"rendered":"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE  SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>Funcion\u00e1rios<span class=\"Apple-converted-space\">\u00a0 <\/span>da campanha \u00e0 Covid-19 , em Luanda , denunciam falta de sal\u00e1rios<span class=\"Apple-converted-space\">\u00a0 <\/span>e<span class=\"Apple-converted-space\">\u00a0 <\/span>subs\u00eddios<span class=\"Apple-converted-space\">\u00a0 <\/span>di\u00e1rios, desde Mar\u00e7o<span class=\"Apple-converted-space\">\u00a0 <\/span>do ano passado.<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><em><b>Jurelma Francisco<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/em><\/span><\/p>\n<p style=\"text-align: justify;\">Numa den\u00fancia feita a este jornal, em jeito de s\u00faplica e desespero, os funcion\u00e1rios disseram que h\u00e1 um despacho emitido pelo Presidente da Rep\u00fablica, Jo\u00e3o<span class=\"Apple-converted-space\">\u00a0 <\/span>Manuel Gon\u00e7alves Louren\u00e7o, advertindo<span class=\"Apple-converted-space\">\u00a0 <\/span>o atraso de pagamento de sal\u00e1rios e subs\u00eddios di\u00e1rios dos funcion\u00e1rios no valor de dois mil kwanzas. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">&#8220;Estes subs\u00eddios deveriam ser pagos mensalmente, e n\u00e3o ao contr\u00e1rio, algumas pessoas come\u00e7aram receber no dia 19 do passado m\u00eas&#8221;, disse, mas para o espanto daqueles funcion\u00e1rios, o Minist\u00e9rio da Sa\u00fade<span class=\"Apple-converted-space\">\u00a0 <\/span>n\u00e3o os faz chegar os valores que alegadamente t\u00eam direito.<\/p>\n<p style=\"text-align: justify;\">Para os funcion\u00e1rios, h\u00e1 uma esp\u00e9cie de jogo da sorte, no processo<span class=\"Apple-converted-space\">\u00a0 <\/span>de pagamento de sal\u00e1rios e subs\u00eddios di\u00e1rios da Covid-19. E, real\u00e7am que n\u00e3o compreendem quais crit\u00e9rios<span class=\"Apple-converted-space\">\u00a0 <\/span>utilizados para a feitura dos pagamentos,<span class=\"Apple-converted-space\">\u00a0 <\/span>situa\u00e7\u00e3o est\u00e1 <span class=\"Apple-converted-space\">\u00a0 <\/span>que tem deixado os funcion\u00e1rios<span class=\"Apple-converted-space\">\u00a0 <\/span>&#8220;curiosos &#8221; , o facto de <span class=\"Apple-converted-space\">\u00a0 <\/span>estarem na campanha<span class=\"Apple-converted-space\">\u00a0 <\/span>mas que nem todos t\u00eam o privil\u00e9gio de usufru\u00edrem<span class=\"Apple-converted-space\">\u00a0 <\/span>do sal\u00e1rio e dos subs\u00eddios di\u00e1rios.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">As fontes avan\u00e7aram que a campanha de vacina\u00e7\u00e3o \u00e0 Covid-19 da Casa da Juventude, Cidadela Desportiva, Paz Flor, Piaget,<span class=\"Apple-converted-space\">\u00a0 <\/span>Zango, Chamavo e Mutu Ya Kevela s\u00e3o<span class=\"Apple-converted-space\">\u00a0 <\/span>os que v\u00eaem-se privados dos sal\u00e1rios<span class=\"Apple-converted-space\">\u00a0 <\/span>e subs\u00eddios<span class=\"Apple-converted-space\">\u00a0 <\/span>di\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">&#8220;Nenhum funcion\u00e1rio destes postos de vacina\u00e7\u00e3o foram pagos,<span class=\"Apple-converted-space\">\u00a0 <\/span>pessoas<span class=\"Apple-converted-space\">\u00a0 <\/span>foram<span class=\"Apple-converted-space\">\u00a0 <\/span>infectadas devido a exposi\u00e7\u00e3o no trabalho de baixo do sol e<span class=\"Apple-converted-space\">\u00a0 <\/span>in\u00fameras chuvas&#8221;, lamentou, para posterior acrescentar que a alimenta\u00e7\u00e3o nunca foi das melhores, v\u00e1rios funcion\u00e1rios ficaram<span class=\"Apple-converted-space\">\u00a0 <\/span>doentes e outros acabaram por perder a vida.<\/p>\n<p style=\"text-align: justify;\">Sem sal\u00e1rios<span class=\"Apple-converted-space\">\u00a0 <\/span>e subs\u00eddios di\u00e1rios os funcion\u00e1rios<span class=\"Apple-converted-space\">\u00a0 <\/span>s\u00e3o obrigados a percorrer longas dist\u00e2ncias para chegarem aos postos de vacina\u00e7\u00e3o <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">As nossas fontes dizem que \u00e9ramos obrigados fazer sacrif\u00edcios em nome da p\u00e1tria, isto \u00e9, entravam \u00e0s 7 horas da manh\u00e3 e largavam \u00e0s 21horas, entretanto, apelam um bom senso de quem de direito \u201ctemos todos trabalhados por uma \u00fanica<span class=\"Apple-converted-space\">\u00a0 <\/span>causa todos os funcion\u00e1rios s\u00e3o angolanos e n\u00e3o pode existir desigualdade quanto ao pagamento sobretudo, porque existe pessoas que nunca estiveram envolvidas no servi\u00e7o de campanha, mas foram os primeiros a serem pagos\u201d, conclu\u00edram.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Funcion\u00e1rios\u00a0 da campanha \u00e0 Covid-19 , em Luanda , denunciam falta de sal\u00e1rios\u00a0 e\u00a0 subs\u00eddios\u00a0 di\u00e1rios, desde Mar\u00e7o\u00a0 do ano passado. Jurelma Francisco\u00a0 Numa den\u00fancia feita a este jornal, em jeito de s\u00faplica e desespero, os funcion\u00e1rios disseram que h\u00e1 um despacho emitido pelo Presidente da Rep\u00fablica, Jo\u00e3o\u00a0 Manuel Gon\u00e7alves Louren\u00e7o, advertindo\u00a0 o atraso de pagamento de sal\u00e1rios e subs\u00eddios di\u00e1rios dos funcion\u00e1rios no valor de dois mil kwanzas. \u00a0 &#8220;Estes subs\u00eddios deveriam ser pagos mensalmente, e n\u00e3o ao contr\u00e1rio, algumas pessoas come\u00e7aram receber no dia 19 do passado m\u00eas&#8221;, disse, mas para o espanto daqueles funcion\u00e1rios, o Minist\u00e9rio da [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Funcion\u00e1rios\u00a0 da campanha \u00e0 Covid-19 , em Luanda , denunciam falta de sal\u00e1rios\u00a0 e\u00a0 subs\u00eddios\u00a0 di\u00e1rios, desde Mar\u00e7o\u00a0 do ano passado. Jurelma Francisco\u00a0 Numa den\u00fancia feita a este jornal, em jeito de s\u00faplica e desespero, os funcion\u00e1rios disseram que h\u00e1 um despacho emitido pelo Presidente da Rep\u00fablica, Jo\u00e3o\u00a0 Manuel Gon\u00e7alves Louren\u00e7o, advertindo\u00a0 o atraso de pagamento de sal\u00e1rios e subs\u00eddios di\u00e1rios dos funcion\u00e1rios no valor de dois mil kwanzas. \u00a0 &#8220;Estes subs\u00eddios deveriam ser pagos mensalmente, e n\u00e3o ao contr\u00e1rio, algumas pessoas come\u00e7aram receber no dia 19 do passado m\u00eas&#8221;, disse, mas para o espanto daqueles funcion\u00e1rios, o Minist\u00e9rio da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-27T22:30:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/05\/1_5470860225f19c25200b51.png\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"253\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO\",\"datePublished\":\"2022-05-27T22:30:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/\"},\"wordCount\":425,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1_5470860225f19c25200b51.png\",\"articleSection\":[\"SOCIEDADE\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/\",\"name\":\"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1_5470860225f19c25200b51.png\",\"datePublished\":\"2022-05-27T22:30:24+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1_5470860225f19c25200b51.png\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1_5470860225f19c25200b51.png\",\"width\":425,\"height\":253},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/","og_locale":"pt_PT","og_type":"article","og_title":"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO - Jornal O Crime","og_description":"Funcion\u00e1rios\u00a0 da campanha \u00e0 Covid-19 , em Luanda , denunciam falta de sal\u00e1rios\u00a0 e\u00a0 subs\u00eddios\u00a0 di\u00e1rios, desde Mar\u00e7o\u00a0 do ano passado. Jurelma Francisco\u00a0 Numa den\u00fancia feita a este jornal, em jeito de s\u00faplica e desespero, os funcion\u00e1rios disseram que h\u00e1 um despacho emitido pelo Presidente da Rep\u00fablica, Jo\u00e3o\u00a0 Manuel Gon\u00e7alves Louren\u00e7o, advertindo\u00a0 o atraso de pagamento de sal\u00e1rios e subs\u00eddios di\u00e1rios dos funcion\u00e1rios no valor de dois mil kwanzas. \u00a0 &#8220;Estes subs\u00eddios deveriam ser pagos mensalmente, e n\u00e3o ao contr\u00e1rio, algumas pessoas come\u00e7aram receber no dia 19 do passado m\u00eas&#8221;, disse, mas para o espanto daqueles funcion\u00e1rios, o Minist\u00e9rio da [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/","og_site_name":"Jornal O Crime","article_published_time":"2022-05-27T22:30:24+00:00","og_image":[{"width":425,"height":253,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/05\/1_5470860225f19c25200b51.png","type":"image\/png"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO","datePublished":"2022-05-27T22:30:24+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/"},"wordCount":425,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/05\/1_5470860225f19c25200b51.png","articleSection":["SOCIEDADE"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/","url":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/","name":"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/05\/1_5470860225f19c25200b51.png","datePublished":"2022-05-27T22:30:24+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/05\/1_5470860225f19c25200b51.png","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/05\/1_5470860225f19c25200b51.png","width":425,"height":253},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/covid-19-funcionarios-denunciam-falta-de-salarios-e-subsidios-diario-ha-um-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Covid-19: FUNCION\u00c1RIOS DENUNCIAM FALTA DE SAL\u00c1RIOS E SUBS\u00cdDIOS DI\u00c1RIO H\u00c1 UM ANO"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=4826"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/4826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/4827"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=4826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=4826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=4826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}