{"id":5120,"date":"2022-07-27T08:18:11","date_gmt":"2022-07-27T07:18:11","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5120"},"modified":"2022-07-27T08:19:03","modified_gmt":"2022-07-27T07:19:03","slug":"marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/","title":{"rendered":"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>3\u00b0 Sub-Chefe da Policia Nacional, Marcos Vieira Jos\u00e9 Caholo, 34 anos, foi mais uma v\u00edtima mortal de uma grupo de marginais composto por oito elementos que actuavam maioritariamente em Luanda. Parte do grupo, abandonou a cidade capital depois de ser filmado a assaltar uma loja de telefones na Mutamba.<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #ff0000;\"><i>Engr\u00e1cia Francisco<\/i><\/span><\/p>\n<p style=\"text-align: justify;\">O assassinato do 3\u00b0 subchefe da PN ocorreu quando ao entrar em sua resid\u00eancia no bairro Carreira de Tiro, foi interpretado pelos marginais, ao reagir ao assalto foi alvejado mortalmente.<\/p>\n<p style=\"text-align: justify;\">O grupo de denominado &#8220;Os Cabe\u00e7a&#8221; composto por oito elementos, incluindo uma mulher, est\u00e1 envolvido em v\u00e1rios crimes de naturezas diversas. O gang \u00e9 o autor do assalto h\u00e1 duas ag\u00eancias de telem\u00f3veis em Luanda, facto que viralizou nas redes socias e, do roubo de mais de oito milh\u00f5es de kwanzas no interior de uma viatura de marca toyota, modelo Hilux, na via-expresso, Avenida Fidel de Castro.<\/p>\n<p style=\"text-align: justify;\">De acordo com o porta-voz do SIC em Malanje, Inspector-Chefe Augusto Barros Andr\u00e9, &#8220;os elementos confessaram ainda terem praticado diversos crimes na Prov\u00edncia de Luanda a destacar Roubos com recurso \u00e0 arma de fogo de diversos computadores, telemov\u00e9is e tablets em duas ag\u00eancias, na Mutamba e na Avenida Brasil&#8221;, disse.<\/p>\n<p style=\"text-align: justify;\">Fazem parte deste grupo perigoso cidad\u00e3os identificados por, Famoroso Jo\u00e3o Sebasti\u00e3o, mais conhecido por Sabad\u00e3o, Nilson Miguel Figueira tcp, Kote, Eliseu Figueira Futa tcp, Taigar, Miguel Afonso, tcp Bruxo, Evanilson Jos\u00e9 Nzunza, tcp Tchutchu, Francisco Roque, tcp Boy Dji e Eva Figueira Victor tcp Vania, com idades compreendidas de 21 a 29 anos.<\/p>\n<p style=\"text-align: justify;\">Os meliantes atrav\u00e9s de informa\u00e7\u00f5es dadas por comparsas naquela localidade, invadiu \u00e0 cada de um reformado da sonangol, no bairro Carreira de Tiro, com recurso a arma de fogo, roubou 20 mil d\u00f3lares, mil randes, 150 euros e 180 mil kwanzas.<\/p>\n<p style=\"text-align: justify;\">SIC-Malanje sai \u00e0 rua e captura grupo considerado altamente perigoso<\/p>\n<p style=\"text-align: justify;\">Face os constantes crimes de roubo com recurso a m\u00e3o-armada em Malanje, com maior realce nos bairros Carreira dr Tiro e Cangambo, o Servi\u00e7o de Investiga\u00e7\u00e3o Criminal, atr\u00e1ves dos seus Departamentos Operativos, no \u00e2mbito do combate a criminalidade, realizou um aturado trabalho investigativo, com prop\u00f4sito de se determinar e esclarecer tais crimes.<\/p>\n<p style=\"text-align: justify;\">&#8220;Fruto de um aturado trabalho de inteligi\u00eancia criminal desencadeado pelos efectivos deste \u00d3rg\u00e3o, foi possivel desmantelar uma Associa\u00e7\u00e3o Criminosa denominada os Cabe\u00e7a envolvidos nos crimes de Homic\u00eddio Qualificado em raz\u00e3o dos motivos, roubo de valores monet\u00e1rios com recurso a Arma de fogo no interior de resid\u00eancia onde os implicados retiraram 20.000usd, 1.000.00 Randes, 150 \u20acuros, 180.000.00kz e Roubos no interior de resid\u00eancia onde os mesmo subtrairam fios de ouro, nos bairros da Carreira de Tiro e Cangambo&#8221;, descreveu.<\/p>\n<p style=\"text-align: justify;\">Foi poss\u00edvel deter um indiv\u00edduo em posse de uma pistola com respectivo carregador, e outro em posse de uma caixa contendo 57 muni\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Faz parte do grupo de marginais um efectivo das Forcas Armadas Angolanas tido como o fornecedor das Armas de Fogos e muni\u00e7\u00f5es usadas pelos meliantes, comercializava ao pre\u00e7o de duzentos e cinquenta mil kwanzas e as muni\u00e7\u00f5es h\u00e1 cinquenta mil kwanzas por caixa.<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Materiais recuperados<\/span><\/h3>\n<p style=\"text-align: justify;\">Salientar que as investiga\u00e7\u00f5es levadas a cabo pelos efectivos do SIC-Malanje foi poss\u00edvel a recupera\u00e7\u00e3o de 3.300.00 usd, 150 \u20acuros, 1.700.00 Randes, 524.000.00kz, duas pistolas com tr\u00eas carregadores de marcas gericho e star e 94 muni\u00e7\u00f5es, cart\u00f5es multicaixa de BPC, BCI, Keve e fios de ouros.<\/p>\n<p style=\"text-align: justify;\">O jornal sabe que os implicados foram presentes ao Minist\u00e9rio p\u00fablico para tr\u00e2mites que se imp\u00f5em, tendo sido conduzidos ao Establecimento Prisional de Malanje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3\u00b0 Sub-Chefe da Policia Nacional, Marcos Vieira Jos\u00e9 Caholo, 34 anos, foi mais uma v\u00edtima mortal de uma grupo de marginais composto por oito elementos que actuavam maioritariamente em Luanda. Parte do grupo, abandonou a cidade capital depois de ser filmado a assaltar uma loja de telefones na Mutamba. Engr\u00e1cia Francisco O assassinato do 3\u00b0 subchefe da PN ocorreu quando ao entrar em sua resid\u00eancia no bairro Carreira de Tiro, foi interpretado pelos marginais, ao reagir ao assalto foi alvejado mortalmente. O grupo de denominado &#8220;Os Cabe\u00e7a&#8221; composto por oito elementos, incluindo uma mulher, est\u00e1 envolvido em v\u00e1rios crimes de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5120","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-nacional","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"3\u00b0 Sub-Chefe da Policia Nacional, Marcos Vieira Jos\u00e9 Caholo, 34 anos, foi mais uma v\u00edtima mortal de uma grupo de marginais composto por oito elementos que actuavam maioritariamente em Luanda. Parte do grupo, abandonou a cidade capital depois de ser filmado a assaltar uma loja de telefones na Mutamba. Engr\u00e1cia Francisco O assassinato do 3\u00b0 subchefe da PN ocorreu quando ao entrar em sua resid\u00eancia no bairro Carreira de Tiro, foi interpretado pelos marginais, ao reagir ao assalto foi alvejado mortalmente. O grupo de denominado &#8220;Os Cabe\u00e7a&#8221; composto por oito elementos, incluindo uma mulher, est\u00e1 envolvido em v\u00e1rios crimes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-27T07:18:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-27T07:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/07\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN\",\"datePublished\":\"2022-07-27T07:18:11+00:00\",\"dateModified\":\"2022-07-27T07:19:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/\"},\"wordCount\":619,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg\",\"articleSection\":[\"NACIONAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/\",\"name\":\"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg\",\"datePublished\":\"2022-07-27T07:18:11+00:00\",\"dateModified\":\"2022-07-27T07:19:03+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg\",\"width\":828,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/","og_locale":"pt_PT","og_type":"article","og_title":"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN - Jornal O Crime","og_description":"3\u00b0 Sub-Chefe da Policia Nacional, Marcos Vieira Jos\u00e9 Caholo, 34 anos, foi mais uma v\u00edtima mortal de uma grupo de marginais composto por oito elementos que actuavam maioritariamente em Luanda. Parte do grupo, abandonou a cidade capital depois de ser filmado a assaltar uma loja de telefones na Mutamba. Engr\u00e1cia Francisco O assassinato do 3\u00b0 subchefe da PN ocorreu quando ao entrar em sua resid\u00eancia no bairro Carreira de Tiro, foi interpretado pelos marginais, ao reagir ao assalto foi alvejado mortalmente. O grupo de denominado &#8220;Os Cabe\u00e7a&#8221; composto por oito elementos, incluindo uma mulher, est\u00e1 envolvido em v\u00e1rios crimes de [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/","og_site_name":"Jornal O Crime","article_published_time":"2022-07-27T07:18:11+00:00","article_modified_time":"2022-07-27T07:19:03+00:00","og_image":[{"width":828,"height":620,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/07\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/"},"author":{"name":"Edson Fortes","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN","datePublished":"2022-07-27T07:18:11+00:00","dateModified":"2022-07-27T07:19:03+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/"},"wordCount":619,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/07\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg","articleSection":["NACIONAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/","url":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/","name":"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/07\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg","datePublished":"2022-07-27T07:18:11+00:00","dateModified":"2022-07-27T07:19:03+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/07\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/07\/46D4322A-31A9-4F63-AEE2-7F40622EBCCE.jpeg","width":828,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/marginais-filmados-a-assaltar-uma-loja-de-telemoveis-em-luanda-detidos-em-malanje-por-matarem-um-agente-da-pn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Marginais filmados a assaltar uma loja de telem\u00f3veis em Luanda detidos em Malanje por matarem um agente da PN"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5120"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/5128"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}