{"id":5369,"date":"2022-09-22T21:00:33","date_gmt":"2022-09-22T20:00:33","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5369"},"modified":"2022-09-22T21:33:43","modified_gmt":"2022-09-22T20:33:43","slug":"suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/","title":{"rendered":"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente"},"content":{"rendered":"<p class=\"article-head-content-headline-lead\" style=\"text-align: left;\"><strong>Advogados de Carlos S\u00e3o Vicente, condenado a 9 anos de cadeia e a multa de 500 milh\u00f5es de d\u00f3lares, consideram &#8220;decis\u00e3o hist\u00f3rica&#8221; que supremo su\u00ed\u00e7o &#8220;reconhece d\u00favidas de julgamento justo em Angola&#8221;.<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/bordalo.observador.pt\/v2\/q:84\/rs:fill:2000:1126\/c:2000:1126:nowe:0:0\/plain\/https:\/\/s3.observador.pt\/wp-content\/uploads\/2022\/02\/11060219\/35378375.jpg\" alt=\"O julgamento do empres\u00e1rio luso-angolano Carlos S\u00e3o Vicente (ao centro de costas), durante o julgamento do empres\u00e1rio luso-angolano, preso desde setembro de 2020 sob acusa\u00e7\u00e3o de fraude fiscal, peculato e branqueamento de capitais, come\u00e7a hoje na 3 \u00aa Sec\u00e7\u00e3o Criminal do Tribunal da Comarca de Luanda, Angula, 26 de janeiro de 2022. AMPE ROG\u00c9RIO\/LUSA\" width=\"2000\" height=\"1126\" \/><\/strong><\/p>\n<p style=\"text-align: justify;\">Os advogados do empres\u00e1rio angolano Carlos S\u00e3o Vicente disseram esta quarta-feira que um tribunal su\u00ed\u00e7o decretou a suspens\u00e3o da coopera\u00e7\u00e3o com as autoridades judiciais angolanas, devido \u00e0 falta de imparcialidade no processo judicial contra o seu cliente.<\/p>\n<div class=\"obs-ad-container obs-ad-container-web_article_middle obs-in-article-container obs-in-article-container-empty\" style=\"text-align: justify;\">\n<div id=\"web_article_middle_1\" class=\"obs-ad \"><\/div>\n<\/div>\n<blockquote><p>O Supremo Tribunal decidiu que as autoridades su\u00ed\u00e7as n\u00e3o podiam cooperar com Angola antes de avaliarem a possibilidade e a efic\u00e1cia da obten\u00e7\u00e3o de v\u00e1rias garantias diplom\u00e1ticas por parte deste pa\u00eds, em particular no que diz respeito \u00e0 independ\u00eancia e imparcialidade dos tribunais e o cumprimento dos direitos processuais de Carlos S\u00e3o Vicente\u201d, l\u00ea-se num comunicado enviado \u00e0 Lusa pelos advogados do empres\u00e1rio.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">No texto, os advogados de Carlos S\u00e3o Vicente, condenado em Luanda, em mar\u00e7o, a <strong>nove anos de cadeia<\/strong> e a uma multa de <strong>500 milh\u00f5es de d\u00f3lares<\/strong>, sensivelmente o mesmo em euros, pelos crimes de <strong>peculato, branqueamento de capitais e fraude<\/strong>, escrevem ainda: \u201cEsta \u00e9 uma <strong>decis\u00e3o hist\u00f3rica, j\u00e1 que o Supremo Tribunal da Su\u00ed\u00e7a reconhece que h\u00e1 s\u00e9rias d\u00favidas<\/strong> sobre o direito do sr. S\u00e3o Vicente a um julgamento justo em <a href=\"https:\/\/observador.pt\/2022\/09\/21\/novo-governo-angolano-conta-com-48-secretarios-de-estado\/\" target=\"_blank\" rel=\"noopener noreferrer\">Angola<\/a>\u201c.<\/p>\n<p style=\"text-align: justify;\">A decis\u00e3o do tribunal su\u00ed\u00e7o, consultada pela Lusa, admite \u201cparcialmente\u201d o recurso colocado por Carlos S\u00e3o Vicente contra a senten\u00e7a su\u00ed\u00e7a, de 23 de maio deste ano, mas rejeita o pedido de descongelamento das contas banc\u00e1rias do empres\u00e1rio angolano.<\/p>\n<div class=\"obs-ad-container obs-ad-container-web_article_double obs-in-article-container-empty obs-in-article-container obs-ad-group-article-double\" style=\"text-align: justify;\" data-amp-ad-marker=\"\">\n<div class=\"obs-ad-container-empty\"><\/div>\n<div class=\"obs-ad-container-empty\"><\/div>\n<\/div>\n<p style=\"text-align: justify;\">S\u00e3o Vicente \u201cespera que outros pa\u00edses sigam o caminho aberto pelo Supremo Tribunal su\u00ed\u00e7o e se recusem a cooperar com os procedimentos irregulares seguidos pelas autoridades angolanas\u201d, escrevem ainda os advogados, na nota que d\u00e1 conta da decis\u00e3o, datada de 30 de agosto.<\/p>\n<p style=\"text-align: justify;\">Preso preventivamente desde setembro de 2020, os crimes imputados a Carlos S\u00e3o Vicente, segundo a acusa\u00e7\u00e3o angolana, envolviam <strong>valores superiores a mil milh\u00f5es<\/strong> de euros, embora na senten\u00e7a agora conhecida os ju\u00edzes su\u00ed\u00e7os falem numa \u201cestimativa de mais de<strong> 4 mil milh\u00f5es<\/strong> de d\u00f3lares\u201d em fundos desviados devido \u00e0s atividades comerciais do condenado.<\/p>\n<p style=\"text-align: justify;\">O empres\u00e1rio, que durante quase duas d\u00e9cadas teve o monop\u00f3lio dos seguros e resseguros da petrol\u00edfera estatal angolana Sonangol, <strong>ter\u00e1 montado um esquema triangular, com empresas em <a href=\"https:\/\/observador.pt\/2022\/09\/21\/diamante-branco-de-131-quilates-descoberto-na-mina-angolana-do-lulo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Angola<\/a>, Londres e Bermudas, que gerou perdas para o tesouro angolano<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Com este esquema, e segundo o mesmo documento, Carlos S\u00e3o Vicente, dono de um dos maiores grupos empresariais privados de ent\u00e3o em Angola, ter\u00e1 tamb\u00e9m conseguido n\u00e3o partilhar lucros do neg\u00f3cio dos seguros e resseguros com outras cosseguradoras, como a seguradora p\u00fablica ENSA, prejudicando, deste modo, estas empresas, bem como a pr\u00f3pria Sonangol.<\/p>\n<div class=\"obs-ad-container obs-ad-container-web_article_middle obs-in-article-container obs-in-article-container-empty\" style=\"text-align: justify;\">\n<div id=\"web_article_middle_2\" class=\"obs-ad \"><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Para a acusa\u00e7\u00e3o, Carlos S\u00e3o Vicente criou a partir de determinada altura uma \u201cesp\u00e9cie de neg\u00f3cio consigo pr\u00f3prio, dentro do grupo AAA (de que era propriet\u00e1rio), causando o desvio de fundos p\u00fablicos\u201d.<\/p>\n<p style=\"text-align: justify;\">As acusa\u00e7\u00f5es e o \u201cexcesso de pris\u00e3o preventiva\u201d foram reiteradas vezes contestadas pela defesa, que prometeu em mar\u00e7o ir recorrer da senten\u00e7a ditada na 3.\u00aa Sec\u00e7\u00e3o Criminal do Tribunal da Comarca de Luanda.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong><em>Fonte: observador.pt<\/em><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Advogados de Carlos S\u00e3o Vicente, condenado a 9 anos de cadeia e a multa de 500 milh\u00f5es de d\u00f3lares, consideram &#8220;decis\u00e3o hist\u00f3rica&#8221; que supremo su\u00ed\u00e7o &#8220;reconhece d\u00favidas de julgamento justo em Angola&#8221;. Os advogados do empres\u00e1rio angolano Carlos S\u00e3o Vicente disseram esta quarta-feira que um tribunal su\u00ed\u00e7o decretou a suspens\u00e3o da coopera\u00e7\u00e3o com as autoridades judiciais angolanas, devido \u00e0 falta de imparcialidade no processo judicial contra o seu cliente. O Supremo Tribunal decidiu que as autoridades su\u00ed\u00e7as n\u00e3o podiam cooperar com Angola antes de avaliarem a possibilidade e a efic\u00e1cia da obten\u00e7\u00e3o de v\u00e1rias garantias diplom\u00e1ticas por parte deste pa\u00eds, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5369","post","type-post","status-publish","format-standard","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Advogados de Carlos S\u00e3o Vicente, condenado a 9 anos de cadeia e a multa de 500 milh\u00f5es de d\u00f3lares, consideram &#8220;decis\u00e3o hist\u00f3rica&#8221; que supremo su\u00ed\u00e7o &#8220;reconhece d\u00favidas de julgamento justo em Angola&#8221;. Os advogados do empres\u00e1rio angolano Carlos S\u00e3o Vicente disseram esta quarta-feira que um tribunal su\u00ed\u00e7o decretou a suspens\u00e3o da coopera\u00e7\u00e3o com as autoridades judiciais angolanas, devido \u00e0 falta de imparcialidade no processo judicial contra o seu cliente. O Supremo Tribunal decidiu que as autoridades su\u00ed\u00e7as n\u00e3o podiam cooperar com Angola antes de avaliarem a possibilidade e a efic\u00e1cia da obten\u00e7\u00e3o de v\u00e1rias garantias diplom\u00e1ticas por parte deste pa\u00eds, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-22T20:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T20:33:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bordalo.observador.pt\/v2\/q:84\/rs:fill:2000:1126\/c:2000:1126:nowe:0:0\/plain\/https:\/\/s3.observador.pt\/wp-content\/uploads\/2022\/02\/11060219\/35378375.jpg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente\",\"datePublished\":\"2022-09-22T20:00:33+00:00\",\"dateModified\":\"2022-09-22T20:33:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/\"},\"wordCount\":578,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bordalo.observador.pt\\\/v2\\\/q:84\\\/rs:fill:2000:1126\\\/c:2000:1126:nowe:0:0\\\/plain\\\/https:\\\/\\\/s3.observador.pt\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/11060219\\\/35378375.jpg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/\",\"name\":\"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente - Jornal O Crime\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bordalo.observador.pt\\\/v2\\\/q:84\\\/rs:fill:2000:1126\\\/c:2000:1126:nowe:0:0\\\/plain\\\/https:\\\/\\\/s3.observador.pt\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/11060219\\\/35378375.jpg\",\"datePublished\":\"2022-09-22T20:00:33+00:00\",\"dateModified\":\"2022-09-22T20:33:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bordalo.observador.pt\\\/v2\\\/q:84\\\/rs:fill:2000:1126\\\/c:2000:1126:nowe:0:0\\\/plain\\\/https:\\\/\\\/s3.observador.pt\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/11060219\\\/35378375.jpg\",\"contentUrl\":\"https:\\\/\\\/bordalo.observador.pt\\\/v2\\\/q:84\\\/rs:fill:2000:1126\\\/c:2000:1126:nowe:0:0\\\/plain\\\/https:\\\/\\\/s3.observador.pt\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/11060219\\\/35378375.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/","og_locale":"pt_PT","og_type":"article","og_title":"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente - Jornal O Crime","og_description":"Advogados de Carlos S\u00e3o Vicente, condenado a 9 anos de cadeia e a multa de 500 milh\u00f5es de d\u00f3lares, consideram &#8220;decis\u00e3o hist\u00f3rica&#8221; que supremo su\u00ed\u00e7o &#8220;reconhece d\u00favidas de julgamento justo em Angola&#8221;. Os advogados do empres\u00e1rio angolano Carlos S\u00e3o Vicente disseram esta quarta-feira que um tribunal su\u00ed\u00e7o decretou a suspens\u00e3o da coopera\u00e7\u00e3o com as autoridades judiciais angolanas, devido \u00e0 falta de imparcialidade no processo judicial contra o seu cliente. O Supremo Tribunal decidiu que as autoridades su\u00ed\u00e7as n\u00e3o podiam cooperar com Angola antes de avaliarem a possibilidade e a efic\u00e1cia da obten\u00e7\u00e3o de v\u00e1rias garantias diplom\u00e1ticas por parte deste pa\u00eds, [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/","og_site_name":"Jornal O Crime","article_published_time":"2022-09-22T20:00:33+00:00","article_modified_time":"2022-09-22T20:33:43+00:00","og_image":[{"url":"https:\/\/bordalo.observador.pt\/v2\/q:84\/rs:fill:2000:1126\/c:2000:1126:nowe:0:0\/plain\/https:\/\/s3.observador.pt\/wp-content\/uploads\/2022\/02\/11060219\/35378375.jpg","type":"","width":"","height":""}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/"},"author":{"name":"Jornal O Crime","@id":"https:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente","datePublished":"2022-09-22T20:00:33+00:00","dateModified":"2022-09-22T20:33:43+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/"},"wordCount":578,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#primaryimage"},"thumbnailUrl":"https:\/\/bordalo.observador.pt\/v2\/q:84\/rs:fill:2000:1126\/c:2000:1126:nowe:0:0\/plain\/https:\/\/s3.observador.pt\/wp-content\/uploads\/2022\/02\/11060219\/35378375.jpg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/","url":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/","name":"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente - Jornal O Crime","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#primaryimage"},"thumbnailUrl":"https:\/\/bordalo.observador.pt\/v2\/q:84\/rs:fill:2000:1126\/c:2000:1126:nowe:0:0\/plain\/https:\/\/s3.observador.pt\/wp-content\/uploads\/2022\/02\/11060219\/35378375.jpg","datePublished":"2022-09-22T20:00:33+00:00","dateModified":"2022-09-22T20:33:43+00:00","author":{"@id":"https:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#primaryimage","url":"https:\/\/bordalo.observador.pt\/v2\/q:84\/rs:fill:2000:1126\/c:2000:1126:nowe:0:0\/plain\/https:\/\/s3.observador.pt\/wp-content\/uploads\/2022\/02\/11060219\/35378375.jpg","contentUrl":"https:\/\/bordalo.observador.pt\/v2\/q:84\/rs:fill:2000:1126\/c:2000:1126:nowe:0:0\/plain\/https:\/\/s3.observador.pt\/wp-content\/uploads\/2022\/02\/11060219\/35378375.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/suica-suspende-cooperacao-com-angola-no-caso-judicial-de-carlos-sao-vicente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Su\u00ed\u00e7a suspende coopera\u00e7\u00e3o com Angola no caso judicial de Carlos S\u00e3o Vicente"}]},{"@type":"WebSite","@id":"https:\/\/jornalocrime.com\/ilnes\/#website","url":"https:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"https:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5369"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5369\/revisions"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}