{"id":5388,"date":"2022-09-26T18:40:10","date_gmt":"2022-09-26T17:40:10","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5388"},"modified":"2022-09-26T18:40:10","modified_gmt":"2022-09-26T17:40:10","slug":"detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/","title":{"rendered":"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES"},"content":{"rendered":"<p style=\"text-align: justify;\">O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal da prov\u00edncia do Bengo, deteve no passado dia 14, um cidad\u00e3o nacional de 36 anos, gestor de contas do Banco Millennium Atl\u00e2ntico, acusado do crime de abuso de confian\u00e7a qualificada e Falsifica\u00e7\u00e3o de documentos, por subtrair 200 milh\u00f5es de kwanzas em contas banc\u00e1rias de clientes.<\/p>\n<p style=\"text-align: justify;\">A informa\u00e7\u00e3o foi avan\u00e7ada pelo Porta-voz do SIC Bengo, Peterson Cassule, que adiantou que os factos ter\u00e3o ocorrido desde o m\u00eas de maio do ano em curso, onde o mesmo foi detido com base em uma den\u00fancia P\u00fablica e no seguimento de um trabalho de investiga\u00e7\u00e3o feito pelo SIC, quando o acusado na qualidade de gestor de contas do Banco Millennium Atl\u00e2ntico, alterava as ordens de pagamentos e em seguida colocava as coordenadas banc\u00e1rias de indiv\u00edduos conhecidos por si, para posterior apoderar-se dos valores monet\u00e1rios que eram transferidos nestas contas.<\/p>\n<p style=\"text-align: justify;\">Peterson Cassule acrescentou, ainda que o acusado em causa, presumivelmente vem praticando de forma reiterada o crime, tendo sido calculado at\u00e9 agora um valor de duzentos milh\u00f5es de kwanzas (200.000.000,00).<\/p>\n<p style=\"text-align: justify;\">De acordo com o porta-voz, o cidad\u00e3o em causa e mais quatro indiv\u00edduos acusados nos crimes de abuso sexual e furtos, presentes \u00e0 imprensa no passado dia 16, j\u00e1 foram presentes ao Minist\u00e9rio Publico, que promoveu o primeiro interrogat\u00f3rio e decretou a medida de coa\u00e7\u00e3o mais gravosa e dever\u00e3o aguardar os ulteriores tr\u00e2mites processuais em regime de Pris\u00e3o Preventiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal da prov\u00edncia do Bengo, deteve no passado dia 14, um cidad\u00e3o nacional de 36 anos, gestor de contas do Banco Millennium Atl\u00e2ntico, acusado do crime de abuso de confian\u00e7a qualificada e Falsifica\u00e7\u00e3o de documentos, por subtrair 200 milh\u00f5es de kwanzas em contas banc\u00e1rias de clientes. A informa\u00e7\u00e3o foi avan\u00e7ada pelo Porta-voz do SIC Bengo, Peterson Cassule, que adiantou que os factos ter\u00e3o ocorrido desde o m\u00eas de maio do ano em curso, onde o mesmo foi detido com base em uma den\u00fancia P\u00fablica e no seguimento de um trabalho de investiga\u00e7\u00e3o feito pelo SIC, quando [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5388","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actual","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal da prov\u00edncia do Bengo, deteve no passado dia 14, um cidad\u00e3o nacional de 36 anos, gestor de contas do Banco Millennium Atl\u00e2ntico, acusado do crime de abuso de confian\u00e7a qualificada e Falsifica\u00e7\u00e3o de documentos, por subtrair 200 milh\u00f5es de kwanzas em contas banc\u00e1rias de clientes. A informa\u00e7\u00e3o foi avan\u00e7ada pelo Porta-voz do SIC Bengo, Peterson Cassule, que adiantou que os factos ter\u00e3o ocorrido desde o m\u00eas de maio do ano em curso, onde o mesmo foi detido com base em uma den\u00fancia P\u00fablica e no seguimento de um trabalho de investiga\u00e7\u00e3o feito pelo SIC, quando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-26T17:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/09\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edson Fortes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edson Fortes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/\"},\"author\":{\"name\":\"Edson Fortes\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"headline\":\"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES\",\"datePublished\":\"2022-09-26T17:40:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/\"},\"wordCount\":269,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/\",\"name\":\"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES - Jornal O Crime\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg\",\"datePublished\":\"2022-09-26T17:40:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg\",\"width\":1125,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/36b742c067c7b8d8944cc6b6bf47fce4\",\"name\":\"Edson Fortes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g\",\"caption\":\"Edson Fortes\"},\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/edson-fortes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/","og_locale":"pt_PT","og_type":"article","og_title":"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES - Jornal O Crime","og_description":"O Servi\u00e7o de Investiga\u00e7\u00e3o Criminal da prov\u00edncia do Bengo, deteve no passado dia 14, um cidad\u00e3o nacional de 36 anos, gestor de contas do Banco Millennium Atl\u00e2ntico, acusado do crime de abuso de confian\u00e7a qualificada e Falsifica\u00e7\u00e3o de documentos, por subtrair 200 milh\u00f5es de kwanzas em contas banc\u00e1rias de clientes. A informa\u00e7\u00e3o foi avan\u00e7ada pelo Porta-voz do SIC Bengo, Peterson Cassule, que adiantou que os factos ter\u00e3o ocorrido desde o m\u00eas de maio do ano em curso, onde o mesmo foi detido com base em uma den\u00fancia P\u00fablica e no seguimento de um trabalho de investiga\u00e7\u00e3o feito pelo SIC, quando [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/","og_site_name":"Jornal O Crime","article_published_time":"2022-09-26T17:40:10+00:00","og_image":[{"width":1125,"height":750,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/09\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg","type":"image\/jpeg"}],"author":"Edson Fortes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Edson Fortes","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/"},"author":{"name":"Edson Fortes","@id":"https:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"headline":"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES","datePublished":"2022-09-26T17:40:10+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/"},"wordCount":269,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/09\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/","url":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/","name":"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES - Jornal O Crime","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/09\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg","datePublished":"2022-09-26T17:40:10+00:00","author":{"@id":"https:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/09\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/09\/7E290997-09D9-496D-B97A-0A3165876ECB.jpeg","width":1125,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/detido-gestor-de-contas-por-subtrair-duzentos-milhoes-de-kwanzas-em-contas-bancarias-de-clientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"DETIDO GESTOR DE CONTAS POR SUBTRAIR DUZENTOS MILH\u00d5ES DE KWANZAS EM CONTAS BANC\u00c1RIAS DE CLIENTES"}]},{"@type":"WebSite","@id":"https:\/\/jornalocrime.com\/ilnes\/#website","url":"https:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"https:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/36b742c067c7b8d8944cc6b6bf47fce4","name":"Edson Fortes","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83ac458f186dbc3c060e7303e7f9520460ccfbbc090a5d2fad6688735007851d?s=96&d=mm&r=g","caption":"Edson Fortes"},"url":"https:\/\/jornalocrime.com\/ilnes\/author\/edson-fortes\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5388"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/5389"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}