{"id":5540,"date":"2022-10-28T18:56:06","date_gmt":"2022-10-28T17:56:06","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5540"},"modified":"2022-10-28T18:56:06","modified_gmt":"2022-10-28T17:56:06","slug":"estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/","title":{"rendered":"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O principal r\u00e9u deste medi\u00e1tico processo, o major Pedro Lussaty, que surpreendeu o pa\u00eds, quando foi detido na denominada &#8220;Opera\u00e7\u00e3o Caranguejo&#8221;, com milh\u00f5es de d\u00f3lares, euros, kwanzas, que se encontravam escondidos em malas de viagens em v\u00e1rios apartamentos, assim como carros de luxos e outros bens, foi ouvido em tribunal, onde alegou ser inocente e s\u00f3 se encontra na condi\u00e7\u00e3o de r\u00e9u por ser alvo de persegui\u00e7\u00e3o pela riqueza que construiu, que \u00e9 fruto do seu trabalho de empreendedorismo que vem exercendo desde adolesc\u00eancia. Eis ao detalhe o interrogat\u00f3rio do Major.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><em>Felicidade Kauanda<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Qual \u00e9 o seu nome?<br \/>\nPedro Lussaty &#8211; Pedro Lussaty<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Qual \u00e9 a sua ocupa\u00e7\u00e3o?<br \/>\nPedro Lussaty &#8211; Militar com grau de major e dedico-me tamb\u00e9m no ramo de empreendorismo.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Os nomes \u00c9dson Paulino Ferreira de Ros\u00e1rio, Denis Campos, Dorivaldo M\u00e1rio Santiago, e J\u00e9ssica Pina. Ajudavam-lhe a tirar dinheiro de Angola para Portugal?<br \/>\nPedro Lussaty \u2013 Merit\u00edssimo, nunca tive necessidade de tirar dinheiro de Angola para Portugal e nunca precisei. Como tenho patrim\u00f3nio em Portugal meu maior problema, sobretudo no per\u00edodo da pandemia, foram os pagamentos das contas ou despesas. Muitas vezes por viver aqui em Angola e porque a minha conta pessoal l\u00e1 sou o \u00fanico a movimentar, entretanto, para execu\u00e7\u00e3o ou pagamentos, como por exemplo da \u00e1gua e energia el\u00e9trica, sou obrigado a ligar para algu\u00e9m l\u00e1, isto \u00e9, um amigo portugu\u00eas ou outra pessoa no sentido de me arranjar 3 ou 5 mil euros para que eu liquide as referidas d\u00edvidas.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; O senhor n\u00e3o adquiriu bens provenientes do Fundo da Casa de Seguran\u00e7a do Presidente da Rep\u00fablica e colocou em nome da senhora Denis Campos dos Santos e do senhor Jomilton?<br \/>\nPedro Lussaty &#8211; Na Casa Militar nunca teve dinheiro para isso. N\u00e3o tem fundos que eu me apossei ou que me permitiu criar esse patrim\u00f3nio. Se o Merit\u00edssimo olhar como um patrim\u00f3nio estaria a generalizar todas unidades. Se as restantes n\u00e3o t\u00eam como \u00e9 que eu tenho? Se tem apenas um \u00fanico chefe que assinala? N\u00e3o existe.<\/p>\n<p style=\"text-align: justify;\">Tribunal \u2013 A senhora Denis levava dinheiro de Angola para Portugal e l\u00e1 depositava na conta do senhor Jomilton para chegar at\u00e9 si?<br \/>\nPedro Lussaty &#8211; N\u00e3o conhe\u00e7o esse senhor e nem essa senhora. Nunca precisei levar dinheiro para fora do pa\u00eds, os valores que precisava era apenas para pagar as despesas da casa que l\u00e1 tenho, como \u00e1gua e energia. Quando quisesse, viajar levava dinheiro desde que fosse a quantia permitida.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Esses senhores compravam moedas estrangeiras para si aqui em Angola para depois lhe fazer chegar em Portugal?<br \/>\nPedro Lussaty &#8211; N\u00e3o sei dizer quem s\u00e3o. Eu n\u00e3o uso pessoas que n\u00e3o conhe\u00e7o e a \u00fanica pessoa que coloquei bem em seu nome \u00e9 o meu sobrinho Fernando, coloquei em seu nome um iate. Sinto-me muito mal pelo facto dele estar preso somente por ter um bem meu em seu nome e este bem \u00e9 um bem de fam\u00edlia.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; O senhor deu dinheiro \u00e0 senhora Denise dos Santos a t\u00edtulo de recompensa e com este valor ela comprou um im\u00f3vel na Samba?<br \/>\nPedro Lussaty \u2013 Merit\u00edssimo, a princ\u00edpio quando disse que n\u00e3o conhe\u00e7o esta pessoa descarta-se a hip\u00f3tese de ter alguma conex\u00e3o ou ter-lhe dado alguma coisa. N\u00e3o dou dinheiro para comprar coisas, se tivesse dado diria que ofereci, \u00e9 dinheiro do meu suor. Agora, se o Merit\u00edssimo tivesse-me perguntado se j\u00e1 ofereci bens, eu responderia que sim, j\u00e1 ofereci carro e tamb\u00e9m j\u00e1 comprei muitos bens.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Senhor Pedro, quando estava a falar dos bens os enquadrou em tr\u00eas categorias: Bens que eram seus, bens que eram de fam\u00edlia. Pelo menos um im\u00f3vel disse que era da sua m\u00e3e. Pode nos esclarecer melhor o que quer dizer bens de fam\u00edlia?<br \/>\nPedro Lussaty \u2013 Sim, por exemplo todos n\u00f3s temos fam\u00edlias com direitos, como ter casa. Portanto, a casa da minha m\u00e3e n\u00e3o \u00e9 minha, mas sim de fam\u00edlia.<br \/>\nTribunal &#8211; O senhor teve alguma interven\u00e7\u00e3o nestes bens de fam\u00edlia?<br \/>\nPedro Lussaty &#8211; Provavelmente que sim, porque sou filho \u00fanico da minha m\u00e3e e tamb\u00e9m o respons\u00e1vel dela.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; O senhor diz que o seu apartamento foi acedido por pessoas estranhas e \u00e9 ali onde acondicionava alguns bens e tamb\u00e9m algumas somas em dinheiro. Quando foi comunicado que o seu apartamento foi assaltado o senhor procurou ir l\u00e1 saber quem e como foi assaltado?<br \/>\nPedro Lussaty \u2013 Sim, quando cheguei no apartamento a porta estava fechada mas indiciava alguma ac\u00e7\u00e3o incorrecta. Por desconfian\u00e7a, liguei a minha irm\u00e3, pedi ao meu sobrinho que viesse porque j\u00e1 h\u00e1 uns anos que recebo chamadas an\u00f3nimas de amea\u00e7as de morte de pessoas e amigos que conhe\u00e7o. S\u00f3 para informa\u00e7\u00e3o, antes deste processo diziam-me que tinha um outro PGR que o seu director do gabinete estava com um processo meu. O mesmo dizia que eu tinha de pagar a essas pessoas. Mas eu dizia que n\u00e3o tenho problema com essa pessoa que me chantageou, se notarmos nos autos \u00e9 a mesma que fez a participa\u00e7\u00e3o para abrir este processo.<br \/>\nFoi da\u00ed que eu fiquei com medo quando fui ao apartamento liguei para o meu sobrinho, e encontramos a casa desorganizada verificamos que eles arrombaram a porta tiraram o dinheiro e trocaram a fechadura. Mandei a minha irm\u00e3 abrir uma queixa no SIC, mas at\u00e9 agora n\u00e3o houve desenvolvimento.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; O senhor disse quando o apartamento foi assaltado algu\u00e9m lhe comunicou por mensagem e lhe aconselhava a fugir. Porque ao inv\u00e9s disso n\u00e3o o disse para ir ver o que faltava?<br \/>\nPedro Lussaty &#8211; Merit\u00edssimo Juiz, antes de ser juiz \u00e9 angolano, e deve saber que aqui em Angola as pessoas que t\u00eam dinheiro n\u00e3o vivem bem, eu, se calhar, foi minha sorte de estar na cadeia para evitar que as coisas viessem \u00e0 superf\u00edcie ou ent\u00e3o iam me fazer o pior.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Ent\u00e3o o senhor n\u00e3o acha estranho que algu\u00e9m se apercebe que a sua resid\u00eancia foi assaltada por pessoas estranhas e vai aconselh\u00e1-lo a colocar-se em fuga, sem sabermos quem efectivamente foi l\u00e1 assaltar?<br \/>\nPedro Lussaty &#8211; J\u00e1 expliquei que a mensagem veio at\u00e9 o nome da pessoa que estava l\u00e1 assaltar, esta pessoa a que me refiro ainda falou comigo, n\u00e3o quero s\u00f3 dizer aqui o nome fica s\u00f3 comigo. O dinheiro que assaltaram \u00e9 o mesmo que apareceu na PGR. N\u00e3o tinha dinheiro na casa V ou C estava todo num s\u00edtio. Como refere os autos 17 milh\u00f5es de d\u00f3lares em numer\u00e1rio e estou aqui amarrado como se tivesse feito alguma coisa.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; O senhor tinha diversas contas banc\u00e1rias, o que lhe levava aguardar avultadas somas dentro de casa ao inv\u00e9s de colocar ao banco?<br \/>\nPedro Lussaty &#8211; Dr. Juiz, eu fa\u00e7o neg\u00f3cios, vou ser sincero, honestamente como militar estudei economia e contabilidade, mas os bancos nunca me deram muita seguran\u00e7a sempre dizia 50 a 50. O banco faliu tenho o meu numer\u00e1rio, sempre fazia assim \u00e9 o meu modelo de gest\u00e3o mesmo quando dava aulas.<br \/>\nAgora, como se aprovou-se, em 2010, a proibi\u00e7\u00e3o de moedas, o assunto para n\u00f3s que fizemos neg\u00f3cios ficou um pouco dif\u00edcil porque antigamente era normal n\u00f3s fazermos um pagamento em numer\u00e1rio do dinheiro que agente quisesse porque n\u00e3o era crime nenhum ter dinheiro, o crime agora \u00e9 reter moeda. Mas em contrapartida, para mim era normal nunca tive medo de ter dinheiro em numer\u00e1rio, porque sempre achava 90% de perigo meu dinheiro no banco do que na minha m\u00e3o, na minha casa que me dava certeza que o dinheiro estava sempre comigo.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Senhor Pedro disse que os bens referidos nos autos encontrados no seu apartamento n\u00e3o s\u00e3o o que verdadeiramente foram, porque tinha muito mais. Tinha tamb\u00e9m um milh\u00e3o de euros. Dos c\u00e1lculos feitos com o sal\u00e1rio que as suas patentes auferem nas for\u00e7as armadas ao lado do patrim\u00f3nio que foi declarado aqui, como \u00e9 que o senhor com este rendimento teve de comer e fazer outras actividades e conseguiu levantar este patrim\u00f3nio todo que, provavelmente, por exemplo, nem todos os generais t\u00eam, quando o sal\u00e1rio \u00e9 s\u00f3 esse? Deixa-me dizer que n\u00e3o \u00e9 mal algum angolano ser rico, ali\u00e1s os angolanos devem trabalhar, e do seu trabalho adquirir riqueza desde que seja de origem l\u00edcita tamb\u00e9m o estado fica feliz porque quando mais recurso t\u00eam mais imposto \u00e9 pago.<br \/>\nPedro Lussaty \u2013 Merit\u00edssimo, n\u00f3s aprendemos em economia o conceito de rendimento. O rendimento n\u00e3o \u00e9 igual a sal\u00e1rio. Outra coisa, os militares das For\u00e7as Armadas Angolanas n\u00e3o auferem sal\u00e1rio, mas sim vencimento, que \u00e9 um conv\u00e9nio fruto da convic\u00e7\u00e3o militar. Significa que eu n\u00e3o tenho sal\u00e1rio eu tenho vencimento. A condi\u00e7\u00e3o militar \u00e9 que me define o valor, fruto disto \u00e9 que num auto de desempenho nas For\u00e7as Armadas um capit\u00e3o pode estar durante um ano a dormir vai receber sempre o mesmo dinheiro de um capit\u00e3o que vai todos os dias trabalhar. Porque recebe vencimento e n\u00e3o salario. Eu major Pedro Lussaty, primeiro, sou habilidoso homem de neg\u00f3cios fruto disto estou aqui neste tribunal porque as pessoas se aproveitaram de mim j\u00e1 que tiveram insucesso, ent\u00e3o me trouxeram aqui.<br \/>\nE eu, aos 14, 15 e 16 anos de idade, sempre fiz neg\u00f3cio desde o mais elementar at\u00e9 aos grandes neg\u00f3cios<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Que tipos de neg\u00f3cios?<br \/>\nPedro Lussaty &#8211; Por exemplo de forma informativa, eu tenho terreno no Talatona, quando comprei o terreno, l\u00e1 era 2mil d\u00f3lares, dez anos depois vendemos 20 milh\u00f5es de euros, s\u00f3 estou a dar um exemplo. O meu terreno da via expressa quem vai para o Zango j\u00e1 arrendei 50 mil d\u00f3lares m\u00eas a uma empresa, mas hoje posso arrendar a quinhentos mil kwanzas m\u00eas.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Esses valores eram pagos via banc\u00e1ria ou recebia em m\u00e3o?<br \/>\nPedro Lussaty &#8211; Naquela altura quando fazia neg\u00f3cios, por exemplo, se estava a vender 5 milh\u00f5es ou 2 milh\u00f5es, pagavam-me em duas tranches, isto \u00e9, uma via banco e outra em cash<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Mas os 20 milh\u00f5es de euros e 50 milh\u00f5es de kwanzas da renda recebia tudo em m\u00e3o?<br \/>\nPedro Lussaty &#8211; Para ser sincero a este tribunal j\u00e1 recebi este dinheiro em m\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Ent\u00e3o sempre que recebia guardavas em casa?<br \/>\nPedro Lussaty \u2013 Sim, por isso n\u00e3o estou seguro do dinheiro que est\u00e1 no tribunal.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Al\u00e9m deste assunto de terrenos incluem tamb\u00e9m casas?<br \/>\nLussaty- Sim.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; Como foi aquisi\u00e7\u00e3o destes terrenos e casas?<br \/>\nPedro Lussaty &#8211; Eu tamb\u00e9m tinha uma carpintaria no Benfica, particip\u00e1vamos numa empresa faz\u00edamos casas era uma empresa que tinha tamb\u00e9m chineses. Nos anos 2005 a 2006 investimos em compras de material de constru\u00e7\u00e3o e os particulares, naquela altura, queriam casas para comprar. Muitas das casas no Benfica foi a nossa empresa que fez , tinha casas que vendemos um milh\u00e3o de d\u00f3lar com investimentos de cem mil d\u00f3lares na altura, o c\u00e2mbio era dez, mas era normal porque as pessoas tivessem liquidez.<\/p>\n<p style=\"text-align: justify;\">Tribunal &#8211; O patrim\u00f3nio que o senhor tem hoje que at\u00e9 foi avaliado n\u00e3o \u00e9 resultante de fundos provenientes da Casa de Seguran\u00e7a do Presidente da Rep\u00fablica, mas sim fruto do trabalho que vem desenvolvendo em fun\u00e7\u00e3o de vendas do seu empreendedorismo ?<br \/>\nPedro Lussaty \u2013 Sim, vendas de terrenos, carpintaria e constru\u00e7\u00e3o civil.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #ff0000;\">\u201cO dinheiro apreendido pela PGR em minha casa n\u00e3o \u00e9 s\u00f3 17 milh\u00f5es de d\u00f3lares\u201d<\/span><\/h2>\n<p style=\"text-align: justify;\">Tribunal &#8211; Este valor ficava normalmente sobre sua responsabilidade n\u00e3o depositava no banco e foi crescendo?<br \/>\nPedro Lussaty \u2013 Sim, mas tamb\u00e9m no banco tem dinheiro. Mas o que esta no banco, n\u00e3o sei porqu\u00ea n\u00e3o tenho estrato n\u00e3o consigo conferir. Acrescento, tamb\u00e9m, senhor juiz, que eu major Pedro Lussaty oficial superior das For\u00e7as Armadas Angolanas, nunca em nenhum momento de forma abusiva e propositada acedi a qualquer Fundo da Casa Militar ou do pa\u00eds.<br \/>\nNunca tive essa autoridade e nunca me foi dado esse poder de o fazer. Porque como major, o chefe que trabalha comigo j\u00e1 sabe que eu tenho dinheiro n\u00e3o me manda quest\u00f5es destas. As pessoas sabem que eu tenho dinheiro n\u00e3o podem me mandar coisas. Agora como o tribunal n\u00e3o me conhece, por isso as perguntas. Quest\u00f5es de trabalho fa\u00e7o ilegal n\u00e3o porque na tropa \u00e9 transpar\u00eancia e rigoroso.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio Publico &#8211; Senhor Pedro enquanto oficial no exerc\u00edcio da Secretaria Geral da Casa de Seguran\u00e7a do Presidente da Rep\u00fablica, alguma vez elaborou, assinou folhas de sal\u00e1rios planos de pagamentos para as unidades de desminagem, chacal e banda de m\u00fasica?<br \/>\nPedro Lussaty \u2013 Dign\u00edssimo, a Casa Militar na sua esfera de trabalho a Desminagem era um projecto, o Chacal tamb\u00e9m, esses projectos estrat\u00e9gicos funcionais. Na Casa de Seguran\u00e7a simplesmente, eu major Pedro Lussaty recebia do meu chefe imediato secret\u00e1rio geral expediente vindo destes projectos o meu chefe dava-me senhor Pedro esse projecto imprime eu imprimia e entregava a ele. No princ\u00edpio n\u00e3o met\u00edamos nenhuma r\u00fabrica porque pens\u00e1vamos que era um pr\u00e9-projecto, mas depois quando o chefe dizia que p\u00f5e alguma coisa aqui para confirmar que saiu daqui eu punha. Mas estes projectos tinham um programa que j\u00e1 encontrei feito por um senhor na Casa Militar que trabalhou nos finais de 2010 a 2011.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Mas eu perguntei se assinava?<br \/>\nPedro Lussaty &#8211; Eu respondi que quando imprim\u00edssemos o chefe dizia que p\u00f5e qualquer coisa para sinalizar que saiu daqui.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Quanto a esse expediente elabora\u00e7\u00e3o de folhas de sal\u00e1rios, planos de pagamentos sobretudo o batalh\u00e3o de desminagem chacal e banda de musica. Sabes se eram conferidas por quem?<br \/>\nPedro Lussaty &#8211; J\u00e1 expliquei, dign\u00edssimo que a desminagem e chacal eram projectos, tem uma estrutura, um chefe de recursos humanos, coordena\u00e7\u00e3o de um tenente general no papel de secret\u00e1rio que despacha para o meu chefe secret\u00e1rio geral, o ministro da Casa Militar. N\u00e3o sei dizer se havia confer\u00eancia ou quem conferia ou n\u00e3o conferia, sei apenas que esse projecto tem uma estrutura, n\u00f3s, simplesmente, imprim\u00edamos. Que eu devo esclarecer aqui \u00e9 que qualquer unidade da Casa Militar, para a execu\u00e7\u00e3o, carece de um empossamento e para existir alguma ac\u00e7\u00e3o de pagamento ou qualquer coisa que fosse \u00e9 preciso um limite de despesas.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico \u2013 Sabe-se que na unidade de desminagem haviam de 1\u00ba at\u00e9 10\u00ba batalh\u00f5es. Mas haviam tamb\u00e9m desses j\u00e1 citados batalh\u00f5es que n\u00e3o eram efectivos, mas elaborava-se tamb\u00e9m sal\u00e1rios e planos de pagamentos para o 6\u00ba e 8\u00ba batalh\u00f5es e n\u00e3o tinham nenhum integrante. O que o senhor tem a dizer?<br \/>\nPedro Lussaty \u2013 Dign\u00edssimo, como j\u00e1 referi, a tomada de decis\u00f5es \u00e9 do Comando, eu fa\u00e7o parte do n\u00edvel t\u00e1ctico, que \u00e9 de execu\u00e7\u00e3o de escriv\u00e3o eu era tipo escriv\u00e3o s\u00f3 consignava, se me dissessem p\u00f5e esta pedra aqui eu punha, se me falassem tira eu tirava. Nas For\u00e7as Armadas, \u00e9 assim, muitas vezes, se o chefe te dizer toma esse envelope poderia passar um m\u00eas n\u00e3o abria.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Resulta dos autos provas sobre o conceito dos batalh\u00f5es que n\u00e3o existiam integrantes, mas por m\u00eas eram processados sal\u00e1rios AKZ 80 milh\u00f5es que em um ano daria AKZ 960 milh\u00f5es s\u00f3 com um batalh\u00e3o. Da\u00ed o n\u00edvel de desfalque essas folhas e planos eram processados na secretaria geral. O que o senhor tem a dizer?<br \/>\nPedro Lussaty &#8211; Vou repetir os mesmos termos que j\u00e1 disse. H\u00e1 uma cadeia de Comando, uma unidade estrat\u00e9gica, um chefe que est\u00e1 num n\u00edvel estrat\u00e9gico e um na desminagem. O que o dign\u00edssimo disse sobre a 6\u00ba e 10\u00ba, fazem parte deste grupo de desminagem que o projecto de desminagem faz parte e t\u00eam uma estrutura que \u00e9 a respons\u00e1vel.<br \/>\nEssa estrutura tem um general que \u00e9 o coordenador, ele por sua vez, despacha a provid\u00eancia para o secret\u00e1rio geral e este me d\u00e1. Eu n\u00e3o fa\u00e7o nada sem ele me dizer. Se ele me disser imprime eu imprimo. Muda a capa eu mudo. Assina eu assino. \u00c9 s\u00f3 isso.<\/p>\n<p>Minist\u00e9rio P\u00fablico &#8211; Conheces o Comandante do batalh\u00e3o de transportes de Cuando Cubango?<br \/>\nPedro Lussaty &#8211; N\u00e3o sei de quem se trata, mas agora que estou na cela estou a lhe ver.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico \u2013 O mandat\u00e1rio dele, na contesta\u00e7\u00e3o, referiu que o dinheiro que sobrava do 6\u00ba e 8\u00ba e outros batalh\u00f5es, em fun\u00e7\u00e3o das folhas infraccionadas todos os meses voltava para Luanda em malas e eram entregues aos generais De Brito, Dilangue e uma mala para si. O que tem a dizer?<br \/>\nPedro Lussaty &#8211; Nas For\u00e7as Armadas, tem cadeia de Comando, tem hierarquia e tem uma lei chamada de \u2018Lei de disciplina militar\u2019. Eu sou major e um major n\u00e3o recebe dossier dum tenente coronel \u00e9 crime, n\u00e3o \u00e9 proibido, mas sim \u00e9 crime, at\u00e9 receber de forma l\u00edcita, est\u00e1 no estatuto militar. Ali\u00e1s, com o meu n\u00edvel de patrim\u00f3nio n\u00e3o \u00e9 poss\u00edvel receber de algu\u00e9m dinheiro que nunca vi.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico \u2013 Por que raz\u00e3o o seu nome consta de um documento de dinheiro pertencente ao r\u00e9u Joaquim Amado?<br \/>\nPedro Lussaty \u2013 Dign\u00edssimo, vou ser sincero, estou a ser v\u00edtima n\u00e3o por estar aqui, mas \u00e9 uma v\u00edtima recorrente. Por exemplo, h\u00e1 uns seis anos o meu chefe imediato chamou-me e disse \u201cPedro, disseram-me que tu tens patrim\u00f3nio\u201d. Eu disse sim, tenho. Porque eu ando com os meus carros, por isso muita gente me conhece, sempre vivi no luxo. Quando as pessoas, de forma propositada, decidem tentar com meu car\u00e1cter, n\u00e3o sei&#8230; mas, em contrapartida, nunca recebi dinheiro porque n\u00e3o havia necessidade. As pessoas me conhecem se tivesse algo ligado ao servi\u00e7o, meu chefe imediato me chamava porque isso \u00e9 muito grave.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Consta ainda nos autos um documento de partilha de dinheiro apreendido em sua casa em que constam tamb\u00e9m os nomes de Ildefonso, An\u00edbal Gomes, Edmundo, Jacinto e Henriques. O que o senhor pode dizer?<br \/>\nPedro Lussaty &#8211; Gostaria que me dessem uma resposta primeiro. Que documentos \u00e9 esse? A minha casa n\u00e3o foi apreendida, ela foi assaltada. Resta saber se estes documentos sa\u00edram mesmo de l\u00e1. Se sa\u00edram \u00e9 um assalto ou furto de documento e, se assim for, n\u00e3o corresponde mat\u00e9ria de provas \u00e9 falso. Segundo, nunca estava escrito partilha de dinheiro assinado por mim.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Quem \u00e9 a pessoa que ligou para si Informando que a sua casa supostamente tinha sido assaltada?<br \/>\nPedro Lussaty &#8211; Eu respondi que recebi massagem.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Quem enviou essa mensagem?<br \/>\nPedro Lussaty &#8211; N\u00e3o sei quem \u00e9, n\u00e3o tinha o n\u00famero gravado. Mas encontrei a casa com a fechadura trocada e isso se concretizou porque o dinheiro esta na PGR. A casa, por ser minha, mandei ir \u00c0 pra\u00e7a para trocar a fechadura depois de me terem sequestrado eles me deram a chave e na casa n\u00e3o tinha nada. Para mim, disseram que foram mandados e o montante consta nos autos, enquanto o dinheiro esta na PGR, n\u00e3o estou a acusar, mas n\u00e3o \u00e9 s\u00f3 17 milh\u00f5es de d\u00f3lares, por isso estou a dizer que o dinheiro n\u00e3o \u00e9 s\u00f3 esse.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Conhece algum familiar do senhor Edson?<br \/>\nPedro Lussaty &#8211; Conhe\u00e7o a m\u00e3e dele, a dona Sonha.<\/p>\n<p style=\"text-align: justify;\">Minist\u00e9rio P\u00fablico &#8211; Alguma vez j\u00e1 entregou somas avultadas cerca de 170 milh\u00f5es a senhora Sonha em dois tambores ou bid\u00f5es?<br \/>\nLussaty &#8211; A Sonha, como diz, \u00e9 a m\u00e3e do Edson, \u00e9 uma senhora do banco. J\u00e1 lhe entreguei dinheiro para depositar.<\/p>\n<p style=\"text-align: justify;\">O recado curioso de Lussaty<br \/>\nQuero que essas pessoas saibam, se eu for ilibado vou para minha vida e ningu\u00e9m mais me chantageia ou me monta cabala\u201d<br \/>\nPedro Lussaty- Merit\u00edssimo, o que eu estava querer falar s\u00e3o as quest\u00f5es ultrajantes e vergonhosas que aconteceram comigo e para que n\u00e3o venham acontecer quest\u00f5es perigosas comigo e tamb\u00e9m n\u00e3o tenho inten\u00e7\u00e3o de pessoalizar.<br \/>\nO tribunal e os advogados pensam que este \u00e9 um processo, mas eu sei que s\u00e3o pessoas porque sei que os filhos destes senhores s\u00e3o meus amigos, ent\u00e3o quero que essas pessoas saibam, a partir do tribunal, se eu for ilibado vou para minha vida, ningu\u00e9m mais vai l\u00e1 me chantagear ou me montar cabala.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa Francisco Muketa &#8211; Quando e em que circunst\u00e2ncias foi detido senhor Pedro Lussaty?<br \/>\nPedro Lussaty &#8211; Eu Lussaty, oficial superior das For\u00e7as Armadas Angolanas, em circunst\u00e2ncia alguma fui detido. Eu fui raptado, quando me entrava no meu condom\u00ednio, encapuzaram-me, meteram-me no porta-bagagem de uma viatura e posto num cativeiro por elementos, antes desconhecidos, que sem me exibirem nada, se fizeram passar por elementos do Estado.<br \/>\nLevaram-me em lugar incerto. Um dia depois apercebi-me com interrogat\u00f3rio que eu tinha que dizer sobre o meu patrim\u00f3nio, entretanto, eu disse-lhe que n\u00e3o sei quem eram as pessoas e nem as motiva\u00e7\u00f5es para me colocarem naquelas condi\u00e7\u00f5es. Perguntei porqu\u00ea tinha de dizer sobre meu patrim\u00f3nio? S\u00f3 me diziam que estavam a cumprir ordens do general e do presidente.<\/p>\n<p style=\"text-align: justify;\">Advogado de Defesa &#8211; Relativamente aos crimes financeiros que pesam sobre si, pode explicar, se alguma vez foi notificado pelo Comando de Altera\u00e7\u00e3o nos anos 2008 at\u00e9 2021 ?<br \/>\nPedro Lussaty &#8211; Tenho rela\u00e7\u00e3o com os bancos e tenho gestores das minhas contas pessoais. A minha rela\u00e7\u00e3o com os bancos \u00e9 di\u00e1ria e nunca me foi informado de alguma altera\u00e7\u00e3o irregular o que vem nos autos s\u00e3o transfer\u00eancias normais. Os instrutivos do BNA sobre transfer\u00eancias para o exterior dizem que todo cidad\u00e3o angolano deve e pode transferir para o exterior acredito 200 mil ou 100 mil e tal euros e \u00e9 esta quantia que todos n\u00f3s transferimos e para se executar depende da disponibilidade do banco e se vou ao banco me informar que j\u00e1 excedi o valor de transfer\u00eancia para este ano, eu espero o pr\u00f3ximo ano. Mas tamb\u00e9m nunca transferi valor acima do necess\u00e1rio porque n\u00e3o tenho conta al\u00e9m das correntes em Portugal para pagar apenas luz e \u00e1gua.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8212; Em que circunst\u00e2ncias foi abordado pelas autoridades angolanas a comercializar moedas estrageiras ou nacional por agentes do Estado?<br \/>\nPedro Lussaty-Nunca. Nenhum agente do Estado ou qualquer entidade ou sequer autoridade disfar\u00e7ada, abordou-me a comercializar moedas. N\u00e3o estou certificado para o fazer, o meu ramo de atividade n\u00e3o \u00e9 cambial, que comercializa s\u00e3o as casas de c\u00e2mbio.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8211; Alguma vez efectuou pagamento da unidade da banda de m\u00fasica?<br \/>\nPedro Lussaty- A banda de m\u00fasica n\u00e3o conhe\u00e7o como unidade, porque se criou uma ideia de que existe, unidade banda de m\u00fasica n\u00e3o existe. Existe unidade da UGP, da USP os projectos especiais de desminagem chacal. Agora, a banda de m\u00fasica n\u00e3o sei qual denomina\u00e7\u00e3o devo atribuir, mas existem elementos que tocam, que em fun\u00e7\u00e3o da sua especialidade e necessidade pontuais era controlado pelo chefe da Casa Militar. Mas em fun\u00e7\u00e3o do espa\u00e7o, estes elementos foram colocados na UGP, mas sempre controlados pelo chefe da casa Militar. Mas na estrutura organizacional da UGP existe uma pequena unidade da banda de m\u00fasica que s\u00e3o militares. Mas a banda de m\u00fasica que \u00e9 falada aqui s\u00e3o civis, s\u00e3o tocadores que, por causa da necessidade e plano estrat\u00e9gico do Presidente da Rep\u00fablica e do Chefe da Casa Militar, entendeu-se que seja ele pessoalmente controlar, mas sei que t\u00eam a depend\u00eancia directa do Presidente da Rep\u00fablica, por isso \u00e9 que tudo que acontece desde as altera\u00e7\u00f5es era o Comandante em Chefe quem tomava as decis\u00f5es<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa \u2013 A quem cabia a distribui\u00e7\u00e3o nos termos da lei a cota financeira mensal e da elabora\u00e7\u00e3o dos planos or\u00e7amentais?<br \/>\nPedro Lussaty &#8211; Cabia aos comandantes das unidades, ao chefe da casa militar e aos secret\u00e1rios da casa militar. A cota financeira \u00e9 uma a dota\u00e7\u00e3o or\u00e7amental que \u00e9 atribu\u00edda todos os meses e corresponde a caixa.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8211; Alguma vez teve acesso \u00e0 tesouraria da Casa de Seguran\u00e7a?<br \/>\nPedro Lussaty &#8211; Desde 2007 que comecei a trabalhar na casa de Seguran\u00e7a do Presidente da Rep\u00fablica at\u00e9 2017, nunca soube nem sequer o local onde era posto o dinheiro nem sei se existia l\u00e1 tesouraria.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa- Qual \u00e9 a entidade que fazia o controlo do OGE da Casa de Seguran\u00e7a do Presidente e das unidades dependentes?<br \/>\nPedro Lussaty &#8211; \u00c9 o Minist\u00e9rio das finan\u00e7as, atrav\u00e9s dos seus \u00f3rg\u00e3os como a Dire\u00e7\u00e3o Nacional de Or\u00e7amento e a Dire\u00e7\u00e3o Nacional de Contabilidade.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8211; Pode esclarecer como eram documentados os planos de receitas na Casa de Seguran\u00e7a do Presidente da Rep\u00fablica?<br \/>\nPedro Lussaty &#8211; Come\u00e7a na unidade em fun\u00e7\u00e3o da orienta\u00e7\u00e3o superior, emitido ao chefe da Casa Militar, este leva ao comandante-em-chefe, presidente da Rep\u00fablica, que \u00e9 o gestor da Casa de Seguran\u00e7a que autoriza as despesas da Casa que subentende autoriza\u00e7\u00e3o da UGP, USP e outras unidades<\/p>\n<p style=\"text-align: justify;\">Advogado- Sobre a depend\u00eancia directa do comandante-em-chefe como era feito o registo contabil\u00edstico financeiro e o controlo da execu\u00e7\u00e3o?<br \/>\nPedro Lussaty &#8211; Todo e qualquer controlo carece da execu\u00e7\u00e3o expressa do Comandante- em-Chefe, entidade m\u00e1xima vocacionada para fazer a n\u00edvel da Casa Militar. A execu\u00e7\u00e3o or\u00e7amental em representa\u00e7\u00e3o do Comandante-em-Chefe era feita pelo Minist\u00e9rio das Finan\u00e7as e o Tribunal de Contas e que inspecionam s\u00e3o as \u00fanicas institui\u00e7\u00f5es vocacionadas.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8211; Pode esclarecer como e quem elaborava os planos e or\u00e7amentos das unidades?<br \/>\nPedro Lussaty &#8211; As unidades da Casa militar t\u00eam or\u00e7amento pr\u00f3prio, porque tem uma estrutura organizacional pr\u00f3pria.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8211; Alguma vez lhe foi dado meios como carros bens de aquartelamento ou objectos similares da Casa de Seguran\u00e7a do Presidente da Rep\u00fablica?<br \/>\nPedro Lussaty &#8211; Nunca a Casa Militar atribuiu-me fun\u00e7\u00e3o ou oportunidade para controlar ou gerir algum meio.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8211; Alguma vez participou do levantamento de dinheiro no BPC para pagamento de sal\u00e1rio?<br \/>\nPedro Lussaty &#8211; Nunca participei no levantamento de dinheiro no BPC para pagamento de sal\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa \u2013 Quem, a n\u00edvel da Casa de Seguran\u00e7a tinha compet\u00eancia de expecionar as ordens de saque?<br \/>\nPedro Lussaty &#8211; \u00c9 o Minist\u00e9rio das Finan\u00e7as, em fun\u00e7\u00e3o das necessidades da unidade or\u00e7amental. Cabia a esta institui\u00e7\u00e3o analisar se est\u00e1 a ser executado ao abrigo da lei averiguar se a ordem de saque est\u00e1 em fun\u00e7\u00e3o do que chamamos documenta\u00e7\u00e3o de despesas que suportam a ordem de saque.<\/p>\n<p style=\"text-align: justify;\">Advogado de defesa &#8211; O que tem a dizer sobre relatos de uma poss\u00edvel fuga sua com malas de dinheiro entre euros e d\u00f3lares para o exterior?<br \/>\nPedro Lussaty &#8211; Sou uma pessoa s\u00e9ria e digna, conhe\u00e7o as leis nunca sa\u00ed do pa\u00eds com malas de dinheiro. O dinheiro de que se fala aqui at\u00e9 \u00e9 vergonhoso falar do mesmo facto que foram roubados prefiro dizer que foram tirados da minha casa e n\u00e3o me punha em fuga porque sabia que tinha pessoas atr\u00e1s de mim e para montar um cen\u00e1rio dizem que fugi, n\u00e3o fugi. Ali\u00e1s eu fa\u00e7o neg\u00f3cios h\u00e1 mais de 20 anos e o dinheiro que tenho j\u00e1 tamb\u00e9m tenho h\u00e1 mais de 20 anos e se quisesse transferir fora j\u00e1 teria feito de forma legal porque tenho empresas. O dinheiro que tenho em caixas \u00e9 de actividade corrente, portanto, \u00e9 falsa essa afirma\u00e7\u00e3o. Gostaria que o tribunal chamasse as pessoas que escreveram isso e se retratassem porque beliscaram a minha imagem, sou consultor de muita gente fora, essas pessoas n\u00e3o vivem c\u00e1 e t\u00eam neg\u00f3cios grandes aqui.<br \/>\nPara descoberta da verdade, Francisco Muteka, ap\u00f3s audi\u00e7\u00e3o do seu constituinte, solicitou ao tribunal para serem ouvidos como declarantes, o Presidente da Rep\u00fablica, na qualidade de Comandante-em-Chefe, a Ministra das Finan\u00e7as, Ver\u00e1 Dalves, o Governador do BNA (Banco Nacional de Angola), Jos\u00e9 de Lima Massano, o Director da AGT, o Inspector Geral das For\u00e7as Armadas, o Inspector Geral do Estado, o Director dos Crimes de Corrup\u00e7\u00e3o entre outras individualidades.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>O principal r\u00e9u deste medi\u00e1tico processo, o major Pedro Lussaty, que surpreendeu o pa\u00eds, quando foi detido na denominada &#8220;Opera\u00e7\u00e3o Caranguejo&#8221;, com milh\u00f5es de d\u00f3lares, euros, kwanzas, que se encontravam escondidos em malas de viagens em v\u00e1rios apartamentos, assim como carros de luxos e outros bens, foi ouvido em tribunal, onde alegou ser inocente e s\u00f3 se encontra na condi\u00e7\u00e3o de r\u00e9u por ser alvo de persegui\u00e7\u00e3o pela riqueza que construiu, que \u00e9 fruto do seu trabalho de empreendedorismo que vem exercendo desde adolesc\u00eancia. Eis ao detalhe o interrogat\u00f3rio do Major. Felicidade Kauanda Tribunal &#8211; Qual \u00e9 o seu nome? [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O principal r\u00e9u deste medi\u00e1tico processo, o major Pedro Lussaty, que surpreendeu o pa\u00eds, quando foi detido na denominada &#8220;Opera\u00e7\u00e3o Caranguejo&#8221;, com milh\u00f5es de d\u00f3lares, euros, kwanzas, que se encontravam escondidos em malas de viagens em v\u00e1rios apartamentos, assim como carros de luxos e outros bens, foi ouvido em tribunal, onde alegou ser inocente e s\u00f3 se encontra na condi\u00e7\u00e3o de r\u00e9u por ser alvo de persegui\u00e7\u00e3o pela riqueza que construiu, que \u00e9 fruto do seu trabalho de empreendedorismo que vem exercendo desde adolesc\u00eancia. Eis ao detalhe o interrogat\u00f3rio do Major. Felicidade Kauanda Tribunal &#8211; Qual \u00e9 o seu nome? [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-28T17:56:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/10\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d\",\"datePublished\":\"2022-10-28T17:56:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/\"},\"wordCount\":4963,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/\",\"name\":\"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg\",\"datePublished\":\"2022-10-28T17:56:06+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg\",\"width\":780,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/","og_locale":"pt_PT","og_type":"article","og_title":"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d - Jornal O Crime","og_description":"O principal r\u00e9u deste medi\u00e1tico processo, o major Pedro Lussaty, que surpreendeu o pa\u00eds, quando foi detido na denominada &#8220;Opera\u00e7\u00e3o Caranguejo&#8221;, com milh\u00f5es de d\u00f3lares, euros, kwanzas, que se encontravam escondidos em malas de viagens em v\u00e1rios apartamentos, assim como carros de luxos e outros bens, foi ouvido em tribunal, onde alegou ser inocente e s\u00f3 se encontra na condi\u00e7\u00e3o de r\u00e9u por ser alvo de persegui\u00e7\u00e3o pela riqueza que construiu, que \u00e9 fruto do seu trabalho de empreendedorismo que vem exercendo desde adolesc\u00eancia. Eis ao detalhe o interrogat\u00f3rio do Major. Felicidade Kauanda Tribunal &#8211; Qual \u00e9 o seu nome? [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/","og_site_name":"Jornal O Crime","article_published_time":"2022-10-28T17:56:06+00:00","og_image":[{"width":780,"height":440,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/10\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"25 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d","datePublished":"2022-10-28T17:56:06+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/"},"wordCount":4963,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/10\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/","url":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/","name":"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/10\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg","datePublished":"2022-10-28T17:56:06+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/10\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2022\/10\/familia-de-lussaty-espancada-em-casa-para-mostrar-malas-de-dinheiro_1644136691-b.jpg","width":780,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/estou-a-ser-alvo-de-perseguicao-por-ser-rico-e-nao-ceder-a-chantagens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"\u201cESTOU A SER ALVO DE PERSEGUI\u00c7\u00c3O POR SER RICO E N\u00c3O CEDER A CHANTAGENS\u201d"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5540"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/5541"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}