{"id":5699,"date":"2023-02-28T07:59:35","date_gmt":"2023-02-28T06:59:35","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5699"},"modified":"2023-02-28T12:47:11","modified_gmt":"2023-02-28T11:47:11","slug":"rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/","title":{"rendered":"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><strong style=\"font-size: 16px;\">Tenho sido apelidado de um baj\u00fa ao servi\u00e7o do MININT por manifestar a minha opini\u00e3o que muitas vezes se posiciona a favor da situa\u00e7\u00e3o, mas tenho que vos dizer que isto n\u00e3o vai atrapalhar nem mudar o meu ponto de vista enquanto cidad\u00e3o e, por isto, aqui fica mais um.<\/strong><\/h3>\n<h3><strong><em><span style=\"color: #ff0000;\">*Chivangulula Fonseca*<\/span><\/em><\/strong><\/h3>\n<p style=\"text-align: justify;\">De falta de patriotismo, sentido de estado, profissionalismo j\u00e1 vimos e tivemos muitos e em momentos diferentes da nossa hist\u00f3ria, mesmo quando o soar dos canh\u00f5es era o p\u00e3o nosso de cada.<\/p>\n<p style=\"text-align: justify;\">Ser nomeado para ocupar um cargo p\u00fablico \u00e9 regozijante, porque passa a ser o reconhecimento do nosso \u201cCHA\u201d (compet\u00eancias, habilidades e atitudes), bem como o saber ser, estar e fazer enquanto requisitos fundamentais na avalia\u00e7\u00e3o que se faz no processo antecedente a nomea\u00e7\u00e3o, isto por um lado.<\/p>\n<p style=\"text-align: justify;\">Por outro lado, quem se beneficia de uma nomea\u00e7\u00e3o para exercer fun\u00e7\u00f5es p\u00fablicas deve saber que a avalia\u00e7\u00e3o que se faz antes deve ser feita durante as fun\u00e7\u00f5es, ou seja, deve ser avaliado durante os anos ou meses que exercer as suas actividades, sendo certo que, o resultado pode ser diferente em fun\u00e7\u00e3o do desempenho e estes podem ser positivos ou negativos.<\/p>\n<p style=\"text-align: justify;\">No final, caber\u00e1 a entidade que promoveu a nomea\u00e7\u00e3o a manter na sua equipa ou promover a exonera\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Esta \u00e9 uma realidade, uma verdade que qualquer agente p\u00fablico, funcion\u00e1rio do Estado deve ter presente. \u00c9 isto que me parece faltar aos efectivos do Servi\u00e7o de Migra\u00e7\u00e3o e Estrangeiros para ser mais concreto, que ao verem a ordem de exonera\u00e7\u00e3o, por parte do ministro do Interior nada mais fizeram sen\u00e3o ir \u00e0 pra\u00e7a p\u00fablica, com a raivosa carta aberta dirigida a entidades m\u00e1ximas do pa\u00eds para expor situa\u00e7\u00f5es que, tristemente s\u00f3 constataram no dia da exonera\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Os jovens do SME exonerados deveriam penitenciar-se, ir a casa, beber um bom vinho, j\u00e1 que sa\u00edram dos lugares com alguma estabilidade financeira resultante das \u201cchambetas\u201d, reflectir para ver o que fizeram mal e se projectar para melhores momentos futuros, pois, a exonera\u00e7\u00e3o n\u00e3o \u00e9 nenhuma pena nem mesmo castigo na fun\u00e7\u00e3o p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">A atitude de ir \u00e0 rua reclamar injusti\u00e7as, falar um amontoado de inverdades, mostrando que o ministro s\u00f3 nomeia familiares n\u00e3o convence a ningu\u00e9m, mesmo que seja visto por fora, como \u00e9 o meu caso, porque o n\u00famero de nomeados e promovidos no minist\u00e9rio \u00e9 superior a fam\u00edlia de qualquer angolano. Ningu\u00e9m tem cinquenta mil familiares nem amigos. Logo, \u00e9 uma t\u00e1ctica de lam\u00farias que revelam que os jovens n\u00e3o est\u00e3o e nunca estiveram comprometidos com a causa.<\/p>\n<p style=\"text-align: justify;\">Estavam na sombra da mulembeira, acomodados com as contrapartidas resultantes das m\u00e1s pr\u00e1ticas de \u201cchambeta\u201d que tinham por pr\u00e1tica reter passaportes, cart\u00f5es de resid\u00eancia e vistos a inocentes cidad\u00e3os.<\/p>\n<p style=\"text-align: justify;\">Isto todos sabemos e conhecemos as pessoas. \u00c9 neste ponto de vista que acho que o Director Geral do SME e o ministro Laborinho para al\u00e9m de exonerarem deveriam promover processos disciplinares e criminais contra alguns dos exonerados para que diante dos instrutores percebessem que o \u00f3rg\u00e3o tinham no\u00e7\u00e3o da forma arrogante, escusada e vergonhosa como tratavam as pessoas e os esquemas montados para benef\u00edcio pr\u00f3prio. Ainda v\u00e3o a tempo.<\/p>\n<p style=\"text-align: justify;\">\u00c9 preciso responsabilizar disciplinar e criminalmente os \u201cchambeteiros de costume\u201d. Hajam como se faz na pol\u00edcia. Expulsem e em hasta p\u00fablica como fazem na Pol\u00edcia. Estes \u201cmeninos bonitos\u201d precisam e os cidad\u00e3os precisam saber quem s\u00e3o. Pelo menos n\u00e3o estariam nas ruas, nos corredores das escolas e universidades a espalhar boatos, inven\u00e7\u00f5es que n\u00e3o fazem sentido.<\/p>\n<p style=\"text-align: justify;\">O SME n\u00e3o pode parar por causa de uma meia d\u00fazia de xicos espertos. S\u00e3o muitos para terem a todos como corruptos por causa de um pequeno grupo que pensa enriquecer de um dia para o outro.<\/p>\n<p style=\"text-align: justify;\">H\u00e1 gente honesta no SME que n\u00e3o pode ser confundida com oportunistas sem no\u00e7\u00e3o das coisas.<\/p>\n<p style=\"text-align: justify;\">O SME n\u00e3o pode parar. As din\u00e2micas que cada respons\u00e1vel entenda imprimir no seu sector n\u00e3o podem depender de uns \u201cmeninos\u201d que assustam com o poder e esquecem respeitar at\u00e9 superiores hier\u00e1rquicos, como est\u00e1vamos habituados a ouvir.<\/p>\n<p style=\"text-align: justify;\">Devemos encorajar o ministro e outros respons\u00e1veis a retirarem do caminho todos aqueles que n\u00e3o corresponderem com as exig\u00eancias do processo de combate \u00e0 corrup\u00e7\u00e3o, nepotismo e que n\u00e3o se assumirem como verdadeiros servidores p\u00fablicos. \u00c9 preciso fazer isto em todos os organismos do \u00f3rg\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Retirem do SME os que querem sempre contrapartidas na emiss\u00e3o e entrega de documentos essenciais na vida das pessoas.<\/p>\n<p style=\"text-align: justify;\">Retirem da Pol\u00edcia de tr\u00e2nsito todos que para entregar uma carta de condu\u00e7\u00e3o, um livrete ou outro documento qualquer o cidad\u00e3o tem de esperar tr\u00eas meses, cansar-se e depois pagar alguma coisa. Retirem das cadeias efectivos que para deixar entrar na cadeia comida, roupa tem de cobrar dinheiro dos familiares do prezo. Retirem quem privilegia presos em troca de \u201cchambetas\u201d.<\/p>\n<p style=\"text-align: justify;\">Retirem do SIC instrutores ou investigadores que inventam crimes, processos para ter contrapartidas.<br \/>\nRetirem dos Bombeiros efectivos que fecham o olho na hora da inspec\u00e7\u00e3o para receber tost\u00f5es. Prossigam com este trabalho.<\/p>\n<p style=\"text-align: justify;\">Combate \u00e0 corrup\u00e7\u00e3o \u00e9 tarefa de todos. Do grande ao pequeno gesto. N\u00e3o importa se recebe mil ou milh\u00f5es. Corrup\u00e7\u00e3o \u00e9 corrup\u00e7\u00e3o e deve ser combatida.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o liguem os que se recusarem a aceitar que viver desonestamente n\u00e3o deve ser regra. N\u00f3s andamos neste pa\u00eds e conhecemos estas coisas.<br \/>\nTenho dito e espero ter ajudado a despertar os dirigentes a olharem para esta carta do efectivo do SME como algo inaceit\u00e1vel no seio de for\u00e7as e servi\u00e7os que deveriam ter cultura castrense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tenho sido apelidado de um baj\u00fa ao servi\u00e7o do MININT por manifestar a minha opini\u00e3o que muitas vezes se posiciona a favor da situa\u00e7\u00e3o, mas tenho que vos dizer que isto n\u00e3o vai atrapalhar nem mudar o meu ponto de vista enquanto cidad\u00e3o e, por isto, aqui fica mais um. *Chivangulula Fonseca* De falta de patriotismo, sentido de estado, profissionalismo j\u00e1 vimos e tivemos muitos e em momentos diferentes da nossa hist\u00f3ria, mesmo quando o soar dos canh\u00f5es era o p\u00e3o nosso de cada. Ser nomeado para ocupar um cargo p\u00fablico \u00e9 regozijante, porque passa a ser o reconhecimento do [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Tenho sido apelidado de um baj\u00fa ao servi\u00e7o do MININT por manifestar a minha opini\u00e3o que muitas vezes se posiciona a favor da situa\u00e7\u00e3o, mas tenho que vos dizer que isto n\u00e3o vai atrapalhar nem mudar o meu ponto de vista enquanto cidad\u00e3o e, por isto, aqui fica mais um. *Chivangulula Fonseca* De falta de patriotismo, sentido de estado, profissionalismo j\u00e1 vimos e tivemos muitos e em momentos diferentes da nossa hist\u00f3ria, mesmo quando o soar dos canh\u00f5es era o p\u00e3o nosso de cada. Ser nomeado para ocupar um cargo p\u00fablico \u00e9 regozijante, porque passa a ser o reconhecimento do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-28T06:59:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-28T11:47:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/02\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA\",\"datePublished\":\"2023-02-28T06:59:35+00:00\",\"dateModified\":\"2023-02-28T11:47:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/\"},\"wordCount\":1003,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg\",\"articleSection\":[\"SOCIEDADE\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/\",\"name\":\"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg\",\"datePublished\":\"2023-02-28T06:59:35+00:00\",\"dateModified\":\"2023-02-28T11:47:11+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg\",\"width\":1170,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/","og_locale":"pt_PT","og_type":"article","og_title":"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA - Jornal O Crime","og_description":"Tenho sido apelidado de um baj\u00fa ao servi\u00e7o do MININT por manifestar a minha opini\u00e3o que muitas vezes se posiciona a favor da situa\u00e7\u00e3o, mas tenho que vos dizer que isto n\u00e3o vai atrapalhar nem mudar o meu ponto de vista enquanto cidad\u00e3o e, por isto, aqui fica mais um. *Chivangulula Fonseca* De falta de patriotismo, sentido de estado, profissionalismo j\u00e1 vimos e tivemos muitos e em momentos diferentes da nossa hist\u00f3ria, mesmo quando o soar dos canh\u00f5es era o p\u00e3o nosso de cada. Ser nomeado para ocupar um cargo p\u00fablico \u00e9 regozijante, porque passa a ser o reconhecimento do [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/","og_site_name":"Jornal O Crime","article_published_time":"2023-02-28T06:59:35+00:00","article_modified_time":"2023-02-28T11:47:11+00:00","og_image":[{"width":1170,"height":767,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/02\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA","datePublished":"2023-02-28T06:59:35+00:00","dateModified":"2023-02-28T11:47:11+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/"},"wordCount":1003,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/02\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg","articleSection":["SOCIEDADE"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/","url":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/","name":"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/02\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg","datePublished":"2023-02-28T06:59:35+00:00","dateModified":"2023-02-28T11:47:11+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/02\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/02\/DE76DEE5-C1A0-4FE8-AE8D-4E2CB0AB9E19-e1677567480533.jpeg","width":1170,"height":767},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/rejeicoes-das-exoneracoes-no-minint-os-maus-da-fita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"REJEI\u00c7\u00d5ES DAS EXONERA\u00c7\u00d5ES NO MININT: OS MAUS DA FITA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5699"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/5700"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}