{"id":5709,"date":"2023-03-01T20:06:16","date_gmt":"2023-03-01T19:06:16","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5709"},"modified":"2023-03-01T20:06:16","modified_gmt":"2023-03-01T19:06:16","slug":"crise-no-tribunal-de-contas-presidente-constituida-arguida","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/","title":{"rendered":"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<strong>A Ju\u00edza Conselheira Presidente do Tribunal de Contas, Exalgina Gamb\u00f4a, foi constitu\u00edda arguida pela Procuradoria Geral da Rep\u00fablica(PGR), por alegadamente estar envolvida na pr\u00e1tica de crimes de peculato, extors\u00e3o e corrup\u00e7\u00e3o .<\/strong><\/p>\n<p><span style=\"color: #ff0000;\">Leal Mundunde<\/span><\/p>\n<p style=\"text-align: justify;\">A medida da PGR tornada p\u00fablica na passada ter\u00e7a-feira, dia 28 de Fevereiro, chega \u00e1tona depois do Presidente da Rep\u00fablica Jo\u00e3o Louren\u00e7o, ter considerado que Exalgina Gamb\u00f4a deixou de ter legitimidade para o exerc\u00edcio das suas fun\u00e7\u00f5es.<br \/>\nPreocupado com as informa\u00e7\u00f5es postas a circular, Jo\u00e3o Louren\u00e7o convidou no passado dia 21 de Fevereiro, Exalgina Gamb\u00f4a para renunciar o mandato, acreditando que tal situa\u00e7\u00e3o est\u00e1 a comprometer o normal funcionamento do Tribunal de contas e manchar o bom nome da Justi\u00e7a angolana.<br \/>\nDias antes, j\u00e1 circulavam informa\u00e7\u00f5es do encontro mantido entre o Presidente da Rep\u00fablica e a Presidente do Tribunal de Contas, o que veio a se confirmar, na nota da Presid\u00eancia da Rep\u00fablica datada do pret\u00e9rito dia 27 de Fevereiro.<br \/>\nA pesar do pedido de renuncia de Jo\u00e3o Louren\u00e7o \u00e0 Presidente do Tribunal de Contas, ficou-se a saber que Exalgina Gamb\u00f4a insistia em permanecer no cargo.<br \/>\nNo dia seguinte, 28 de Fevereiro, a Procuradoria Geral da Rep\u00fablica deu a conhecer que em fun\u00e7\u00e3o da denuncia posta a circular, abriu um processo de inqu\u00e9rito para averiguar a autenticidade dos factos.<br \/>\nNo mesmo processo em que est\u00e1 constitu\u00edda arguida a Juiza Conselheira Presidente do Tribunal de Contas, est\u00e1 de igual modo, envolvido o filho Hail\u00e9 Musap\u00e9 Vicente da Cruz, pelos crimes de Extors\u00e3o e corrup\u00e7\u00e3o.<br \/>\nDe acordo ao Maka Angola, Exalgina Gamb\u00f4a convocou recentemente o ministro dos Petr\u00f3leos e Recursos Minerais, Diamantino de Azevedo, para que fosse inclu\u00edda com um por cento, na estrutura accionista da Refinaria do Lobito, em Benguela.<br \/>\nSegundo a fonte, a Ju\u00edza alegou que tinha anu\u00eancia do Presidente da Rep\u00fablica Jo\u00e3o Louren\u00e7o, para merecer a percentagem no neg\u00f3cio de refina\u00e7\u00e3o de petr\u00f3leos.<br \/>\nEm seguida, Diamantino de Azevedo contactou Jo\u00e3o Louren\u00e7o para comprovar a veracidade do pedido de Exalgina Gamb\u00f4a.<br \/>\nA ju\u00edza \u00e9 acusada tamb\u00e9m de desvios de fundos do Tribunal de Contas, gastos para o seu benef\u00edcio, bem como para as viagens dos filhos no exterior<br \/>\nRecordar que o Vice-Procurador Geral da Rep\u00fablica, Mota Liz, recentemente apelou a sociedade a estar envolvida no combate a corrup\u00e7\u00e3o, tendo exortado a necessidade de se primar no aspecto preventivo para que os crimes n\u00e3o aconte\u00e7am.<br \/>\nMota Liz, defendeu por sua vez, que \u00e9 importante que se adopte mecanismos de transpar\u00eancia na gest\u00e3o \u201cda coisa p\u00fablica, na educa\u00e7\u00e3o c\u00edvica para a honestidade dos cidad\u00e3os\u201d.<br \/>\nA den\u00fancia p\u00fablica sobre o envolvimento da Ju\u00edza Conselheira Presidente do Tribunal de Contas, Exalgina Gamb\u00f4a, n\u00e3o \u00e9 deste ano, \u00e9 um facto que circula desde o ano 2022.<br \/>\nExalgina Gamb\u00f4a lidera o Tribunal de Contas h\u00e1 cinco anos, desde a tomada de posse em 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ju\u00edza Conselheira Presidente do Tribunal de Contas, Exalgina Gamb\u00f4a, foi constitu\u00edda arguida pela Procuradoria Geral da Rep\u00fablica(PGR), por alegadamente estar envolvida na pr\u00e1tica de crimes de peculato, extors\u00e3o e corrup\u00e7\u00e3o . Leal Mundunde A medida da PGR tornada p\u00fablica na passada ter\u00e7a-feira, dia 28 de Fevereiro, chega \u00e1tona depois do Presidente da Rep\u00fablica Jo\u00e3o Louren\u00e7o, ter considerado que Exalgina Gamb\u00f4a deixou de ter legitimidade para o exerc\u00edcio das suas fun\u00e7\u00f5es. Preocupado com as informa\u00e7\u00f5es postas a circular, Jo\u00e3o Louren\u00e7o convidou no passado dia 21 de Fevereiro, Exalgina Gamb\u00f4a para renunciar o mandato, acreditando que tal situa\u00e7\u00e3o est\u00e1 a comprometer [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"A Ju\u00edza Conselheira Presidente do Tribunal de Contas, Exalgina Gamb\u00f4a, foi constitu\u00edda arguida pela Procuradoria Geral da Rep\u00fablica(PGR), por alegadamente estar envolvida na pr\u00e1tica de crimes de peculato, extors\u00e3o e corrup\u00e7\u00e3o . Leal Mundunde A medida da PGR tornada p\u00fablica na passada ter\u00e7a-feira, dia 28 de Fevereiro, chega \u00e1tona depois do Presidente da Rep\u00fablica Jo\u00e3o Louren\u00e7o, ter considerado que Exalgina Gamb\u00f4a deixou de ter legitimidade para o exerc\u00edcio das suas fun\u00e7\u00f5es. Preocupado com as informa\u00e7\u00f5es postas a circular, Jo\u00e3o Louren\u00e7o convidou no passado dia 21 de Fevereiro, Exalgina Gamb\u00f4a para renunciar o mandato, acreditando que tal situa\u00e7\u00e3o est\u00e1 a comprometer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T19:06:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/03\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida\",\"datePublished\":\"2023-03-01T19:06:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/\"},\"wordCount\":528,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/\",\"name\":\"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg\",\"datePublished\":\"2023-03-01T19:06:16+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg\",\"width\":595,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/crise-no-tribunal-de-contas-presidente-constituida-arguida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/","og_locale":"pt_PT","og_type":"article","og_title":"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida - Jornal O Crime","og_description":"A Ju\u00edza Conselheira Presidente do Tribunal de Contas, Exalgina Gamb\u00f4a, foi constitu\u00edda arguida pela Procuradoria Geral da Rep\u00fablica(PGR), por alegadamente estar envolvida na pr\u00e1tica de crimes de peculato, extors\u00e3o e corrup\u00e7\u00e3o . Leal Mundunde A medida da PGR tornada p\u00fablica na passada ter\u00e7a-feira, dia 28 de Fevereiro, chega \u00e1tona depois do Presidente da Rep\u00fablica Jo\u00e3o Louren\u00e7o, ter considerado que Exalgina Gamb\u00f4a deixou de ter legitimidade para o exerc\u00edcio das suas fun\u00e7\u00f5es. Preocupado com as informa\u00e7\u00f5es postas a circular, Jo\u00e3o Louren\u00e7o convidou no passado dia 21 de Fevereiro, Exalgina Gamb\u00f4a para renunciar o mandato, acreditando que tal situa\u00e7\u00e3o est\u00e1 a comprometer [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/","og_site_name":"Jornal O Crime","article_published_time":"2023-03-01T19:06:16+00:00","og_image":[{"width":595,"height":341,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/03\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida","datePublished":"2023-03-01T19:06:16+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/"},"wordCount":528,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/03\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/","url":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/","name":"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/03\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg","datePublished":"2023-03-01T19:06:16+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/03\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/03\/62EFFD25-7E24-4EFD-9CEC-C2458821A5AE.jpeg","width":595,"height":341},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/crise-no-tribunal-de-contas-presidente-constituida-arguida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"CRISE NO TRIBUNAL DE CONTAS: Presidente constitu\u00edda arguida"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5709"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/5710"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}