{"id":5728,"date":"2023-04-11T02:14:48","date_gmt":"2023-04-11T01:14:48","guid":{"rendered":"https:\/\/jornalocrime.com\/?p=5728"},"modified":"2023-04-11T02:26:23","modified_gmt":"2023-04-11T01:26:23","slug":"jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/","title":{"rendered":"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A primeira inst\u00e2ncia achou provas irrefut\u00e1veis que levaram a condenar o jornalista pivot da TV Zimbo, David Jos\u00e9 Diogo, \u00e0 pena de 5 anos de pris\u00e3o e pagamento de uma indemniza\u00e7\u00e3o, pelo crime de agress\u00e3o sexual contra uma menor de 17 anos, ocorrido em 2020.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline; color: #ff0000;\"><em>Felicidade Kauanda <\/em><\/span><\/p>\n<p style=\"text-align: justify;\">Oac\u00f3rd\u00e3o, lido por volta das 10 horas da manh\u00e3, na 8 \u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal da Comarca de Belas, no Benfica, deixa claro que ficou provado que David Jos\u00e9 Diogo, um dos rostos conhecidos do jornal da TV Zimbo, de 53 anos \u00e0 data dos factos, \u00e9 culpado do crime de viola\u00e7\u00e3o sexual em que foi v\u00edtima a menor Domingas C\u00e2mia da Silva, na altura com 17 anos, tendo sido condenado ao abrigo da lei penal antiga, pelo facto de o crime ter ocorrido na vig\u00eancia daquele diploma.<br \/>\nInsatisfeito, Jos\u00e9 Carlos, advogado de David Diogo, interp\u00f4s recurso com efeito suspensivo, e solicitou as c\u00f3pias das actas de todas sess\u00f5es de julgamento e do ac\u00f3rd\u00e3o.<\/p>\n<blockquote><p>\u201cdo abuso at\u00e9 ao momento, ela continua com acompanhamento psicol\u00f3gico, porque ficou um tempo sem estudar, por for\u00e7a do bullying&#8230; Mas, felizmente, j\u00e1 retomou; temos tido maior aten\u00e7\u00e3o, porque ao longo desses tr\u00eas anos o indiv\u00edduo foi cercando, fazia manobras que at\u00e9 me levou a mudar de resid\u00eancia, pois sabemos a influ\u00eancia que o mesmo tem, por isso levamos o processo at\u00e9 \u00e0 \u00faltima inst\u00e2ncia. Como pai, sinto que foi um dever cumprido\u201d<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Por outro lado, Osvaldo Salupula, advogado assistente, pediu que se alterasse a medida de coa\u00e7\u00e3o de David Diogo, uma vez que o mesmo responde em liberdade, alegando que tal medida garantir\u00e1 o auto da sua defesa.<br \/>\nO tribunal deferiu o requerimento de recurso e emitiu a obrigatoriedade de David Diogo apresentar-se quinzenalmente ao cart\u00f3rio daquele tribunal, dando, desta forma, resposta positiva \u00e0 solicita\u00e7\u00e3o de altera\u00e7\u00e3o da medida de coa\u00e7\u00e3o do r\u00e9u, conforme solicitada pela assist\u00eancia,<br \/>\n\u201cEstamos confiantes que haver\u00e1 condena\u00e7\u00e3o no recurso\u201d<br \/>\nA condena\u00e7\u00e3o de David Diogo n\u00e3o foi totalmente satisfat\u00f3ria pela v\u00edtima, que se p\u00f4s aos choros, manifestando descontentamento, sendo que nem mesmo conseguia prestar declara\u00e7\u00f5es, recebendo consolo do seu advogado, Osvaldo Salupula, \u201cfica calma, o dif\u00edcil j\u00e1 passou, o senhor David Diogo, j\u00e1 foi condenado\u201d.<br \/>\nPor seu turno, sobre uma possibilidade de David Diogo ser absolvido em segunda inst\u00e2ncia, Osvaldo Salupula disse que \u201ccom as provas produzidas em sede de julgamento, n\u00f3s n\u00e3o vemos essa possibilidade, temos que observar que o senhor David Diogo n\u00e3o \u00e9 uma pessoa an\u00f3nima&#8230; vejamos que, para chegar at\u00e9 esta fase, foram volvidos tr\u00eas anos e s\u00f3 hoje conseguimos efectivamente, pelo menos no tribunal de primeira inst\u00e2ncia, ter uma condena\u00e7\u00e3o, por conta de um trabalho \u00e1rduo. Tivemos de trabalhar durante anos, atr\u00e1s do processo, porque, se fosse diferente, nem mesmo o julgamento em primeira inst\u00e2ncia ter\u00edamos&#8230; de qualquer forma, estamos confiantes que haver\u00e1 condena\u00e7\u00e3o do senhor David Diogo, em sede de recurso, e a condu\u00e7\u00e3o do mesmo \u00e0 cadeia\u201d.<br \/>\nPerguntado ainda se satisfaz ou n\u00e3o com a senten\u00e7a da primeira inst\u00e2ncia, disse \u201cestamos parcialmente satisfeitos, porque o crime de viola\u00e7\u00e3o deixa normalmente sequelas devastadoras. Na verdade, n\u00e3o \u00e9 a condena\u00e7\u00e3o que minimiza a situa\u00e7\u00e3o da v\u00edtima, ela est\u00e1 agora com 19 anos, notamos que a personalidade dela, depois do ocorrido, mudou, precisa de acompanhamento e apoio, porque at\u00e9 ao momento continua com a mente muito baixa e a auto-estima muito reduzida\u201d.<br \/>\nSentimento de dever cumprido<br \/>\nV\u00edctor Germano, pai da menor, n\u00e3o foi diferente, ao se pronunciar para n\u00f3s sobre a senten\u00e7a: \u201cN\u00e3o \u00e9 uma quest\u00e3o de satisfa\u00e7\u00e3o, mas aquilo que o tribunal achou justo na causa! O senhor David Diogo cometeu um acto macabro, vejamos um adulto de 53 anos privar a liberdade e abusar sexualmente de uma menina menor de 17 anos, \u00e9 de todo conden\u00e1vel.<br \/>\nFez in\u00fameras manobras neste processo, tanto \u00e9 que, para ser julgado e condenado, levou tr\u00eas anos, mas a justi\u00e7a foi feita, vamos seguir o processo em outra inst\u00e2ncia\u201d.<\/p>\n<blockquote><p>Se \u201cquem n\u00e3o deve, n\u00e3o teme\u201d, por que estaria disposto a negociar um processo criminal, com um poss\u00edvel acordo financeiro com o pai da menor?<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Quanto ao estado de sa\u00fade actual da filha, disse, \u201cdo abuso at\u00e9 ao momento, ela continua com acompanhamento psicol\u00f3gico, porque ficou um tempo sem estudar, por for\u00e7a do bullying&#8230; Mas, felizmente, j\u00e1 retomou; temos tido maior aten\u00e7\u00e3o, porque ao longo desses tr\u00eas anos o indiv\u00edduo foi cercando, fazia manobras que at\u00e9 me levou a mudar de resid\u00eancia, pois sabemos a influ\u00eancia que o mesmo tem, por isso levamos o processo at\u00e9 \u00e0 \u00faltima inst\u00e2ncia. Como pai, sinto que foi um dever cumprido\u201d.<br \/>\nPor outro lado, solicitado ao \u2018O Crime\u2019 para igualmente se pronunciar em torno da senten\u00e7a, Jos\u00e9 Carlos, advogado de David Diogo, em poucas palavras e sem gravar entrevista, disse que falaria em momento oportuno, pois n\u00e3o tinha nada para dizer, uma vez que a senten\u00e7a vai ainda ser apreciada no tribunal de segunda inst\u00e2ncia.<br \/>\nTer\u00e1 pago caro por querer ver os pais?<br \/>\nSegundo os autos, tudo aconteceu quando a v\u00edtima, Domingas C\u00e2mia da Silva, na altura com 17 anos, vivia em Luanda, munic\u00edpio de Talatona, com os pais adoptivos.<br \/>\nPortanto, era de costume, ir passar as f\u00e9rias na prov\u00edncia do Kwanza Sul, com seus pais biol\u00f3gicos e os irm\u00e3os.<br \/>\nNa altura, a prov\u00edncia de Luanda encontrava-se sob cerca sanit\u00e1ria, devido \u00e0 pandemia da covid-19. Foi ent\u00e3o que no dia 23 de Julho daquele ano, 2020, por volta das 10 horas da manh\u00e3, Domingas saiu de casa dos pais adoptivos, na companhia do seu irm\u00e3o mais novo, apenas conhecido por Ef\u00e9sios, com a inten\u00e7\u00e3o de comprar pipoca.<br \/>\nEnquanto orientava o irm\u00e3o a pagar os sacos de pipocas, apercebendo-se que este estava distra\u00eddo, fugiu at\u00e9 \u00e0s bombas de combust\u00edvel do bairro Cariango, onde foi vista a chorar por um camionista, n\u00e3o identificado nos autos, que a abordou sobre a raz\u00e3o do choro, tendo contado que pretendia ir visitar a irm\u00e3 g\u00e9mea, na prov\u00edncia do Kwanza sul. O camionista, por seu turno, informou que n\u00e3o era poss\u00edvel, por conta da cerca sanit\u00e1ria, mas que a levaria at\u00e9 ao posto fronteiri\u00e7o do Longa e, a partir da\u00ed, ela solicitaria ajuda das autoridades policiais. Assim, a menina seguiu viagem at\u00e9 ao referido local. L\u00e1 chegados, foi impedida de continuar a viagem pelos agentes policiais e teve de pernoitar ali.<br \/>\nNo dia seguinte, por volta das 14 horas, enquanto incitava dilig\u00eancias, Ad\u00e3o Pedro Zanga, mais conhecido por Calibrado, que tamb\u00e9m se encontrava no local, passava de um lado para o outro, observando os movimentos da rapariga. Posteriormente, aproximou-se dela e disse-lhe que o seu tio, um jornalista da TV Zimbo, estava a cham\u00e1-la, para ajud\u00e1-la. No in\u00edcio, recusou, mas, dada a insist\u00eancia, cedeu.<br \/>\nChegando no local onde se encontrava David Diogo, Osvaldo Ernesto e Hugo, este \u00faltimo agente da Pol\u00edcia Nacional, Ad\u00e3o Zanga apresentou-lhe a todos como sendo sua namorada, pedindo a David Diogo que a ajudasse a ir \u00e0 prov\u00edncia do Kwanza Sul, por conta do falecimento da sua m\u00e3e, o que foi aceite pelo jornalista.<br \/>\nNa sequ\u00eancia, David Diogo perguntou \u00e0 mesma se tinha algum documento, tendo \u201cn\u00e3o\u201d como resposta. Seguidamente, convidou-a a subir numa viatura e dirigiram-se com os companheiros, Ad\u00e3o Zanga, Osvaldo Ernesto e Hugo, em direc\u00e7\u00e3o \u00e0 praia. L\u00e1, retiraram peixe da embarca\u00e7\u00e3o do sobrinho de David Diogo, de nome Jos\u00e9 Henrique, e de seguida, com o r\u00e9u ao volante, dirigiram-se a uma lanchonete do citado sobrinho, onde conviveram at\u00e9 por volta das 23 horas.<br \/>\nEnquanto isso, a menor permanecia no interior da viatura, onde, posteriormente, foi abusada sexualmente por David Diogo, tendo depois pedido aos companheiros que aumentassem o volume da m\u00fasica, ao que lhe foi negado por conta do recolher obrigat\u00f3rio imposto pelas autoridades, devido \u00e0 pandemia, contentando-se por aumentar o som da m\u00fasica na sua viatura.<br \/>\nPosteriormente, subiram todos \u00e0 viatura e, pelo caminho, cada um dos seus companheiros foi descendo no seu ponto, at\u00e9 que ficaram apenas David Diogo e a menina, tendo-a levado a um contentor-quarto em que ele \u00e9 propriet\u00e1rio.<br \/>\nNessa altura, os familiares da menor j\u00e1 estavam preocupados com o seu desaparecimento, pois seus pais adoptivos, Const\u00e2ncia de Oliveira e V\u00edctor, faziam dilig\u00eancias para encontr\u00e1-la, mediante exibi\u00e7\u00e3o de uma fotografia. Por volta das 23 horas, Rog\u00e9rio Francisco, irm\u00e3o da menor, fez participa\u00e7\u00e3o \u00e0 Pol\u00edcia.<br \/>\nNa sequ\u00eancia das dilig\u00eancias, foi poss\u00edvel saber dos acompanhantes de David Diogo, que este estava com a menina. A 1 hora da madrugada, David Diogo foi interpelado com a menor no interior da sua viatura. Quando esta desceu, estava aos prantos e confessou ao irm\u00e3o que David Diogo for\u00e7ou-lhe a ter rela\u00e7\u00f5es sexuais, o que foi confirmado pela enfermeira que a atendeu seguidamente num centro m\u00e9dico sito em Cabo Ledo.<br \/>\nA nega\u00e7\u00e3o sem fundo e suposto acordo<br \/>\nEm audi\u00eancia de julgamento, o r\u00e9u, David Jos\u00e9 Diogo, contou que foi Ad\u00e3o Pedro Zanga, tamb\u00e9m conhecido por Calibrado, declarante nos autos, quem apresentou-lhe a menor como sua namorada, assegurando que ela precisava passar a cerca sanit\u00e1ria, para chegar ao Kwanza Sul, por conta do falecimento da sua m\u00e3e, necessitando, deste modo, da sua ajuda, devido \u00e0 sua posi\u00e7\u00e3o.<br \/>\nDavid Diogo disse tamb\u00e9m que, dada a insist\u00eancia da menina, solicitou \u00e0s autoridades policiais que a ajudassem, mas foi negado, tendo-a aconselhado a aguardar por outro turno da Pol\u00edcia, para ent\u00e3o transpor a cerca sanit\u00e1ria. Da\u00ed, diz o r\u00e9u, a menor afastou-se, para conversar com elementos por ele desconhecidos.<br \/>\nEntretanto, como j\u00e1 havia combinado com os seus companheiros, Osvaldo, Ad\u00e3o e Hugo, tamb\u00e9m declarantes, irem \u00e0 praia, \u00e0 sua sa\u00edda, foi avisado que a menina fazia sinal para ele. Parou a viatura e convidou-a a acompanh\u00e1-los, para passar tempo e conhecer a praia, ao que ela cedeu.<br \/>\nTodavia, David Diogo negou veementemente os factos, dizendo que apenas quis ajud\u00e1-la, por ter ficado comovido com a hist\u00f3ria do falecimento da m\u00e3e. Entretanto, questionado o facto de ter pedido, na lanchonete, que aumentassem o volume da m\u00fasica e, n\u00e3o tendo \u00eaxito, ter ele mesmo aumentado o da viatura, no sentido de estar a s\u00f3s com a menor, respondeu que em nenhum momento isso aconteceu, pois, segundo ele, o \u00fanico momento que esteve a s\u00f3s com a menina foi quando a acompanhou at\u00e9 \u00e0 viatura para destrancar a porta.<br \/>\nA dado momento, contrariando a pr\u00f3pria vers\u00e3o, disse que n\u00e3o convidou a menina em momento algum, o que levou o Minist\u00e9rio P\u00fablico a confront\u00e1-lo com as declara\u00e7\u00f5es passadas, nas quais afirmava que convidou a menina para acompanh\u00e1-lo at\u00e9 \u00e0 aldeia dos pescadores, com objectivo de desanuviar e as pessoas se aperceberem que eram efectivamente pr\u00f3ximos, a fim de facilitar o contacto com os agentes pol\u00edcias que fiscalizavam a cerca sanit\u00e1ria.<br \/>\nInclusivamente, sublinhou que na ocasi\u00e3o a menina lhe aparentava ter entre os 22 a 24 anos de idade.<br \/>\nAdemais, o jornalista conta que chegou a ser contactado por V\u00edctor, pai da v\u00edtima, no sentido de parar o andamento do processo criminal movido contra si, desde que chegassem a um acordo. Por\u00e9m, diz, n\u00e3o aceitou, pois, no seu entender, seria imposs\u00edvel parar, porque o processo j\u00e1 se encontrava em ju\u00edzo.<br \/>\nTodavia, foi aconselhado pela fam\u00edlia a conversar com o senhor, para que fizesse uma declara\u00e7\u00e3o por escrito, por\u00e9m, este nunca mais atendeu as suas chamadas telef\u00f3nicas.<br \/>\nFirmeza da v\u00edtima nas declara\u00e7\u00f5es<br \/>\nDomingas C\u00e2mia, a v\u00edtima nos autos, foi contra as declara\u00e7\u00f5es de seu carrasco, sublinhando que, desde o in\u00edcio, foi convidada por aquele a subir na sua viatura, dizendo \u201csobe, vamos!\u201d, tendo ele aceite apenas porque pensava que fossem passar a cerca sanit\u00e1ria.<br \/>\nSegundo a v\u00edtima, quando foram \u00e0 praia, juntamente com os companheiros de David Diogo, levaram o peixe e dirigiram-se, posteriormente, \u00e0 cantina de seu sobrinho, Jos\u00e9 Henrique, onde pediu que lhe dessem uma banheira para tomar banho, por ter estado longas horas fora de casa, sendo que, depois do banho, voltou a permanecer no interior da viatura, devido ao frio que fazia, \u00e0 espera da ajuda prometida por David Diogo.<br \/>\nSequ\u00eancia que, de seguida, Osvaldo Ernesto foi ao seu encontro, mostrou-lhe uma arma de fogo do tipo ca\u00e7adeira, que tinha retirado do porta-malas do ve\u00edculo, perguntando se j\u00e1 havia visto uma arma de fogo, tendo ela respondido que n\u00e3o, dizendo ainda que ela devia fazer um sacrif\u00edcio, mas, sem desenvolver, retirou-se.<br \/>\nPor\u00e9m, conta, depois ouviu David Diogo a dizer, \u201ceu quero l\u00e1 saber, vai ficar aqui durante dois meses\u201d, palavras que a ter\u00e3o deixado assustada. E foi assim que David Diogo pediu aos companheiros que aumentassem o volume da m\u00fasica, tendo aumentado o do seu carro, ap\u00f3s a nega\u00e7\u00e3o. Nesse momento, conta a jovem, ele entrou de forma bruta \u00e0 viatura, trancou as portas, atirou a chave na parte de tr\u00e1s, agarrou-a, apertou-a entre os bancos traseiros, retirou-lhe a cal\u00e7a \u00e0 for\u00e7a e passou ent\u00e3o a abus\u00e1-la sexualmente.<br \/>\nPortanto, Domingas C\u00e2mia nega ter sido encontrada deitada dentro de um caminh\u00e3o, escondida numa cama, por um efectivo da Pol\u00edcia Nacional, enquanto era impedida de passar a cerca, como afirmou o agente policial, Martins Domingos, na qualidade de declarante arrolado pelo advogado de David Diogo. Pois, disse a v\u00edtima, em nenhum momento foi retirada do interior do caminh\u00e3o naquelas condi\u00e7\u00f5es, afirmando ter visto apenas o citado efectivo na esquadra policial.<br \/>\nCabala para o jornalista ou plano de defesa mal feito?<br \/>\nAs provas que levaram o tribunal a condenar o piv\u00f4 do Jornal da Zimbo foram baseadas nos depoimentos da v\u00edtima, nas contradi\u00e7\u00f5es dos depoimentos do r\u00e9u e dos seus acompanhantes, bem como dos documentos levados aos autos pelos peritos, m\u00e9dicos e a enfermeira que fez o primeiro atendimento \u00e0 menor.<br \/>\nPrud\u00eancia Julieta Manuel, enfermeira que atendeu a menor depois dos factos, afirmou que quando Domingas deu entrada ao centro de sa\u00fade do Cabo Ledo, acompanhada de dois agentes policiais, depois de observ\u00e1-la, detectou sangue na vagina, por\u00e9m, n\u00e3o se tratava de hemorragia, inclusive mostrou a luva que usou com vest\u00edgios de sangue aos dois agentes.<br \/>\nDiante do sangramento que a menor apresentava, porque o centro m\u00e9dico estava desprovido de ambul\u00e2ncia, achou melhor transferi-la para \u00e0 Maternidade Lucr\u00e9cia Pa\u00edm, para fazer exames mais aprofundados.<br \/>\nPor outra, o legista, Miguel Manuel Melo, afecto ao Servi\u00e7o de Investiga\u00e7\u00e3o Criminal, que confirmou a autenticidade das folhas contadas nos autos de natureza sexual, alegando ter sido assinado por ele, disse que lembrava muito bem do caso, pois muitas vezes examinou a menor.<br \/>\nApesar de concluir que ela j\u00e1 n\u00e3o era virgem antes de violada, esclareceu as causas que levam uma adolescente a perder a virgindade, como exerc\u00edcios violentos, andar de bicicleta e actividade sexual. Entretanto, refere que tais situa\u00e7\u00f5es n\u00e3o inviabilizam o facto de ter sido v\u00edtima de abuso sexual.<br \/>\nPor fim, foram ainda real\u00e7adas as provas trazidas pelo perito Ant\u00f3nio Paxi, que fez a recolha dos vest\u00edgios do \u00e2mbito biol\u00f3gico encontrados na viatura, entre eles, cabelo, cotenetes, as roupas da menor com manchas de sangue e as duas armas de fogo do tipo ca\u00e7adeira com moni\u00e7\u00f5es.<br \/>\nTodavia, para al\u00e9m das contradi\u00e7\u00f5es nos depoimentos de David Diogo, muitas quest\u00f5es n\u00e3o foram convincentemente esclarecidas, tais como:<br \/>\nPor que David Diogo foi o \u00fanico arrolado como autor do crime, no meio de quatro senhores, com o grau de participa\u00e7\u00e3o de cada um devidamente descrito, o que sugeriria algum tipo de comparticipa\u00e7\u00e3o criminosa?<br \/>\nNa sequ\u00eancia da primeira, em rela\u00e7\u00e3o aos outros senhores, David Diogo era o mais respeitado e conhecido pela zona, tendo em conta que \u00e9 o local onde nasceu. Ser\u00e1 normal essa \u201cfama suja\u201d ter-se espalhado assim, apontando-o como \u00fanico vil\u00e3o? Se David Diogo afirmou que estava h\u00e1 sensivelmente dois meses sem ter rela\u00e7\u00f5es sexuais, como se explica os preservativos usados, recolhidos no interior do seu ve\u00edculo? Os ter\u00e1 usado e deixado l\u00e1 por esse tempo todo?<br \/>\nSe n\u00e3o havia outra mulher, al\u00e9m da menor, no ve\u00edculo, como ele mesmo afirmou, nem esta tinha sangrado, de quem seria o sangue encontrado na blusa da v\u00edtima, nos guardanapos e entre os \u00e2ngulos da viatura, recolhidos pela per\u00edcia?<br \/>\nSe \u201cquem n\u00e3o deve, n\u00e3o teme\u201d, por que estaria disposto a negociar um processo criminal, com um poss\u00edvel acordo financeiro com o pai da menor?<br \/>\nApesar de se ter passado tr\u00eas anos, como o declarante Martins Domingos Gabriel, efectivo da Pol\u00edcia Nacional, arrolado pelo advogado de David Diogo, conseguiria reconhecer o motorista do caminh\u00e3o onde supostamente a v\u00edtima foi encontrada, como afirmou, mas n\u00e3o se lembra da blusa que a menina vestia?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A primeira inst\u00e2ncia achou provas irrefut\u00e1veis que levaram a condenar o jornalista pivot da TV Zimbo, David Jos\u00e9 Diogo, \u00e0 pena de 5 anos de pris\u00e3o e pagamento de uma indemniza\u00e7\u00e3o, pelo crime de agress\u00e3o sexual contra uma menor de 17 anos, ocorrido em 2020. Felicidade Kauanda Oac\u00f3rd\u00e3o, lido por volta das 10 horas da manh\u00e3, na 8 \u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal da Comarca de Belas, no Benfica, deixa claro que ficou provado que David Jos\u00e9 Diogo, um dos rostos conhecidos do jornal da TV Zimbo, de 53 anos \u00e0 data dos factos, \u00e9 culpado do crime [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-em-tribunal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"A primeira inst\u00e2ncia achou provas irrefut\u00e1veis que levaram a condenar o jornalista pivot da TV Zimbo, David Jos\u00e9 Diogo, \u00e0 pena de 5 anos de pris\u00e3o e pagamento de uma indemniza\u00e7\u00e3o, pelo crime de agress\u00e3o sexual contra uma menor de 17 anos, ocorrido em 2020. Felicidade Kauanda Oac\u00f3rd\u00e3o, lido por volta das 10 horas da manh\u00e3, na 8 \u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal da Comarca de Belas, no Benfica, deixa claro que ficou provado que David Jos\u00e9 Diogo, um dos rostos conhecidos do jornal da TV Zimbo, de 53 anos \u00e0 data dos factos, \u00e9 culpado do crime [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-11T01:14:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T01:26:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/04\/DSC_0627-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA\",\"datePublished\":\"2023-04-11T01:14:48+00:00\",\"dateModified\":\"2023-04-11T01:26:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/\"},\"wordCount\":2940,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DSC_0627-scaled.jpg\",\"articleSection\":[\"EM TRIBUNAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/\",\"name\":\"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DSC_0627-scaled.jpg\",\"datePublished\":\"2023-04-11T01:14:48+00:00\",\"dateModified\":\"2023-04-11T01:26:23+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DSC_0627-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DSC_0627-scaled.jpg\",\"width\":2560,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/","og_locale":"pt_PT","og_type":"article","og_title":"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA - Jornal O Crime","og_description":"A primeira inst\u00e2ncia achou provas irrefut\u00e1veis que levaram a condenar o jornalista pivot da TV Zimbo, David Jos\u00e9 Diogo, \u00e0 pena de 5 anos de pris\u00e3o e pagamento de uma indemniza\u00e7\u00e3o, pelo crime de agress\u00e3o sexual contra uma menor de 17 anos, ocorrido em 2020. Felicidade Kauanda Oac\u00f3rd\u00e3o, lido por volta das 10 horas da manh\u00e3, na 8 \u00aa Sec\u00e7\u00e3o dos Crimes Comuns do Tribunal da Comarca de Belas, no Benfica, deixa claro que ficou provado que David Jos\u00e9 Diogo, um dos rostos conhecidos do jornal da TV Zimbo, de 53 anos \u00e0 data dos factos, \u00e9 culpado do crime [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/","og_site_name":"Jornal O Crime","article_published_time":"2023-04-11T01:14:48+00:00","article_modified_time":"2023-04-11T01:26:23+00:00","og_image":[{"width":2560,"height":1700,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/04\/DSC_0627-scaled.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA","datePublished":"2023-04-11T01:14:48+00:00","dateModified":"2023-04-11T01:26:23+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/"},"wordCount":2940,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/04\/DSC_0627-scaled.jpg","articleSection":["EM TRIBUNAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/","url":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/","name":"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/04\/DSC_0627-scaled.jpg","datePublished":"2023-04-11T01:14:48+00:00","dateModified":"2023-04-11T01:26:23+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/04\/DSC_0627-scaled.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/04\/DSC_0627-scaled.jpg","width":2560,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/jornalista-david-diogo-condenado-a-5-anos-de-prisao-e-6-milhoes-de-indemnizacao-a-vitima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"JORNALISTA DAVID DIOGO CONDENADO A 5 ANOS DE PRIS\u00c3O E 6 MILH\u00d5ES DE INDEMNIZA\u00c7\u00c3O \u00c0 V\u00cdTIMA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=5728"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/5728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/5729"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=5728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=5728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=5728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}