{"id":6070,"date":"2023-09-03T23:10:16","date_gmt":"2023-09-03T22:10:16","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=6070"},"modified":"2023-09-10T11:21:10","modified_gmt":"2023-09-10T10:21:10","slug":"presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/","title":{"rendered":"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><span class=\"Apple-converted-space\">\u00a0<\/span>O Presidente da Associa\u00e7\u00e3o de Apoio aos Antigos Combatentes das Ex-FAPLA (ASCOFA), Caetano Marcolino est\u00e1 a ser acusado de desvio de fundos e vendas de bens diversos para o benef\u00edcio pessoal.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #ff0000;\"><span class=\"Apple-converted-space\">\u00a0<\/span><b>Leal<span class=\"Apple-converted-space\">\u00a0 <\/span>Mundunde<\/b><\/span><\/em><\/p>\n<blockquote><p><b>Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no documento constarem informa\u00e7\u00f5es comprometedoras, levantadas por dois delegados, a do Sambizanga e a de Cacuaco.<\/b><\/p><\/blockquote>\n<p style=\"text-align: justify;\">Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no documento constarem informa\u00e7\u00f5es comprometedoras, levantadas por dois delegados, a do Sambizanga e a de Cacuaco. H\u00e1 quatro anos na frente da Associa\u00e7\u00e3o de Apoio aos Antigos Combatentes das Ex-FAPLA (ASCOFA), Caetano Marcolino tamb\u00e9m \u00e9 acusado de criar um grupo de revolucion\u00e1rios que culminou com a destitui\u00e7\u00e3o do cargo do antigo presidente, Ant\u00f3nio Fernando \u201cSamora\u201d, que foi condenado a 3 anos de pris\u00e3o com pena suspensa, por desvios de fundos e bens da associa\u00e7\u00e3o.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><b>Presidente da ASCOFA nega acusa\u00e7\u00f5es<\/b><\/span><\/h4>\n<p style=\"text-align: justify;\">O Presidente da Associa\u00e7\u00e3o de Apoio aos Antigos Combatentes das Ex-FAPLA (ASCOFA), Caetano Marcolino nega todas as acusa\u00e7\u00f5es que foram levantadas contra si. O mesmo afirma, que durante os quatro anos de seu consulado, nunca beneficiou de qualquer projecto habitacional nas centralidades de Luanda e desafia a todos que queiram confrontar, que se dirijam as entidades competentes.<\/p>\n<p style=\"text-align: justify;\">Caetano Marcolino diz que a associa\u00e7\u00e3o, na vig\u00eancia da antiga lideran\u00e7a recebeu mais de 130 resid\u00eancias, que foram distribu\u00eddas em algumas associa\u00e7\u00f5es ligadas ao Minist\u00e9rio da Defesa. As resid\u00eancias foram atribu\u00eddas atrav\u00e9s de um conv\u00eanio estabelecido entre o Minist\u00e9rio da Defesa Nacional, Antigos Combatentes e Veteranos da P\u00e1tria e uma empresa privada, tendo a ASCOFA se beneficiado de 89 resid\u00eancias, das quais n\u00e3o teve acesso porque na altura n\u00e3o era membro do corpo directivo.<\/p>\n<p style=\"text-align: justify;\">O representante da associa\u00e7\u00e3o, fez saber ainda que as resid\u00eancias questionadas \u00e0 antiga direc\u00e7\u00e3o foram entregues a alguns membros de direc\u00e7\u00e3o, oficiais, vi\u00favas, outros trabalhadores e algumas com destinos n\u00e3o explicados, o que resultou na abertura do processo que decorreu no tribunal. Quanto \u00e0s viaturas, o mesmo explica que n\u00e3o foram adquiridas durante o seu mandato. \u201cOs ve\u00edculos foram comprados por uma empresa privada e atribu\u00eddos a ex-militares, que pagariam por estes de forma faseada\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Ap\u00f3s a condena\u00e7\u00e3o do antigo presidente da associa\u00e7\u00e3o, o tribunal orientou a devolu\u00e7\u00e3o das viaturas \u00e0 empresa privada que as adquiriu, pese embora, ainda faltam dezesseis viaturas por recuperar, como fez saber Caetano Marcolino, que acrescenta ter chegado recentemente a um acordo com a referida empresa privada, para que sete das dezesseis viaturas por recuperar, sejam entregues \u00e0 direc\u00e7\u00e3o da associa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Caetano Marcolino, actual presidente da associa\u00e7\u00e3o que controla mais de 70 mil associados a n\u00edvel nacional, n\u00e3o tem d\u00favidas de que os queijosos est\u00e3o do lado da antiga direc\u00e7\u00e3o, sendo que alguns deles, foram indicados por ele para o exerc\u00edcio de algumas fun\u00e7\u00f5es na direc\u00e7\u00e3o. \u201cBrevemente, ser\u00e1 encerrada a delega\u00e7\u00e3o da ASCOFA no distrito do Sambizanga, tendo em conta a alegada postura negativa do representante local\u201d, garantiu.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><b>ESTADO ANGOLANO DEIXA DE ASSISTIR ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><b>Associa\u00e7\u00e3o de Apoio aos Antigos Combatentes das Ex-FAPLA (ASCOFA), que controla mais de 70 mil associados, em todo o pa\u00eds, revela n\u00e3o receber do Estado mais de tr\u00eas milh\u00f5es de kwanzas h\u00e1 4 anos.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6072 alignleft\" src=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/362495903_198142362952543_5614753179824500843_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/362495903_198142362952543_5614753179824500843_n-300x225.jpg 300w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/362495903_198142362952543_5614753179824500843_n-1024x768.jpg 1024w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/362495903_198142362952543_5614753179824500843_n-768x576.jpg 768w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/362495903_198142362952543_5614753179824500843_n-400x300.jpg 400w, https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/362495903_198142362952543_5614753179824500843_n.jpg 1170w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O\u00a0Estado, por interm\u00e9dio do Minist\u00e9rio da Defesa Nacional, Antigos Combatentes e Veteranos da P\u00e1tria, apoiava a associa\u00e7\u00e3o com um valor na ordem dos 3. 200.000 kwanzas anuais, quantia que deixou de depositar h\u00e1 cerca de 4 anos, deixando a associa\u00e7\u00e3o com v\u00e1rias d\u00edvidas por liquidar.<\/p>\n<p style=\"text-align: justify;\">A informa\u00e7\u00e3o foi avan\u00e7ada pelo presidente da associa\u00e7\u00e3o, Caetano Marcolino, que garante que a \u201cquantia n\u00e3o chega aos cofres da ASCOFA desde que assumiu as fun\u00e7\u00f5es\u201d. O presidente explicou que o corte do valor aconteceu antes da tomada de posse do seu consulado e justifica que a medida do Minist\u00e9rio ocorreu devido a n\u00e3o transpar\u00eancia da gest\u00e3o dos fundos recebidos pela antiga direc\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Com d\u00edvidas por liquidar, desde a renda do im\u00f3vel entre outros servi\u00e7os, o presidente da ASCOFA, garantiu que \u201ctodas tentativas foram feitas no sentido de o Estado retomar o apoio devido\u201d, mas n\u00e3o teve o sucesso desejado e, lamenta o facto de que a quota dos membros n\u00e3o ser suficiente para liquidar. O presidente fez saber ainda que contraiu dividas de cerca de 32 milh\u00f5es de kwanzas a uma firma de dois advogados e mais 12 milh\u00f5es a um outro advogado, todos contratados para seguir junto do tribunal o processo que condenou o antigo presidente da associa\u00e7\u00e3o, pelos crimes de m\u00e1 gest\u00e3o e desvio de bens da ASCOFA.<\/p>\n<p style=\"text-align: justify;\">Sem nenhum valor para pagar o acordado com os advogados, j\u00e1 que o per\u00edodo estipulado no contrato \u00e9 referente ao m\u00eas de Agosto, Caetano Marcolino aventa a venda de algum patrim\u00f3nio da associa\u00e7\u00e3o como umas das vias para liquidar uma parte do valor acordado com os advogados. Pelo que garante que continuar\u00e1 lutando com seu elenco at\u00e9 que a normalidade se restabele\u00e7a e espera que o Minist\u00e9rio da Defesa retome o pagamento anual do or\u00e7amento da associa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>\u00a0O Presidente da Associa\u00e7\u00e3o de Apoio aos Antigos Combatentes das Ex-FAPLA (ASCOFA), Caetano Marcolino est\u00e1 a ser acusado de desvio de fundos e vendas de bens diversos para o benef\u00edcio pessoal.\u00a0 \u00a0Leal\u00a0 Mundunde Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no documento constarem informa\u00e7\u00f5es comprometedoras, levantadas por dois delegados, a do Sambizanga e a de Cacuaco. Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-6070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"\u00a0O Presidente da Associa\u00e7\u00e3o de Apoio aos Antigos Combatentes das Ex-FAPLA (ASCOFA), Caetano Marcolino est\u00e1 a ser acusado de desvio de fundos e vendas de bens diversos para o benef\u00edcio pessoal.\u00a0 \u00a0Leal\u00a0 Mundunde Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no documento constarem informa\u00e7\u00f5es comprometedoras, levantadas por dois delegados, a do Sambizanga e a de Cacuaco. Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-03T22:10:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-10T10:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG-20221116-WA0049.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"343\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS\",\"datePublished\":\"2023-09-03T22:10:16+00:00\",\"dateModified\":\"2023-09-10T10:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/\"},\"wordCount\":946,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG-20221116-WA0049.jpg\",\"articleSection\":[\"SOCIEDADE\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/\",\"name\":\"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG-20221116-WA0049.jpg\",\"datePublished\":\"2023-09-03T22:10:16+00:00\",\"dateModified\":\"2023-09-10T10:21:10+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG-20221116-WA0049.jpg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG-20221116-WA0049.jpg\",\"width\":640,\"height\":343},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/","og_locale":"pt_PT","og_type":"article","og_title":"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS - Jornal O Crime","og_description":"\u00a0O Presidente da Associa\u00e7\u00e3o de Apoio aos Antigos Combatentes das Ex-FAPLA (ASCOFA), Caetano Marcolino est\u00e1 a ser acusado de desvio de fundos e vendas de bens diversos para o benef\u00edcio pessoal.\u00a0 \u00a0Leal\u00a0 Mundunde Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no documento constarem informa\u00e7\u00f5es comprometedoras, levantadas por dois delegados, a do Sambizanga e a de Cacuaco. Segundo o que chegou ao conhecimento deste Jornal, Caetano Marcolino recusa-se assinar a acta da reuni\u00e3o do dia 12 de Junho de 2023, por suspostamente no [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/","og_site_name":"Jornal O Crime","article_published_time":"2023-09-03T22:10:16+00:00","article_modified_time":"2023-09-10T10:21:10+00:00","og_image":[{"width":640,"height":343,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG-20221116-WA0049.jpg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS","datePublished":"2023-09-03T22:10:16+00:00","dateModified":"2023-09-10T10:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/"},"wordCount":946,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG-20221116-WA0049.jpg","articleSection":["SOCIEDADE"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/","url":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/","name":"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG-20221116-WA0049.jpg","datePublished":"2023-09-03T22:10:16+00:00","dateModified":"2023-09-10T10:21:10+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG-20221116-WA0049.jpg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG-20221116-WA0049.jpg","width":640,"height":343},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/presindente-da-associacao-de-apoio-aos-antigos-combatentes-das-ex-fapla-denunciado-por-desvios-de-fundos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"PRESINDENTE DA ASSOCIA\u00c7\u00c3O DE APOIO AOS ANTIGOS COMBATENTES DAS EX-FAPLA DENUNCIADO POR DESVIOS DE FUNDOS"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=6070"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/6071"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=6070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=6070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=6070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}