{"id":6279,"date":"2023-09-15T20:47:15","date_gmt":"2023-09-15T19:47:15","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=6279"},"modified":"2023-09-15T20:49:04","modified_gmt":"2023-09-15T19:49:04","slug":"para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/","title":{"rendered":"Para evitar acidentes rodovi\u00e1rios:  Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O comandante da Esquadra da Madeira, ex-12.\u00aa Esquadra do Comando da 3.\u00aa Divis\u00e3o do Cazenga, Pedro Ngola Issenguel, apelou, esta sexta-feira, 15 de Setembro, os mototaxistas do distrito urbano do Tala Hady a observarem as regras do C\u00f3digo de Estrada para evitarem acidentes<\/strong><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #ff0000;\">Por: Littera de Alexandria<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Ngola Issenguel fez este apelo durante um acto de sensibiliza\u00e7\u00e3o e reflex\u00e3o sobre a sinistralidade rodovi\u00e1ria, que decorreu hoje, dia 15 de Setembro , no Cine Cazenga, no distrito urbano do Tala Hady, no \u00e2mbito das ac\u00e7\u00f5es que visam a redu\u00e7\u00e3o da sinistralidade rodovi\u00e1ria envolvendo mototaxistas.<\/p>\n<p style=\"text-align: justify;\">Na ocasi\u00e3o, o comandante destacou que os acidentes envolvendo motorizadas se devem, em grande parte, ao incumprimento do C\u00f3digo de Estrada e das regras de condu\u00e7\u00e3o defensiva e segura.<\/p>\n<p style=\"text-align: justify;\">Por isso, segundo o respons\u00e1vel, realizou-se o acto de sensibiliza\u00e7\u00e3o e reflex\u00e3o sobre a sinistralidade rodovi\u00e1ria com o objectivo de, entre outras coisas, exortar os mototaxistas do distrito a observarem as normas do C\u00f3digo de Estrada para evitar acidentes.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de centenas de mototaxistas, moradores do distrito urbano do Tala Hady tamb\u00e9m participaram do acto de sensibiliza\u00e7\u00e3o e reflex\u00e3o sobre a sinistralidade rodovi\u00e1ria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O comandante da Esquadra da Madeira, ex-12.\u00aa Esquadra do Comando da 3.\u00aa Divis\u00e3o do Cazenga, Pedro Ngola Issenguel, apelou, esta sexta-feira, 15 de Setembro, os mototaxistas do distrito urbano do Tala Hady a observarem as regras do C\u00f3digo de Estrada para evitarem acidentes Por: Littera de Alexandria Ngola Issenguel fez este apelo durante um acto de sensibiliza\u00e7\u00e3o e reflex\u00e3o sobre a sinistralidade rodovi\u00e1ria, que decorreu hoje, dia 15 de Setembro , no Cine Cazenga, no distrito urbano do Tala Hady, no \u00e2mbito das ac\u00e7\u00f5es que visam a redu\u00e7\u00e3o da sinistralidade rodovi\u00e1ria envolvendo mototaxistas. Na ocasi\u00e3o, o comandante destacou que os [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6279","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actual","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O comandante da Esquadra da Madeira, ex-12.\u00aa Esquadra do Comando da 3.\u00aa Divis\u00e3o do Cazenga, Pedro Ngola Issenguel, apelou, esta sexta-feira, 15 de Setembro, os mototaxistas do distrito urbano do Tala Hady a observarem as regras do C\u00f3digo de Estrada para evitarem acidentes Por: Littera de Alexandria Ngola Issenguel fez este apelo durante um acto de sensibiliza\u00e7\u00e3o e reflex\u00e3o sobre a sinistralidade rodovi\u00e1ria, que decorreu hoje, dia 15 de Setembro , no Cine Cazenga, no distrito urbano do Tala Hady, no \u00e2mbito das ac\u00e7\u00f5es que visam a redu\u00e7\u00e3o da sinistralidade rodovi\u00e1ria envolvendo mototaxistas. Na ocasi\u00e3o, o comandante destacou que os [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-15T19:47:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-15T19:49:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4157.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada\",\"datePublished\":\"2023-09-15T19:47:15+00:00\",\"dateModified\":\"2023-09-15T19:49:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/\"},\"wordCount\":221,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4157.jpeg\",\"articleSection\":[\"ACTUAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/\",\"name\":\"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4157.jpeg\",\"datePublished\":\"2023-09-15T19:47:15+00:00\",\"dateModified\":\"2023-09-15T19:49:04+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4157.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4157.jpeg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/","og_locale":"pt_PT","og_type":"article","og_title":"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada - Jornal O Crime","og_description":"O comandante da Esquadra da Madeira, ex-12.\u00aa Esquadra do Comando da 3.\u00aa Divis\u00e3o do Cazenga, Pedro Ngola Issenguel, apelou, esta sexta-feira, 15 de Setembro, os mototaxistas do distrito urbano do Tala Hady a observarem as regras do C\u00f3digo de Estrada para evitarem acidentes Por: Littera de Alexandria Ngola Issenguel fez este apelo durante um acto de sensibiliza\u00e7\u00e3o e reflex\u00e3o sobre a sinistralidade rodovi\u00e1ria, que decorreu hoje, dia 15 de Setembro , no Cine Cazenga, no distrito urbano do Tala Hady, no \u00e2mbito das ac\u00e7\u00f5es que visam a redu\u00e7\u00e3o da sinistralidade rodovi\u00e1ria envolvendo mototaxistas. Na ocasi\u00e3o, o comandante destacou que os [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/","og_site_name":"Jornal O Crime","article_published_time":"2023-09-15T19:47:15+00:00","article_modified_time":"2023-09-15T19:49:04+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4157.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada","datePublished":"2023-09-15T19:47:15+00:00","dateModified":"2023-09-15T19:49:04+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/"},"wordCount":221,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4157.jpeg","articleSection":["ACTUAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/","url":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/","name":"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4157.jpeg","datePublished":"2023-09-15T19:47:15+00:00","dateModified":"2023-09-15T19:49:04+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4157.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4157.jpeg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/para-evitar-acidentes-rodoviarios-comandante-ngola-apela-mototaxistas-para-que-cumpram-as-regras-do-codigo-de-estrada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Para evitar acidentes rodovi\u00e1rios: Comandante Ngola apela mototaxistas para que cumpram as regras do C\u00f3digo de Estrada"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=6279"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/6280"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=6279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=6279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=6279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}