{"id":6310,"date":"2023-09-24T18:08:08","date_gmt":"2023-09-24T17:08:08","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=6310"},"modified":"2023-09-25T10:52:15","modified_gmt":"2023-09-25T09:52:15","slug":"todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/","title":{"rendered":"&#8220;TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES&#8221; GARANTE CANDIDATO DA LISTA &#8220;E&#8221;, ANT\u00d3NIO VICENTE GIMBE"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O candidato da lista &#8220;E&#8221; \u00e0s elei\u00e7\u00f5es ao Cofre de Provid\u00eancia da Pol\u00edcia Nacional de Angola (PNA), Comiss\u00e1rio-chefe Ant\u00f3nio Vicente Gimbe, defendeu, sexta-feira, 22 de Setembro de 2023, um novo modelo de vota\u00e7\u00e3o \u00e0s elei\u00e7\u00f5es do Cofre e garantiu que, caso seja eleito, todos os associados ter\u00e3o direito ao voto.<\/strong><\/p>\n<p style=\"text-align: justify;\">A garantia foi dada durante a campanha que o candidato realizou nas instala\u00e7\u00f5es da Pol\u00edcia de Seguran\u00e7a Pessoal e Entidades Protocolares (PSPEP), onde apresentou os seus projectos para a lideran\u00e7a do \u00f3rg\u00e3o minimalista da PNA.<\/p>\n<p style=\"text-align: justify;\">O Comiss\u00e1rio-chefe reprovou o actual modelo de vota\u00e7\u00e3o, feito por representa\u00e7\u00e3o. &#8220;N\u00e3o aceito que quatro pessoas representem um \u00f3rg\u00e3o de mais de mil efectivos. Isto tem de acabar e, caso ven\u00e7a as elei\u00e7\u00f5es, todos os associados ter\u00e3o direito ao voto&#8221;, assegurou o Oficial Comiss\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">O actual Director de Educa\u00e7\u00e3o Patri\u00f3tica da Corpora\u00e7\u00e3o lamentou o facto de o Cofre existir a quase um s\u00e9culo e at\u00e9 ao momento n\u00e3o corresponder satisfatoriamente \u00e0s necessidades dos associados&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;A gest\u00e3o do Cofre est\u00e1 aqu\u00e9m das expectativas. Nesses anos de sua exist\u00eancia, os contribuintes debatem-se com a falta de resolu\u00e7\u00e3o dos m\u00faltiplos problemas sociais que os afligem, problemas estes que deveriam ser resolvidos se houvesse um pouco mais de aten\u00e7\u00e3o por parte dos gestores deste \u00f3rg\u00e3o&#8221;, criticou.<\/p>\n<p style=\"text-align: justify;\">Ant\u00f3nio Vicente assegurou que o foco do seu programa ser\u00e1 de dar respostas concretas e imediatas aos associados, por via da complementaridade.<br \/>\n&#8220;O associado n\u00e3o pode esperar, o seu problema deve ser resolvido imediatamente, falo de sa\u00fade, educa\u00e7\u00e3o, habita\u00e7\u00e3o e outros problemas de base dos efectivos e suas fam\u00edlias, uma vez que o pol\u00edcia \u00e9 o principal activo do Cofre. Este \u00e9 um dos nossos principais foco, dar respostas imediatas&#8221;, concluiu o candidato a presidente do Cofre.<\/p>\n<p style=\"text-align: justify;\">De salientar que, a actividade ficou marcada de v\u00e1rios momentos culturais, como: declama\u00e7\u00e3o de poesia e can\u00e7\u00f5es inspiradas nas obras de Agostinho Neto, primeiro presidente de Angola, em alus\u00e3o ao seu anivers\u00e1rio, tendo como um dos principais protagonistas em palco o m\u00fasico e Inspector da PNA, Ac\u00e1cio, que, ao seu jeito, cantou e encantou a multid\u00e3o presente, deixando-se tamb\u00e9m encantar pela pequena poetisa Wendy Bocado.<\/p>\n<p style=\"text-align: justify;\">Participaram do encontro o 2\u00b0 Comandante da PSPEP, Subcomiss\u00e1rio Sebasti\u00e3o Xavier Neto, em representa\u00e7\u00e3o do titular do \u00f3rg\u00e3o, Comiss\u00e1rio Jos\u00e9 Martinez Ant\u00f3nio, ladeado do Superintendente-chefe Augusto Pinto da Costa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O candidato da lista &#8220;E&#8221; \u00e0s elei\u00e7\u00f5es ao Cofre de Provid\u00eancia da Pol\u00edcia Nacional de Angola (PNA), Comiss\u00e1rio-chefe Ant\u00f3nio Vicente Gimbe, defendeu, sexta-feira, 22 de Setembro de 2023, um novo modelo de vota\u00e7\u00e3o \u00e0s elei\u00e7\u00f5es do Cofre e garantiu que, caso seja eleito, todos os associados ter\u00e3o direito ao voto. A garantia foi dada durante a campanha que o candidato realizou nas instala\u00e7\u00f5es da Pol\u00edcia de Seguran\u00e7a Pessoal e Entidades Protocolares (PSPEP), onde apresentou os seus projectos para a lideran\u00e7a do \u00f3rg\u00e3o minimalista da PNA. O Comiss\u00e1rio-chefe reprovou o actual modelo de vota\u00e7\u00e3o, feito por representa\u00e7\u00e3o. &#8220;N\u00e3o aceito que quatro [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6310","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-politica","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES&quot; GARANTE CANDIDATO DA LISTA &quot;E&quot;, ANT\u00d3NIO VICENTE GIMBE - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES&quot; GARANTE CANDIDATO DA LISTA &quot;E&quot;, ANT\u00d3NIO VICENTE GIMBE - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O candidato da lista &#8220;E&#8221; \u00e0s elei\u00e7\u00f5es ao Cofre de Provid\u00eancia da Pol\u00edcia Nacional de Angola (PNA), Comiss\u00e1rio-chefe Ant\u00f3nio Vicente Gimbe, defendeu, sexta-feira, 22 de Setembro de 2023, um novo modelo de vota\u00e7\u00e3o \u00e0s elei\u00e7\u00f5es do Cofre e garantiu que, caso seja eleito, todos os associados ter\u00e3o direito ao voto. A garantia foi dada durante a campanha que o candidato realizou nas instala\u00e7\u00f5es da Pol\u00edcia de Seguran\u00e7a Pessoal e Entidades Protocolares (PSPEP), onde apresentou os seus projectos para a lideran\u00e7a do \u00f3rg\u00e3o minimalista da PNA. O Comiss\u00e1rio-chefe reprovou o actual modelo de vota\u00e7\u00e3o, feito por representa\u00e7\u00e3o. &#8220;N\u00e3o aceito que quatro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-24T17:08:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-25T09:52:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4285.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"&#8220;TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES&#8221; GARANTE CANDIDATO DA LISTA &#8220;E&#8221;, ANT\u00d3NIO VICENTE GIMBE\",\"datePublished\":\"2023-09-24T17:08:08+00:00\",\"dateModified\":\"2023-09-25T09:52:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/\"},\"wordCount\":455,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4285.jpeg\",\"articleSection\":[\"POL\u00cdTICA\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/\",\"name\":\"\\\"TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES\\\" GARANTE CANDIDATO DA LISTA \\\"E\\\", ANT\u00d3NIO VICENTE GIMBE - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4285.jpeg\",\"datePublished\":\"2023-09-24T17:08:08+00:00\",\"dateModified\":\"2023-09-25T09:52:15+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4285.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_4285.jpeg\",\"width\":1032,\"height\":774},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES&#8221; GARANTE CANDIDATO DA LISTA &#8220;E&#8221;, ANT\u00d3NIO VICENTE GIMBE\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES\" GARANTE CANDIDATO DA LISTA \"E\", ANT\u00d3NIO VICENTE GIMBE - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/","og_locale":"pt_PT","og_type":"article","og_title":"\"TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES\" GARANTE CANDIDATO DA LISTA \"E\", ANT\u00d3NIO VICENTE GIMBE - Jornal O Crime","og_description":"O candidato da lista &#8220;E&#8221; \u00e0s elei\u00e7\u00f5es ao Cofre de Provid\u00eancia da Pol\u00edcia Nacional de Angola (PNA), Comiss\u00e1rio-chefe Ant\u00f3nio Vicente Gimbe, defendeu, sexta-feira, 22 de Setembro de 2023, um novo modelo de vota\u00e7\u00e3o \u00e0s elei\u00e7\u00f5es do Cofre e garantiu que, caso seja eleito, todos os associados ter\u00e3o direito ao voto. A garantia foi dada durante a campanha que o candidato realizou nas instala\u00e7\u00f5es da Pol\u00edcia de Seguran\u00e7a Pessoal e Entidades Protocolares (PSPEP), onde apresentou os seus projectos para a lideran\u00e7a do \u00f3rg\u00e3o minimalista da PNA. O Comiss\u00e1rio-chefe reprovou o actual modelo de vota\u00e7\u00e3o, feito por representa\u00e7\u00e3o. &#8220;N\u00e3o aceito que quatro [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/","og_site_name":"Jornal O Crime","article_published_time":"2023-09-24T17:08:08+00:00","article_modified_time":"2023-09-25T09:52:15+00:00","og_image":[{"width":1032,"height":774,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4285.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"&#8220;TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES&#8221; GARANTE CANDIDATO DA LISTA &#8220;E&#8221;, ANT\u00d3NIO VICENTE GIMBE","datePublished":"2023-09-24T17:08:08+00:00","dateModified":"2023-09-25T09:52:15+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/"},"wordCount":455,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4285.jpeg","articleSection":["POL\u00cdTICA"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/","url":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/","name":"\"TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES\" GARANTE CANDIDATO DA LISTA \"E\", ANT\u00d3NIO VICENTE GIMBE - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4285.jpeg","datePublished":"2023-09-24T17:08:08+00:00","dateModified":"2023-09-25T09:52:15+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4285.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/09\/IMG_4285.jpeg","width":1032,"height":774},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/todos-associados-do-cofre-de-previdencia-terao-direito-ao-voto-nas-proximas-eleicoes-garante-candidato-da-lista-e-antonio-vicente-gimbe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"&#8220;TODOS ASSOCIADOS DO COFRE DE PREVID\u00caNCIA TER\u00c3O DIREITO AO VOTO NAS PR\u00d3XIMAS ELEI\u00c7\u00d5ES&#8221; GARANTE CANDIDATO DA LISTA &#8220;E&#8221;, ANT\u00d3NIO VICENTE GIMBE"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=6310"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/6314"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=6310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=6310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=6310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}