{"id":6383,"date":"2023-10-26T02:10:46","date_gmt":"2023-10-26T01:10:46","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=6383"},"modified":"2023-10-26T02:11:15","modified_gmt":"2023-10-26T01:11:15","slug":"mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/","title":{"rendered":"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO:  EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA"},"content":{"rendered":"<p><span class=\"s3\"><span class=\"bumpedFont15\">Mais de 9<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> milh\u00f5es de crian\u00e7as a n\u00edvel nacional n\u00e3o t\u00eam acesso a escolas, por falta de <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">infra-estruturas<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> no sector e p\u00e9ssimas condi\u00e7\u00f5es das salas de aulas.<\/span><\/span><\/p>\n<p><span class=\"s2\" style=\"color: #ff0000;\"><span class=\"bumpedFont15\">Maiomona Paxe<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">O sistema de ensino em Angola, h\u00e1 muito que vem oscilando, revelando uma decad\u00eancia <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">naquilo que s\u00e3o os pilares de uma sociedade em vias de desenvolvimento.<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> A qualidade de ensino tem reduzido<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> de forma tremenda<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> ap\u00f3s a era colonial<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, que ao contr\u00e1rio do que se previa,<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> se verifica um aut\u00eantico descalabro no sector da educa\u00e7\u00e3o.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">O<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> n\u00famero de <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">crian\u00e7as fora do sistema de ensino, tem revelado a falta de compromisso<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> do executivo angolano, <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">o que demonstra ser um enclave n<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">o desenvolvimento do pa\u00eds<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">. <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">A falta de escolas e de pol\u00edticas adequadas \u00e0 realidade angolana, tem contribu\u00eddo de forma repetitiva no crescente n\u00famero de crian\u00e7as e adultos fora do sistema de ensino.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">Segundo o relat\u00f3rio da UNICEF-Angola, <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">divulgado em 2012, mais de 5 milh\u00f5es de crian\u00e7as entre os 3 aos 17 anos <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">n\u00e3o tiveram acesso <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">\u00e0<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> escola<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">. De l\u00e1 para c\u00e1, o n\u00famero cresceu<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">consideravelmente, tendo<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> em conta as desist\u00eancias <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">efectivadas<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, n\u00e3o s\u00f3<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> pelo n\u00famero reduzido de escolas, como tamb\u00e9m <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">pela<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> falta de condi\u00e7\u00f5es <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">e<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> precariedade de vida que v\u00e1rios cidad\u00e3os enfrentam.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">De acordo com os dados apresentados recentemente pelo Movimento dos Estudantes Angolanos (MEA), <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">a<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">quando do arranque<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> do ano<\/span><\/span> <span class=\"s3\"><span class=\"bumpedFont15\">lectivo<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> 2023\/<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">2024, <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">cerca de <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">10 milh\u00f5es <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">de crian\u00e7as<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> em todo pa\u00eds,<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> se encontram fora do sistema de ensino, estat\u00edstica<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> que revela ser um atentado contra o progresso do ensino<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">e consequente entrave no desenvolvimento<\/span><\/span> <span class=\"s3\"><span class=\"bumpedFont15\">da na\u00e7\u00e3o, que possui uma extens\u00e3o territorial de 1.246, 700km<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">\u00b2<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">. O MEA (Movimento dos estudantes angolanos), acusa o governo de ser o principal violador dos direitos da crian\u00e7a e da educa\u00e7\u00e3o, por n\u00e3o permitir o acesso a<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">o ensino <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">e n\u00e3o <\/span><\/span><a name=\"_GoBack\"><\/a><span class=\"s3\"><span class=\"bumpedFont15\">garantir uma educa\u00e7\u00e3o de qualidade.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">S\u00f3 em Luanda, <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">segundo declara\u00e7\u00f5es do Governador, Manuel Homem, proferido em <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">Maio<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> do ano em curso, em 2022 a cidade capital reg<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">istou mais de um milh\u00e3o e meio <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">de crian\u00e7as fora do sistema de ensino<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">,<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> por falta de <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">infra-estruturas<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> escolares.<\/span><\/span> <span class=\"s3\"><span class=\"bumpedFont15\">N\u00fameros que levaram o MEA a calcular a taxa das demais prov\u00edncias, que diferente da densidade populacional da prov\u00edncia de Luanda<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, registaram cerca de <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">500 mil crian\u00e7as, perfazendo um total de 10 milh\u00f5es de crian\u00e7as fora do sistema de ensino em todo territ\u00f3rio nacional.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">Estes dados representam uma defici\u00eancia no sector da educa\u00e7\u00e3o, que h\u00e1 anos o executivo n\u00e3o tem sabido ultrapassar. <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">\u201c<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">A insi<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">st\u00eancia na estagna\u00e7\u00e3o do processo<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> de ensino e aprendizagem, demonstra claramente a inten\u00e7\u00e3o do executivo <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">em \u201camputar\u201d<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> e prover um ensino deficiente\u201d.<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> A t\u00edtulo elucidativo, <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">a prov\u00edncia de Luanda, com maior densidade populacional, conta apenas com cerca de 3.747 escolas p\u00fablicas e privadas<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, insuficiente para atender a demanda.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">A par <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">da falta de <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">infra-estruturas<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> escolares, o presidente do MEA, Francisco Teixeira, <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">cita a falta de manuten\u00e7\u00e3o e aus\u00eancia de obras de benfeitoria em v\u00e1rias escolas, superlota\u00e7\u00e3o, falta de carteiras, bem como<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> a falta de escolas para estudantes com necessidades especiais,<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> o<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> n\u00famero reduzido de docentes <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">e falta de materiais <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">did\u00e1cticos<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, como sendo as causas da p\u00e9ssima qualidade de ensino. Para <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">se ter uma ideia, h\u00e1 escolas do ensino prim\u00e1rio com uma m\u00e9dia de 70 alunos, em cada sala de aula e, 80 alunos no <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">I\u00ba<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> ciclo, o que dificulta as movimenta\u00e7\u00f5es dos professores no interior da sala.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">Como prova da falta de compromisso do executivo ao progresso do sector da educa\u00e7\u00e3o, a escola prim\u00e1ria N\u00ba 3014, sito no bairro Adriano Moreira, munic\u00edpio do Cazenga<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, foi encerrada por falta de <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">interven\u00e7\u00e3o n<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">a estrutura que h\u00e1 muito n\u00e3o oferecia condi\u00e7\u00f5es para<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> processo de ensino e aprendizagem<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">. Os alunos foram transferid<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">os para a<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> escola N\u00ba 3022, onde enfrentam a problem\u00e1tica da superlota\u00e7\u00e3o, que culmina na maioria das vezes no baixo aproveitamento acad\u00eamico.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">Outro sim, que contribui<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> na perman\u00eancia do ensino \u201cmutilado\u201d<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, tem que ver com a corrup\u00e7\u00e3o e falta de transpar\u00eancia no processo das matr\u00edculas de novos estudantes. <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">V\u00e1rias fam\u00edlias s\u00e3o obrigadas a pernoitar defronte as institui\u00e7\u00f5es afim de garantir vagas para seus educandos, sob pena dos mesmos perderem o ano <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">l<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">ectivo<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">devido ao n\u00famero reduzido<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> de vagas disponibilizadas. <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">Por outro lado, os funcion\u00e1rios e professores corruptos,<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> comerci<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">alizam vagas no valor de cinquenta mil (50.000kz) a oitenta mil kwanzas (80.000kz)<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, para o ensino prim\u00e1rio e <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">I\u00ba<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> ciclo<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">. No ensino m\u00e9dio as vagas chegam a custar at\u00e9 400 mil kwanzas (400.000kz)<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, tendo os institutos t\u00e9cnico<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">s de sa\u00fade a n\u00edvel de Luanda, IMEL (Instituto M\u00e9dio de Economia de Luanda)<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> e <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">IMIL (Instituto M\u00e9dio Industrial de Luanda), como os maiores pontos de exist\u00eancia de esquemas de corrup\u00e7\u00e3o, envolvendo funcion\u00e1rios administrativos e docentes.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">Por\u00e9m, as fam\u00edlias com menos condi\u00e7\u00f5es finan<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">ceiras s\u00e3o as mais prejudicadas<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">, numa altura em que<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> o governo autorizou <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">a subida do pre\u00e7o das propinas <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">nas escolas privadas, na ordem dos 10,62 por cento.<\/span><\/span><\/p>\n<p><span class=\"s3\"><span class=\"bumpedFont15\">Por sua vez, o<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> presidente do MEA, Francisco Teixeira,<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> afirma ser uma p\u00e9ssima decis\u00e3o do executivo ao autorizar a subida das propinas, <\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">uma vez que o pa\u00eds ainda apresenta n\u00fameros consider\u00e1v<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\">eis de cidad\u00e3os fora do sistema<\/span><\/span><span class=\"s3\"><span class=\"bumpedFont15\"> de ensino.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 9 milh\u00f5es de crian\u00e7as a n\u00edvel nacional n\u00e3o t\u00eam acesso a escolas, por falta de infra-estruturas no sector e p\u00e9ssimas condi\u00e7\u00f5es das salas de aulas. Maiomona Paxe O sistema de ensino em Angola, h\u00e1 muito que vem oscilando, revelando uma decad\u00eancia naquilo que s\u00e3o os pilares de uma sociedade em vias de desenvolvimento. A qualidade de ensino tem reduzido de forma tremenda ap\u00f3s a era colonial, que ao contr\u00e1rio do que se previa, se verifica um aut\u00eantico descalabro no sector da educa\u00e7\u00e3o. O n\u00famero de crian\u00e7as fora do sistema de ensino, tem revelado a falta de compromisso do [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Mais de 9 milh\u00f5es de crian\u00e7as a n\u00edvel nacional n\u00e3o t\u00eam acesso a escolas, por falta de infra-estruturas no sector e p\u00e9ssimas condi\u00e7\u00f5es das salas de aulas. Maiomona Paxe O sistema de ensino em Angola, h\u00e1 muito que vem oscilando, revelando uma decad\u00eancia naquilo que s\u00e3o os pilares de uma sociedade em vias de desenvolvimento. A qualidade de ensino tem reduzido de forma tremenda ap\u00f3s a era colonial, que ao contr\u00e1rio do que se previa, se verifica um aut\u00eantico descalabro no sector da educa\u00e7\u00e3o. O n\u00famero de crian\u00e7as fora do sistema de ensino, tem revelado a falta de compromisso do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T01:10:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T01:11:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/10\/IMG_5372.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA\",\"datePublished\":\"2023-10-26T01:10:46+00:00\",\"dateModified\":\"2023-10-26T01:11:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/\"},\"wordCount\":953,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IMG_5372.jpeg\",\"articleSection\":[\"OUTROS\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/\",\"name\":\"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IMG_5372.jpeg\",\"datePublished\":\"2023-10-26T01:10:46+00:00\",\"dateModified\":\"2023-10-26T01:11:15+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IMG_5372.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/IMG_5372.jpeg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/","og_locale":"pt_PT","og_type":"article","og_title":"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA - Jornal O Crime","og_description":"Mais de 9 milh\u00f5es de crian\u00e7as a n\u00edvel nacional n\u00e3o t\u00eam acesso a escolas, por falta de infra-estruturas no sector e p\u00e9ssimas condi\u00e7\u00f5es das salas de aulas. Maiomona Paxe O sistema de ensino em Angola, h\u00e1 muito que vem oscilando, revelando uma decad\u00eancia naquilo que s\u00e3o os pilares de uma sociedade em vias de desenvolvimento. A qualidade de ensino tem reduzido de forma tremenda ap\u00f3s a era colonial, que ao contr\u00e1rio do que se previa, se verifica um aut\u00eantico descalabro no sector da educa\u00e7\u00e3o. O n\u00famero de crian\u00e7as fora do sistema de ensino, tem revelado a falta de compromisso do [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/","og_site_name":"Jornal O Crime","article_published_time":"2023-10-26T01:10:46+00:00","article_modified_time":"2023-10-26T01:11:15+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/10\/IMG_5372.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA","datePublished":"2023-10-26T01:10:46+00:00","dateModified":"2023-10-26T01:11:15+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/"},"wordCount":953,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/10\/IMG_5372.jpeg","articleSection":["OUTROS"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/","url":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/","name":"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/10\/IMG_5372.jpeg","datePublished":"2023-10-26T01:10:46+00:00","dateModified":"2023-10-26T01:11:15+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/10\/IMG_5372.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2023\/10\/IMG_5372.jpeg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/mais-de-9-milhoes-de-criancas-fora-do-sistema-de-ensino-executivo-acusado-de-amputar-o-sistema-de-ensino-em-angola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"MAIS DE 9 MILH\u00d5ES DE CRIAN\u00c7AS FORA DO SISTEMA DE ENSINO: EXECUTIVO ACUSADO DE AMPUTAR O SISTEMA DE ENSINO EM ANGOLA"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=6383"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/6385"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=6383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=6383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=6383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}