{"id":6758,"date":"2024-03-20T17:52:15","date_gmt":"2024-03-20T16:52:15","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=6758"},"modified":"2024-03-20T17:53:45","modified_gmt":"2024-03-20T16:53:45","slug":"greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/","title":{"rendered":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O primeiro dia de greve nacional a n\u00edvel da fun\u00e7\u00e3o p\u00fablica, que teve in\u00edcio \u00e0s 7horas desta quarta-feira, dia 20 de Mar\u00e7o,registou a deten\u00e7\u00e3o de tr\u00eas sindicalistas e intimida\u00e7\u00e3o de v\u00e1rios trabalhadores.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Leal Mundunde<\/span><\/p>\n<p style=\"text-align: justify;\">As tr\u00eas centrais sindicais que convocaram a greve nacional que decorre at\u00e9 ao dia 22 de Mar\u00e7o, denunciam que no primeiro dia da greve, registaram a deten\u00e7\u00e3o de trabalhadores nas prov\u00edncias do Bengo e Huambo, por parte de efectivos da Pol\u00edcia Nacional.<\/p>\n<p style=\"text-align: justify;\">Tratam-se de Abr\u00e3o Messamessa Faustino, pertencente ao Minist\u00e9rio da Educa\u00e7\u00e3o, Narciso Chipalavela e Laurindo Chipesse M\u00e1rio, ambos da Empresa Nacional de Electricidade (ENDE).<\/p>\n<p style=\"text-align: justify;\">A organiza\u00e7\u00e3o, apela as autoridades no sentido de libertarem urgentemente os sindicalistas que lutam pelos seus direitos e dos demais cidad\u00e3os, sob pena de desencadeaream ac\u00e7\u00e3o judicial contra os agentes da corpora\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">De acordo as centrais sindicais, caso os trabalhadores n\u00e3o forem libertos, prometem levar a cabo manifesta\u00e7\u00f5es p\u00fablicas a n\u00edvel do pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">At\u00e9 ao momento, s\u00e3o desconhecidas as circunst\u00e2ncias em que ocorreu a deten\u00e7\u00e3o dos tr\u00eas sindicalistas.<\/p>\n<p style=\"text-align: justify;\">Fala-se tamb\u00e9m de intimida\u00e7\u00e3o aos trabalhadores do sector da Sa\u00fade, Educa\u00e7\u00e3o e do Minist\u00e9rio da Justi\u00e7a e Direitos Humanos, por aderirem a grave, o que consideram por viola\u00e7\u00e3o a este Direito &#8220;constitucionalmente consagrado&#8221;.<\/p>\n<p style=\"text-align: justify;\">A Uni\u00e3o Nacional dos Trabalhadores Angolanos &#8211; Central Sindical (UNTA-CS), Central Geral de Sindicatos Independentes e Livres de Angola (CGSILA), For\u00e7a Sindical Angolana (FSA-CS), em comunicado datado do dia 20 de Mar\u00e7o, reafirmam que, a greve visa o resgate da dignidade social dos trabalhadores angolanos.<\/p>\n<p style=\"text-align: justify;\">No primeiro dia da greve, em que os trabalhadores do sector p\u00fablico foram chamados a manterem-se em casa, as tr\u00eas centrais sindicais falam em ades\u00e3o na ordem dos 95 por cento.<\/p>\n<p style=\"text-align: justify;\">A revis\u00e3o do sal\u00e1rio m\u00ednimo nacional da fun\u00e7\u00e3o p\u00fablica para corresponder com o custo de vida da popula\u00e7\u00e3o, implementa\u00e7\u00e3o pr\u00e1tica dos subs\u00eddios de isolamento e instala\u00e7\u00e3o em todos as localidades, bem como, o desagravamento do Imposto sobre o Rendimento de Trabalho (IRT) na ordem dos 10 por cento e actualiza\u00e7\u00e3o dos subs\u00eddios previstos no sistema das presta\u00e7\u00f5es sociais (de aleitamento materno,funeral, de morte e abandono familiar), s\u00e3o algumas das reivindica\u00e7\u00f5es dos trabalhadores.<\/p>\n<p style=\"text-align: justify;\">Durante o per\u00edodo de grave, os organizadores prometem que estar\u00e3o a disposi\u00e7\u00e3o da popula\u00e7\u00e3o v\u00e1rios servi\u00e7os:banco de urg\u00eancia, maternidade, Hemodi\u00e1lise, cemit\u00e9rios, \u00e1gua e energia.<\/p>\n<p style=\"text-align: justify;\">Depois desta fase, caso n\u00e3o houver entendimento entre o governo e as tr\u00eas centrais sindicais, ter\u00e1 lugar a segunda fase da grave com in\u00edcio previsto para o per\u00edodo de 22 a 30 de Abril e a terceira, para 3 a 14 de Junho.<\/p>\n<p style=\"text-align: justify;\">UNTA-CS, CGSILA e For\u00e7a Sindical, a pesar da grave ser destinada para a fun\u00e7\u00e3o p\u00fablica, apelam tamb\u00e9m a solidariedade de institui\u00e7\u00f5es privadas do pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O primeiro dia de greve nacional a n\u00edvel da fun\u00e7\u00e3o p\u00fablica, que teve in\u00edcio \u00e0s 7horas desta quarta-feira, dia 20 de Mar\u00e7o,registou a deten\u00e7\u00e3o de tr\u00eas sindicalistas e intimida\u00e7\u00e3o de v\u00e1rios trabalhadores. Leal Mundunde As tr\u00eas centrais sindicais que convocaram a greve nacional que decorre at\u00e9 ao dia 22 de Mar\u00e7o, denunciam que no primeiro dia da greve, registaram a deten\u00e7\u00e3o de trabalhadores nas prov\u00edncias do Bengo e Huambo, por parte de efectivos da Pol\u00edcia Nacional. Tratam-se de Abr\u00e3o Messamessa Faustino, pertencente ao Minist\u00e9rio da Educa\u00e7\u00e3o, Narciso Chipalavela e Laurindo Chipesse M\u00e1rio, ambos da Empresa Nacional de Electricidade (ENDE). A [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6758","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-nacional","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O primeiro dia de greve nacional a n\u00edvel da fun\u00e7\u00e3o p\u00fablica, que teve in\u00edcio \u00e0s 7horas desta quarta-feira, dia 20 de Mar\u00e7o,registou a deten\u00e7\u00e3o de tr\u00eas sindicalistas e intimida\u00e7\u00e3o de v\u00e1rios trabalhadores. Leal Mundunde As tr\u00eas centrais sindicais que convocaram a greve nacional que decorre at\u00e9 ao dia 22 de Mar\u00e7o, denunciam que no primeiro dia da greve, registaram a deten\u00e7\u00e3o de trabalhadores nas prov\u00edncias do Bengo e Huambo, por parte de efectivos da Pol\u00edcia Nacional. Tratam-se de Abr\u00e3o Messamessa Faustino, pertencente ao Minist\u00e9rio da Educa\u00e7\u00e3o, Narciso Chipalavela e Laurindo Chipesse M\u00e1rio, ambos da Empresa Nacional de Electricidade (ENDE). A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T16:52:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T16:53:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8344.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES\",\"datePublished\":\"2024-03-20T16:52:15+00:00\",\"dateModified\":\"2024-03-20T16:53:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/\"},\"wordCount\":526,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8344.jpeg\",\"articleSection\":[\"NACIONAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/\",\"name\":\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8344.jpeg\",\"datePublished\":\"2024-03-20T16:52:15+00:00\",\"dateModified\":\"2024-03-20T16:53:45+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8344.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8344.jpeg\",\"width\":425,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/","og_locale":"pt_PT","og_type":"article","og_title":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES - Jornal O Crime","og_description":"O primeiro dia de greve nacional a n\u00edvel da fun\u00e7\u00e3o p\u00fablica, que teve in\u00edcio \u00e0s 7horas desta quarta-feira, dia 20 de Mar\u00e7o,registou a deten\u00e7\u00e3o de tr\u00eas sindicalistas e intimida\u00e7\u00e3o de v\u00e1rios trabalhadores. Leal Mundunde As tr\u00eas centrais sindicais que convocaram a greve nacional que decorre at\u00e9 ao dia 22 de Mar\u00e7o, denunciam que no primeiro dia da greve, registaram a deten\u00e7\u00e3o de trabalhadores nas prov\u00edncias do Bengo e Huambo, por parte de efectivos da Pol\u00edcia Nacional. Tratam-se de Abr\u00e3o Messamessa Faustino, pertencente ao Minist\u00e9rio da Educa\u00e7\u00e3o, Narciso Chipalavela e Laurindo Chipesse M\u00e1rio, ambos da Empresa Nacional de Electricidade (ENDE). A [&hellip;]","og_url":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/","og_site_name":"Jornal O Crime","article_published_time":"2024-03-20T16:52:15+00:00","article_modified_time":"2024-03-20T16:53:45+00:00","og_image":[{"width":425,"height":600,"url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8344.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#article","isPartOf":{"@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES","datePublished":"2024-03-20T16:52:15+00:00","dateModified":"2024-03-20T16:53:45+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/"},"wordCount":526,"commentCount":0,"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8344.jpeg","articleSection":["NACIONAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/","url":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/","name":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#primaryimage"},"image":{"@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8344.jpeg","datePublished":"2024-03-20T16:52:15+00:00","dateModified":"2024-03-20T16:53:45+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8344.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8344.jpeg","width":425,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publica-com-detencoes-de-sindicalistas-e-intimidacoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA COM DETEN\u00c7\u00d5ES DE SINDICALISTAS E INTIMIDA\u00c7\u00d5ES"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=6758"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/6759"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=6758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=6758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=6758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}