{"id":6763,"date":"2024-03-21T18:06:02","date_gmt":"2024-03-21T17:06:02","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=6763"},"modified":"2024-03-21T18:06:02","modified_gmt":"2024-03-21T17:06:02","slug":"greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/","title":{"rendered":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Os alunos do ensino p\u00fablico, no bairro Cassequel, tencionavam efectuar as provas do II\u00ba Trimestre, regressaram tristes em casa, na manh\u00e3 desta quinta-feira,21 de Mar\u00e7o, devido a greve geral da fun\u00e7\u00e3o p\u00fablica que decorre em todos os sectores a n\u00edvel nacional.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Leal Mundunde<\/span><\/p>\n<p style=\"text-align: justify;\">No bairro Cassequel, distrito Urbano da Maianga, em Luanda, os professores das escolas p\u00fablicas aderiram em massa a greve,numa altura em que decorre a semana de provas.<\/p>\n<p style=\"text-align: justify;\">Depois da quarta-feira, 20 de Mar\u00e7o, os alunos terem voltado a casa sem terem feito as avalia\u00e7\u00f5es, em alguns ainda residia a esperan\u00e7a na mudan\u00e7a do quadro, por isso, na manh\u00e3 de quinta-feira,novamente regressaram as institui\u00e7\u00f5es e o cen\u00e1rio foi o mesmo.<\/p>\n<p style=\"text-align: justify;\">Os alunos com quem interagimos, disseram que que os pais exigiram que fossem a escola, sob protesto de perderem as provas, acreditando que poderia eventualmente existir um professor que fosse a institui\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">&#8220;Os alunos est\u00e3o a ficar prejudicados&#8221;, disse Maria Jo\u00e3o, encarregada de educa\u00e7\u00e3o, que optou em acompanhar o seu educando da 2\u00aa classe,na escola do I\u00ba ciclo do ensino secund\u00e1rio n\u00ba 1160 ex 2065.<\/p>\n<p style=\"text-align: justify;\">Por exemplo, durante o per\u00edodo em que permanecemos naquela escola, nos deparamos com v\u00e1rios alunos que se dirigiam na institui\u00e7\u00e3o preparados para as provas.<\/p>\n<p style=\"text-align: justify;\">Em grupo ou individualmente,voltavam tristes, por verem que a greve n\u00e3o havia terminado.<\/p>\n<p style=\"text-align: justify;\">&#8220;De novo mais um dia sem provas?&#8221;, questionou um dos alunos t\u00e3o logo observou os colegas fora da escola.<\/p>\n<p style=\"text-align: justify;\">Miguel Adelino,caminhava sozinho trajado com a bata branca, saia da escola do estado na zona da Terra Vermelha, preocupado com mais um dia sem ter feito as provas.<\/p>\n<p style=\"text-align: justify;\">O mesmo disse que poucos alunos apareceram face a paralisa\u00e7\u00e3o que se verifica nas institui\u00e7\u00f5es da fun\u00e7\u00e3o p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Miguel, espera que esta fase termine imediatamente, por reconhecer que ser\u00e3o os mais prejudicados.<\/p>\n<p style=\"text-align: justify;\">&#8220;Vamos estudar em casa para fazermos as provas assim que os professores voltarem&#8221;, acresceu,lamentando o facto dos seus colegas de escolas privadas estarem avan\u00e7ados.<\/p>\n<p style=\"text-align: justify;\">A encarregada de Educa\u00e7\u00e3o Maria Jo\u00e3o, afirmou que os seus vizinhos preferiram manter as crian\u00e7as em casa.<\/p>\n<p style=\"text-align: justify;\">A mesma, augura bom senso por parte do governo, para atender as preocupa\u00e7\u00f5es dos trabalhadores.<\/p>\n<p style=\"text-align: justify;\">Em fun\u00e7\u00e3o desta realidade que afecta as institui\u00e7\u00f5es da fun\u00e7\u00e3o p\u00fablica, o Governo Provincial de Luanda, por via do Gabinete de Educa\u00e7\u00e3o, informou que as avalia\u00e7\u00f5es do II\u00ba Trimestre, retomam no dia 25 de Mar\u00e7o.<\/p>\n<p style=\"text-align: justify;\">Depois da UNTA-CS, CGSILA e For\u00e7a Sindical, anunciarem a realiza\u00e7\u00e3o da greve nacional com dura\u00e7\u00e3o de tr\u00eas dias, o Movimento dos Estudantes Angolanos(MEA), em jeito de solidariedade com as tr\u00eas centrais sindicais, apelou aos alunos no sentido de permanecerem em casa.<\/p>\n<p style=\"text-align: justify;\">A pesar de reconhecer que a greve vai prejudicar os estudantes, o Secret\u00e1rio Provincial do MEA, em Luanda, Jonas Dami\u00e3o Andr\u00e9 Sebasti\u00e3o, defende que a medida \u00e9 a mais acertada, tendo em conta aos objectivos elencados pela organiza\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">As tr\u00eas centrais sindicais defendem a revis\u00e3o do sal\u00e1rio m\u00ednimo nacional da fun\u00e7\u00e3o p\u00fablica para corresponder com o custo de vida da popula\u00e7\u00e3o, implementa\u00e7\u00e3o pr\u00e1tica dos subs\u00eddios de isolamento e instala\u00e7\u00e3o em todos as localidades, bem como, o desagravamento do Imposto sobre o Rendimento de Trabalho (IRT) na ordem dos 10 por cento e actualiza\u00e7\u00e3o dos subs\u00eddios previstos no sistema das presta\u00e7\u00f5es sociais (de aleitamento materno,funeral, de morte e abandono familiar), s\u00e3o algumas das reivindica\u00e7\u00f5es dos trabalhadores.<\/p>\n<p style=\"text-align: justify;\">De recordar que, logo no primeiro dia de greve que teve lugar na passada quarta-feira, dia 20 de Mar\u00e7o, a Pol\u00edcia Nacional no Huambo e Bengo, detiveram tr\u00eas sindicalistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os alunos do ensino p\u00fablico, no bairro Cassequel, tencionavam efectuar as provas do II\u00ba Trimestre, regressaram tristes em casa, na manh\u00e3 desta quinta-feira,21 de Mar\u00e7o, devido a greve geral da fun\u00e7\u00e3o p\u00fablica que decorre em todos os sectores a n\u00edvel nacional. Leal Mundunde No bairro Cassequel, distrito Urbano da Maianga, em Luanda, os professores das escolas p\u00fablicas aderiram em massa a greve,numa altura em que decorre a semana de provas. Depois da quarta-feira, 20 de Mar\u00e7o, os alunos terem voltado a casa sem terem feito as avalia\u00e7\u00f5es, em alguns ainda residia a esperan\u00e7a na mudan\u00e7a do quadro, por isso, na [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Os alunos do ensino p\u00fablico, no bairro Cassequel, tencionavam efectuar as provas do II\u00ba Trimestre, regressaram tristes em casa, na manh\u00e3 desta quinta-feira,21 de Mar\u00e7o, devido a greve geral da fun\u00e7\u00e3o p\u00fablica que decorre em todos os sectores a n\u00edvel nacional. Leal Mundunde No bairro Cassequel, distrito Urbano da Maianga, em Luanda, os professores das escolas p\u00fablicas aderiram em massa a greve,numa altura em que decorre a semana de provas. Depois da quarta-feira, 20 de Mar\u00e7o, os alunos terem voltado a casa sem terem feito as avalia\u00e7\u00f5es, em alguns ainda residia a esperan\u00e7a na mudan\u00e7a do quadro, por isso, na [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T17:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8349.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"878\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS\",\"datePublished\":\"2024-03-21T17:06:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/\"},\"wordCount\":655,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8349.jpeg\",\"articleSection\":[\"NACIONAL\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/\",\"name\":\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8349.jpeg\",\"datePublished\":\"2024-03-21T17:06:02+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8349.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_8349.jpeg\",\"width\":1170,\"height\":878},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/","og_locale":"pt_PT","og_type":"article","og_title":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS - Jornal O Crime","og_description":"Os alunos do ensino p\u00fablico, no bairro Cassequel, tencionavam efectuar as provas do II\u00ba Trimestre, regressaram tristes em casa, na manh\u00e3 desta quinta-feira,21 de Mar\u00e7o, devido a greve geral da fun\u00e7\u00e3o p\u00fablica que decorre em todos os sectores a n\u00edvel nacional. Leal Mundunde No bairro Cassequel, distrito Urbano da Maianga, em Luanda, os professores das escolas p\u00fablicas aderiram em massa a greve,numa altura em que decorre a semana de provas. Depois da quarta-feira, 20 de Mar\u00e7o, os alunos terem voltado a casa sem terem feito as avalia\u00e7\u00f5es, em alguns ainda residia a esperan\u00e7a na mudan\u00e7a do quadro, por isso, na [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/","og_site_name":"Jornal O Crime","article_published_time":"2024-03-21T17:06:02+00:00","og_image":[{"width":1170,"height":878,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8349.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS","datePublished":"2024-03-21T17:06:02+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/"},"wordCount":655,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8349.jpeg","articleSection":["NACIONAL"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/","url":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/","name":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8349.jpeg","datePublished":"2024-03-21T17:06:02+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8349.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/03\/IMG_8349.jpeg","width":1170,"height":878},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/greve-geral-da-funcao-publicaalunos-do-cassequel-esperancosos-em-fazer-provas-regressam-a-casa-decepcionados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"GREVE GERAL DA FUN\u00c7\u00c3O P\u00daBLICA:ALUNOS DO CASSEQUEL ESPERAN\u00c7OSOS EM FAZER PROVAS REGRESSAM A CASA DECEPCIONADOS"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=6763"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/6764"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=6763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=6763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=6763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}