{"id":6901,"date":"2024-06-23T11:47:45","date_gmt":"2024-06-23T10:47:45","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=6901"},"modified":"2024-06-23T11:47:45","modified_gmt":"2024-06-23T10:47:45","slug":"no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/","title":{"rendered":"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma"},"content":{"rendered":"<p style=\"text-align: justify;\">Am\u00e9lia Francisco Gaeta, 69 anos de idade, foi barbaramente assassinada,no passado dia 13 de Junho, em casa, no munic\u00edpio do Cazenga, pelo filho, com golpes de faca na regi\u00e3o do abd\u00f4men e nos bra\u00e7os, ao ponto de ser retirada os intestinos.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\">Leal Mundunde<\/span><\/p>\n<p style=\"text-align: justify;\">Jorge Francisco ou simplesmente &#8220;Tio Bij\u00fa&#8221;, de 40 anos de idade, \u00e9 o autor do assassinato de forma B\u00e1rbara da pr\u00f3pria m\u00e3e, naquele fat\u00eddico dia, por volta das 13horas, no bairro Hoji Ya Henda, munic\u00edpio do Cazenga, em Luanda.<\/p>\n<p style=\"text-align: justify;\">O triste epis\u00f3dio aconteceu, quando &#8220;Tio Bij\u00fa&#8221;, terceiro filho num universo de quatro irm\u00e3os, aproveitou-se da aus\u00eancia dos parentes em casa, para perpetrar ac\u00e7\u00e3o criminosa, que vitimou aquela mulher.<\/p>\n<p style=\"text-align: justify;\">A malograda, foi encontrada j\u00e1 morta na cama, por um dos netos identificado por Josefe Paulo, que saia fazer compras. Logo a entrada de casa, foi alertado por uma vizinha que viu o suposto assassino a sair \u00e0s pressas de casa com o corpo ensanguentado.<\/p>\n<p style=\"text-align: justify;\">&#8220;Encontro av\u00f3, esfaqueada duas vezes na regi\u00e3o do abd\u00f4men e uma nos bra\u00e7os, com os p\u00e9s amarrados e foi retirado os intestinos, que escondeu por baixo da cama&#8221;, recordou o neto, tendo acrescido que as paredes estavam rodeadas de sangue.<\/p>\n<p style=\"text-align: justify;\">Josefe Paulo,a primeira pessoa que chegou no local do assassinato de Am\u00e9lia Francisco Gaeta, refere que, ainda encontrou a faca partida no ch\u00e3o, usada no homic\u00eddio e a camisa do tio, cheia de sangue,provas estas, que se encontram em posse do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal.<\/p>\n<p style=\"text-align: justify;\">A irm\u00e3 da v\u00edtima, Teresa Francisco, sublinha que recentemente, antes de Jorge, matar a m\u00e3e, por raz\u00f5es que desconhece, tentou golpear com faca a sobrinha menor, por sorte, a mesma pediu socorro, contando com a pronta interven\u00e7\u00e3o dos vizinhos.<\/p>\n<p style=\"text-align: justify;\">&#8220;Ela ao tentar defender-se, travou a faca com a m\u00e3o e aleijou&#8221;, lamentou.<\/p>\n<p style=\"text-align: justify;\">A fam\u00edlia diz que, o comportamento agressivo de Jorge, que dependia principalmente da m\u00e3e, come\u00e7ou ainda aos 22 anos de idade e recorda que sempre teve o v\u00edcio de solicitar dinheiro a m\u00e3e, que a dava regularmente.<\/p>\n<p style=\"text-align: justify;\">De acordo a tia de Jorge, este, havia adquirido uma viatura, usada para actividade de t\u00e1xi.<\/p>\n<p style=\"text-align: justify;\">Com tempo, quando a viatura come\u00e7ou apresentar problemas, para adquirir novas pe\u00e7as, sempre batia a porta da m\u00e3e, para ajud\u00e1-lo.<\/p>\n<p style=\"text-align: justify;\">Caso n\u00e3o fosse satisfeita as suas necessidades, tornava-se agressivo com a m\u00e3e e outros familiares pr\u00f3ximos.<\/p>\n<p style=\"text-align: justify;\">&#8220;Lutava comigo, amea\u00e7ava-me com faca&#8221;, avan\u00e7ou Teresa Francisco.Ela, desconfia, que o seu sobrinho eventualmente ao longo dos anos tenha recorrido a casa obscuras, facto que ter\u00e1 influenciado ao comportamento desviante que foi tendo ao longo dos anos.<\/p>\n<p style=\"text-align: justify;\">Outrossim, os familiares afirmam que o mesmo teve problemas mentais, chegou de ser acompanhado por um psiquiatria, depois teve alta. Mas volte e meia, tornava-se violento.<\/p>\n<p style=\"text-align: justify;\">A fam\u00edlia que se encontra insegura, pelo facto do suspeito estar foragido, pede a quem o vir, que fa\u00e7a participa\u00e7\u00e3o a Pol\u00edcia ou ao Servi\u00e7o de Investiga\u00e7\u00e3o Criminal, para que n\u00e3o surjam outras consequ\u00eancias nefastas.<\/p>\n<p style=\"text-align: justify;\">A fam\u00edlia, reitera que Jorge, \u00e9 sim, o verdadeiro autor do acto e espera que seja responsabilizado, criminalmente.<\/p>\n<p style=\"text-align: justify;\">Am\u00e9lia Francisco Gaeta, vi\u00fava, reformada, do pouco que mensalmente ganhava, cuidava das despesas de casa e ajudava os familiares com quem morava, dentre eles, o filho e seus netos.<\/p>\n<p style=\"text-align: justify;\">A mesma, em Julho completaria 70 anos de idade e sua trajet\u00f3ria de vida,terminou com ac\u00e7\u00e3o protagonizada por quem residiu no seu ventre durante nove meses.<\/p>\n<p style=\"text-align: justify;\">O caso j\u00e1 est\u00e1 sob tutela, dos \u00f3rg\u00e3os de justi\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am\u00e9lia Francisco Gaeta, 69 anos de idade, foi barbaramente assassinada,no passado dia 13 de Junho, em casa, no munic\u00edpio do Cazenga, pelo filho, com golpes de faca na regi\u00e3o do abd\u00f4men e nos bra\u00e7os, ao ponto de ser retirada os intestinos. Leal Mundunde Jorge Francisco ou simplesmente &#8220;Tio Bij\u00fa&#8221;, de 40 anos de idade, \u00e9 o autor do assassinato de forma B\u00e1rbara da pr\u00f3pria m\u00e3e, naquele fat\u00eddico dia, por volta das 13horas, no bairro Hoji Ya Henda, munic\u00edpio do Cazenga, em Luanda. O triste epis\u00f3dio aconteceu, quando &#8220;Tio Bij\u00fa&#8221;, terceiro filho num universo de quatro irm\u00e3os, aproveitou-se da aus\u00eancia dos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"Am\u00e9lia Francisco Gaeta, 69 anos de idade, foi barbaramente assassinada,no passado dia 13 de Junho, em casa, no munic\u00edpio do Cazenga, pelo filho, com golpes de faca na regi\u00e3o do abd\u00f4men e nos bra\u00e7os, ao ponto de ser retirada os intestinos. Leal Mundunde Jorge Francisco ou simplesmente &#8220;Tio Bij\u00fa&#8221;, de 40 anos de idade, \u00e9 o autor do assassinato de forma B\u00e1rbara da pr\u00f3pria m\u00e3e, naquele fat\u00eddico dia, por volta das 13horas, no bairro Hoji Ya Henda, munic\u00edpio do Cazenga, em Luanda. O triste epis\u00f3dio aconteceu, quando &#8220;Tio Bij\u00fa&#8221;, terceiro filho num universo de quatro irm\u00e3os, aproveitou-se da aus\u00eancia dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-23T10:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/06\/IMG_0267.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma\",\"datePublished\":\"2024-06-23T10:47:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/\"},\"wordCount\":636,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_0267.jpeg\",\"articleSection\":[\"OUTROS\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/\",\"name\":\"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_0267.jpeg\",\"datePublished\":\"2024-06-23T10:47:45+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_0267.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_0267.jpeg\",\"width\":960,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/","og_locale":"pt_PT","og_type":"article","og_title":"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma - Jornal O Crime","og_description":"Am\u00e9lia Francisco Gaeta, 69 anos de idade, foi barbaramente assassinada,no passado dia 13 de Junho, em casa, no munic\u00edpio do Cazenga, pelo filho, com golpes de faca na regi\u00e3o do abd\u00f4men e nos bra\u00e7os, ao ponto de ser retirada os intestinos. Leal Mundunde Jorge Francisco ou simplesmente &#8220;Tio Bij\u00fa&#8221;, de 40 anos de idade, \u00e9 o autor do assassinato de forma B\u00e1rbara da pr\u00f3pria m\u00e3e, naquele fat\u00eddico dia, por volta das 13horas, no bairro Hoji Ya Henda, munic\u00edpio do Cazenga, em Luanda. O triste epis\u00f3dio aconteceu, quando &#8220;Tio Bij\u00fa&#8221;, terceiro filho num universo de quatro irm\u00e3os, aproveitou-se da aus\u00eancia dos [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/","og_site_name":"Jornal O Crime","article_published_time":"2024-06-23T10:47:45+00:00","og_image":[{"width":960,"height":1280,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/06\/IMG_0267.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma","datePublished":"2024-06-23T10:47:45+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/"},"wordCount":636,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/06\/IMG_0267.jpeg","articleSection":["OUTROS"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/","url":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/","name":"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/06\/IMG_0267.jpeg","datePublished":"2024-06-23T10:47:45+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/06\/IMG_0267.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2024\/06\/IMG_0267.jpeg","width":960,"height":1280},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/no-municipio-do-cazengafilho-mata-propria-mae-e-retira-os-intestinos-da-mesma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"NO MUNIC\u00cdPIO DO CAZENGA:Filho mata pr\u00f3pria m\u00e3e e retira os intestinos da mesma"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=6901"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/6901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/6902"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=6901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=6901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=6901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}