{"id":7257,"date":"2025-01-18T14:30:39","date_gmt":"2025-01-18T13:30:39","guid":{"rendered":"https:\/\/jornalocrime.com\/ilnes\/?p=7257"},"modified":"2025-01-18T14:30:39","modified_gmt":"2025-01-18T13:30:39","slug":"encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro","status":"publish","type":"post","link":"https:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/","title":{"rendered":"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>O embaixador da Guin\u00e9 Equatorial acreditado em Angola, Potasio Edu Edjang Nngana, acusado por trabalhadores angolanos de estar a desviar os sal\u00e1rios dos funcion\u00e1rios angolanos e de maus tratos, criou uma esp\u00e9cie de ca\u00e7a \u00e0s bruxas, e est\u00e1 a criar uma esp\u00e9cie de press\u00e3o psicol\u00f3gica contra os trabalhadores angolanos.<\/strong><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #ff0000;\">Fonte: Na Mira do Crime<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Secret\u00e1ria, seguran\u00e7as, motoristas e jardineiros t\u00eam o trabalho por um fio, tudo porque descobriram \u00e0s falcatruas do Edu.<\/p>\n<p style=\"text-align: justify;\">Para come\u00e7ar, come\u00e7ou a interrogar cada funcion\u00e1rio quer seja da sua resid\u00eancia como da embaixada, amea\u00e7ando com expuls\u00e3o, assim que descobrir quem denunciou as suas \u2018malabarices\u2019 ao Na Mira do Crime.<\/p>\n<p style=\"text-align: justify;\">O diplomata, que na verdade parece mais um \u2018mixeiro\u2019, n\u00e3o consegue entender como \u00e9 que os trabalhadores nacionais foram capazes de soltar o verbo, quando na verdade pareciam mais uns \u2018escravos assalariados\u2019.<\/p>\n<p style=\"text-align: justify;\">Para fazer face \u00e0s den\u00fancias, fonte do Na Mira sabe que, o que Edu \u2018fugiu\u2019 fazer aos microfones deste jornal, dando o contradit\u00f3rio, procura agora noutros jornais para \u2018desinformar\u2019 o que est\u00e1 claro.<\/p>\n<p style=\"text-align: justify;\">Agora acusa o director deste jornal de tentativa de extors\u00e3o, mas, a grava\u00e7\u00e3o da \u00fanica conversa mantida entre ambos est\u00e1 dispon\u00edvel, e foi enviada ao jornalista do Jornal Folha 8, onde ele agora procura limpar a sujeira.<\/p>\n<p style=\"text-align: justify;\">\u00c9 facto que o diplomata troca d\u00f3lares no bairro M\u00e1rtires do kifangondo para pagar os sal\u00e1rios em m\u00e3os, diferente do que era feito, no banco BIC e Santander, dando oportunidades aos nacionais de puderem contrair empr\u00e9stimos aos bancos e assim desenvolverem projectos pessoais.<\/p>\n<p style=\"text-align: justify;\">\u00c9 facto que Potasio Edu Edjang Nngana n\u00e3o paga a seguran\u00e7a social dos seus trabalhadores, alguns com mais de 13 anos de trabalho.<\/p>\n<p style=\"text-align: justify;\">Para este cidad\u00e3o equato-guineense, o seu pa\u00eds faz um favor ao pagar os sal\u00e1rios aos nacionais, e quanto mais acima do sal\u00e1rio b\u00e1sico, que para ele \u00e9 como se o seu pa\u00eds estivesse a \u2018deitar dinheiro\u2019, da\u00ed a necessidade dele mesmo amealhar alguns trocados, para sua satisfa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Este jornal segue uma investiga\u00e7\u00e3o aturada contra este diplomata, que \u00e9 ainda acusado de recrutar jovens angolanas para sua satisfa\u00e7\u00e3o sexual, na sua resid\u00eancia diplom\u00e1tica, em colabora\u00e7\u00e3o com uma outra entidade da Guin\u00e9 Equatorial, colocado na Comiss\u00e3o do Golfo da Guin\u00e9, cujo o nome seguimos a investigar, e vamos trazer detalhes da vida nocturna destas personalidades, do pa\u00eds de Baltazar.<\/p>\n<p style=\"text-align: justify;\">Ao Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores, os trabalhadores angolanos pedem interven\u00e7\u00e3o urgente, para que os seus direitos n\u00e3o sejam pisoteados em solo p\u00e1trio, por aqueles que se dizem irm\u00e3os de Angola, conforme frisou o Presidente Obiang Nguema na sua \u00faltima visita \u00e0 Angola.<\/p>\n<p style=\"text-align: justify;\">Recorde-se que uma carta deste jornal foi enviada a embaixada da Guin\u00e9 Equatorial para o devido contradit\u00f3rio, na manh\u00e3 de segunda-feira, 13, mas a miss\u00e3o diplom\u00e1tica remeteu-se ao sil\u00eancio.<br \/>\nhttps:\/\/www.namiradocrime.info\/show\/13057<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O embaixador da Guin\u00e9 Equatorial acreditado em Angola, Potasio Edu Edjang Nngana, acusado por trabalhadores angolanos de estar a desviar os sal\u00e1rios dos funcion\u00e1rios angolanos e de maus tratos, criou uma esp\u00e9cie de ca\u00e7a \u00e0s bruxas, e est\u00e1 a criar uma esp\u00e9cie de press\u00e3o psicol\u00f3gica contra os trabalhadores angolanos. Fonte: Na Mira do Crime Secret\u00e1ria, seguran\u00e7as, motoristas e jardineiros t\u00eam o trabalho por um fio, tudo porque descobriram \u00e0s falcatruas do Edu. Para come\u00e7ar, come\u00e7ou a interrogar cada funcion\u00e1rio quer seja da sua resid\u00eancia como da embaixada, amea\u00e7ando com expuls\u00e3o, assim que descobrir quem denunciou as suas \u2018malabarices\u2019 ao Na [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":7258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro - Jornal O Crime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro - Jornal O Crime\" \/>\n<meta property=\"og:description\" content=\"O embaixador da Guin\u00e9 Equatorial acreditado em Angola, Potasio Edu Edjang Nngana, acusado por trabalhadores angolanos de estar a desviar os sal\u00e1rios dos funcion\u00e1rios angolanos e de maus tratos, criou uma esp\u00e9cie de ca\u00e7a \u00e0s bruxas, e est\u00e1 a criar uma esp\u00e9cie de press\u00e3o psicol\u00f3gica contra os trabalhadores angolanos. Fonte: Na Mira do Crime Secret\u00e1ria, seguran\u00e7as, motoristas e jardineiros t\u00eam o trabalho por um fio, tudo porque descobriram \u00e0s falcatruas do Edu. Para come\u00e7ar, come\u00e7ou a interrogar cada funcion\u00e1rio quer seja da sua resid\u00eancia como da embaixada, amea\u00e7ando com expuls\u00e3o, assim que descobrir quem denunciou as suas \u2018malabarices\u2019 ao Na [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal O Crime\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-18T13:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2025\/01\/IMG_2687.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jornal O Crime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jornal O Crime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/\"},\"author\":{\"name\":\"Jornal O Crime\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"headline\":\"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro\",\"datePublished\":\"2025-01-18T13:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/\"},\"wordCount\":520,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_2687.jpeg\",\"articleSection\":[\"OUTROS\"],\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/\",\"name\":\"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro - Jornal O Crime\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_2687.jpeg\",\"datePublished\":\"2025-01-18T13:30:39+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#breadcrumb\"},\"inLanguage\":\"pt-AO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_2687.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/IMG_2687.jpeg\",\"width\":1024,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#website\",\"url\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/\",\"name\":\"Jornal o Crime\",\"description\":\"Portal Angolano de Not\u00edcias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-AO\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/jornalocrime.com\\\/ilnes\\\/#\\\/schema\\\/person\\\/011492e5dd3c64074b4f80a5d4161dc0\",\"name\":\"Jornal O Crime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-AO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g\",\"caption\":\"Jornal O Crime\"},\"sameAs\":[\"http:\\\/\\\/jornalocrime.com\"],\"url\":\"https:\\\/\\\/jornalocrime.com\\\/ilnes\\\/author\\\/o-crime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro - Jornal O Crime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/","og_locale":"pt_PT","og_type":"article","og_title":"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro - Jornal O Crime","og_description":"O embaixador da Guin\u00e9 Equatorial acreditado em Angola, Potasio Edu Edjang Nngana, acusado por trabalhadores angolanos de estar a desviar os sal\u00e1rios dos funcion\u00e1rios angolanos e de maus tratos, criou uma esp\u00e9cie de ca\u00e7a \u00e0s bruxas, e est\u00e1 a criar uma esp\u00e9cie de press\u00e3o psicol\u00f3gica contra os trabalhadores angolanos. Fonte: Na Mira do Crime Secret\u00e1ria, seguran\u00e7as, motoristas e jardineiros t\u00eam o trabalho por um fio, tudo porque descobriram \u00e0s falcatruas do Edu. Para come\u00e7ar, come\u00e7ou a interrogar cada funcion\u00e1rio quer seja da sua resid\u00eancia como da embaixada, amea\u00e7ando com expuls\u00e3o, assim que descobrir quem denunciou as suas \u2018malabarices\u2019 ao Na [&hellip;]","og_url":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/","og_site_name":"Jornal O Crime","article_published_time":"2025-01-18T13:30:39+00:00","og_image":[{"width":1024,"height":670,"url":"http:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2025\/01\/IMG_2687.jpeg","type":"image\/jpeg"}],"author":"Jornal O Crime","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jornal O Crime","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#article","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/"},"author":{"name":"Jornal O Crime","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"headline":"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro","datePublished":"2025-01-18T13:30:39+00:00","mainEntityOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/"},"wordCount":520,"commentCount":0,"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2025\/01\/IMG_2687.jpeg","articleSection":["OUTROS"],"inLanguage":"pt-AO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/","url":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/","name":"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro - Jornal O Crime","isPartOf":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#primaryimage"},"image":{"@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2025\/01\/IMG_2687.jpeg","datePublished":"2025-01-18T13:30:39+00:00","author":{"@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0"},"breadcrumb":{"@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#breadcrumb"},"inLanguage":"pt-AO","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-AO","@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#primaryimage","url":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2025\/01\/IMG_2687.jpeg","contentUrl":"https:\/\/jornalocrime.com\/ilnes\/wp-content\/uploads\/2025\/01\/IMG_2687.jpeg","width":1024,"height":670},{"@type":"BreadcrumbList","@id":"http:\/\/jornalocrime.com\/ilnes\/encurralado-embaixador-da-guine-equatorial-em-angola-atormenta-funcionarios-angolanos-e-procura-escapatoria-contra-acusacoes-de-desvios-de-dinheiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/jornalocrime.com\/ilnes\/"},{"@type":"ListItem","position":2,"name":"Encurralado: Embaixador da Guin\u00e9 Equatorial em Angola atormenta funcion\u00e1rios angolanos e procura escapat\u00f3ria contra acusa\u00e7\u00f5es de desvios de dinheiro"}]},{"@type":"WebSite","@id":"http:\/\/jornalocrime.com\/ilnes\/#website","url":"http:\/\/jornalocrime.com\/ilnes\/","name":"Jornal o Crime","description":"Portal Angolano de Not\u00edcias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jornalocrime.com\/ilnes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-AO"},{"@type":"Person","@id":"http:\/\/jornalocrime.com\/ilnes\/#\/schema\/person\/011492e5dd3c64074b4f80a5d4161dc0","name":"Jornal O Crime","image":{"@type":"ImageObject","inLanguage":"pt-AO","@id":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6eeeb476b27816f868f7630f3e27933ff4c2613eac6c8744248978644dba30d4?s=96&d=mm&r=g","caption":"Jornal O Crime"},"sameAs":["http:\/\/jornalocrime.com"],"url":"https:\/\/jornalocrime.com\/ilnes\/author\/o-crime\/"}]}},"_links":{"self":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/7257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/comments?post=7257"}],"version-history":[{"count":0,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/posts\/7257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media\/7258"}],"wp:attachment":[{"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/media?parent=7257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/categories?post=7257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalocrime.com\/ilnes\/wp-json\/wp\/v2\/tags?post=7257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}